{"id":10588,"date":"2021-10-13T00:01:00","date_gmt":"2021-10-12T23:01:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=10588"},"modified":"2021-10-12T18:25:19","modified_gmt":"2021-10-12T17:25:19","slug":"justice-plusieurs-textes-soumis-a-lapn","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/","title":{"rendered":"Justice : Plusieurs textes soumis \u00e0 l\u2019APN"},"content":{"rendered":"\n<p>Les projets de lois portant approbation de six ordonnances relatives notamment \u00e0 la Loi organique sur le r\u00e9gime \u00e9lectoral, aux proc\u00e9dures p\u00e9nales, au Code p\u00e9nal, et \u00e0 la protection des informations et des documents administratifs ont \u00e9t\u00e9 au menu d\u2019un expos\u00e9 pr\u00e9sent\u00e9 lundi devant la Commission des Affaires juridiques, administratives et des libert\u00e9s de l&rsquo;Assembl\u00e9e populaire nationale (APN) par le ministre de la Justice, Garde des Sceaux, Abderrachid Tabi qui estim\u00e9&nbsp; dans son intervention que \u00ab\u00a0la pr\u00e9sentation de l&rsquo;ordonnance 21-01 du 10 mars 2021 portant Loi organique relative au r\u00e9gime \u00e9lectoral ,modifi\u00e9e et compl\u00e9t\u00e9e, aux membres de la Commission pour validation intervient conform\u00e9ment aux dispositions de la Constitution\u00a0\u00bb, soulignant que \u00ab\u00a0cette ordonnance\u00a0\u00bb , avant sa promulgation par le Pr\u00e9sident de la R\u00e9publique, a \u00e9t\u00e9 pr\u00e9sent\u00e9e, au pr\u00e9alable, au Conseil d&rsquo;Etat et au Conseil constitutionnel et a \u00e9t\u00e9 d\u00e9battue et adopt\u00e9e par le Conseil des ministres.<\/p>\n\n\n\n<p>Pour Abderrachid Tabi, la promulgation de la Loi organique relative au r\u00e9gime \u00e9lectoral s&rsquo;inscrit dans le cadre des r\u00e9formes politiques contenues dans le programme du Pr\u00e9sident de la R\u00e9publique, approuv\u00e9es par la Constitution et adopt\u00e9es lors du r\u00e9f\u00e9rendum du 1er novembre 2020&Prime;, d\u2019autant plus que \u00ab\u00a0le Pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune a accord\u00e9 une grande importance \u00e0 l&rsquo;\u00e9laboration d&rsquo;une nouvelle Loi organique relative aux \u00e9lections, la classant en deuxi\u00e8me priorit\u00e9 apr\u00e8s la r\u00e9vision de la Constitution, en vue de recomposer des assembl\u00e9es \u00e9lues l\u00e9gitimes issues d&rsquo;\u00e9lections r\u00e9guli\u00e8res qui expriment la volont\u00e9 du peuple et qui auront pour pr\u00e9rogatives le d\u00e9bat et l&rsquo;adoption des r\u00e9formes \u00e9conomiques et structurelles n\u00e9cessaires pour consacrer son programme visant \u00e0 instaurer un Etat de droit et \u00e0 b\u00e2tir la nouvelle Alg\u00e9rie.Ainsi, le ministre de la Justice, garde des Sceaux qui a \u00e9voqu\u00e9 les principaux objectifs de la Loi organique relative aux \u00e9lections, visant essentiellement \u00e0 \u00ab\u00a0consacrer la d\u00e9mocratie, lutter contre l&rsquo;argent sale, garantir une participation populaire aux \u00e9ch\u00e9ances et r\u00e9habiliter la volont\u00e9 populaire\u00a0\u00bb n\u2019a pas omis de mentionner l\u2019importance du projet de loi N 21-10 relatif \u00e0 la Loi \u00e9lectorale dont les principaux axes, sont notamment \u00ab\u00a0la possibilit\u00e9 d&rsquo;abrogation de la condition de parit\u00e9 pour les listes des candidats parrain\u00e9s par des partis politiques ou des listes ind\u00e9pendantes n&rsquo;ayant pas pu remplir cette condition, \u00e0 condition de demander \u00e0 l&rsquo;autorit\u00e9 ind\u00e9pendante de d\u00e9livrer une autorisation\u00a0\u00bb. Cette loi, pr\u00e9cise-t-il, contient un article sur \u00ab\u00a0la r\u00e9duction du nombre de signatures requises pour l&rsquo;\u00e9lection des Assembl\u00e9es populaires communales (APC) pour les communes dont le nombre d&rsquo;habitants est \u00e9gal ou inf\u00e9rieur \u00e0 20.000\u00a0\u00bb.<\/p>\n\n\n\n<p>Par ailleurs, M. Tabi qui a estim\u00e9 que \u00ab\u00a0l&rsquo;organisation des pr\u00e9c\u00e9dentes \u00e9lections l\u00e9gislatives a donn\u00e9, tant aux citoyens et qu&rsquo;\u00e0 la classe politique, une vision claire du processus de changement institutionnel entam\u00e9 par le pr\u00e9sident de la R\u00e9publique, en application de ses engagements \u00e9lectoraux et qui aspire \u00e0 la concr\u00e9tisation des ambitions populaires exprim\u00e9es\u00a0\u00bb&nbsp; a aussi pr\u00e9sent\u00e9 un expos\u00e9 d&rsquo;un projet de loi portant \u00ab\u00a0approbation de l&rsquo;ordonnance 21-09 relative \u00e0 la protection des informations et des documents administratifs de toute menace sur l&rsquo;int\u00e9grit\u00e9 et la s\u00e9curit\u00e9 du pays, notamment la divulgation des informations via les moyens de communication. Un crime dont peut se rendre coupable un fonctionnaire publique en divulguant des secrets ou des informations pouvant \u00eatre truqu\u00e9es pour porter pr\u00e9judice \u00e0 l&rsquo;Etat et \u00e0 ses institutions\u00a0\u00bb.Enfin, estimant l&rsquo;arsenal juridique en Alg\u00e9rie et en d\u00e9pit de sa diversit\u00e9, insuffisant pour lutter contre les cons\u00e9quences de l&rsquo;augmentation de l&rsquo;utilisation des Technologies de l&rsquo;information et de la communication (TIC) pour commettre diff\u00e9rents crimes, d&rsquo;autant qu&rsquo;il est devenu n\u00e9cessaire de mettre de nouveaux m\u00e9canismes, en vue de lutte contre ce type de criminalit\u00e9, le ministre de la Justice a fait \u00e9tat de \u00ab\u00a0la cr\u00e9ation d&rsquo;un p\u00f4le p\u00e9nal \u00e0 comp\u00e9tence nationale charg\u00e9 de lutte contre la criminalit\u00e9 en lien avec les TIC intervient dans le cadre de la d\u00e9marche d&rsquo;adaptation des dispositifs nationaux charg\u00e9s de la lutte contre ce crime\u00a0\u00bb.<\/p>\n\n\n\n<p><strong>Akli A.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les projets de lois portant approbation de six ordonnances relatives notamment \u00e0 la Loi organique sur le r\u00e9gime \u00e9lectoral, aux<\/p>\n","protected":false},"author":3,"featured_media":10590,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-10588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Justice : Plusieurs textes soumis \u00e0 l\u2019APN - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Justice : Plusieurs textes soumis \u00e0 l\u2019APN - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Les projets de lois portant approbation de six ordonnances relatives notamment \u00e0 la Loi organique sur le r\u00e9gime \u00e9lectoral, aux\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-12T23:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/10\/image_2021-10-12_182507.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Justice : Plusieurs textes soumis \u00e0 l\u2019APN\",\"datePublished\":\"2021-10-12T23:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/\"},\"wordCount\":737,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/image_2021-10-12_182507.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/\",\"name\":\"Justice : Plusieurs textes soumis \u00e0 l\u2019APN - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/image_2021-10-12_182507.png\",\"datePublished\":\"2021-10-12T23:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/image_2021-10-12_182507.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/image_2021-10-12_182507.png\",\"width\":850,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/10\\\/13\\\/justice-plusieurs-textes-soumis-a-lapn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Justice : Plusieurs textes soumis \u00e0 l\u2019APN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Justice : Plusieurs textes soumis \u00e0 l\u2019APN - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/","og_locale":"fr_FR","og_type":"article","og_title":"Justice : Plusieurs textes soumis \u00e0 l\u2019APN - La Sentinelle","og_description":"Les projets de lois portant approbation de six ordonnances relatives notamment \u00e0 la Loi organique sur le r\u00e9gime \u00e9lectoral, aux","og_url":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2021-10-12T23:01:00+00:00","og_image":[{"width":850,"height":480,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/10\/image_2021-10-12_182507.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Justice : Plusieurs textes soumis \u00e0 l\u2019APN","datePublished":"2021-10-12T23:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/"},"wordCount":737,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/10\/image_2021-10-12_182507.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/","url":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/","name":"Justice : Plusieurs textes soumis \u00e0 l\u2019APN - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/10\/image_2021-10-12_182507.png","datePublished":"2021-10-12T23:01:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/10\/image_2021-10-12_182507.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/10\/image_2021-10-12_182507.png","width":850,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/10\/13\/justice-plusieurs-textes-soumis-a-lapn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Justice : Plusieurs textes soumis \u00e0 l\u2019APN"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/10588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=10588"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/10588\/revisions"}],"predecessor-version":[{"id":10591,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/10588\/revisions\/10591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/10590"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=10588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=10588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=10588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}