{"id":13152,"date":"2021-11-15T00:05:00","date_gmt":"2021-11-14T23:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=13152"},"modified":"2021-11-14T20:08:21","modified_gmt":"2021-11-14T19:08:21","slug":"hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/","title":{"rendered":"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La crainte d\u2019une quatri\u00e8me vague de propagation du covid-19 est r\u00e9elle. Le regain des contaminations quotidiennes, associ\u00e9 au rel\u00e2chement dans le respect des gestes barri\u00e8res, ainsi que la d\u00e9fiance vis-\u00e0-vis de la vaccination, augure de l\u2019arriv\u00e9e de cette quatri\u00e8me vague tant redout\u00e9e.Et le ministre de la Sant\u00e9 n\u2019h\u00e9site pas \u00e0 avertir les Alg\u00e9riens des risques que cette situation induit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le ministre de la Sant\u00e9, de la Population et de la R\u00e9forme hospitali\u00e8re, Pr Abderrahmane Benbouzid a appel\u00e9 les Alg\u00e9riens \u00e0 se pr\u00e9parer \u00e0 une quatri\u00e8me vague de contaminations. \u00ab&nbsp;On doit bien se pr\u00e9parer \u00e0 affronter une quatri\u00e8me vague avec tout son impact&nbsp;\u00bb, a-t-il affirm\u00e9 lors de son intervention sur les ondes de la Radio alg\u00e9rienne, faisant remarquer dans le m\u00eame sillage que\u00ab&nbsp;dans certains pays, on parle d\u00e9j\u00e0 d&rsquo;une cinqui\u00e8me vague&nbsp;\u00bb. Il soulignera ainsi la n\u00e9cessit\u00e9 de revenir aux premi\u00e8res mesures datant de l&rsquo;av\u00e8nement de la pand\u00e9mie du Covid 19 prises actuellement dans certains pays europ\u00e9ens qui vivent un regain des contaminations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le premier responsable du secteur de la sant\u00e9 saisira d\u2019ailleurs l\u2019occasion de son intervention \u00e0 la Radio alg\u00e9rienne pour renouveler son appel pour une vaccination massive tant qu\u2019il est encore temps, car \u00e9tant le seul moyen d\u2019\u00e9viter des formes de contamination graves au coronavirus. Il rappelle ainsi que le taux actuel de vaccination atteint apr\u00e8s la grande campagne \u00ab&nbsp;Bigday&nbsp;\u00bb a atteint 25% de l\u2019objectif cibl\u00e9 pour atteindre l&rsquo;immunit\u00e9 collective. Ainsi, le nombre de personnes vaccin\u00e9es est de 11 millions dont cinq millions ont re\u00e7u les deux doses. &nbsp;Ainsi et malgr\u00e9 le volume des vaccins import\u00e9s, la campagne a ralenti, laissant des stocks importants de vaccins sans utilisation. \u00ab&nbsp;Le minist\u00e8re de la sant\u00e9 a re\u00e7u des propositions pour l\u2019acquisition fe millions de doses de vaccins \u00e9manant de pays amis mais, nous ne pouvons en accepter \u00e9tant donn\u00e9 que nos stocks sont pleinse a-t-il assur\u00e9.Abordant la question du pass sanitaire, le ministre de la Sant\u00e9, de la Population et de la R\u00e9forme hospitali\u00e8re affirme que \u00ab\u00a0le prochain match &nbsp;de l&rsquo;\u00c9quipe nationale face au Burkina Faso sera soumis \u00e0 cette mesure sanitaire imposable \u00e0 tous les supporters\u00a0\u00bb. \u00ab\u00a0En concertation avec le minist\u00e8re de la Jeunesse et des Sports, nous avons discut\u00e9 de l&rsquo;\u00e9ventualit\u00e9 de soumettre la prochaine rencontre de l&rsquo;\u00c9quipe nationale \u00e0 l&rsquo;obligation de justifier la vaccination \u00e0 tous les supporters qui veulent suivre la rencontre sur les gradins du Stade de Blida\u00a0\u00bb a assur\u00e9 le Pr Benbouzid qui a expliqu\u00e9 que la d\u00e9cision finale d&rsquo;appliquer un pass sanitaire n&rsquo;est pas du ressort de son d\u00e9partement.Pr Benbouzid a insist\u00e9 par ailleurs sur la n\u00e9cessit\u00e9 de poursuivre le travail de sensibilisation \u00e9tant donn\u00e9 que le virus peut toujours \u00eatre parmi nous durant l&rsquo;ann\u00e9e prochaine. D&rsquo;o\u00f9, ajoute-t-il, l&rsquo;importance de s&rsquo;y pr\u00e9parer de la mani\u00e8re la plus rigoureuse en mati\u00e8re de protocole et d&rsquo;oxyg\u00e8ne notamment tout en observant qu'\u00a0\u00bbentre l&rsquo;Europe et l&rsquo;Alg\u00e9rie, il y a environ deux mois de d\u00e9calage entre deux vagues\u00a0\u00bb. Le d\u00e9placement des personnes \u00e0 l&rsquo;international a \u00e9galement \u00e9t\u00e9 au menu de l&rsquo;intervention du ministre qui a soulign\u00e9 que les gens sont libres dans leurs choix, expliquant que le vaccin russe n&rsquo;est pas homologu\u00e9 par l&rsquo;OMS, le vaccin chinois accept\u00e9 par une dizaine de pays europ\u00e9en. Des vaccins disponibles chez-nous en plus d&rsquo;Astra Zeneca. Pr Benbouzid pr\u00e9cisera d&rsquo;ailleurs que les gens ne sont pas oblig\u00e9s de prendre le m\u00eame vaccin pour la troisi\u00e8me dose. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur un autre volet, au chapitre de la p\u00e9nurie de certains m\u00e9dicaments, Pr Benbouzid a rejet\u00e9 la responsabilit\u00e9 de son d\u00e9partement expliquant que l&rsquo;importation des m\u00e9dicaments d\u00e9pend de la Pharmacie centrale des h\u00f4pitaux et un autre minist\u00e8re en pr\u00e9cisant que la p\u00e9nurie existait d\u00e9j\u00e0 mais on n&rsquo;en parlait pas. Enfin, d\u00e9plorant \u00ab\u00a0le retard accus\u00e9 dans la r\u00e9fection des 42 h\u00f4pitaux pr\u00e9fabriqu\u00e9s r\u00e9alis\u00e9s en 1984 pour une dur\u00e9e de vie qui ne d\u00e9passe pas vingt ann\u00e9es\u00a0\u00bb, il assure de la disponibilit\u00e9 de l&rsquo;Etat sous l&rsquo;impulsion du pr\u00e9sident de la R\u00e9publique, \u00e0 am\u00e9liorer les conditions socioprofessionnelles des personnels de la sant\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Kamel Nait Ameur<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crainte d\u2019une quatri\u00e8me vague de propagation du covid-19 est r\u00e9elle. Le regain des contaminations quotidiennes, associ\u00e9 au rel\u00e2chement dans<\/p>\n","protected":false},"author":3,"featured_media":13241,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-13152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague ! - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague ! - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La crainte d\u2019une quatri\u00e8me vague de propagation du covid-19 est r\u00e9elle. Le regain des contaminations quotidiennes, associ\u00e9 au rel\u00e2chement dans\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-14T23:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/11\/corona.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1665\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague !\",\"datePublished\":\"2021-11-14T23:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/\"},\"wordCount\":775,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/corona.png\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/\",\"name\":\"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague ! - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/corona.png\",\"datePublished\":\"2021-11-14T23:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/corona.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/corona.png\",\"width\":1665,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/11\\\/15\\\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague ! - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/","og_locale":"fr_FR","og_type":"article","og_title":"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague ! - La Sentinelle","og_description":"La crainte d\u2019une quatri\u00e8me vague de propagation du covid-19 est r\u00e9elle. Le regain des contaminations quotidiennes, associ\u00e9 au rel\u00e2chement dans","og_url":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2021-11-14T23:05:00+00:00","og_image":[{"width":1665,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/11\/corona.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague !","datePublished":"2021-11-14T23:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/"},"wordCount":775,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/11\/corona.png","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/","url":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/","name":"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague ! - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/11\/corona.png","datePublished":"2021-11-14T23:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/11\/corona.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/11\/corona.png","width":1665,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/11\/15\/hausse-des-contaminations-au-covid-19-gare-a-la-quatrieme-vague\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Hausse des contaminations au covid-19 : Gare \u00e0 la quatri\u00e8me vague !"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/13152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=13152"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/13152\/revisions"}],"predecessor-version":[{"id":13211,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/13152\/revisions\/13211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/13241"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=13152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=13152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=13152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}