{"id":15192,"date":"2021-12-15T00:05:00","date_gmt":"2021-12-14T23:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=15192"},"modified":"2021-12-14T21:02:23","modified_gmt":"2021-12-14T20:02:23","slug":"flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/","title":{"rendered":"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique"},"content":{"rendered":"\n<p>Le ministre des Affaires \u00e9trang\u00e8res et de la Communaut\u00e9 nationale \u00e0 l\u2019\u00e9tranger,&nbsp;Ramtane Lamamra, a&nbsp;plaid\u00e9&nbsp;pour une approche globale pour la lutte contre les flux financiers et des armes ill\u00e9gaux.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Intervenant&nbsp;lors de la r\u00e9union minist\u00e9rielle du Conseil de paix et de s\u00e9curit\u00e9 de l&rsquo;Union africaine (UA), tenue par visioconf\u00e9rence, sur \u00ab\u00a0le lien entre la paix, la s\u00e9curit\u00e9 et le d\u00e9veloppement\u00a0\u00bb, le ministre des&nbsp;Affaires \u00e9trang\u00e8res et de la Communaut\u00e9 nationale \u00e0 l&rsquo;\u00e9tranger&nbsp;mis en garde contre les vecteurs d&rsquo;instabilit\u00e9 en Afrique que sont les flux financiers illicites et les flux illicites d&rsquo;armes dans la r\u00e9gion, soulignant \u00ab\u00a0la n\u00e9cessit\u00e9 d&rsquo;une approche globale pour y faire face\u00a0\u00bb.&nbsp;Cette r\u00e9union dont le th\u00e8me trait\u00e9 est le lien entre la paix, la s\u00e9curit\u00e9 et le d\u00e9veloppement, a en effet \u00e9t\u00e9 mise \u00e0 profit&nbsp;par le chef de la diplomatie alg\u00e9rienne pour souligner que malgr\u00e9 les diff\u00e9rences dans les apparences,&nbsp;ces ph\u00e9nom\u00e8nes constituent un facteur d&rsquo;instabilit\u00e9 dans le continent et dans la r\u00e9gion.<\/p>\n\n\n\n<p>En effet, pour M. Lamamra, la s\u00e9curit\u00e9 et la paix sont indispensables pour le d\u00e9veloppement. D&rsquo;o\u00f9, souligne-t-il, la n\u00e9cessit\u00e9 de mettre en place une approche globale commune et toujours adapt\u00e9e \u00e0 l&rsquo;\u00e9volution via ses m\u00e9canismes d&rsquo;action en vue de diagnostiquer les causes profondes qui engendrent les conflits&nbsp;&nbsp;via notamment une vision globale et collective et \u00e0 plusieurs dimensions. Aussi, recommande le chef de la diplomatie alg\u00e9rienne, les efforts visant \u00e0 asseoir un travail compl\u00e9mentaire entre les pays du continent pour un d\u00e9veloppement commun, le besoin d&rsquo;un travail concert\u00e9 se fait parall\u00e8lement sentir pour trouver des solutions p\u00e9rennes pour tous les conflits qui traversent le continent.<\/p>\n\n\n\n<p>Dans cette optique, M. Lamamra n&rsquo;a pas non plus manqu\u00e9 de mettre l&rsquo;accent&nbsp;sur la n\u00e9cessit\u00e9 pour les pays africains de compter sur soit pour des solutions africaines aux probl\u00e8mes des africains.&nbsp;Une approche commune qui passe, ajoute-t-il, par des partenariats \u00e9quilibr\u00e9s et responsables qui prennent en compte&nbsp;&nbsp;du droit des pays africains au d\u00e9veloppement qui lui permettra de d\u00e9passer le temps de la marginalisation dont il souffrait.<\/p>\n\n\n\n<p>A noter que la rencontre \u00e0 laquelle a pris part&nbsp;le ministre des Affaires \u00e9trang\u00e8res&nbsp;&nbsp;s&rsquo;est tenue sous la pr\u00e9sidence&nbsp;de son homologue&nbsp;la&nbsp;R\u00e9publique f\u00e9d\u00e9rale d&rsquo;Ethiopie&nbsp;et&nbsp;a vu la participation de quinze ministres des Affaires \u00e9trang\u00e8res du continent. Une r\u00e9union qui a ainsi permis au chef de la diplomatie alg\u00e9rienne d&rsquo;expliquer la vision alg\u00e9rienne du d\u00e9veloppement qui repose sur la n\u00e9cessit\u00e9 d&rsquo;une paix durable et d&rsquo;une s\u00e9curit\u00e9 qui garantit \u00e0 tous les peuples du continent le droit au d\u00e9veloppement \u00e9conomique.&nbsp;Ce d\u00e9veloppement, assure&nbsp;Lamamra, ne peut \u00eatre concr\u00e9tis\u00e9 sans au pr\u00e9alable avoir trouv\u00e9 des solutions aux diff\u00e9rents conflits qui traversent le continent.<\/p>\n\n\n\n<p>Enfin, il est \u00e0 rappeler que le continent africain est le th\u00e9\u00e2tre de plusieurs conflits r\u00e9gionaux dont deux sont aux fronti\u00e8res de l&rsquo;Alg\u00e9rie. Le conflit au Mali ainsi que la crise libyenne sont deux probl\u00e8mes dans lesquels l&rsquo;Alg\u00e9rie est pleinement engag\u00e9e via une diplomatie&nbsp;&nbsp;tr\u00e8s dynamique.&nbsp;<\/p>\n\n\n\n<p><strong>Akli Amor<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre des Affaires \u00e9trang\u00e8res et de la Communaut\u00e9 nationale \u00e0 l\u2019\u00e9tranger,&nbsp;Ramtane Lamamra, a&nbsp;plaid\u00e9&nbsp;pour une approche globale pour la lutte<\/p>\n","protected":false},"author":3,"featured_media":15193,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-15192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le ministre des Affaires \u00e9trang\u00e8res et de la Communaut\u00e9 nationale \u00e0 l\u2019\u00e9tranger,&nbsp;Ramtane Lamamra, a&nbsp;plaid\u00e9&nbsp;pour une approche globale pour la lutte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-14T23:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/12\/la.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique\",\"datePublished\":\"2021-12-14T23:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/\"},\"wordCount\":603,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/la.png\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/\",\"name\":\"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/la.png\",\"datePublished\":\"2021-12-14T23:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/la.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/la.png\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/12\\\/15\\\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique - La Sentinelle","og_description":"Le ministre des Affaires \u00e9trang\u00e8res et de la Communaut\u00e9 nationale \u00e0 l\u2019\u00e9tranger,&nbsp;Ramtane Lamamra, a&nbsp;plaid\u00e9&nbsp;pour une approche globale pour la lutte","og_url":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2021-12-14T23:05:00+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/12\/la.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique","datePublished":"2021-12-14T23:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/"},"wordCount":603,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/12\/la.png","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/","url":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/","name":"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/12\/la.png","datePublished":"2021-12-14T23:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/12\/la.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/12\/la.png","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/12\/15\/flux-financiers-illicites-et-trafic-darmes-une-menace-pour-la-stabilite-de-lafrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Flux financiers illicites et trafic d\u2019armes : Une menace pour la stabilit\u00e9 de l\u2019Afrique"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/15192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=15192"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/15192\/revisions"}],"predecessor-version":[{"id":15194,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/15192\/revisions\/15194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/15193"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=15192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=15192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=15192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}