{"id":16848,"date":"2022-02-13T00:05:00","date_gmt":"2022-02-12T23:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=16848"},"modified":"2022-02-12T20:35:49","modified_gmt":"2022-02-12T19:35:49","slug":"investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/","title":{"rendered":"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10%"},"content":{"rendered":"\n<p>La nouvelle loi sur l&rsquo;investissement pr\u00e9voit plusieurs nouvelles mesures pour faciliter les investissements \u00e9trangers en Alg\u00e9rie, dont la cr\u00e9ation d&rsquo;un guichet unique, a affirm\u00e9&nbsp;hier&nbsp;le ministre de l&rsquo;Industrie, Ahmed Zeghdar.&nbsp;Dans l\u2019entretien qu\u2019il a accord\u00e9 \u00e0 l\u2019Agence officielle, le ministre affirm\u00e9 que \u00abla nouvelle loi sur l&rsquo;investissement est en cours d&rsquo;examen au niveau du&nbsp;Gouvernement \u00bb. \u00abElle pr\u00e9voit la cr\u00e9ation d&rsquo;un guichet unique pour les grands investissements et les investissements comptant des \u00e9trangers, et ce pour une prise en charge rapide et efficace de ces projets\u00bb, a-t-il expliqu\u00e9. Pour le ministre, la cr\u00e9ation du guichet unique porte dans ses dimensions \u00abla promotion de l&rsquo;Alg\u00e9rie en tant qu&rsquo;importante destination d&rsquo;investissement au niveau mondial\u00bb. \u00abIl aura un r\u00f4le prospectif pour d\u00e9finir les domaines \u00e0 fort potentiel en mati\u00e8re d&rsquo;investissement\u00bb, a-t-il soulign\u00e9, avant de revenir sur les avantages pr\u00e9vus dans ce nouveau texte. En ce sens, Zeghdar a \u00e9voqu\u00e9 \u00abla red\u00e9finition du concept de l&rsquo;investissement en vue de pallier les lacunes observ\u00e9es dans la loi sur l&rsquo;investissement en vigueur\u00bb, en plus de la r\u00e9vision de plusieurs proc\u00e9dures entrant dans le cadre des facilitations accord\u00e9es \u00e0 l&rsquo;acte d&rsquo;investissement. Il s\u2019agit, selon le ministre, \u00abde l\u2019octroi de larges pr\u00e9rogatives aux repr\u00e9sentants des administrations aupr\u00e8s des guichets uniques d&rsquo;investissement relevant de l&rsquo;Agence nationale de d\u00e9veloppement de l&rsquo;investissement (ANDI), au niveau des wilayas\u00bb. \u00c0 ce titre, le ministre cite \u00ables pr\u00e9rogatives conf\u00e9r\u00e9es pour l&rsquo;octroi d&rsquo;avantages d&rsquo;exploitation du guichet unique local\u00bb. Le ministre de l\u2019Industrie fera savoir que \u00abla nouvelle loi pr\u00e9voit aussi la r\u00e9organisation de l&rsquo;ANDI afin de redynamiser et de renforcer son r\u00f4le\u00bb. La nouvelle loi s\u2019ajoute, explique Zeghdar,&nbsp;\u00e0&nbsp;la mise en place d&rsquo;un r\u00e9seau d&rsquo;\u00e9valuation et de normalisation des avantages accord\u00e9s aux projets d&rsquo;investissement qui repr\u00e9sentent une importance particuli\u00e8re \u00e0 l&rsquo;\u00e9conomie nationale. Ce r\u00e9seau d\u00e9finit les pr\u00e9rogatives suivant l\u2019ensemble de normes d\u00e9j\u00e0 indiqu\u00e9es et projette l\u2019octroi de meilleurs avantages au projet dans la mesure o\u00f9 celui-ci pr\u00e9sente une valeur ajout\u00e9e \u00e0 l&rsquo;\u00e9conomie nationale. Ce n\u2019est pas tout. La nouvelle loi fixe \u00e9galement l\u2019emploi de la main-d&rsquo;\u0153uvre \u00e9trang\u00e8re en la plafonnant \u00e0 un seuil ne d\u00e9passant pas le taux de 10%, encourage le recrutement par les investisseurs \u00e9trangers de la main-d&rsquo;\u0153uvre locale, notamment celles ne n\u00e9cessitant pas de comp\u00e9tences particuli\u00e8res. Le ministre a cit\u00e9 les exemples d\u2019investissements-recrutement local retenus dans plusieurs pays du monde\u00bb. \u00abLe recrutement d&#8217;employ\u00e9s \u00e9trangers, \u00e0 l&rsquo;entr\u00e9e en exploitation du projet, est fix\u00e9 \u00e0 10% au maximum de l&rsquo;ensemble des postes cr\u00e9\u00e9s dans le cadre de l&rsquo;investissement\u00bb, a affirm\u00e9 le ministre, soulignant \u00abla possibilit\u00e9 de porter ce pourcentage \u00e0 15% du nombre total de postes cr\u00e9\u00e9s en cas d&rsquo;absence de comp\u00e9tences requises au niveau local\u00bb.&nbsp;&nbsp;\u00abUne fois approuv\u00e9 par le Gouvernement, le nouveau texte sera pr\u00e9sent\u00e9 au Conseil des ministres puis aux deux chambres du Parlement \u00bb, a affirm\u00e9 le ministre.&nbsp;<\/p>\n\n\n\n<p><strong>Audit des groupes industriels<\/strong><\/p>\n\n\n\n<p>Le premier responsable du secteur de l\u2019industrie a \u00e9galement annonc\u00e9 le lancement d\u2019un&nbsp;audit global dans tous les groupes sous tutelle afin d&rsquo;y \u00e9valuer la gouvernance et le niveau de performance.&nbsp;&nbsp;Le ministre a rappel\u00e9 qu&rsquo;un rapport \u00e9labor\u00e9 par les minist\u00e8res de l&rsquo;Industrie et des Finances avaient \u00e9t\u00e9 transmis au Premier minist\u00e8re pour examen, portant sur les lacunes relev\u00e9es en mati\u00e8re de gouvernance et de performance des gestionnaires ainsi que les solutions propos\u00e9s.&nbsp;A ce propos, des m\u00e9canismes pour l&rsquo;am\u00e9lioration de la gouvernance des entreprises ont \u00e9t\u00e9 mis en place dont la conclusion de contrats de performance adapt\u00e9s aux sp\u00e9cificit\u00e9s de chaque groupe industriel ou holding en plus de l&rsquo;\u00e9laboration d&rsquo;un r\u00e8glement int\u00e9rieur pour le conseil d&rsquo;administration et d&rsquo;un code de d\u00e9ontologie pour les membres de ces conseils.&nbsp;A une question sur la possibilit\u00e9 de consacrer des financements suppl\u00e9mentaires pour certaines unit\u00e9s industrielles publiques, M. Zeghdar a affirm\u00e9 que \u00ab\u00a0le Gouvernement \u00a3uvre \u00e0 l&rsquo;accompagnement des entreprises via une approche purement \u00e9conomique\u00a0\u00bb.&nbsp;Ainsi, \u00ab\u00a0tous les \u00e9tablissements sont appel\u00e9s \u00e0 s&rsquo;adapter \u00e0 la nouvelle situation \u00e9conomique en vue d&rsquo;assurer leur p\u00e9rennit\u00e9 tout en contribuant \u00e0 la cr\u00e9ation de la richesse et de la valeur ajout\u00e9e\u00a0\u00bb, ajoute le ministre.&nbsp;&nbsp;&nbsp;En pratique, le minist\u00e8re de l&rsquo;Industrie a mis en place un groupe de travail charg\u00e9 d&rsquo;\u00e9tudier minutieusement le situation et l&rsquo;\u00e9tat de chaque entreprise ou unit\u00e9 \u00e9conomique industrielle s\u00e9par\u00e9ment, afin de proposer des solutions pour les relancer en \u00e9laborant une feuille de route qui comprend des d\u00e9lais pour toutes les mesures et les proc\u00e9dures \u00e0 prendre.&nbsp;Au total, 51 entreprises et unit\u00e9s industrielles publiques \u00e0 l\u2019arr\u00eat, ont \u00e9t\u00e9 d\u00e9nombr\u00e9s, selon M. Zeghdar, qui a indiqu\u00e9 que ce nombre a diminu\u00e9 car certains d&rsquo;entre elles ont pu reprendre leur activit\u00e9, en attendant le d\u00e9collage du reste des entreprises.&nbsp;Quant aux entreprises en grandes difficult\u00e9s, leur nombre est estim\u00e9 \u00e0 30, selon les chiffres pr\u00e9sent\u00e9s par le ministre.<\/p>\n\n\n\n<p>Salim Abdenour<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nouvelle loi sur l&rsquo;investissement pr\u00e9voit plusieurs nouvelles mesures pour faciliter les investissements \u00e9trangers en Alg\u00e9rie, dont la cr\u00e9ation d&rsquo;un<\/p>\n","protected":false},"author":3,"featured_media":16863,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,29],"tags":[],"class_list":["post-16848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10% - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10% - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La nouvelle loi sur l&rsquo;investissement pr\u00e9voit plusieurs nouvelles mesures pour faciliter les investissements \u00e9trangers en Alg\u00e9rie, dont la cr\u00e9ation d&rsquo;un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-12T23:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/02\/2021-07-14_215442.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1387\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10%\",\"datePublished\":\"2022-02-12T23:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/\"},\"wordCount\":926,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/2021-07-14_215442.png\",\"articleSection\":[\"\u00c0 la Une\",\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/\",\"name\":\"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10% - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/2021-07-14_215442.png\",\"datePublished\":\"2022-02-12T23:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/2021-07-14_215442.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/2021-07-14_215442.png\",\"width\":1387,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/02\\\/13\\\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10% - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/","og_locale":"fr_FR","og_type":"article","og_title":"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10% - La Sentinelle","og_description":"La nouvelle loi sur l&rsquo;investissement pr\u00e9voit plusieurs nouvelles mesures pour faciliter les investissements \u00e9trangers en Alg\u00e9rie, dont la cr\u00e9ation d&rsquo;un","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-02-12T23:05:00+00:00","og_image":[{"width":1387,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/02\/2021-07-14_215442.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10%","datePublished":"2022-02-12T23:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/"},"wordCount":926,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/02\/2021-07-14_215442.png","articleSection":["\u00c0 la Une","\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/","name":"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10% - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/02\/2021-07-14_215442.png","datePublished":"2022-02-12T23:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/02\/2021-07-14_215442.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/02\/2021-07-14_215442.png","width":1387,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/02\/13\/investissements-le-recours-a-la-main-doeuvre-etrangere-plafonne-a-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Investissements\u00a0: Le recours \u00e0 la main d\u2019\u0153uvre \u00e9trang\u00e8re plafonn\u00e9 \u00e0 10%"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/16848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=16848"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/16848\/revisions"}],"predecessor-version":[{"id":16868,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/16848\/revisions\/16868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/16863"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=16848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=16848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=16848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}