{"id":19369,"date":"2022-04-05T00:01:00","date_gmt":"2022-04-04T23:01:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=19369"},"modified":"2022-04-04T17:48:13","modified_gmt":"2022-04-04T16:48:13","slug":"proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/","title":{"rendered":"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ouvert dimanche, le proc\u00e8s&nbsp;en appel&nbsp;de l\u2019ancien&nbsp;Directeur g\u00e9n\u00e9ral de la S\u00fbret\u00e9 nationale Abdelghani Hamel, de son fils et d&rsquo;ex-cadres de la wilaya de Tipasa se poursuit \u00e0 la chambre p\u00e9nale pr\u00e8s la cour de justice de Boumerd\u00e8s. Appel\u00e9s \u00e0 apporter leurs versions des faits, les mis en cause ont, dans leur totalit\u00e9, clam\u00e9 leur innocence. Les deux ex-walis de Tipaza, Kadi Abdelkader et Layadi Mustapha,&nbsp;ainsi que&nbsp;l&rsquo;ancien directeur des Domaines de Tipaza, Ali Bouamrir\u00e8ne, ont r\u00e9fut\u00e9 les accusations pour lesquelles ils ont \u00e9t\u00e9 poursuivis, notamment les griefs&nbsp;retenus&nbsp;contre eux comme le trafic d&rsquo;influence et&nbsp;le&nbsp;non-respect des proc\u00e9dures l\u00e9gales dans l&rsquo;octroi des actes de concession et du foncier destin\u00e9 \u00e0 l&rsquo;investissement. Lors des auditions, ils ont \u00e9galement ni\u00e9 \u00abl\u2019existence d\u2019une pression qu\u2019aurait exerc\u00e9 contre eux l\u2019ancien DGSN, Abdelghani Hamel pour faciliter les proc\u00e9dures de la demande d\u00e9pos\u00e9e par son fils Chafik pour b\u00e9n\u00e9ficier du foncier industriel \u00bb. Ils ont expliqu\u00e9 que \u00abla demand\u00e9 formul\u00e9e par le fils de l\u2019ancien DGSN a \u00e9t\u00e9 trait\u00e9e dans le cadre de la loi en vigueur \u00e0 l&rsquo;\u00e9poque\u00bb. A leur tour, les avocats de la d\u00e9fense ont requis \u00abl&rsquo;extinction de l&rsquo;action publique pour tous les accus\u00e9s poursuivis, notamment, pour dilapidation des biens publics, abus de fonction et trafic d&rsquo;influence&nbsp;\u00bb. Le proc\u00e8s en appel a \u00e9t\u00e9 relanc\u00e9 par les mis en cause ayant interjet\u00e9 un pourvoi en cassation aupr\u00e8s de la Cour supr\u00eame. Apr\u00e8s acceptation dans le fond et la forme, la Cour supr\u00eame a renvoy\u00e9 l\u2019affaire devant la chambre p\u00e9nale pr\u00e8s la&nbsp;Cour de Boumerdes et ce pour un nouveau proc\u00e9s. Cette affaire cite, outre l&rsquo;ancien Directeur g\u00e9n\u00e9ral de la S\u00fbret\u00e9 nationale Abdelghani Hamel, son fils, de nombreux de walis et d&rsquo;ex-cadres de la wilaya de Tipasa,&nbsp;poursuivis&nbsp;pour plusieurs chefs d&rsquo;accusation, notamment d\u00e9tournement de foncier agricole et trafic d&rsquo;influence. Le proc\u00e8s en appel a \u00e9t\u00e9 inscrit au r\u00f4le une premi\u00e8re fois le 22 septembre dernier avant d&rsquo;\u00eatre report\u00e9 successivement par la Chambre p\u00e9nale de la Cour de justice de Boumerdes, \u00e0 la demande du collectif de d\u00e9fense. Le tribunal de premi\u00e8re instance de Boumerdes avait rendu le 4 juin 2020 son verdict dans cette affaire, en condamnant l&rsquo;ancien DGSN, Abdelghani Hamel et l&rsquo;ancien wali de Tipasa Moussa Ghelai \u00e0 12 ans de prison ferme. Le m\u00eame tribunal a \u00e9galement confirm\u00e9 la peine de 10 ans de prison ferme contre chacun des ex-walis de Tipasa, Kadi Abdelkader et Layadi Mustapha, ainsi que la peine de 3 ans de prison ferme contre Chafik Hamel (fils de l&rsquo;ancien DGSN) et Salim Djai Djai, ex-chef de la s\u00fbret\u00e9 de wilaya de Tipasa. La m\u00eame juridiction a condamn\u00e9, dans la m\u00eame affaire, \u00e0 4 ans de prison avec sursis l&rsquo;ancien ministre des Finances, Hadji Baba Ammi, et \u00e0 5 ans de prison ferme l&rsquo;ancien directeur des domaines de Tipasa, Ali Bouamrane. Une peine de 2 ans de prison ferme a \u00e9t\u00e9 prononc\u00e9e contre l&rsquo;ancien directeur de l&rsquo;Industrie et des mines de Tipasa, Haddou Abderrazak, et l&rsquo;ancien Conservateur foncier de Kol\u00e9a, Mohamed Bouamama, outre une ann\u00e9e ferme contre l&rsquo;investisseur priv\u00e9 Zerad Abdelhakim. Seul l\u2019ancien Directeur g\u00e9n\u00e9ral des Domaines, Kheznadji Djamel,&nbsp;&nbsp;a&nbsp;&nbsp;\u00e9t\u00e9 acquitt\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Salim Abdenour<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ouvert dimanche, le proc\u00e8s&nbsp;en appel&nbsp;de l\u2019ancien&nbsp;Directeur g\u00e9n\u00e9ral de la S\u00fbret\u00e9 nationale Abdelghani Hamel, de son fils et d&rsquo;ex-cadres de la<\/p>\n","protected":false},"author":3,"featured_media":19381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-19369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Ouvert dimanche, le proc\u00e8s&nbsp;en appel&nbsp;de l\u2019ancien&nbsp;Directeur g\u00e9n\u00e9ral de la S\u00fbret\u00e9 nationale Abdelghani Hamel, de son fils et d&rsquo;ex-cadres de la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-04T23:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/hamel-scaled-copie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1788\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes\",\"datePublished\":\"2022-04-04T23:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/\"},\"wordCount\":611,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/hamel-scaled-copie.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/\",\"name\":\"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/hamel-scaled-copie.png\",\"datePublished\":\"2022-04-04T23:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/hamel-scaled-copie.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/hamel-scaled-copie.png\",\"width\":1788,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/05\\\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/","og_locale":"fr_FR","og_type":"article","og_title":"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes - La Sentinelle","og_description":"Ouvert dimanche, le proc\u00e8s&nbsp;en appel&nbsp;de l\u2019ancien&nbsp;Directeur g\u00e9n\u00e9ral de la S\u00fbret\u00e9 nationale Abdelghani Hamel, de son fils et d&rsquo;ex-cadres de la","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-04-04T23:01:00+00:00","og_image":[{"width":1788,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/hamel-scaled-copie.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes","datePublished":"2022-04-04T23:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/"},"wordCount":611,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/hamel-scaled-copie.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/","name":"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/hamel-scaled-copie.png","datePublished":"2022-04-04T23:01:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/hamel-scaled-copie.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/hamel-scaled-copie.png","width":1788,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/05\/proces-en-appel-de-lex-dgsn-les-plaidoiries-de-la-defense-closes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Proc\u00e8s en appel de l\u2019ex-DGSN\u00a0: Les plaidoiries de la d\u00e9fense closes"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/19369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=19369"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/19369\/revisions"}],"predecessor-version":[{"id":19382,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/19369\/revisions\/19382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/19381"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=19369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=19369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=19369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}