{"id":20084,"date":"2022-04-20T00:05:00","date_gmt":"2022-04-19T23:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=20084"},"modified":"2022-04-19T18:48:05","modified_gmt":"2022-04-19T17:48:05","slug":"palestine-occupee-lescalade-sioniste-sintensifie","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/","title":{"rendered":"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Malgr\u00e9 un redressement des indicateurs de l\u2019\u00e9conomie alg\u00e9rienne en 2021, le Fonds mon\u00e9taire international pr\u00e9voit un ralentissement de la croissance en 2022 et 2023, dans le sillage de perspectives moroses pour l\u2019\u00e9conomie mondiale, impact\u00e9e par la guerre en Ukraine et les sanctions occidentales contre la Russie.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans son rapport pour les perspectives de l\u2019\u00e9conomie mondiale publi\u00e9 hier \u00e0 l\u2019occasion de la tenue des Assembl\u00e9es annuelles de printemps des institutions de de Bretton Woods, Le Fonds mon\u00e9taire international am\u00e9liore ses perspectives de croissance pour l\u2019\u00e9conomie alg\u00e9rienne. C\u2019est ainsi qu\u2019il a actualis\u00e9 les indicateurs de cl\u00f4ture pour l\u2019exercice 2021 et situe la croissance du PIB \u00e0 4% pour l\u2019exercice clos contre une pr\u00e9vision de 3,4% anticip\u00e9e au mois d\u2019octobre dernier \u00e0 l\u2019issue des consultations au titre de l\u2019Article IV des statuts du FMI. Il en est de m\u00eame pour les \u00e9quilibres financiers externes, le FMI faisant \u00e9tat d\u2019un d\u00e9ficit de la balance du compte courant \u00e0 2,9% du PIB contre une pr\u00e9vision anticip\u00e9e de d\u00e9ficit de 7,6% du PIB. Une am\u00e9lioration qui d\u00e9note d\u2019ailleurs du r\u00e9\u00e9quilibrage des comptes externes dans le sillage du redressement des cours du p\u00e9trole et du gaz, mais aussi l\u2019augmentation de la valeur des exportations hors hydrocarbures. D\u2019ailleurs, l\u2019institution de Bretton Woods am\u00e9liore ses pr\u00e9visions pour les exercices 2022 et 2023. C\u2019est ainsi qu\u2019elle pr\u00e9voit un solde positif de la balance du compte courant durant l\u2019ann\u00e9e en cours de 2,9 % du PIB contre une pr\u00e9vision de d\u00e9ficit de 5,5% du PIB dans le rapport d\u2019octobre. Elle table \u00e9galement sur un l\u00e9ger d\u00e9ficit \u00e0 0,2% du PIB en 2023. Il en est de m\u00eame pour la croissance. S\u2019il est vrai que le FMI anticipe une baisse de la croissance du PIB \u00e0 2,4% en 2022 et 2023, ces niveaux demeurent plus \u00e9lev\u00e9s que les derni\u00e8res pr\u00e9visions qui tablaient sur une croissance r\u00e9elle du PIB de&nbsp;1,9% en 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Inflation record&nbsp;!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour ce qui est de l\u2019emploi, le FMI indique que le taux de ch\u00f4mage a atteint 13,4 % en 2021, r\u00e9sidu du choc de la pand\u00e9mie sur l\u2019\u00e9conomie nationale. Cependant, ce taux devrait \u00eatre r\u00e9sorb\u00e9 progressivement \u00e0 11,1% en 2022 et \u00e0 9,8% en 2023. Seule ombre au tableau, une inflation record qui devrait persister jusqu\u2019en 2023. Selon les chiffres du FMI, l\u2019inflation en Alg\u00e9rie a atteint les 7,2% en 2021 et devrait culminer \u00e0 8,7% en 2022 et 8,2% en 2023&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une inflation d\u2019ailleurs aliment\u00e9e par la mont\u00e9e des pouss\u00e9e inflationnistes au niveau mondial. Une question qui est d\u2019ailleurs au c\u0153ur des pr\u00e9occupations du FMI, notamment dans un contexte g\u00e9ostrat\u00e9gique tendu marqu\u00e9 par la guerre en Ukraine qui alimente la hausse des prix des commodities et risque d\u2019affecter la croissance au niveau mondial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;inflation, aliment\u00e9e par la hausse des cours des mati\u00e8res premi\u00e8res et la g\u00e9n\u00e9ralisation des tensions sur les prix, devrait rester \u00e9lev\u00e9e plus longtemps que pr\u00e9vu,&nbsp;explique&nbsp;le FMI en soulignant que la situation pourrait s&rsquo;aggraver si les d\u00e9s\u00e9quilibres entre l&rsquo;offre et la demande se creusent.&nbsp;Pour 2022, il table sur une inflation de 5,7% dans les \u00e9conomies avanc\u00e9es et de 8,7% dans les \u00e9conomies \u00e9mergentes et en d\u00e9veloppement, soit respectivement 1,8 point et 2,8 points de plus qu&rsquo;en janvier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aussi, la diminution de l&rsquo;offre mondiale de p\u00e9trole, de gaz naturel et de m\u00e9taux d&rsquo;origine russe, ainsi que de bl\u00e9 et de ma\u00efs produits en Russie et en Ukraine, a d\u00e9j\u00e0 provoqu\u00e9 une forte hausse des cours de ces produits \u00e0 l&rsquo;\u00e9chelle mondiale.&nbsp;\u00ab\u00a0L&rsquo;inflation est devenue un danger clair et bien pr\u00e9sent pour de nombreux pays\u00a0\u00bb, \u00e9crit Pierre-Olivier Gourinchas, directeur du d\u00e9partement des \u00e9tudes au FMI&nbsp;dans une note de blog publi\u00e9e&nbsp;hier.&nbsp;&nbsp;M\u00eame si la R\u00e9serve f\u00e9d\u00e9rale am\u00e9ricaine et de nombreuses autres banques centrales ont d\u00e9j\u00e0 commenc\u00e9 \u00e0 resserrer leur politique mon\u00e9taire, les cons\u00e9quences de la guerre exacerbent les tensions inflationnistes, explique-t-il.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Fonds a \u00e9galement&nbsp;r\u00e9duit ses pr\u00e9visions de croissance mondiale en raison de l&rsquo;impact direct et des retomb\u00e9es de la guerre en Ukraine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De nouvelles sanctions visant le secteur russe de l&rsquo;\u00e9nergie, un \u00e9largissement du conflit arm\u00e9, une d\u00e9c\u00e9l\u00e9ration plus marqu\u00e9e qu&rsquo;anticip\u00e9 en Chine ou encore une r\u00e9surgence de la pand\u00e9mie pourraient accentuer le ralentissement mondial tout en amplifiant l&rsquo;inflation, ajoute le FMI en soulignant que l&rsquo;envol\u00e9e des prix menace de d\u00e9clencher des troubles sociaux dans les pays \u00e9mergents et en d\u00e9veloppement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Fonds table d\u00e9sormais sur une croissance mondiale de 3,6% en 2022 comme en 2023, soit 0,8 point de pourcentage de moins que pr\u00e9vu en janvier pour cette ann\u00e9e et 0,2 point de moins pour l&rsquo;an prochain, en raison de l&rsquo;impact direct de la guerre sur les \u00e9conomies de l&rsquo;Ukraine et de la Russie, et de ses retomb\u00e9es sur le reste du monde.La croissance \u00e0 moyen terme devrait ralentir autour de 3,3%, contre 4,1% en moyenne sur la p\u00e9riode 2004-2013.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;Ukraine comme la Russie devraient subir une forte contraction de leur \u00e9conomie et la croissance dans l&rsquo;Union europ\u00e9enne devrait \u00eatre amput\u00e9e de 1,1 point cette ann\u00e9e et de 0,3 point l&rsquo;an prochain par rapport aux pr\u00e9visions de janvier.&nbsp;\u00ab\u00a0La guerre s&rsquo;ajoute \u00e0 la s\u00e9rie de chocs d&rsquo;offre qui a frapp\u00e9 l&rsquo;\u00e9conomie mondiale ces derni\u00e8res ann\u00e9es. Tels des ondes sismiques, ses effets vont se propager profond\u00e9ment et loin, par le biais des march\u00e9s de mati\u00e8res premi\u00e8res, du commerce international et des relations financi\u00e8res\u00a0\u00bb, explique Pierre-Olivier Gourinchas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Samira Ghrib<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malgr\u00e9 un redressement des indicateurs de l\u2019\u00e9conomie alg\u00e9rienne en 2021, le Fonds mon\u00e9taire international pr\u00e9voit un ralentissement de la croissance<\/p>\n","protected":false},"author":3,"featured_media":20092,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,29],"tags":[],"class_list":["post-20084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Malgr\u00e9 un redressement des indicateurs de l\u2019\u00e9conomie alg\u00e9rienne en 2021, le Fonds mon\u00e9taire international pr\u00e9voit un ralentissement de la croissance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-19T23:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/FMI.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie\",\"datePublished\":\"2022-04-19T23:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/\"},\"wordCount\":1001,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/FMI.png\",\"articleSection\":[\"\u00c0 la Une\",\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/\",\"name\":\"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/FMI.png\",\"datePublished\":\"2022-04-19T23:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/FMI.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/FMI.png\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/04\\\/20\\\/palestine-occupee-lescalade-sioniste-sintensifie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/","og_locale":"fr_FR","og_type":"article","og_title":"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie - La Sentinelle","og_description":"Malgr\u00e9 un redressement des indicateurs de l\u2019\u00e9conomie alg\u00e9rienne en 2021, le Fonds mon\u00e9taire international pr\u00e9voit un ralentissement de la croissance","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-04-19T23:05:00+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/FMI.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie","datePublished":"2022-04-19T23:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/"},"wordCount":1001,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/FMI.png","articleSection":["\u00c0 la Une","\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/","name":"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/FMI.png","datePublished":"2022-04-19T23:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/FMI.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/FMI.png","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/04\/20\/palestine-occupee-lescalade-sioniste-sintensifie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Elle s\u2019est \u00e9tablie \u00e0 4% en 2021\u00a0: Le FMI am\u00e9liore les pr\u00e9visions de croissance pour l\u2019Alg\u00e9rie"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/20084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=20084"}],"version-history":[{"count":3,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/20084\/revisions"}],"predecessor-version":[{"id":20091,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/20084\/revisions\/20091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/20092"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=20084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=20084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=20084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}