{"id":21051,"date":"2022-05-16T00:01:00","date_gmt":"2022-05-15T23:01:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=21051"},"modified":"2022-05-15T19:48:30","modified_gmt":"2022-05-15T18:48:30","slug":"transport-maritime-moundji-passe-en-revue-le-secteur","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/","title":{"rendered":"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur"},"content":{"rendered":"\n<p>Pr\u00e9sidant la r\u00e9union de coordination sur les activit\u00e9s de transport maritime des voyageurs et de marchandises et la gestion portuaire, le ministre des Transports, Abdallah Moundji, est revenu sur l\u2019ensemble des chantiers devant \u00eatre relanc\u00e9s&nbsp;dans le secteur. Il s\u2019agit essentiellement des textes de loi encadrant ces activit\u00e9s pour lesquels le ministre a mis l\u2019accent sur la n\u00e9cessit\u00e9 de leur actualisation et les adapter \u00e0 la conjoncture actuelle. Cette r\u00e9union a servi pour le ministre pour faire valoir le secteur et donner une s\u00e9rie d&rsquo;orientations entrant dans le cadre de l&rsquo;approche relative \u00e0 l&rsquo;am\u00e9lioration de la performance du transport maritime et de la gestion portuaire. Le communiqu\u00e9 du minist\u00e8re des&nbsp;Transports fait savoir que le&nbsp;&nbsp;ministre a mis l\u2019accent sur la n\u00e9cessit\u00e9 de \u00abl\u2019actualisation des textes de loi encadrant cette activit\u00e9 et leur adaptation aux&nbsp;r\u00e8glements&nbsp;de l&rsquo;Organisation maritime internationale et les diff\u00e9rents engagements de l&rsquo;Alg\u00e9rie sur le plan international\u00bb. \u00c0 ce propos, ajoute le document, Abdallah Moundji a appel\u00e9 \u00ab\u00e0 la mise en place d&rsquo;un programme d&rsquo;action pour honorer les engagements du secteur au titre du plan d&rsquo;action du Gouvernement ; notamment dans son volet li\u00e9 au d\u00e9veloppement de l&rsquo;\u00e9conomie maritime du pays et la modernisation de la gestion des activit\u00e9s de transport maritime et des ports\u00bb. La m\u00eame source explique qu\u2019il\u2019\u00abs\u2019agit pour ce faire de mettre en place un syst\u00e8me d&rsquo;information permettant la modernisation et le d\u00e9veloppement de la gestion de ce mode de transport, en accordant davantage d&rsquo;int\u00e9r\u00eat \u00e0 la formation et au d\u00e9veloppement des ressources humaines, outre la modernisation des syst\u00e8mes de gestion conform\u00e9ment aux normes internationales\u00bb. Le ministre a \u00e9galement instruit les cadres et les responsables de son d\u00e9partement les invitant \u00e0 passer rapidement \u00e0 la d\u00e9mat\u00e9rialisation et \u00e0 la num\u00e9risation de toutes les proc\u00e9dures relatives \u00e0 l&rsquo;activit\u00e9 de transport maritime et \u00e0 la gestion portuaire, en focalisant sur les services \u00e9lectroniques efficaces au profit des citoyens et des op\u00e9rateurs \u00e9conomiques, en plus du r\u00e9examen des activit\u00e9s de sous-traitance, et ce, dans l&rsquo;objectif de les limiter et d&rsquo;\u00e9tudier la possibilit\u00e9 de recourir au march\u00e9 national pour r\u00e9duire le transfert de devises\u00bb. Le document du d\u00e9partement des&nbsp;Transports explique que \u00abcette rencontre entre dans le cadre de l&rsquo;examen de la contribution du secteur des Transports \u00e0 la mise en \u0153uvre du plan d&rsquo;action du Gouvernement\u00bb, \u00abLe directeur g\u00e9n\u00e9ral de la marine marchande et des ports, qui \u00e9tait accompagn\u00e9 des cadres de la direction g\u00e9n\u00e9ral, a, \u00e0 son tour, expos\u00e9 la strat\u00e9gie et le plan d&rsquo;action trac\u00e9 pour le d\u00e9veloppement de ce domaine vital, en plus des diff\u00e9rentes mesures prises dans ce cadre\u00bb, ajoute-t-on de m\u00eame source, soulignant que \u00ables projets futurs sur lesquels le Gouvernement compte pour la relance et la modernisation de ce mode de transport ont \u00e9galement \u00e9t\u00e9 \u00e9voqu\u00e9s\u00bb,<\/p>\n\n\n\n<p><strong>Amar Malki<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9sidant la r\u00e9union de coordination sur les activit\u00e9s de transport maritime des voyageurs et de marchandises et la gestion portuaire,<\/p>\n","protected":false},"author":3,"featured_media":21089,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[29],"tags":[],"class_list":["post-21051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Pr\u00e9sidant la r\u00e9union de coordination sur les activit\u00e9s de transport maritime des voyageurs et de marchandises et la gestion portuaire,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-15T23:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/moundji.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1427\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur\",\"datePublished\":\"2022-05-15T23:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/\"},\"wordCount\":527,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/moundji.png\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/\",\"name\":\"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/moundji.png\",\"datePublished\":\"2022-05-15T23:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/moundji.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/moundji.png\",\"width\":1427,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/16\\\/transport-maritime-moundji-passe-en-revue-le-secteur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/","og_locale":"fr_FR","og_type":"article","og_title":"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur - La Sentinelle","og_description":"Pr\u00e9sidant la r\u00e9union de coordination sur les activit\u00e9s de transport maritime des voyageurs et de marchandises et la gestion portuaire,","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-05-15T23:01:00+00:00","og_image":[{"width":1427,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/moundji.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur","datePublished":"2022-05-15T23:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/"},"wordCount":527,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/moundji.png","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/","name":"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/moundji.png","datePublished":"2022-05-15T23:01:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/moundji.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/moundji.png","width":1427,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/16\/transport-maritime-moundji-passe-en-revue-le-secteur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Transport maritime\u00a0:\u00a0Moundji passe en revue le secteur"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/21051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=21051"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/21051\/revisions"}],"predecessor-version":[{"id":21092,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/21051\/revisions\/21092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/21089"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=21051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=21051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=21051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}