{"id":21421,"date":"2022-05-23T00:01:00","date_gmt":"2022-05-22T23:01:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=21421"},"modified":"2022-05-22T19:07:41","modified_gmt":"2022-05-22T18:07:41","slug":"plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/","title":{"rendered":"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s"},"content":{"rendered":"\n<p>La&nbsp;Direction g\u00e9n\u00e9rale des for\u00eats a mis tous les moyens n\u00e9cessaires pour faire face aux incendies durant la saison estivale, selon le&nbsp;Directeur g\u00e9n\u00e9ral de cet organisme, Djamel Touahria qui a pr\u00e9cis\u00e9 hier&nbsp;hier&nbsp;lors de son passage dans l\u2019\u00e9mission matinale de la cha\u00eene Une de la radio alg\u00e9rienne que \u00ab\u00a0pour cet objectif, ses services ont proc\u00e9d\u00e9 \u00e0 l\u2019ouverture de nombreuses pistes parall\u00e8lement \u00e0 la plantation de quelques 800.000&nbsp;arbres dans le cadre de la campagne nationale de plantation d\u2019arbres\u00a0\u00bb. La nouvelle strat\u00e9gie nationale de lutte contre les feux de for\u00eats, explique-t-il, implique les citoyens, les associations activant dans le domaine de la protection de l\u2019environnement et des for\u00eats. Une collaboration qui se fera, ajoute-t-il, en partenariat avec les services de la&nbsp;Protection civile.<\/p>\n\n\n\n<p>Dans ce cadre justement, explique M. Touahria, \u00ab\u00a0plusieurs actions sont d\u00e9j\u00e0 entam\u00e9es \u00e0 l\u2019instar des op\u00e9rations de nettoyage des for\u00eats ainsi que la r\u00e9partition \u00e0 travers les for\u00eats de points d\u2019eau permettant ainsi l\u2019intervention dans les meilleurs d\u00e9lais\u00a0\u00bb.&nbsp;&nbsp;Le m\u00eame responsable fera \u00e9tat \u00e9galement de \u00ab\u00a0la mobilisation d\u2019engins pour les interventions rapides dans une quarantaine de wilayas outre les postes de contr\u00f4les et de surveillance permettant de donner l\u2019alerte rapidement en cas d\u00e9clenchement d\u2019un incendie\u00a0\u00bb. Sur le plan de la sensibilisation, M. Touahria a \u00e9voqu\u00e9 l\u2019un des facteurs humains les plus r\u00e9pandus parmi les causes des incendies \u00e0 savoir \u00ab\u00a0les incendies caus\u00e9s dans les for\u00eats par les familles qui viennent pour les pique-niques et repartent en abandonnant les feux allum\u00e9s. L\u2019intervenant appellera d\u2019ailleurs \u00e0 ce sujet les familles \u00e0 ne pas allumer des feux dans les for\u00eats pour \u00e9viter des incendies ravageurs\u00a0\u00bb.&nbsp;Abordant par ailleurs plus longuement la campagne nationale de reboisement, le&nbsp;Directeur g\u00e9n\u00e9ral des services des for\u00eats a fait \u00e9tat de \u00ab\u00a0la plantation de 800 000 arbres tandis que les op\u00e9rations se poursuivent encore&nbsp;&nbsp;en collaboration avec le mouvement associatif impliqu\u00e9 dans la protection de l\u2019environnement et des for\u00eats\u00a0\u00bb. M. Touahria qui \u00e9voque&nbsp;\u00e0 ce m\u00eame sujet la c\u00e9l\u00e9bration de la&nbsp;Journ\u00e9e internationale de la biodiversit\u00e9 c\u00e9l\u00e9br\u00e9e le 22 mai de chaque ann\u00e9e, n\u2019a pas manqu\u00e9 de signaler le riche programme de sensibilisation qui se d\u00e9roulera,&nbsp;&nbsp;\u00e0 cette occasion, \u00e0 travers toutes les wilayas. Le sujet, explique-t-il, est d\u2019une grande importance&nbsp;&nbsp;pour le r\u00f4le vital du potentiel forestier qu\u2019il faudra absolument prot\u00e9ger notamment avec la mise sur pied d\u2019un v\u00e9ritable arsenal juridique. Un objectif pour lequel, ajoute M. Touahria, l\u2019Alg\u00e9rie est pleinement engag\u00e9e aux c\u00f4t\u00e9s d\u2019autres pays et des organisations internationales pour la protection de la biodiversit\u00e9. Dans cette optique justement, conclut-il, \u00ab\u00a0l&rsquo;Alg\u00e9rie a sign\u00e9 de nombreuses conventions notamment avec l\u2019Organisation des Nations Unies pour l\u2019alimentation et l\u2019agriculture\u00a0\u00bb.&nbsp;<\/p>\n\n\n\n<p><strong>Kamel Na\u00eft Ameur<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La&nbsp;Direction g\u00e9n\u00e9rale des for\u00eats a mis tous les moyens n\u00e9cessaires pour faire face aux incendies durant la saison estivale, selon<\/p>\n","protected":false},"author":3,"featured_media":21433,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-21421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La&nbsp;Direction g\u00e9n\u00e9rale des for\u00eats a mis tous les moyens n\u00e9cessaires pour faire face aux incendies durant la saison estivale, selon\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-22T23:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/incendie-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1491\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s\",\"datePublished\":\"2022-05-22T23:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/\"},\"wordCount\":534,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/incendie-1.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/\",\"name\":\"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/incendie-1.png\",\"datePublished\":\"2022-05-22T23:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/incendie-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/incendie-1.png\",\"width\":1491,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/05\\\/23\\\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/","og_locale":"fr_FR","og_type":"article","og_title":"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s - La Sentinelle","og_description":"La&nbsp;Direction g\u00e9n\u00e9rale des for\u00eats a mis tous les moyens n\u00e9cessaires pour faire face aux incendies durant la saison estivale, selon","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-05-22T23:01:00+00:00","og_image":[{"width":1491,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/incendie-1.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s","datePublished":"2022-05-22T23:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/"},"wordCount":534,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/incendie-1.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/","name":"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/incendie-1.png","datePublished":"2022-05-22T23:01:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/incendie-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/05\/incendie-1.png","width":1491,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/05\/23\/plan-de-lutte-contre-les-feux-de-forets-des-pistes-ouvertes-et-800-000-arbres-plantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Plan de lutte contre les feux de for\u00eats\u00a0:\u00a0Des pistes ouvertes et 800.000\u00a0arbres plant\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/21421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=21421"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/21421\/revisions"}],"predecessor-version":[{"id":21436,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/21421\/revisions\/21436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/21433"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=21421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=21421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=21421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}