{"id":21941,"date":"2022-06-02T00:01:00","date_gmt":"2022-06-01T23:01:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=21941"},"modified":"2022-06-01T19:47:06","modified_gmt":"2022-06-01T18:47:06","slug":"annaba-le-stockage-des-cereales-se-poursuit","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/","title":{"rendered":"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit"},"content":{"rendered":"\n<p>La campagne moissons-battage bat son plein \u00e0 Annaba et l\u2019op\u00e9ration de r\u00e9ception et de stockage des c\u00e9r\u00e9ales et du colza se poursuit depuis deux&nbsp;&nbsp;semaines \u00e0 travers les structures relevant de la Coop\u00e9rative des c\u00e9r\u00e9ales et l\u00e9gumes secs (CCLS) d\u2019Annaba.<\/p>\n\n\n\n<p>Entam\u00e9e le 25 mai&nbsp;dernier, l\u2019op\u00e9ration minutieusement pr\u00e9par\u00e9e par les responsables des services de l\u2019agriculture de la wilaya&nbsp;&nbsp;semble&nbsp;donner des r\u00e9sultats satisfaisants. Depuis le d\u00e9but du processus de moisson-battage, pour cette saison 2021\/2022 les premi\u00e8res r\u00e9coltes d\u2019orge et de colza&nbsp;&nbsp;ont afflu\u00e9 au niveau de la structure de la CCLS d\u2019El-Hadjar. Les structures de stockage de Chebaita Mokhtar, Bouhadjar et A\u00efn-Assel, dans la wilaya d\u2019El Tarf, ont pour leur part commenc\u00e9 \u00e0 recevoir des quantit\u00e9s des deux produits. L\u2019op\u00e9ration de stockage des c\u00e9r\u00e9ales est suivie de tr\u00e8s pr\u00e8s&nbsp;&nbsp;par Djamel Eddine Berrimi, wali d\u2019Annaba. Cet accompagnement vise \u00e0 assurer la r\u00e9ussite de la saison agricole et l\u2019augmentation des capacit\u00e9s de stockage qui restent un probl\u00e8me, limitant le potentiel productif de la wilaya. Ceci co\u00efncide avec la strat\u00e9gie nationale de r\u00e9duction des importations de l\u2019huile de table par l\u2019encouragement de la culture de colza via des formules d\u2019aide et d\u2019achat de la production \u00e0 des prix susceptibles d\u2019assurer la continuit\u00e9 du d\u00e9veloppement de la fili\u00e8re.&nbsp;&nbsp;Rappelons toutefois que contrairement \u00e0 la pr\u00e9c\u00e9dente saison agricole qui \u00e9tait une saison pilote pour la culture du colza, cette ann\u00e9e semble porter plusieurs menaces pour cette culture&nbsp;naissante. A travers le pays et durant les derni\u00e8res semaines, plusieurs coop\u00e9ratives de c\u00e9r\u00e9ales et de l\u00e9gumes secs \u2018\u2019CCLS\u2019\u2019 se sont abstenues de recevoir les r\u00e9coltes de colza&nbsp;car n\u2019ayant pas&nbsp;re\u00e7u des instructions de la part de la tutelle. Ainsi, les CCLS qui ont fourni les graines aux agriculteurs au d\u00e9but de la saison et lou\u00e9 leurs moissonneuses pour la r\u00e9colte, n\u2019ont pas eu l\u2019accord de la direction g\u00e9n\u00e9rale pour ouvrir les d\u00e9p\u00f4ts. Une probl\u00e9matique \u00e0 priori d\u00e9pass\u00e9e mais,&nbsp;&nbsp;constitue encore une menace s\u00e9rieuse qui pourrait dissuader certains fellahs&nbsp;de s\u2019orienter vers&nbsp;cette culture strat\u00e9gique de transformation, la prochaine saison.<\/p>\n\n\n\n<p><strong>Sofia Chahine<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La campagne moissons-battage bat son plein \u00e0 Annaba et l\u2019op\u00e9ration de r\u00e9ception et de stockage des c\u00e9r\u00e9ales et du colza<\/p>\n","protected":false},"author":3,"featured_media":21951,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-21941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La campagne moissons-battage bat son plein \u00e0 Annaba et l\u2019op\u00e9ration de r\u00e9ception et de stockage des c\u00e9r\u00e9ales et du colza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-01T23:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/Stockage_a_la_ferme.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1601\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit\",\"datePublished\":\"2022-06-01T23:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/\"},\"wordCount\":426,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Stockage_a_la_ferme.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/\",\"name\":\"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Stockage_a_la_ferme.png\",\"datePublished\":\"2022-06-01T23:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Stockage_a_la_ferme.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Stockage_a_la_ferme.png\",\"width\":1601,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/02\\\/annaba-le-stockage-des-cereales-se-poursuit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/","og_locale":"fr_FR","og_type":"article","og_title":"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit - La Sentinelle","og_description":"La campagne moissons-battage bat son plein \u00e0 Annaba et l\u2019op\u00e9ration de r\u00e9ception et de stockage des c\u00e9r\u00e9ales et du colza","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-06-01T23:01:00+00:00","og_image":[{"width":1601,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/Stockage_a_la_ferme.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit","datePublished":"2022-06-01T23:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/"},"wordCount":426,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/Stockage_a_la_ferme.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/","name":"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/Stockage_a_la_ferme.png","datePublished":"2022-06-01T23:01:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/Stockage_a_la_ferme.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/Stockage_a_la_ferme.png","width":1601,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/02\/annaba-le-stockage-des-cereales-se-poursuit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Annaba\u00a0:\u00a0Le stockage des c\u00e9r\u00e9ales se poursuit"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/21941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=21941"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/21941\/revisions"}],"predecessor-version":[{"id":21952,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/21941\/revisions\/21952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/21951"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=21941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=21941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=21941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}