{"id":22159,"date":"2022-06-07T00:01:00","date_gmt":"2022-06-06T23:01:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=22159"},"modified":"2022-06-06T19:29:18","modified_gmt":"2022-06-06T18:29:18","slug":"laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/","title":{"rendered":"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le parquet g\u00e9n\u00e9ral pr\u00e8s la Cour de Blida a requis hier une peine de 20 ans de prison \u00e0 l\u2019encontre d\u2019Abdelmoum\u00e8ne Khalifa. En effet, le proc\u00e8s en appel&nbsp;de l\u2019affaire Khalifa&nbsp;Bank&nbsp;s\u2019est ouvert dimanche. Le dossier&nbsp;cite \u00e9galement 10 autres accus\u00e9s constitu\u00e9s d\u2019anciens cadres de l\u2019\u00c9tat. Appel\u00e9s \u00e0 la barre lors du premier jour de leur jugement, les accus\u00e9s, dont Abdelmoumen Khalifa, ont ni\u00e9 tous les chefs d\u2019accusations, \u00e0 savoir association de malfaiteurs,&nbsp;&nbsp;escroquerie, vol, abus de confiance, falsification de documents bancaires, abus de pouvoir, trafic d\u2019influence. L\u2019ancien&nbsp;P-DG&nbsp;de Khalifa Bank a \u00e9galement ni\u00e9 avoir us\u00e9 de deux faux contrats pour obtenir deux pr\u00eats de l\u2019agence Staoueli de&nbsp;&nbsp;la&nbsp;Banque de d\u00e9veloppement local au profit de son \u00ab entreprise pharmaceutique\u00bb, expliquant&nbsp;qu\u2019il \u00e9tait&nbsp;\u00ab&nbsp;propri\u00e9taire de cette soci\u00e9t\u00e9 bien avant la cr\u00e9ation de la banque (Khalifa Banque)\u00bb. Abdelmoumen Khalifa a \u00e9galement ni\u00e9 \u00ab\u00eatre au&nbsp;fait de l\u2019hypoth\u00e8que de sa villa familiale de Hydra et d\u2019un local commercial \u00e0 Cheraga\u00bb. L\u2019ancien directeur de l\u2019agence de la&nbsp;&nbsp;Banque de d\u00e9veloppement local&nbsp;de Staoueli, Idir Mourad, a, pour sa part, r\u00e9fut\u00e9 son implication dans les deux pr\u00eats bancaires accord\u00e9s \u00e0 Khalifa \u00e0 base de deux documents falsifi\u00e9s. Le dossier d\u2019accusation comprend deux affaires distinctes, citant Khalifa Abdelmoumen, les fr\u00e8res Keramane et 11 autres individus, ayant interjet\u00e9 un pourvoi en cassation devant la Cour Supr\u00eame. L\u2019affaire met en cause Karamane Abdelwahab, son fr\u00e8re Abdenour et sa fille Yasmine, poursuivis pour participation \u00e0 vol en r\u00e9union. La Cour supr\u00eame, ayant \u00e9tudi\u00e9 le pourvoi en cassation, a&nbsp;&nbsp;jug\u00e9 utile de r\u00e9unir les deux dossiers pour en construire une seule affaire \u00e9tant donn\u00e9 que toutes les parties sont poursuivies pour les m\u00eames faits. Le Pr\u00e9sident du Tribunal Criminel de Blida a expliqu\u00e9 que \u00abl\u2019acceptation de l\u2019appel en cassation dans l\u2019affaire Khalifa Bank \u00e9tait due au d\u00e9faut de&nbsp;prestation de&nbsp;serment d\u2019office du liquidateur de la Banque Mouncef Badsi&nbsp;&nbsp;et de l\u2019expert comptable Hamid Foffa lors du proc\u00e8s tenu&nbsp;au&nbsp;mois de novembre 2020 apr\u00e8s que le pourvoir en cassation ait \u00e9t\u00e9 accord\u00e9 par la Cour supr\u00eame&nbsp;\u00bb&nbsp;rappelant que Khalifa Abdelmoumen a fait appel&nbsp;du verdict ayant \u00e9t\u00e9 prononc\u00e9 \u00e0 son encontre, le condamnant \u00e0 une peine de 18 ans et \u00e0 une amende de 1 million de dinars, en plus de la confiscation de ses biens. Cette m\u00eame sentence&nbsp;a \u00e9t\u00e9&nbsp;prononc\u00e9e \u00e0 son encontre en 2015. Le proc\u00e8s en appel des accus\u00e9s dans l&rsquo;affaire Khalifa Bank a \u00e9t\u00e9 ouvert en d\u00e9but de cette semaine par le tribunal correctionnel pr\u00e8s la Cour de Blida, suite \u00e0 un pourvoi en cassation interjet\u00e9 aupr\u00e8s de la Cour supr\u00eame. Le proc\u00e8s a \u00e9t\u00e9 ouvert sous la direction de la pr\u00e9sidente du tribunal Rahali Hassiba, avec l\u2019audience d\u2019Abdelmoumene Khalifa, par visioconf\u00e9rence, \u00e0 partir de l&rsquo;\u00e9tablissement p\u00e9nitentiaire de Chlef, alors que le reste des accus\u00e9s ont \u00e9t\u00e9 auditionn\u00e9s dans l\u2019apr\u00e8s-midi, au m\u00eame titre que la poursuite de l\u2019audience de l\u2019accus\u00e9 principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Amar Malki<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le parquet g\u00e9n\u00e9ral pr\u00e8s la Cour de Blida a requis hier une peine de 20 ans de prison \u00e0 l\u2019encontre<\/p>\n","protected":false},"author":3,"featured_media":22163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-22159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le parquet g\u00e9n\u00e9ral pr\u00e8s la Cour de Blida a requis hier une peine de 20 ans de prison \u00e0 l\u2019encontre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-06T23:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/khalifa-bank-scaled-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa\",\"datePublished\":\"2022-06-06T23:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/\"},\"wordCount\":585,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/khalifa-bank-scaled-1.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/\",\"name\":\"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/khalifa-bank-scaled-1.png\",\"datePublished\":\"2022-06-06T23:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/khalifa-bank-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/khalifa-bank-scaled-1.png\",\"width\":1599,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/06\\\/07\\\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa - La Sentinelle","og_description":"Le parquet g\u00e9n\u00e9ral pr\u00e8s la Cour de Blida a requis hier une peine de 20 ans de prison \u00e0 l\u2019encontre","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-06-06T23:01:00+00:00","og_image":[{"width":1599,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/khalifa-bank-scaled-1.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa","datePublished":"2022-06-06T23:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/"},"wordCount":585,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/khalifa-bank-scaled-1.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/","name":"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/khalifa-bank-scaled-1.png","datePublished":"2022-06-06T23:01:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/khalifa-bank-scaled-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/06\/khalifa-bank-scaled-1.png","width":1599,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/06\/07\/laffaire-khalifa-devant-la-cour-de-blida-20-ans-de-prison-requis-contre-abdelmoumene-khalifa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"L\u2019affaire Khalifa devant\u00a0la Cour\u00a0de Blida\u00a0: 20 ans de prison requis contre Abdelmoum\u00e8ne Khalifa"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/22159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=22159"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/22159\/revisions"}],"predecessor-version":[{"id":22165,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/22159\/revisions\/22165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/22163"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=22159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=22159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=22159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}