{"id":23665,"date":"2022-07-06T00:05:00","date_gmt":"2022-07-05T23:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=23665"},"modified":"2022-07-05T19:33:33","modified_gmt":"2022-07-05T18:33:33","slug":"un-systeme-de-defense-sophistique-et-professionnel","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/","title":{"rendered":"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel"},"content":{"rendered":"\n<p>C\u2019est un d\u00e9fil\u00e9 militaire grandiose qui a \u00e9t\u00e9&nbsp;supervis\u00e9&nbsp;hier&nbsp;par le Pr\u00e9sident de la R\u00e9publique,&nbsp;Chef&nbsp;supr\u00eame des Forces Arm\u00e9es&nbsp;et ministre de la D\u00e9fense&nbsp;nationale, Abdelmadjid Tebboune, dans le cadre des c\u00e9l\u00e9brations comm\u00e9morant le soixanti\u00e8me anniversaire du&nbsp;recouvrement&nbsp;de la souverainet\u00e9 nationale. L\u2019\u00e9v\u00e8nement&nbsp;a marqu\u00e9 la participation distincte de diverses forces de l\u2019Arm\u00e9e nationale populaire&nbsp;et&nbsp;a d\u00e9montr\u00e9 le d\u00e9veloppement important du syst\u00e8me de d\u00e9fense nationale et la modernit\u00e9 de l\u2019\u00e9quipement&nbsp;de&nbsp;pr\u00e9cision militaire. La parade a sillonn\u00e9 la&nbsp;RN&nbsp;11, adjacente&nbsp;de la Grande Mosqu\u00e9e d\u2019Alger, en pr\u00e9sence des&nbsp;Chefs&nbsp;d\u2019\u00c9tats&nbsp;de la Tunisie, de la Palestine, du Niger, de la r\u00e9publique d\u00e9mocratique du Congo, de l\u2019Ethiopie, de la R\u00e9publique Arabes Sahraouie D\u00e9mocratique et des d\u00e9l\u00e9gations de plusieurs pays fr\u00e8res et amis, \u00e0 l\u2019image de la ministre libyenne des AE et du ministre \u00e9mirati de la Tol\u00e9rance, entre autres.<\/p>\n\n\n\n<p>Le pr\u00e9sident Tebboune, accompagn\u00e9 par le chef d\u2019\u00e9tat-major de l\u2019Arm\u00e9e populaire nationale, Sa\u00efd Chanegriha, a inspect\u00e9 les carr\u00e9s participant \u00e0 l\u2019\u00e9v\u00e9nement qui a compt\u00e9 pr\u00e8s de 100 carr\u00e9s, repr\u00e9sentant toutes les forces de l\u2019Arm\u00e9e nationale populaire, sur fond de musique militaire et le retentissement de soixante (60) coups de canon.&nbsp;<\/p>\n\n\n\n<p>Dans une allocution prononc\u00e9e \u00e0 l&rsquo;occasion, le pr\u00e9sident de la R\u00e9publique a adress\u00e9 ses v\u0153ux au peuple alg\u00e9rien en cette glorieuse occasion qu\u2019il c\u00e9l\u00e8bre \u00e0 l\u2019ombre de l\u2019Alg\u00e9rie nouvelle.&nbsp;\u00ab&nbsp;En ce grand et m\u00e9morable jour, et devant cette imposante d\u00e9monstration d\u2019une l\u2019Alg\u00e9rie fi\u00e8re de ses gloires et fid\u00e8le \u00e0 ses Chouhada, je pr\u00e9sente \u00e0 notre vaillant peuple toutes mes f\u00e9licitations et tous mes v\u0153ux, alors que nous marquons un \u00e9v\u00e8nement exceptionnel pour la c\u00e9l\u00e9bration du 60e anniversaire du recouvrement de la souverainet\u00e9 nationale, \u00e0 un moment o\u00f9 les institutions et les instances constitutionnelles de l\u2019Etat ont abouti \u00e0 une phase de l\u2019Alg\u00e9rie confiante en son pr\u00e9sent et pleine d\u2019espoir en son avenir&nbsp;\u00bb, a-t-il affirm\u00e9.&nbsp;Le chef de l&rsquo;Etat a \u00e9galement salu\u00e9 les grandes r\u00e9alisations de l\u2019ANP, digne h\u00e9riti\u00e8re de l\u2019Arm\u00e9e de lib\u00e9ration nationale, jugeant \u00ab\u00a0important, devant cette imposante d\u00e9monstration, de r\u00e9it\u00e9rer les sentiments de gratitude que porte la Nation au bouclier de l\u2019Alg\u00e9rie, notre Arm\u00e9e nationale populaire, porte-\u00e9tendard de l\u2019Arm\u00e9e de lib\u00e9ration, aux c\u00f4t\u00e9s de laquelle nous assistons avec fiert\u00e9, \u00e0 l\u2019occasion de cet \u00e9v\u00e9nement historique, aux grandes r\u00e9alisations et acquis qu\u2019elle a accomplis\u00a0\u00bb.<\/p>\n\n\n\n<p>Le d\u00e9fil\u00e9&nbsp;a \u00e9t\u00e9 caract\u00e9ris\u00e9 par une performance impressionnante et tr\u00e8s pr\u00e9cise des formations de la Force a\u00e9rienne de l\u2019Arm\u00e9e nationale populaire.&nbsp;<\/p>\n\n\n\n<p>Ce d\u00e9fil\u00e9 militaire&nbsp;a commenc\u00e9 par&nbsp;&nbsp;les carr\u00e9s de la Formation musicale et de la Cavalerie, relevant de la Garde r\u00e9publicaine, suivis des carr\u00e9s des Moudjahidine, des Cadets de la Nation, des Commandements de Forces, des Ecoles militaires, ainsi que les carr\u00e9s de la Direction g\u00e9n\u00e9rale de la S\u00fbret\u00e9 nationale, de la Direction g\u00e9n\u00e9rale des douanes et la Direction g\u00e9n\u00e9rale de la Protection civile.&nbsp;Ces carr\u00e9s ont laiss\u00e9 place aux \u00ab\u00a0formations de v\u00e9hicules de combat, \u00e0 leur t\u00eate, les diff\u00e9rents types de Chars, les v\u00e9hicules de l\u2019Infanterie m\u00e9canis\u00e9e et motoris\u00e9, de l\u2019artillerie, les divers types de v\u00e9hicules lance-roquettes, divers syst\u00e8mes d\u2019artillerie contre a\u00e9ronefs et des syst\u00e8mes de missiles de d\u00e9fense antia\u00e9rien, \u00e0 l\u2019instar des syst\u00e8mes \u2018BUK-M3\u2019 et \u2018S-300\u2019, les divers syst\u00e8mes de radar, des v\u00e9hicules blind\u00e9s l\u00e9gers, des v\u00e9hicules de reconnaissance et d\u2019assaut\u00a0\u00bb.&nbsp;Les formations des diff\u00e9rents engins du G\u00e9nie de Combat d\u00e9di\u00e9s \u00e0 l\u2019ouverture des routes et la pose de ponts et divers v\u00e9hicules de soutien multiforme, y compris technique et sanitaire, ont ensuite pris le relais, devan\u00e7ant la formation des motocycles relevant de la Gendarmerie nationale.&nbsp;Par ailleurs, les formations a\u00e9riennes ont embelli le ciel de la Baie d\u2019Alger \u00e0 travers des figures a\u00e9riennes ex\u00e9cut\u00e9es par des avions relevant des Forces a\u00e9riennes dont des avions de transport tactique, de reconnaissance et des avions de chasse et bombardiers aux c\u00f4t\u00e9s des formations d\u2019h\u00e9licopt\u00e8res de combat, de reconnaissance, de transport et d\u2019h\u00e9licopt\u00e8res de recherche et de sauvetage \u00e0 c\u00f4t\u00e9 desquels ont particip\u00e9 des h\u00e9licopt\u00e8res de la Gendarmerie nationale, de la DGSN et de la Direction g\u00e9n\u00e9rale de la Protection Civile.<\/p>\n\n\n\n<p>Ce d\u00e9fil\u00e9 militaire imposant a \u00e9t\u00e9 marqu\u00e9 par une performance brillante et une extr\u00eame pr\u00e9cision des formations des forces a\u00e9riennes de l&rsquo;ANP, o\u00f9 une formation a\u00e9rienne de 6 avions d&rsquo;entra\u00eenement de base et avanc\u00e9, a d\u00e9cor\u00e9 le ciel de la capitale aux couleurs nationales, suivie d&rsquo;une formation a\u00e9rienne d&rsquo;un avion d&rsquo;instruction avanc\u00e9e de transport, accompagn\u00e9 de deux avions d&rsquo;instruction de base et avanc\u00e9e.<\/p>\n\n\n\n<p>Un escadron de 8 avions d&rsquo;instruction avanc\u00e9e et appui-feu YAK-130, une formation a\u00e9rienne de 3 avions de transport tactique C-130, un escadron de 3 avions de transport BE-350 et un avion de transport tactique IL 76-MD ont survol\u00e9 la tribune officielle install\u00e9e au niveau de Djama\u00e2 El-Djaza\u00efr, sous les applaudissements des invit\u00e9s de l&rsquo;Alg\u00e9rie.&nbsp;Les pilotes des forces a\u00e9riennes ont ex\u00e9cut\u00e9 une op\u00e9ration de ravitaillement en vol par un avion ravitailleur IL-78, accompagn\u00e9 de 2 SU 30-MKI. A la fin de l&rsquo;exhibition a\u00e9rienne, un quadruple d&rsquo;avion de chasse accompagn\u00e9 de deux SU-24-MK, ont simul\u00e9 une op\u00e9ration de ravitaillement en vol.&nbsp;L&rsquo;exhibition a \u00e9t\u00e9 appr\u00e9ci\u00e9e par l&rsquo;assistance de m\u00eame que l&rsquo;exposition du mat\u00e9riel militaire t\u00e9moignant de l&rsquo;int\u00e9r\u00eat accord\u00e9 par le Haut Commandement de l&rsquo;Arm\u00e9e \u00e0 la modernisation du syst\u00e8me de d\u00e9fense national et au renforcement de l&rsquo;industrie militaire.&nbsp;Ont \u00e9galement particip\u00e9 \u00e0 ce d\u00e9fil\u00e9 des chars modernis\u00e9s, des chars TERMINATOR, des BMP-2 avec rampe de lance missiles et des v\u00e9hicules de reconnaissances.&nbsp;Des obusiers ont, par la suite, rejoint le d\u00e9fil\u00e9 outre des v\u00e9hicules LRM, des camions dot\u00e9s de deux canon anti-a\u00e9riens, des syst\u00e8mes automoteur antia\u00e9rien et des engins de combat antia\u00e9rien avec syst\u00e8me de missiles Sol-Air.&nbsp;Le syst\u00e8me antia\u00e9rien Longue port\u00e9e \u00ab\u00a0S-300\u00a0\u00bb, a \u00e9t\u00e9 pr\u00e9sent\u00e9 en sus de VLTT dot\u00e9s d&rsquo;un canon sans recul, des VLTT blind\u00e9s et des v\u00e9hicules blind\u00e9s \u00e0 roues.&nbsp;Ensuite, il a \u00e9t\u00e9 proc\u00e9d\u00e9 \u00e0 l&rsquo;exposition des \u00e9chelles d&rsquo;assaut, des chars poseurs de ponts, des diff\u00e9rents types de stations radar, des chars de r\u00e9paration et d&rsquo;\u00e9vacuation, des BMP ambulances en en plus des camions plateaux 4&#215;4 et 6&#215;6 et des camions ateliers de r\u00e9paration \u00e9lectrique avec camion de m\u00e9canique g\u00e9n\u00e9rale et tracteur grue.&nbsp;Des exhibitions de sauts en parachute ex\u00e9cut\u00e9es par les \u00e9quipes nationales militaires de saut en parachute, masculine et f\u00e9minine, ont \u00e9galement empreint cette parade militaire, avant l\u2019entr\u00e9e des formations des Forces navales constitu\u00e9es de divers b\u00e2timents de guerre et navires polyvalents \u00e0 l\u2019image de sous-marins, de bateaux de Commandement et de Projection des Forces, de soutien et de support, de Fr\u00e9gates, de Corvettes, de Dragueurs de mines, des navires d\u2019instruction et des navires de recherche et de sauvetage.&nbsp;Le d\u00e9fil\u00e9, auquel ont pris part cent formations, a pris fin avec des spectacles artistiques divertissants accompli par la troupe de cornemuse relevant de la Garde r\u00e9publicaine.<\/p>\n\n\n\n<p><strong>Forte affluence de la population<\/strong><\/p>\n\n\n\n<p>Le d\u00e9fil\u00e9 militaire, auquel ont&nbsp;assist\u00e9&nbsp;des hauts fonctionnaires de l\u2019Etat, des conseillers du Pr\u00e9sident de la R\u00e9publique et des membres du Gouvernement et rassembl\u00e9s des moudjahidines, ainsi que des repr\u00e9sentants du corps diplomatique accr\u00e9dit\u00e9 en Alg\u00e9rie, a \u00e9galement \u00e9t\u00e9 marqu\u00e9e par une forte pr\u00e9sence de citoyens qui avaient afflu\u00e9 au parc&nbsp;des&nbsp;Sablettes depuis les premi\u00e8res heures du matin et ont interagi avec diverses pr\u00e9sentations, en particulier celles faites par l\u2019aviation.&nbsp;Des citoyens de diff\u00e9rentes r\u00e9gions de la&nbsp;Capitale et des wilayas limitrophes ont afflu\u00e9 massivement&nbsp;hier&nbsp;matin vers Les Sablettes. Quelques heures avant le coup d&rsquo;envoi du d\u00e9fil\u00e9, des dizaines de milliers de citoyens, des familles et des jeunes notamment, arborant le drapeau national, scandant des slogans nationalistes et entonnant des chants patriotiques, \u00e9taient d\u00e9j\u00e0 mass\u00e9s de part et d&rsquo;autre de la route nationale RN 11 adjacente \u00e0 Djama\u00e2 El Djaza\u00efr. Le public a afflu\u00e9 sans encombres gr\u00e2ce \u00e0 la bonne organisation assur\u00e9e par les autorit\u00e9s s\u00e9curitaires et militaires, les agents des services de la wilaya et les acteurs de la soci\u00e9t\u00e9 civile, pr\u00e9sents en force, notamment les cadets des Scouts musulmans alg\u00e9riens (SMA), qui ont orient\u00e9 et veill\u00e9 au confort des citoyens, d\u00e8s les premi\u00e8res heures. Pour Abdallah, un septuag\u00e9naire habitant dans la commune de Rouiba, cette c\u00e9l\u00e9bration est un \u00e9v\u00e9nement historique. Il a salu\u00e9 la d\u00e9cision permettant aux citoyens d&rsquo;assister \u00e0 ce d\u00e9fil\u00e9 qui lui rappelle, a-t-il dit, le dernier d\u00e9fil\u00e9 du genre organis\u00e9 il y a plus de 30 ans au m\u00eame endroit. \u00ab\u00a0C&rsquo;\u00e9tait l&rsquo;occasion de revivre les moments de liesse et de joie de l&rsquo;ind\u00e9pendance, quelques ann\u00e9es apr\u00e8s l&rsquo;affranchissement de l&rsquo;Alg\u00e9rie du joug colonial\u00a0\u00bb, a-t-il pr\u00e9cis\u00e9.&nbsp;<\/p>\n\n\n\n<p><strong>Amar Malki<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est un d\u00e9fil\u00e9 militaire grandiose qui a \u00e9t\u00e9&nbsp;supervis\u00e9&nbsp;hier&nbsp;par le Pr\u00e9sident de la R\u00e9publique,&nbsp;Chef&nbsp;supr\u00eame des Forces Arm\u00e9es&nbsp;et ministre de la D\u00e9fense&nbsp;nationale,<\/p>\n","protected":false},"author":3,"featured_media":23682,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-23665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"C\u2019est un d\u00e9fil\u00e9 militaire grandiose qui a \u00e9t\u00e9&nbsp;supervis\u00e9&nbsp;hier&nbsp;par le Pr\u00e9sident de la R\u00e9publique,&nbsp;Chef&nbsp;supr\u00eame des Forces Arm\u00e9es&nbsp;et ministre de la D\u00e9fense&nbsp;nationale,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-05T23:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/50-29.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel\",\"datePublished\":\"2022-07-05T23:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/\"},\"wordCount\":1719,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/50-29.png\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/\",\"name\":\"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/50-29.png\",\"datePublished\":\"2022-07-05T23:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/50-29.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/50-29.png\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/06\\\/un-systeme-de-defense-sophistique-et-professionnel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/","og_locale":"fr_FR","og_type":"article","og_title":"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel - La Sentinelle","og_description":"C\u2019est un d\u00e9fil\u00e9 militaire grandiose qui a \u00e9t\u00e9&nbsp;supervis\u00e9&nbsp;hier&nbsp;par le Pr\u00e9sident de la R\u00e9publique,&nbsp;Chef&nbsp;supr\u00eame des Forces Arm\u00e9es&nbsp;et ministre de la D\u00e9fense&nbsp;nationale,","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-07-05T23:05:00+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/50-29.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel","datePublished":"2022-07-05T23:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/"},"wordCount":1719,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/50-29.png","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/","name":"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/50-29.png","datePublished":"2022-07-05T23:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/50-29.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/50-29.png","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/06\/un-systeme-de-defense-sophistique-et-professionnel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Un syst\u00e8me de d\u00e9fense sophistiqu\u00e9 et professionnel"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/23665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=23665"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/23665\/revisions"}],"predecessor-version":[{"id":23683,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/23665\/revisions\/23683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/23682"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=23665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=23665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=23665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}