{"id":24534,"date":"2022-07-24T00:01:00","date_gmt":"2022-07-23T23:01:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=24534"},"modified":"2022-07-23T17:49:39","modified_gmt":"2022-07-23T16:49:39","slug":"all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/","title":{"rendered":"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne"},"content":{"rendered":"\n<p>\u00ab&nbsp;All Star 5, au th\u00e9\u00e2tre des merveilles&nbsp;\u00bb, un spectacle de chants et de danses classiques et contemporaines a \u00e9t\u00e9 anim\u00e9, jeudi soir \u00e0 Alger, par l\u2019association culturelle \u00ab\u00a0Ahl El Fen\u00a0\u00bb pour la musique, la danse et le th\u00e9\u00e2tre, devant un public nombreux.<\/p>\n\n\n\n<p>Accueilli au Th\u00e9\u00e2tre national Mahieddine-Bachtarzi (TNA), le spectacle a permis d\u2019appr\u00e9cier un programme riche et vari\u00e9, pr\u00e9par\u00e9 par les 150 membres de l\u2019association, sous la houlette de Nesrine Bourahla, pr\u00e9sidente de ce collectif.&nbsp;Durant plus de trois heures de temps, les \u00e9l\u00e8ves de l\u2019association, de diff\u00e9rents \u00e2ges et niveaux ont pr\u00e9sent\u00e9 leurs programmes respectifs, sous la direction artistique de Hani et Chaker Bourahla pour la musique et la danse respectivement.&nbsp;&nbsp;Apr\u00e8s une sc\u00e8ne d\u2019exposition, une danse fusionnant les genres classique et moderne intitul\u00e9e \u00ab\u00a0Cinq saisons pr\u00e9sentent leurs Stars\u00a0\u00bb a \u00e9t\u00e9 men\u00e9e par une quinzaine de ballerines, toutes de rouge v\u00eatues, qui ont accompagn\u00e9 les solistes Kamelia Oukid et Chakir Bourahla.&nbsp;Alternant danses et chants, l\u2019association Ahl El Fen a ensuite pr\u00e9sent\u00e9 le jeune Orchestre de la classe initiale et sa trentaine de ch\u00e9rubins, qui s\u2019est essay\u00e9 avec succ\u00e8s \u00e0 reprendre quelques chansons de r\u00e9f\u00e9rence de la musique andalouse.&nbsp;Soutenue par de petits virtuoses, \u00e0 l\u2019instar de Sophia et Racim Ameur (5 et 4 ans), la petite soliste In\u00e8s Sa\u00efdj (5ans) s\u2019est particuli\u00e8rement distingu\u00e9e avec sa voix juste au ton cristallin.&nbsp;Apr\u00e8s la brillante prestation de l\u2019Orchestre cha\u00e2bi f\u00e9minin, nouveaut\u00e9 dans l\u2019association, qui a entonn\u00e9 quelques pi\u00e8ces du r\u00e9pertoire populaire, les voix suaves d\u2019Anais Oukid et Im\u00e8ne Amarouche ont pris le relai, interpr\u00e9tant, entre autres pi\u00e8ces, \u00ab\u00a0Ya loun el a\u00e2ssel\u00a0\u00bb, \u00ab\u00a0Amchi ya Rassoul\u00a0\u00bb et \u00ab\u00a0Ya ness djarat\u2019li el gharayeb\u00a0\u00bb.&nbsp;\u00ab\u00a0La Casa d\u2019el TNA\u00a0\u00bb, une autre chor\u00e9graphie brillamment rendue par l\u2019ensemble des danseurs du collectif, a vu le jeune Abderrahmane La\u00efhem (10ans) se d\u00e9marquer, avec quelques figures de style particuli\u00e8rement difficiles, qu\u2019il a ex\u00e9cut\u00e9es dans la gr\u00e2ce du mouvement et la beaut\u00e9 du geste.&nbsp;La classe sup\u00e9rieure et \u00ab\u00a0Tarboucha Project\u00a0\u00bb, l\u2019autre nouveaut\u00e9 de l\u2019association, qui consiste \u00e0 reprendre les chansons alg\u00e9riennes \u00e0 succ\u00e8s et les restituer dans un nouvel habillage artistique, qui m\u00eale la musique \u00e0 la danse a clos le spectacle tr\u00e8s appr\u00e9ci\u00e9 par l\u2019assistance.<\/p>\n\n\n\n<p>APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&nbsp;All Star 5, au th\u00e9\u00e2tre des merveilles&nbsp;\u00bb, un spectacle de chants et de danses classiques et contemporaines a \u00e9t\u00e9 anim\u00e9,<\/p>\n","protected":false},"author":3,"featured_media":24542,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[36],"tags":[],"class_list":["post-24534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"\u00ab&nbsp;All Star 5, au th\u00e9\u00e2tre des merveilles&nbsp;\u00bb, un spectacle de chants et de danses classiques et contemporaines a \u00e9t\u00e9 anim\u00e9,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-23T23:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/tna-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne\",\"datePublished\":\"2022-07-23T23:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/\"},\"wordCount\":441,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/tna-.jpeg\",\"articleSection\":[\"Culture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/\",\"name\":\"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/tna-.jpeg\",\"datePublished\":\"2022-07-23T23:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/tna-.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/tna-.jpeg\",\"width\":850,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/07\\\/24\\\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne - La Sentinelle","og_description":"\u00ab&nbsp;All Star 5, au th\u00e9\u00e2tre des merveilles&nbsp;\u00bb, un spectacle de chants et de danses classiques et contemporaines a \u00e9t\u00e9 anim\u00e9,","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-07-23T23:01:00+00:00","og_image":[{"width":850,"height":480,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/tna-.jpeg","type":"image\/jpeg"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne","datePublished":"2022-07-23T23:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/"},"wordCount":441,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/tna-.jpeg","articleSection":["Culture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/","name":"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/tna-.jpeg","datePublished":"2022-07-23T23:01:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/tna-.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/tna-.jpeg","width":850,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/07\/24\/all-stars-5-au-theatre-des-merveilles-de-lassociation-ahl-el-fen-musique-et-danse-en-scene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0All Stars 5, au th\u00e9\u00e2tre des merveilles\u00a0\u00bb de l\u2019association Ahl El Fen\u00a0: Musique et danse en sc\u00e8ne"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/24534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=24534"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/24534\/revisions"}],"predecessor-version":[{"id":24543,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/24534\/revisions\/24543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/24542"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=24534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=24534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=24534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}