{"id":26066,"date":"2022-08-22T00:05:00","date_gmt":"2022-08-21T23:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=26066"},"modified":"2022-08-21T19:21:58","modified_gmt":"2022-08-21T18:21:58","slug":"les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/","title":{"rendered":"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La ministre de la Solidarit\u00e9 nationale, de la Famille et de la Condition de la Femme, Kaouthar Krikou, a insist\u00e9&nbsp;&nbsp;hier&nbsp;\u00e0 El Tarf sur l\u2019importance de la prise en charge psychologique et sociale efficace des familles sinistr\u00e9es.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s le brasier qui a affect\u00e9 plusieurs wilayas du pays, et notamment la wilaya d\u2019El Tarf, la situation est ma\u00eetris\u00e9e sur le terrain. La prise en charge des sinistr\u00e9s est aujourd\u2019hui une priorit\u00e9. Au-del\u00e0 du processus d\u2019indemnisation dont les phases pr\u00e9liminaires ont \u00e9t\u00e9 lanc\u00e9es, c\u2019est la prise en charge psychologique des personnes affect\u00e9es, lesquels ont perdu des proches, o\u00f9 les enfants traumatis\u00e9s par le drame, s\u2019impose comme une n\u00e9cessit\u00e9. Dans ce contexte la ministre de la&nbsp;Solidarit\u00e9 nationale, de la Famille et de la Condition de la Femme, laquelle effectue des visites dans les wilayas affect\u00e9es, notamment Souk Ahras et El Tarf a insist\u00e9 hier sur ce volet bien pr\u00e9cis.&nbsp;&nbsp;Kaouthar Krikou a&nbsp;pr\u00e9cis\u00e9 dans ce sens que&nbsp;des instructions fermes ont \u00e9t\u00e9 donn\u00e9es aux cellules de proximit\u00e9 relevant de son secteur pour assurer la prise en charge psychologique et sociale en coordination avec les services de la protection civile et de la sant\u00e9 des familles sinistr\u00e9es notamment des enfants scolaris\u00e9s en pr\u00e9vision de la prochaine rentr\u00e9e scolaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est utile de rappeler dans ce sens que&nbsp;des cellules de proximit\u00e9 dans les wilayas sinistr\u00e9es&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">compos\u00e9es de psychologues et de m\u00e9decins ont \u00e9t\u00e9 mobilis\u00e9es afin d&rsquo;apporter une prise en charge psychologique et sociale aux sinistr\u00e9s, en attendant le recensement de leurs besoins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, une cellule de crise a \u00e9t\u00e9 mise sur pied au niveau du minist\u00e8re afin de suivre le d\u00e9roulement de l&rsquo;op\u00e9ration d&rsquo;intervention au niveau local et donner des instructions aux services des cellules de proximit\u00e9 \u00e0 l&rsquo;effet de fournir tous les moyens mat\u00e9riels et humains et d&rsquo;intensifier les sorties sur le terrain dans les villages.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ministre&nbsp;a affirm\u00e9 avoir relev\u00e9 \u00ab\u00a0un excellent\u00a0\u00bb encadrement de l\u2019op\u00e9ration de la prise en charge des sinistr\u00e9s par la commission de wilaya install\u00e9e \u00e0 cet effet et pr\u00e9sid\u00e9e par le wali d\u2019El Tarf, Harfouche Benarar, et qui comprend des membres de tous les secteurs concern\u00e9s et assure la r\u00e9ception et la distribution de aides et r\u00e9alise des enqu\u00eates sociales pour identifier les familles qui ont le plus grand besoin de ces aides.&nbsp;La ministre s\u2019est ensuite rendue en compagnie du pr\u00e9sident de l\u2019Observatoire national de la soci\u00e9t\u00e9 civile et des autorit\u00e9s locales vers les villages Reghia dans la commune de Berrihane et El Meleha dans la commune d\u2019El Kala ainsi que la commune d\u2019El Ayoune.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hocine Fadheli<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ministre de la Solidarit\u00e9 nationale, de la Famille et de la Condition de la Femme, Kaouthar Krikou, a insist\u00e9&nbsp;&nbsp;hier&nbsp;\u00e0<\/p>\n","protected":false},"author":3,"featured_media":26076,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-26066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La ministre de la Solidarit\u00e9 nationale, de la Famille et de la Condition de la Femme, Kaouthar Krikou, a insist\u00e9&nbsp;&nbsp;hier&nbsp;\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-21T23:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/krikou.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique\",\"datePublished\":\"2022-08-21T23:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/\"},\"wordCount\":504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/krikou.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/\",\"name\":\"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/krikou.png\",\"datePublished\":\"2022-08-21T23:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/krikou.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/krikou.png\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/08\\\/22\\\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/","og_locale":"fr_FR","og_type":"article","og_title":"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique - La Sentinelle","og_description":"La ministre de la Solidarit\u00e9 nationale, de la Famille et de la Condition de la Femme, Kaouthar Krikou, a insist\u00e9&nbsp;&nbsp;hier&nbsp;\u00e0","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-08-21T23:05:00+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/krikou.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique","datePublished":"2022-08-21T23:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/"},"wordCount":504,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/krikou.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/","name":"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/krikou.png","datePublished":"2022-08-21T23:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/krikou.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/krikou.png","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/08\/22\/les-familles-des-victimes-pleurent-leurs-morts-la-necessaire-prise-en-charge-psychologique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Les familles des victimes pleurent leurs morts\u00a0: La n\u00e9cessaire prise en charge psychologique"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/26066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=26066"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/26066\/revisions"}],"predecessor-version":[{"id":26077,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/26066\/revisions\/26077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/26076"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=26066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=26066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=26066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}