{"id":26706,"date":"2022-09-01T00:05:00","date_gmt":"2022-08-31T23:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=26706"},"modified":"2022-08-31T20:50:05","modified_gmt":"2022-08-31T19:50:05","slug":"energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/","title":{"rendered":"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La situation se complique sur le march\u00e9 europ\u00e9en. Le g\u00e9ant russe Gazprom a d\u00e9cid\u00e9 d\u2019une nouvelle suspension des livraisons de gaz \u00e0 l\u2019Europe durant trois jours, tandis que la France qui refuse de payer en roubles rejoint la cohorte des pays qui ne recevront plus de gaz russe.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En effet, a&nbsp;Gazprom suspend \u00ab compl\u00e8tement \u00bb ses livraisons au groupe fran\u00e7ais Engie d\u00e8s&nbsp;aujourd\u2019hui, en raison du non-paiement par ce dernier de l\u2019int\u00e9gralit\u00e9 de celles effectu\u00e9es en juillet.&nbsp;\u00ab Gazprom Export a notifi\u00e9 Engie d\u2019une suspension compl\u00e8te des livraisons de gaz \u00e0 partir du 1er septembre 2022 jusqu\u2019\u00e0 la r\u00e9ception en int\u00e9gralit\u00e9 des sommes financi\u00e8res dues pour les livraisons \u00bb, a indiqu\u00e9 le groupe russe dans un communiqu\u00e9 publi\u00e9 mardi soir sur son compte Telegram.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En vertu d\u2019un d\u00e9cret du pr\u00e9sident russe, Vladimir Poutine, sign\u00e9 fin mars, Gazprom pr\u00e9cise qu\u2019\u00ab il est interdit de livrer davantage de gaz naturel \u00e0 un acheteur \u00e9tranger si l\u2019acheteur n\u2019a pas effectu\u00e9 le paiement en int\u00e9gralit\u00e9 dans le d\u00e9lai fix\u00e9 dans le contrat \u00bb. Or, Gazprom affirme qu\u2019il n\u2019avait pas re\u00e7u mardi en fin de journ\u00e9e toutes les sommes dues pour les livraisons de juillet.&nbsp;Dans la matin\u00e9e de mardi, Engie avait annonc\u00e9 que Gazprom l\u2019avait inform\u00e9 de r\u00e9ductions suppl\u00e9mentaires et imm\u00e9diates de ses livraisons de gaz \u00ab en raison d\u2019un d\u00e9saccord entre les parties sur l\u2019application de contrats \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les Europ\u00e9ens sont de nouveau en alerte apr\u00e8s une interruption des livraisons via le gazoduc Nord Stream&nbsp;depuis hier. Annonc\u00e9e cet \u00e9t\u00e9 par le g\u00e9ant russe Gazprom, cette interruption serait li\u00e9e \u00e0 des travaux \u00ab n\u00e9cessaires \u00bb dans une station de compression, situ\u00e9e en Russie. Le flux de gaz est effectivement tomb\u00e9 \u00e0 z\u00e9ro aux premi\u00e8res heures de la matin\u00e9e,&nbsp;selon les donn\u00e9es mises en ligne par le r\u00e9seau europ\u00e9en de transport de gaz Entsog et par le site de la soci\u00e9t\u00e9 Nord Stream.&nbsp;Gazprom avait annonc\u00e9 de son c\u00f4t\u00e9 avoir \u00ab enti\u00e8rement \u00bb suspendu ses livraisons de gaz\u200b vers l\u2019Europe via Nord Stream, conduite qui relie directement les champs gaziers sib\u00e9riens au nord de l\u2019Allemagne, d\u2019o\u00f9 le gaz est ensuite export\u00e9 \u00e0 d\u2019autres pays europ\u00e9ens. Ces travaux de maintenance, programm\u00e9s jusqu\u2019\u00e0 samedi, doivent \u00eatre effectu\u00e9s \u00ab toutes les 1.000 heures \u00bb, avait assur\u00e9 pr\u00e9c\u00e9demment Gazprom, propri\u00e9taire du gazoduc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur les march\u00e9s, le gaz naturel europ\u00e9en baissait un peu&nbsp;hier, malgr\u00e9 l&rsquo;interruption des livraisons russes via Nord Stream 1, l&rsquo;Europe ayant fait \u00e9tat de stocks de gaz plus rapidement remplis que pr\u00e9vu.&nbsp;Vers 12H40 GMT, le TTF n\u00e9erlandais, r\u00e9f\u00e9rence du march\u00e9 europ\u00e9en, c\u00e9dait 3% \u00e0 248,995 euros le m\u00e9gawattheure (MWh).&nbsp;Depuis son r\u00e9cent sommet depuis le d\u00e9but de la guerre en Ukraine atteint la semaine pass\u00e9e \u00e0 plus de 342 euros le MWh, le gaz a chut\u00e9 d&rsquo;environ 27%.&nbsp;\u00ab\u00a0Le risque pour l&rsquo;approvisionnement hivernal de l&rsquo;Europe demeure toutefois\u00a0\u00bb,&nbsp;&nbsp;explique&nbsp;note Wei Xiong, de Rystad Energy. \u00e9tant donn\u00e9 les faibles livraisons en provenance de Russie, et l&rsquo;UE pourrait \u00eatre confront\u00e9 \u00ab\u00a0\u00e0 la concurrence des importateurs asiatiques \u00e0 l&rsquo;approche de l&rsquo;hiver\u00a0\u00bb.&nbsp;Le PDG de Gazprom Alexe\u00ef Miller a affirm\u00e9 mercredi que le gazier augmente constamment les approvisionnements via le gazoduc Power of Siberia vers la Chine, au-del\u00e0 des quantit\u00e9s quotidiennes contractuelles.&nbsp;\u00ab\u00a0La non-reprise des flux samedi serait un coup dur pour ce qui s&rsquo;annonce d\u00e9j\u00e0 comme un hiver difficile et co\u00fbteux\u00a0\u00bb, affirme \u00e9galement Craig Erlam, analyste chez Oanda.&nbsp;De leur c\u00f4t\u00e9, les prix du p\u00e9trole \u00e9taient quant \u00e0 eux une nouvelle fois lest\u00e9s mercredi par l&rsquo;inflation et les craintes de r\u00e9cession qui pourraient affecter la demande.&nbsp;Le baril de Brent&nbsp;de la mer du Nord pour livraison en octobre perdait 3,45% \u00e0 95,88 dollars.&nbsp;Le baril de West Texas Intermediate (WTI) am\u00e9ricain pour livraison en septembre baissait quant \u00e0 lui de 2,97%, \u00e0 88,92 dollars, glissant sous les 90 dollars le baril.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R.E.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La situation se complique sur le march\u00e9 europ\u00e9en. Le g\u00e9ant russe Gazprom a d\u00e9cid\u00e9 d\u2019une nouvelle suspension des livraisons de<\/p>\n","protected":false},"author":3,"featured_media":26715,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[29],"tags":[],"class_list":["post-26706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La situation se complique sur le march\u00e9 europ\u00e9en. Le g\u00e9ant russe Gazprom a d\u00e9cid\u00e9 d\u2019une nouvelle suspension des livraisons de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-31T23:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/gazprom-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe\",\"datePublished\":\"2022-08-31T23:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/\"},\"wordCount\":714,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/gazprom-5.png\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/\",\"name\":\"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/gazprom-5.png\",\"datePublished\":\"2022-08-31T23:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/gazprom-5.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/gazprom-5.png\",\"width\":1800,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/01\\\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/","og_locale":"fr_FR","og_type":"article","og_title":"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe - La Sentinelle","og_description":"La situation se complique sur le march\u00e9 europ\u00e9en. Le g\u00e9ant russe Gazprom a d\u00e9cid\u00e9 d\u2019une nouvelle suspension des livraisons de","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-08-31T23:05:00+00:00","og_image":[{"width":1800,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/gazprom-5.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe","datePublished":"2022-08-31T23:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/"},"wordCount":714,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/gazprom-5.png","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/","name":"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/gazprom-5.png","datePublished":"2022-08-31T23:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/gazprom-5.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/08\/gazprom-5.png","width":1800,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/01\/energie-gazprom-coupe-une-nouvelle-fois-le-gaz-a-leurope\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Energie\u00a0: Gazprom coupe, une nouvelle fois, le gaz \u00e0 l\u2019Europe"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/26706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=26706"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/26706\/revisions"}],"predecessor-version":[{"id":26719,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/26706\/revisions\/26719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/26715"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=26706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=26706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=26706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}