{"id":26752,"date":"2022-09-04T00:05:00","date_gmt":"2022-09-03T23:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=26752"},"modified":"2022-09-03T18:36:51","modified_gmt":"2022-09-03T17:36:51","slug":"enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/","title":{"rendered":"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les listes des&nbsp;enseignants&nbsp;contractuels d&rsquo;anglais du palier primaire seront, au plus tard, publi\u00e9es aujourd&rsquo;hui. Le ministre de l&rsquo;\u00c9ducation nationale, Abdelhakim Belabed, a jug\u00e9 utile d\u2019anticiper les \u00e9v\u00e9nements en mettant l\u2019accent sur la c\u00e9l\u00e9rit\u00e9 des proc\u00e9dures. Lors de la derni\u00e8re r\u00e9union qu\u2019il a pr\u00e9sid\u00e9e \u00e0 l\u2019aide de la visio-conf\u00e9rence&nbsp;avec les directeurs de l\u2019\u00e9ducation, il a instruit&nbsp;ces derniers de&nbsp;publier les listes des professeurs d&rsquo;anglais afin de passer aux \u00e9tapes suivante qui consistent&nbsp;en&nbsp;la remise des dossiers des contrats afin de lancer la formation des ma\u00eetres et enseignants en question \u00e0 partir de jeudi&nbsp;prochain.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre,&nbsp;le ministre a fait savoir que le manuel d&rsquo;anglais pour la troisi\u00e8me ann\u00e9e primaire \u00e9tait pr\u00eat apr\u00e8s avoir \u00e9t\u00e9 homologu\u00e9 et approuv\u00e9 par l&rsquo;INRE le 1 septembre 2022, ce qui permettra \u00e0 l&rsquo;Office national des publications scolaire (ONPS) d&rsquo;entamer l&rsquo;impression pour assurer sa disponibilit\u00e9 avant la rentr\u00e9e scolaire.&nbsp;Le ministre de l&rsquo;Education a instruit, dans ce cadre, les directeurs des de l&rsquo;\u00e9ducation \u00e0 l&rsquo;effet de \u00ab\u00a0mettre en place un dispositif de suivi de l&rsquo;op\u00e9ration de distribution de ce manuel aux \u00e9tablissement scolaires \u00e0 partir de ce dimanche 4 septembre&nbsp;(aujourd\u2019hui, NDLR)\u00a0\u00bb.Belabed est revenu, lors de cette conf\u00e9rence, sur les \u00e9tapes ayant pr\u00e9c\u00e9d\u00e9 l&rsquo;annonce du retour au mode d&rsquo;enseignement habituel durant cette ann\u00e9e scolaire, en application des instructions du Pr\u00e9sident de la R\u00e9publique relatives \u00e0 la consultation des partenaires sociaux et l&rsquo;examen de leurs propositions, et ce, au cours d&rsquo;une r\u00e9union tenue le 1 septembre sous la pr\u00e9sidence du Premier ministre en pr\u00e9sence des ministres de l&rsquo;Education et de la Sant\u00e9.&nbsp;Evoquant l&rsquo;enseignement de l&rsquo;anglais au primaire au titre de l&rsquo;ann\u00e9e scolaire 2022\/2023, le ministre a mis en avant la n\u00e9cessit\u00e9 de veiller \u00e0 l&rsquo;application stricte des consignes en vue de traiter les op\u00e9rations li\u00e9es \u00e0 ce dossier en toute transparence et de communiquer au moment opportun la liste des recrut\u00e9s contractuels apr\u00e8s \u00e9puisement, bien entendu, des listes des dipl\u00f4m\u00e9s des Ecoles normales sup\u00e9rieures (ENS).&nbsp;Le ministre a instruit, par ailleurs, d&rsquo;effectuer une \u00e9valuation et un \u00e9tat des lieux de l&rsquo;op\u00e9ration de vente du manuel scolaire au niveau des \u00e9coles primaires, et de suivre la distribution des tablettes \u00e9lectroniques dans les \u00e9coles pilotes.&nbsp;Quant \u00e0 la circulaire relative au protocole de redoublement, il a jug\u00e9 primordial d&rsquo;annoncer les dates de cette chance tellement importante pour nos enfants, et d&rsquo;en informer les parents pour leur \u00e9viter de se rendre aux \u00e9tablissements d&rsquo;enseignement ou aux directions de l&rsquo;Education, a conclu le communiqu\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Amar Malki<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les listes des&nbsp;enseignants&nbsp;contractuels d&rsquo;anglais du palier primaire seront, au plus tard, publi\u00e9es aujourd&rsquo;hui. Le ministre de l&rsquo;\u00c9ducation nationale, Abdelhakim Belabed,<\/p>\n","protected":false},"author":3,"featured_media":24014,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-26752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Les listes des&nbsp;enseignants&nbsp;contractuels d&rsquo;anglais du palier primaire seront, au plus tard, publi\u00e9es aujourd&rsquo;hui. Le ministre de l&rsquo;\u00c9ducation nationale, Abdelhakim Belabed,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-03T23:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/belabed.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1427\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui\",\"datePublished\":\"2022-09-03T23:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/\"},\"wordCount\":498,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/belabed.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/\",\"name\":\"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/belabed.png\",\"datePublished\":\"2022-09-03T23:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/belabed.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/belabed.png\",\"width\":1427,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/09\\\/04\\\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/","og_locale":"fr_FR","og_type":"article","og_title":"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui - La Sentinelle","og_description":"Les listes des&nbsp;enseignants&nbsp;contractuels d&rsquo;anglais du palier primaire seront, au plus tard, publi\u00e9es aujourd&rsquo;hui. Le ministre de l&rsquo;\u00c9ducation nationale, Abdelhakim Belabed,","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-09-03T23:05:00+00:00","og_image":[{"width":1427,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/belabed.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui","datePublished":"2022-09-03T23:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/"},"wordCount":498,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/belabed.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/","name":"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/belabed.png","datePublished":"2022-09-03T23:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/belabed.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/07\/belabed.png","width":1427,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/09\/04\/enseignement-de-langlais-au-cycle-primaire-la-liste-des-enseignants-affiche-des-aujourdhui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Enseignement de l\u2019Anglais au cycle primaire\u00a0: La liste des enseignants affich\u00e9 d\u00e8s aujourd\u2019hui"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/26752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=26752"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/26752\/revisions"}],"predecessor-version":[{"id":26764,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/26752\/revisions\/26764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/24014"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=26752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=26752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=26752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}