{"id":28503,"date":"2022-10-05T22:00:00","date_gmt":"2022-10-05T21:00:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=28503"},"modified":"2022-10-05T16:27:43","modified_gmt":"2022-10-05T15:27:43","slug":"guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/","title":{"rendered":"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Kremlin a promis hier de r\u00e9cup\u00e9rer les territoires perdus r\u00e9cemment par Moscou dans les r\u00e9gions annex\u00e9es dans le sud et l&rsquo;est de l&rsquo;Ukraine, tout en assurant que ces r\u00e9gions seront avec la Russie \u00abpour toujours\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCertains territoires seront repris et nous allons continuer \u00e0 mener des consultations avec la population (locale) sur son souhait de vivre en Russie\u00bb, a d\u00e9clar\u00e9 \u00e0 la presse le porte-parole de la pr\u00e9sidence russe, Dmitri Peskov, interrog\u00e9 sur les fronti\u00e8res exactes de ces r\u00e9gions annex\u00e9es, o\u00f9 les forces russes ont abandonn\u00e9 certaines localit\u00e9s apr\u00e8s des contre-offensives ukrainiennes.Toujours dans le contexte de la guerre en Ukraine, la Russie a exig\u00e9 hier de participer \u00e0 l&rsquo;enqu\u00eate sur les fuites des gazoducs Nord Stream 1 et 2, la Su\u00e8de, en charge des investigations, ayant bloqu\u00e9 l&rsquo;acc\u00e8s \u00e0 la zone de ce sabotage pr\u00e9sum\u00e9 en mer Baltique. \u00abIl devrait vraiment y avoir une enqu\u00eate, naturellement, avec la participation de la Russie\u00bb, a d\u00e9clar\u00e9 un vice-ministre russe des Affaires \u00e9trang\u00e8res, Sergue\u00ef Verchinine, cit\u00e9 par les agences de presse Tass et Ria Novosti.Vendredi, le Conseil de s\u00e9curit\u00e9 de l&rsquo;ONU s&rsquo;est r\u00e9uni pour \u00e9voquer cet incident qui a suscit\u00e9 l&rsquo;indignation de Moscou. Les livraisons de gaz russes \u00e9taient toutefois d\u00e9j\u00e0 suspendues via ces tubes, en pleines tensions li\u00e9es au conflit en Ukraine. Selon Sergue\u00ef Verchinine, lors de la r\u00e9union aux Nations unies, \u00abl&rsquo;opinion partag\u00e9e\u00bb \u00e9tait \u00abqu&rsquo;il s&rsquo;agissait d&rsquo;un sabotage et qu&rsquo;une enqu\u00eate \u00e9tait n\u00e9cessaire\u00bb. Mais \u00abaucune d\u00e9cision n&rsquo;a \u00e9t\u00e9 prise\u00bb sur la tenue d&rsquo;une telle enqu\u00eate internationale, a-t-il regrett\u00e9. Il a \u00e9galement demand\u00e9 ardemment que l&rsquo;Allemagne, o\u00f9 arrivent Nord Stream 1 et 2 depuis la Russie, participe \u00e0 l&rsquo;enqu\u00eate. La Su\u00e8de a entam\u00e9 les investigations de son c\u00f4t\u00e9, en bloquant l&rsquo;acc\u00e8s depuis lundi \u00e0 la zone de ce sabotage pr\u00e9sum\u00e9 \u00abafin de mener une enqu\u00eate de sc\u00e8ne de crime\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quatre vastes fuites ont touch\u00e9 depuis le d\u00e9but de la semaine derni\u00e8re les gazoducs Nord Stream 1 et 2 au large de l&rsquo;\u00eele danoise de Bornholm. Selon Stockholm et Copenhague, elles ont \u00e9t\u00e9 provoqu\u00e9es par des explosions sous-marines \u00e9quivalant \u00e0 \u00abdes centaines de kilos de TNT\u00bb qui ont lib\u00e9r\u00e9 des milliers de tonnes de m\u00e9thane. Les gardes-c\u00f4tes su\u00e9dois ont indiqu\u00e9 mardi que les bouillonnements entra\u00een\u00e9s par les fuites ont cess\u00e9 au-dessus du gazoduc endommag\u00e9 Nord Stream 1, mais toujours pas de Nord Stream 2. Les auteurs de cet incident rarissime restent pour l&rsquo;heure myst\u00e9rieux. Soup\u00e7onn\u00e9e d&rsquo;\u00eatre \u00e0 l&rsquo;origine des fuites, la Russie a contre-attaqu\u00e9 en pointant les \u00c9tats-Unis qui ont \u00e0 leur tour ni\u00e9 toute responsabilit\u00e9. Les fuites \u00abne sont n&rsquo;est rien d&rsquo;autre qu&rsquo;un acte de terrorisme international, dont les cons\u00e9quences peuvent \u00eatre importantes pour la population europ\u00e9enne\u00bb, a fustig\u00e9 hier le chef du Conseil de s\u00e9curit\u00e9 russe, Nikola\u00ef Patrouchev. \u00abIl est \u00e9vident que les \u00c9tats-Unis en sont le b\u00e9n\u00e9ficiaire, avant tout \u00e9conomique\u00bb, a-t-il lanc\u00e9, cit\u00e9 par les agences de presse russes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Khider L.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Kremlin a promis hier de r\u00e9cup\u00e9rer les territoires perdus r\u00e9cemment par Moscou dans les r\u00e9gions annex\u00e9es dans le sud<\/p>\n","protected":false},"author":3,"featured_media":28508,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[37],"tags":[],"class_list":["post-28503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le Kremlin a promis hier de r\u00e9cup\u00e9rer les territoires perdus r\u00e9cemment par Moscou dans les r\u00e9gions annex\u00e9es dans le sud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-05T21:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/Dmitri-Peskov.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1601\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es\",\"datePublished\":\"2022-10-05T21:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/\"},\"wordCount\":551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Dmitri-Peskov.png\",\"articleSection\":[\"Monde\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/\",\"name\":\"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Dmitri-Peskov.png\",\"datePublished\":\"2022-10-05T21:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Dmitri-Peskov.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Dmitri-Peskov.png\",\"width\":1601,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/05\\\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/","og_locale":"fr_FR","og_type":"article","og_title":"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es - La Sentinelle","og_description":"Le Kremlin a promis hier de r\u00e9cup\u00e9rer les territoires perdus r\u00e9cemment par Moscou dans les r\u00e9gions annex\u00e9es dans le sud","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-10-05T21:00:00+00:00","og_image":[{"width":1601,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/Dmitri-Peskov.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es","datePublished":"2022-10-05T21:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/"},"wordCount":551,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/Dmitri-Peskov.png","articleSection":["Monde"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/","name":"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/Dmitri-Peskov.png","datePublished":"2022-10-05T21:00:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/Dmitri-Peskov.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/Dmitri-Peskov.png","width":1601,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/05\/guerre-en-ukraine-moscou-promet-de-reprendre-les-territoires-perdus-dans-les-regions-annexees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Guerre en Ukraine\u00a0: Moscou promet de reprendre les territoires perdus dans les r\u00e9gions annex\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/28503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=28503"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/28503\/revisions"}],"predecessor-version":[{"id":28509,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/28503\/revisions\/28509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/28508"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=28503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=28503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=28503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}