{"id":28659,"date":"2022-10-09T22:00:00","date_gmt":"2022-10-09T21:00:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=28659"},"modified":"2022-10-09T17:01:41","modified_gmt":"2022-10-09T16:01:41","slug":"annaba-des-ecoliers-reclament-le-transport-scolaire","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/","title":{"rendered":"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire"},"content":{"rendered":"\n<p>Moins d\u2019un mois apr\u00e8s la rentr\u00e9e scolaire, les \u00e9l\u00e8ves de plusieurs localit\u00e9s pointent du doigt le manque de transport scolaire.<\/p>\n\n\n\n<p>De la Nouvelle-ville \u00e0 Laib Amar dans la commune d\u2019Oued El Aneb, relevant de la da\u00efra de Berrahal, des dizaines d\u2019\u00e9l\u00e8ves des \u00e9tablissements scolaires&nbsp; ont manifest\u00e9 pour revendiquer le transport scolaire. Fatigu\u00e9s de parcourir des dizaines de kilom\u00e8tres pour rejoindre leurs \u00e9tablissements scolaires, les \u00e9coliers des localit\u00e9s \u00e9loign\u00e9es pris de col\u00e8re ont, apr\u00e8s une protestation devant les si\u00e8ges des APC de Draa Errich et Laib Amar, d\u00e9cid\u00e9 de radicaliser leur mouvement.&nbsp; Une&nbsp; radicalisation \u00e0 travers laquelle les \u00e9coliers tentent de faire entendre \u00e0 qui veut les \u00e9couter leur souffrance, des ann\u00e9es durant, en mati\u00e8re de transport scolaire. En effet, ces \u00e9coliers, coll\u00e9giens et lyc\u00e9ens ont bloqu\u00e9 la circulation de la RN n\u00b0 44, reliant Annaba \u00e0 Berrahal, causant un&nbsp; interminable embouteillage. Les petits protestataires ont d\u00e9nonc\u00e9 la politique de deux poids, deux mesures en mati\u00e8re de prise en charge des dol\u00e9ances des habitants et surtout des \u00e9l\u00e8ves qui souffrent le martyre sur le chemins des \u00e9coles. Des localit\u00e9s dont les habitants, les \u00e9l\u00e8ves entre autres, sont livr\u00e9s \u00e0 eux m\u00eames. Ces propos t\u00e9moignent de la col\u00e8re qui a fait sortir les \u00e9l\u00e8ves dans la da\u00efra de Berrahalpour revendiquer le droit au transport scolaire. Il faut dire que si ces \u00e9l\u00e8ves ont eu le courage de sortir dans la rue pour crier leur malaise d\u00fb \u00e0 l\u2019absence du transport scolaire, d\u2019autres n\u2019ont peut-\u00eatre pas eu le m\u00eame courage et continuent de subir en silence les dysfonctionnements \u00e0 la pelle dans ce secteur.&nbsp; Et pourtant,au cours des multiples r\u00e9unions&nbsp; organis\u00e9es avec le premier responsable de la wilaya, les acteurs charg\u00e9s du secteur de l\u2019\u00e9ducation ont avanc\u00e9 que toutes les conditions requises son garanties afin d\u2019assurer les meilleures conditions de scolarisation. Or, \u00e0 moins d\u2019un&nbsp; moins de la rentr\u00e9e scolaire, voil\u00e0 que les d\u00e9sagr\u00e9ments frappent les \u00e9l\u00e8ves, notamment ceux des localit\u00e9s \u00e9loign\u00e9es. Des zones o\u00f9 des \u00e9tablissements scolaires ne semblent pas exister du tout ! Et pourtant les projets de r\u00e9alisation d\u2019\u00e9tablissements scolaires susceptibles de r\u00e9duire les trajets emprunt\u00e9s quotidiennement par les \u00e9l\u00e8ves ont \u00e9t\u00e9 lanc\u00e9s. Le comble est que des centaines de milliards de centimes sont d\u00e9gag\u00e9s par les pouvoirs publics pour l\u2019embellissement et restauration des \u00e9tablissements scolaires, alors que des \u00e9l\u00e8ves sont priv\u00e9s du droit le plus \u00e9l\u00e9mentaires, celui du transport scolaire. Les coll\u00e9giens ont \u00e9galement d\u00e9nonc\u00e9 le d\u00e9faut d\u2019eau potable&nbsp; et les repas chauds pour les \u00e9coliers. En effet, les protestataires comptent parmi eux &nbsp;beaucoup qui &nbsp;vivent dans des conditions ne leur permettant pas des d\u00e9penses pour le transport, les taxis notamment.&nbsp; Ainsi, en l\u2019absence du transport scolaire, les \u00e9l\u00e8ves ont recours le plus souvent \u00e0 l\u2019autostop. \u00c0 d\u00e9faut, ils marchent des kilom\u00e8tres \u00e0 pied jusqu\u2019\u00e0 l\u2019usure de leurs chaussures.&nbsp; Les lyc\u00e9ens r\u00e9clament la r\u00e9alisation d\u2019une passerelle devenue n\u00e9cessaire pour sauver des vies humaines, \u00e0 hauteur des arr\u00eats de bus implant\u00e9s dans un virage qui sont devenus un v\u00e9ritable danger pour eux. Une revendication formul\u00e9e \u00e9galement par les parents qui accompagnaient les \u00e9l\u00e8ves dans leur mouvement de contestation. Pour la plupart ces derniers,&nbsp; l\u2019appr\u00e9hension du pire est un sentiment quotidien \u00e0 chaque fois que leurs enfants traversent la route \u00e0 grande circulation pour rejoindre leurs \u00e9tablissements scolaires, principalement ceux du chef-lieu de la commune de Berrahal. Les contestataires signalent \u00e0 cet \u00e9gard l\u2019enregistrement de plusieurs accidents de la circulation, dont certains mortels, au niveau de ce virage. Autant de d\u00e9sagr\u00e9ments ont fait sortir des \u00e9l\u00e8ves, des coll\u00e9giens et des lyc\u00e9ens pour revendiquer un minimum de droits, le transport scolaire en l\u2019occurrence. Une revendication qui \u00e0 priori n\u2019a suscit\u00e9 aucune r\u00e9action des autorit\u00e9s concern\u00e9es, du fait qu\u2019aucun responsable ne s\u2019est manifest\u00e9 encore moins les \u00e9lus. Signalons&nbsp; que la fermeture de la route par les \u00e9coliers a occasionn\u00e9 un d\u00e9sagr\u00e9ment aux usagers de la RN n\u00b0 44 o\u00f9, des automobilistes, des camionneurs et des taxieurs sont rest\u00e9s coinc\u00e9s durant toute la matin\u00e9e.<\/p>\n\n\n\n<p><strong>Sofia Chahine<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moins d\u2019un mois apr\u00e8s la rentr\u00e9e scolaire, les \u00e9l\u00e8ves de plusieurs localit\u00e9s pointent du doigt le manque de transport scolaire.<\/p>\n","protected":false},"author":3,"featured_media":28660,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[31],"tags":[],"class_list":["post-28659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Moins d\u2019un mois apr\u00e8s la rentr\u00e9e scolaire, les \u00e9l\u00e8ves de plusieurs localit\u00e9s pointent du doigt le manque de transport scolaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-09T21:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/transport.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1491\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire\",\"datePublished\":\"2022-10-09T21:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/\"},\"wordCount\":760,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/transport.png\",\"articleSection\":[\"R\u00e9gions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/\",\"name\":\"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/transport.png\",\"datePublished\":\"2022-10-09T21:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/transport.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/transport.png\",\"width\":1491,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/09\\\/annaba-des-ecoliers-reclament-le-transport-scolaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire - La Sentinelle","og_description":"Moins d\u2019un mois apr\u00e8s la rentr\u00e9e scolaire, les \u00e9l\u00e8ves de plusieurs localit\u00e9s pointent du doigt le manque de transport scolaire.","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-10-09T21:00:00+00:00","og_image":[{"width":1491,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/transport.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire","datePublished":"2022-10-09T21:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/"},"wordCount":760,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/transport.png","articleSection":["R\u00e9gions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/","name":"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/transport.png","datePublished":"2022-10-09T21:00:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/transport.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/transport.png","width":1491,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/09\/annaba-des-ecoliers-reclament-le-transport-scolaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Annaba\u00a0: Des \u00e9coliers r\u00e9clament le transport scolaire"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/28659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=28659"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/28659\/revisions"}],"predecessor-version":[{"id":28661,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/28659\/revisions\/28661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/28660"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=28659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=28659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=28659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}