{"id":29144,"date":"2022-10-17T22:05:00","date_gmt":"2022-10-17T21:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=29144"},"modified":"2022-10-17T21:02:12","modified_gmt":"2022-10-17T20:02:12","slug":"avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/","title":{"rendered":"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance"},"content":{"rendered":"\n<p>L&rsquo;avant-projet de la loi de finance 2023, au-del\u00e0 de \u00ab\u00a0la garantie de la disponibilit\u00e9 et de la stabilit\u00e9 des produits alimentaires, notamment ceux subventionn\u00e9s\u00a0\u00bb et \u00ab\u00a0l&rsquo;am\u00e9lioration de la situation sociale du citoyen\u00a0\u00bb, accorde beaucoup d&rsquo;importance au climat des affaires en mettant en place des m\u00e9canismes qui vont accorder des avantages fiscaux \u00e0 certaines branches d&rsquo;activit\u00e9s. A cet effet, et dans le souci de booster les entreprises innovantes par exemple, il a \u00e9t\u00e9 institu\u00e9, d&rsquo;apr\u00e8s l&rsquo;article 16, un taux forfaitaire unique de 5% pour les entreprises exer\u00e7ant des activit\u00e9s dans le cadre de la loi sur l&rsquo;auto-entrepreneur, et ce, dans la limite d&rsquo;un chiffre d&rsquo;affaires annuel de 5 millions de dinars. Un avantage accord\u00e9 au vu de l&rsquo;essor que conna\u00eet ce segment de l&rsquo;\u00e9conomie \u00e0 l&rsquo;image des soci\u00e9t\u00e9s de d\u00e9veloppement web ou des VTC (transport), pour ne citer que celles-l\u00e0. Par ailleurs, un changement a \u00e9t\u00e9 apport\u00e9 \u00e0 l&rsquo;article 171 du code des imp\u00f4ts directs et taxes assimil\u00e9es, puisque d\u00e9sormais \u00ab\u00a0sont d\u00e9ductibles du revenu ou du b\u00e9n\u00e9fice imposable, jusqu\u2018\u00e0 concurrence de 30 pour cent (30%) du montant de ce revenu ou b\u00e9n\u00e9fice, dans la limite d\u2018un plafond de deux cent millions de dinars (200.000.000 DA), les d\u00e9penses engag\u00e9es dans le cadre de la recherche d\u00e9veloppement au sein de l\u2018entreprise, \u00e0 condition que le montant admis en d\u00e9duction soit r\u00e9investi dans le cadre de cette recherche\u00a0\u00bb. Auparavant, il \u00e9tait question de 10% et de 100 millions de dinars. L&rsquo;objectif vis\u00e9 \u00e0 travers cet amendement est d&rsquo; \u00ab\u00a0encourager la recherche et le d\u00e9veloppement\u00a0\u00bb, indique l&rsquo;Ex\u00e9cutif dans son expos\u00e9 des motifs. L&rsquo;autre activit\u00e9 sur laquelle semble miser le gouvernement est celle relative \u00e0 la p\u00eache et l&rsquo;aquaculture. A cet effet, l&rsquo;article 7 de l&rsquo;avant-projet de la loi de finance 2023 int\u00e8gre cette activit\u00e9 dans la liste de celles qui b\u00e9n\u00e9ficient d\u2018une exon\u00e9ration totale de l\u2018imp\u00f4t sur les b\u00e9n\u00e9fices des soci\u00e9t\u00e9s d&rsquo;une mani\u00e8re permanente. L&rsquo;objectif \u00e9tant de \u00ab\u00a0d\u00e9velopper cette fili\u00e8re qui rev\u00eat un int\u00e9r\u00eat strat\u00e9gique pour le pays\u00a0\u00bb. Dans le m\u00eame ordre, un avantage a \u00e9t\u00e9 \u00e9galement accord\u00e9 aux entreprises qui ont d\u00e9croch\u00e9 des projets dans les pays limitrophes. Ainsi, d&rsquo;apr\u00e8s l&rsquo;article 45, leurs camions et v\u00e9hicules qui passent la fronti\u00e8re sont exempt\u00e9s de l&rsquo;imp\u00f4t sur la consommation de carburant. Sur un autre plan, un changement a \u00e9t\u00e9 apport\u00e9 pour ce qui est des revenus soumis \u00e0 l&rsquo;imp\u00f4t concernant la location de biens immobiliers \u00ab\u00a0b\u00e2tis et non b\u00e2tis\u00a0\u00bb, \u00e0 usage d&rsquo;habitation ou professionnel. L&rsquo;article 5 de l&rsquo;avant-projet de loi de finance 2023, amendant l&rsquo;article 104 du code des imp\u00f4ts directs et taxes assimil\u00e9es, revoie l&rsquo;assiette soumise \u00e0 l&rsquo;Imp\u00f4t sur le revenu global pour ce qui est de la location de ces biens en portant \u00e0 la hausse, de 600 000 \u00e0 1 800 000 dinars, le plafond concern\u00e9 par les taux r\u00e9duit de 7 et 15%, et ce prenant \u00ab\u00a0en consid\u00e9ration les prix pratiqu\u00e9s sur le march\u00e9\u00a0\u00bb. L&rsquo;objectif de cet amendement, selon l&rsquo;Ex\u00e9cutif, est d'\u00a0\u00bball\u00e9ger le poids de l&rsquo;imp\u00f4t sur une large cat\u00e9gorie des propri\u00e9taires de biens lou\u00e9s\u00a0\u00bb. Il permet \u00e9galement, ajoute-t-on encore, \u00ab\u00a0de faciliter la d\u00e9claration fiscale et de s&rsquo;acquitter de l&rsquo;imp\u00f4t en une seule fois et au niveau du lieu o\u00f9 se trouve le bien lou\u00e9, ce qui va permettre de hisser le niveau des recouvrements de l&rsquo;IRG\/revenu immobilier\u00a0\u00bb. Les articles 12, 19 et 21 feront en sorte, par ailleurs, de s\u00e9parer les activit\u00e9s de promotion immobili\u00e8re et de construction.<\/p>\n\n\n\n<p><strong>Cigarettes \u00e9lectroniques et alcoolstax\u00e9s<\/strong><\/p>\n\n\n\n<p>D&rsquo;autres parts, de nouvelles taxes ou des hausses, ont \u00e9t\u00e9 d\u00e9cid\u00e9es pour ce qui est des cigarettes \u00e9lectroniques et des boissons alcoolis\u00e9es. La cigarette \u00e9lectronique sera donc soumise \u00e0 une taxe int\u00e9rieure sur la consommation de 40%, comme pour ce qui est des tabacs. Les briquets et allumettes seront, pour leurs parts, soumis \u00e0 une taxe de 20%. Pour ce qui est des boissons alcoolis\u00e9es, les tarifs du \u00ab\u00a0droit \u00e0 la circulation\u00a0\u00bb ont \u00e9t\u00e9 revus \u00e0 la hausse. Pour les vins, par exemple, il passe de 8800 dinars l&rsquo;hectolitre \u00e0 10 000 dinars. Dans l&rsquo;expos\u00e9 des motifs, le Gouvernement explique que cette hausse a \u00e9t\u00e9 institu\u00e9e pour compenser le manque \u00e0 gagner enregistr\u00e9 suite \u00e0 la suppression de la TVA existante dans l&rsquo;article 48 du Code des imp\u00f4ts indirects, celle-ci ayant \u00e9t\u00e9 difficile \u00e0 calculer. L&rsquo;autre hausse concerne l&rsquo;importation de produits finis destin\u00e9s \u00e0 la consommation en l&rsquo;\u00e9tat. L&rsquo;article 59 stipule donc que la \u00ab\u00a0contribution solidaire\u00a0\u00bb est port\u00e9e de 2 \u00e0 4%. Celle-ci est revers\u00e9e \u00e0 la Caisse nationale de retraite (CNR). L&rsquo;objectif est d&rsquo;all\u00e9ger le d\u00e9ficit que conna\u00eet cette caisse.<\/p>\n\n\n\n<p>En dernier lieu, l&rsquo;avant-projet de loi de finance pour l&rsquo;exercice 2023 \u00e9voque \u00e9galement quelques autres questions notamment celles en lien avec l&rsquo;exercice de fonctions des agents de l&rsquo;administration fiscale. L&rsquo;Article 34, par exemple, \u00e9largit leurs missions pour ce qui est du contr\u00f4le des personnes susceptibles d&rsquo;\u00eatre concern\u00e9es par l&rsquo;imp\u00f4t sur la fortune, afin de permettre un meilleur contr\u00f4le surtout pour identifier les personnes concern\u00e9es par cet imp\u00f4t.<\/p>\n\n\n\n<p><strong>Elyas Nour<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;avant-projet de la loi de finance 2023, au-del\u00e0 de \u00ab\u00a0la garantie de la disponibilit\u00e9 et de la stabilit\u00e9 des produits<\/p>\n","protected":false},"author":3,"featured_media":29148,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-29144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;avant-projet de la loi de finance 2023, au-del\u00e0 de \u00ab\u00a0la garantie de la disponibilit\u00e9 et de la stabilit\u00e9 des produits\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-17T21:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/finance.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance\",\"datePublished\":\"2022-10-17T21:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/\"},\"wordCount\":919,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/finance.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/\",\"name\":\"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/finance.png\",\"datePublished\":\"2022-10-17T21:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/finance.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/finance.png\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/10\\\/17\\\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/","og_locale":"fr_FR","og_type":"article","og_title":"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance - La Sentinelle","og_description":"L&rsquo;avant-projet de la loi de finance 2023, au-del\u00e0 de \u00ab\u00a0la garantie de la disponibilit\u00e9 et de la stabilit\u00e9 des produits","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-10-17T21:05:00+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/finance.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance","datePublished":"2022-10-17T21:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/"},"wordCount":919,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/finance.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/","name":"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/finance.png","datePublished":"2022-10-17T21:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/finance.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/10\/finance.png","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/10\/17\/avant-projet-de-loi-de-finance-2023-de-nouvelles-mesures-en-faveur-de-linvestissement-et-de-la-croissance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Avant-projet de loi de finances 2023\u00a0: De nouvelles mesures en faveur de l\u2019investissement et de la croissance"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/29144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=29144"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/29144\/revisions"}],"predecessor-version":[{"id":29168,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/29144\/revisions\/29168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/29148"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=29144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=29144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=29144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}