{"id":30818,"date":"2022-11-15T22:00:00","date_gmt":"2022-11-15T21:00:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=30818"},"modified":"2022-11-15T18:18:54","modified_gmt":"2022-11-15T17:18:54","slug":"can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/","title":{"rendered":"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale"},"content":{"rendered":"\n<p>Alors que l\u2019on croyait la qualification en quart de finale de la CAN-2022 acquise pour les Vertes, celles-ci ont finalement \u00e9t\u00e9 \u00e9limin\u00e9e d\u00e8s la phase de groupe ne pourront pas pr\u00e9tendre \u00e0 tenter une qualification pour le prochain mondial de la discipline.<\/p>\n\n\n\n<p>Malgr\u00e9 une victoire lors du dernier match de la phase de groupe, la s\u00e9lection nationale f\u00e9minine de handball n\u2019ira pas en quart de finale de la CAN \u00e0 Dakar. La s\u00e9lection alg\u00e9rienne f\u00e9minine de handball s&rsquo;est impos\u00e9e devant son homologue cap-verdienne sur le score de 36 \u00e0 30 (mi-temps : 19-11), en match comptant pour la 3e et derni\u00e8re journ\u00e9e du groupe A de la Coupe d&rsquo;Afrique des nations (CAN-2022), disput\u00e9 lundi \u00e0 Dakar.C&rsquo;est le premier succ\u00e8s des handballeuses alg\u00e9riennes dans le tournoi, apr\u00e8s deux d\u00e9faites conc\u00e9d\u00e9es face \u00e0 l&rsquo;Angola (17-29) et la RD Congo (23-32).<\/p>\n\n\n\n<p>A l&rsquo;issue de cette victoire l&rsquo;Alg\u00e9rie termine \u00e0 la troisi\u00e8me place du groupe A avec deux points et une diff\u00e9rence de but (-15). Un r\u00e9sultat, malheureusement insuffisant pour se qualifier en quart de finale. Selon la formule de comp\u00e9tition, les trois premiers du groupe B (compos\u00e9 de cinq \u00e9quipes), ainsi que les deux premiers et le meilleur troisi\u00e8me des groupes (A et C) se qualifieront aux quarts de finale du tournoi. Dans ce sens ce sont les Ivoiriennes (Groupe C) qui se sont qualifi\u00e9es gr\u00e2ce \u00e0 meilleur goal average (-2) contre -15 pour les Alg\u00e9riennes. La s\u00e9lection ivoirienne s\u2019\u00e9tait impos\u00e9e par un score de 40 \u00e0 14 face aux Malgaches. Les handballeuses alg\u00e9riennes voient leur objectif leur filer entre les mains. Il est vrai que la S\u00e9lection nationale a p\u00e2ti d\u2019une pr\u00e9paration chaotique perturb\u00e9e par des changements d\u2019entraineurs au fil des changements \u00e0 la t\u00eate de la FAHB. En effet, \u00e9lue \u00e0 la t\u00eate de la F\u00e9d\u00e9ration en octobre, Karima Taleb avait d\u00e9sign\u00e9 dans un premier temps, Ryad Oulmane, \u00e0 la place de Rabah Gra\u00efchi. Mais cette d\u00e9cision est devenue caduque, suite \u00e0 la d\u00e9cision de la F\u00e9d\u00e9ration internationale (IHF) d&rsquo;invalider les derni\u00e8res \u00e9lections de la FAHB, ce qui a induitle retour de Gra\u00efchi \u00e0 son poste.Les Vertes ont ensuite eu moins d\u2019une semaine de stage de pr\u00e9paration avant le d\u00e9but de la comp\u00e9tition africaine. Le coach des Vertes visaient une qualification pour le Mondial, ce qui n\u2019est plus possible aujourd\u2019hui. En effet, les quatre premiers de la CAN-2022 se qualifieront pour le prochain Mondial f\u00e9minin, pr\u00e9vu du 30 novembre au 17 d\u00e9cembre 2023 au Danemark, en Su\u00e8de et en Norv\u00e8ge.<\/p>\n\n\n\n<p>R.S.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que l\u2019on croyait la qualification en quart de finale de la CAN-2022 acquise pour les Vertes, celles-ci ont finalement<\/p>\n","protected":false},"author":3,"featured_media":30829,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[33],"tags":[],"class_list":["post-30818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Alors que l\u2019on croyait la qualification en quart de finale de la CAN-2022 acquise pour les Vertes, celles-ci ont finalement\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-15T21:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/hand-bonne.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale\",\"datePublished\":\"2022-11-15T21:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/\"},\"wordCount\":474,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/hand-bonne.jpeg\",\"articleSection\":[\"Sports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/\",\"name\":\"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/hand-bonne.jpeg\",\"datePublished\":\"2022-11-15T21:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/hand-bonne.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/hand-bonne.jpeg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/15\\\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale - La Sentinelle","og_description":"Alors que l\u2019on croyait la qualification en quart de finale de la CAN-2022 acquise pour les Vertes, celles-ci ont finalement","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-11-15T21:00:00+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/hand-bonne.jpeg","type":"image\/jpeg"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale","datePublished":"2022-11-15T21:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/"},"wordCount":474,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/hand-bonne.jpeg","articleSection":["Sports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/","name":"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/hand-bonne.jpeg","datePublished":"2022-11-15T21:00:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/hand-bonne.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/hand-bonne.jpeg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/15\/can-2022-de-handball-dames-les-vertes-ratent-la-qualification-pour-les-quarts-de-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"CAN-2022 de handball (Dames)\u00a0: Les Vertes Ratent la qualification pour les quarts de finale"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/30818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=30818"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/30818\/revisions"}],"predecessor-version":[{"id":30830,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/30818\/revisions\/30830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/30829"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=30818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=30818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=30818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}