{"id":31847,"date":"2022-11-30T22:05:00","date_gmt":"2022-11-30T21:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=31847"},"modified":"2022-11-30T20:11:01","modified_gmt":"2022-11-30T19:11:01","slug":"tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/","title":{"rendered":"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison"},"content":{"rendered":"\n<p>Le Tribunal criminel de premi\u00e8re instance de Dar El Beida (Alger) a condamn\u00e9, hier, le terroriste Mohamed Zitout \u00e0 une peine de 20 ans de prison ferme avec confirmation du mandat d&rsquo;arr\u00eat international \u00e9mis \u00e0 son encontre pour \u00ab\u00a0complot pour changer le r\u00e9gime en place\u00a0\u00bb et \u00ab\u00a0gestion d&rsquo;un groupe terroriste subversif\u00a0\u00bb.Dans le cadre de la m\u00eame affaire, le tribunal a condamn\u00e9 l&rsquo;accus\u00e9 Hassan Bourras \u00e0 deux (2) ans de prison ferme, dont une ann\u00e9e avec sursis, et acquitt\u00e9 Mustapha Kira.<\/p>\n\n\n\n<p>Le procureur g\u00e9n\u00e9ral pr\u00e8s le m\u00eame tribunal avait requis plus t\u00f4t une peine de 20 ans de prison ferme \u00e0 l&rsquo;encontre du terroriste Mohamed Zitout avec confirmation du mandat d&rsquo;arr\u00eat international \u00e9mis \u00e0 son encontre, et une peine de 15 ans de prison ferme contre les deux accus\u00e9s Mustapha Kira et Hassan Bourras.Les trois accus\u00e9s sont poursuivis dans cette affaire pour \u00ab\u00a0outrage \u00e0 corps constitu\u00e9, diffusion pr\u00e9m\u00e9dit\u00e9e d&rsquo;informations fallacieuses et calomnieuses, et apologie d&rsquo;actes terroristes\u00a0\u00bb.<\/p>\n\n\n\n<p>Dans une autre affaire, le Procureur de la R\u00e9publique pr\u00e8s le P\u00f4le p\u00e9nal \u00e9conomique et financier du Tribunal de Sidi M&rsquo;hamed (Alger) a requisune peine de 15 ans de prison ferme contre l&rsquo;ancien ministre des Ressources en eau, Arezki Berraki, poursuivi pour corruption.La m\u00eame peine a \u00e9t\u00e9 requise contre l&rsquo;ancien Secr\u00e9taire g\u00e9n\u00e9ral du m\u00eame minist\u00e8re, Mustapha Karim Rahiel, ainsi qu&rsquo;une peine de 10 ans de prison ferme contre l&rsquo;ancien directeur de l&rsquo;Agence nationale des barrages et des transferts (ANB), Abdennacer Kalli qui est en fuite et fait l&rsquo;objet d&rsquo;un mandat d&rsquo;arr\u00eat international.Dans cette m\u00eame affaire, des peines allant de 3 \u00e0 8 ans de prison ferme ont \u00e9t\u00e9 requises \u00e0 l&rsquo;encontre des accus\u00e9s restants.En qualit\u00e9 d&rsquo;ancien directeur g\u00e9n\u00e9ral de l&rsquo;Agence nationale des barrages et des transferts (ANB), l&rsquo;ancien ministre, Arezki Berraki est poursuivi, avec ses coaccus\u00e9s, anciens cadres de cette agence, pour dilapidation de deniers publics, abus de fonction, octroi d&rsquo;indus avantages et autres.<\/p>\n\n\n\n<p>R.N. avec APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Tribunal criminel de premi\u00e8re instance de Dar El Beida (Alger) a condamn\u00e9, hier, le terroriste Mohamed Zitout \u00e0 une<\/p>\n","protected":false},"author":3,"featured_media":31848,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-31847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le Tribunal criminel de premi\u00e8re instance de Dar El Beida (Alger) a condamn\u00e9, hier, le terroriste Mohamed Zitout \u00e0 une\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-30T21:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/Sans-titre-1-11.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1592\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison\",\"datePublished\":\"2022-11-30T21:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/\"},\"wordCount\":366,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Sans-titre-1-11.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/\",\"name\":\"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Sans-titre-1-11.png\",\"datePublished\":\"2022-11-30T21:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Sans-titre-1-11.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Sans-titre-1-11.png\",\"width\":1592,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/11\\\/30\\\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/","og_locale":"fr_FR","og_type":"article","og_title":"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison - La Sentinelle","og_description":"Le Tribunal criminel de premi\u00e8re instance de Dar El Beida (Alger) a condamn\u00e9, hier, le terroriste Mohamed Zitout \u00e0 une","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-11-30T21:05:00+00:00","og_image":[{"width":1592,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/Sans-titre-1-11.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison","datePublished":"2022-11-30T21:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/"},"wordCount":366,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/Sans-titre-1-11.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/","name":"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/Sans-titre-1-11.png","datePublished":"2022-11-30T21:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/Sans-titre-1-11.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/Sans-titre-1-11.png","width":1592,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/11\/30\/tribunal-de-dar-el-beida-20-ans-de-prison-ferme-requis-a-lencontre-de-larbi-zitout\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Tribunal de Dar El Beida\u00a0: Larbi Zitout condamn\u00e9 \u00e0 20 ans de prison"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/31847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=31847"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/31847\/revisions"}],"predecessor-version":[{"id":31856,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/31847\/revisions\/31856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/31848"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=31847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=31847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=31847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}