{"id":32612,"date":"2022-12-14T22:05:00","date_gmt":"2022-12-14T21:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=32612"},"modified":"2022-12-14T19:20:18","modified_gmt":"2022-12-14T18:20:18","slug":"vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/","title":{"rendered":"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain"},"content":{"rendered":"\n<p>Le ministre de l&rsquo;Energie et des Mines, Mohamed Arkab, a re\u00e7u, hier \u00e0 Alger, une importante d\u00e9l\u00e9gation de la R\u00e9publique de Cuba, conduite par le vice-Premier ministre, Ricardo Cabrisas Ruiz, accompagn\u00e9 du ministre de l&rsquo;Energie et des Mines, Vicente de la O Levy, et de hauts cadres du minist\u00e8re cubain de l&rsquo;Energie et des Mines.Selon un communiqu\u00e9, cette rencontre s&rsquo;est tenue en pr\u00e9sence de l&rsquo;ambassadeur de la R\u00e9publique de Cuba \u00e0 Alger, ainsi que du PDG du groupe Sonelgaz. Au cours de cette audience, les deux parties ont qualifi\u00e9 les relations bilat\u00e9rales \u00abd&rsquo;excellentes et d&rsquo;historiques\u00bb, notamment dans le domaine de l&rsquo;\u00e9nergie et des hydrocarbures.Les discussions ont port\u00e9 sur l&rsquo;\u00e9tat de la coop\u00e9ration bilat\u00e9rale dans le domaine de l&rsquo;\u00e9nergie et des mines ainsi que les perspectives de leur renforcement, en particulier \u00abdans le domaine de la production et de la maintenance \u00e9lectrique, les hydrocarbures et les \u00e9nergies renouvelables\u00bb, pr\u00e9cise la m\u00eame source.Les deux parties ont \u00e9galement \u00e9chang\u00e9 notamment sur les modalit\u00e9s de mise en oeuvre des actions de coop\u00e9ration convenues \u00e0 l&rsquo;occasion de la visite en Alg\u00e9rie du pr\u00e9sident de la R\u00e9publique de Cuba, M. Miguel Diaz-Canel Bermudez, dans le domaine des hydrocarbures et des approvisionnements en produits p\u00e9troliers, ainsi que la r\u00e9alisation d&rsquo;une centrale \u00e9lectrique solaire, par Sonelgaz, \u00e0 Cuba, est-il soulign\u00e9 dans le communiqu\u00e9.A cet effet, un comit\u00e9 de coordination conjoint a \u00e9t\u00e9 install\u00e9 ce mercredi pour la mise en oeuvre de ces actions, selon la m\u00eame source.A l&rsquo;occasion, M. Arkab a exprim\u00e9 son enti\u00e8re satisfaction du d\u00e9roulement de cette rencontre, \u00e9mettant le souhait de voir les relations de coop\u00e9ration alg\u00e9ro-cubaine se renforcer davantage et b\u00e9n\u00e9ficier de l&rsquo;exp\u00e9rience et du savoir-faire cubain en mati\u00e8re d&rsquo;exploration mini\u00e8re et de l&rsquo;exploitation des min\u00e9raux en Alg\u00e9rie, ajoute le communiqu\u00e9.<\/p>\n\n\n\n<p>APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l&rsquo;Energie et des Mines, Mohamed Arkab, a re\u00e7u, hier \u00e0 Alger, une importante d\u00e9l\u00e9gation de la R\u00e9publique<\/p>\n","protected":false},"author":3,"featured_media":32656,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[29],"tags":[],"class_list":["post-32612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le ministre de l&rsquo;Energie et des Mines, Mohamed Arkab, a re\u00e7u, hier \u00e0 Alger, une importante d\u00e9l\u00e9gation de la R\u00e9publique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-14T21:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-14_192010074.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain\",\"datePublished\":\"2022-12-14T21:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/image_2022-12-14_192010074.png\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/\",\"name\":\"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/image_2022-12-14_192010074.png\",\"datePublished\":\"2022-12-14T21:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/image_2022-12-14_192010074.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/image_2022-12-14_192010074.png\",\"width\":600,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/14\\\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/","og_locale":"fr_FR","og_type":"article","og_title":"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain - La Sentinelle","og_description":"Le ministre de l&rsquo;Energie et des Mines, Mohamed Arkab, a re\u00e7u, hier \u00e0 Alger, une importante d\u00e9l\u00e9gation de la R\u00e9publique","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-12-14T21:05:00+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-14_192010074.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain","datePublished":"2022-12-14T21:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-14_192010074.png","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/","name":"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-14_192010074.png","datePublished":"2022-12-14T21:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-14_192010074.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-14_192010074.png","width":600,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/14\/vers-la-realisation-dune-centrale-electrique-solaire-sonelgaz-met-le-cap-sur-le-marche-cubain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Vers la r\u00e9alisation d\u2019une centrale \u00e9lectrique solaire\u00a0: Sonelgaz met le cap sur le march\u00e9 cubain"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/32612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=32612"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/32612\/revisions"}],"predecessor-version":[{"id":32657,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/32612\/revisions\/32657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/32656"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=32612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=32612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=32612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}