{"id":33367,"date":"2022-12-27T22:05:00","date_gmt":"2022-12-27T21:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=33367"},"modified":"2022-12-27T19:46:13","modified_gmt":"2022-12-27T18:46:13","slug":"anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/","title":{"rendered":"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La veuve du regrett\u00e9 pr\u00e9sident Houari Boumedi\u00e8ne, Anissa Boumedi\u00e8ne, a fait hier une intervention \u00e9mouvante et remarqu\u00e9e lors du colloque national sur le d\u00e9funt pr\u00e9sident Houari Boumediene au Centre international des conf\u00e9rences, sous le th\u00e8me \u00ab\u00a0Houari Boumediene: un homme d&rsquo;Etat avec une d\u00e9termination d&rsquo;une nation\u00a0\u00bb. Elle a tenu \u00e0 corriger certaines contre-v\u00e9rit\u00e9s \u00e0 propos du d\u00e9funt pr\u00e9sident de la R\u00e9publique. Anissa Boumedi\u00e8ne a mis en avant son r\u00f4le central de m\u00eame qu\u2019elle a d\u00e9voil\u00e9 une facette du leader peu connu des Alg\u00e9riens. Elle d\u00e9crit ainsi un homme d\u2019ordre qui a horreur du d\u00e9sordre. \u00ab&nbsp;Il d\u00e9teste l\u2019improvisation. Il r\u00e9fl\u00e9chissait aux cons\u00e9quences de ses d\u00e9cisions et \u00e9tudiait toutes les dimensions d\u2019un probl\u00e8me&nbsp;\u00bb dira-t-elle. \u00ab&nbsp;Boumedi\u00e8neavait une forte volont\u00e9, il supportait tout sans se plaindre et ne s\u2019int\u00e9ressait pas aux choses mat\u00e9rielles&nbsp;\u00bb, dira encore Anissa Boumedi\u00e8ne qui se rem\u00e9more un homme qui se caract\u00e9risait par son \u00ab&nbsp;grand humanisme et qui se pr\u00e9occupait des plus pauvres et des travailleurs&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La veuve du d\u00e9funt pr\u00e9sidenta \u00e9voqu\u00e9 lors de son intervention les principales \u00e9tapes de la vie politique et les positions remarquables du d\u00e9funt pr\u00e9sident envers les causes nationales et arabes, ainsi que ses d\u00e9cisions qui ont renforc\u00e9 la souverainet\u00e9 nationale et r\u00e9alis\u00e9 le d\u00e9veloppement, la nationalisation des richesses du pays et la protection des fronti\u00e8res.\u00a0\u00bbLa mort du d\u00e9funt pr\u00e9sident avait suscit\u00e9 l&rsquo;\u00e9moi et la tristesse de tout le peuple alg\u00e9rien\u00a0\u00bb, a-t-elle rappel\u00e9, soulignant que \u00ab\u00a0l&rsquo;\u00e8re du d\u00e9funt pr\u00e9sident Houari Boumediene restera grav\u00e9e dans la m\u00e9moire des Alg\u00e9riens au fil des temps\u00a0\u00bb. De son c\u00f4t\u00e9, le ministre des Moudjahidine et des Ayants-droit, La\u00efd Rebiga a affirm\u00e9 que l&rsquo;\u00e8re du d\u00e9funt pr\u00e9sident Houari Boumediene<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0est une brillante page &lsquo;\u00e9dification et de construction\u00a0\u00bb.Il a soulign\u00e9 que le d\u00e9funt pr\u00e9sident \u00ab\u00a0a jet\u00e9 les bases de l&rsquo;Etat des institutions, servi le pays et le peuple, lutt\u00e9 contre la pauvret\u00e9 et l&rsquo;ignorance, nationalis\u00e9 les richesses et prot\u00e9g\u00e9 la dignit\u00e9 du citoyen par la justice sociale, le d\u00e9veloppement \u00e9conomique et la renaissance culturelle\u00a0\u00bb.Lors de ce colloque organis\u00e9 \u00e0 l&rsquo;occasion du 44e anniversaire de la disparition de Houari Boumediene, le ministre a indiqu\u00e9 que le d\u00e9funt pr\u00e9sident, jouissant d&rsquo;une vision future et proactive, \u00ab\u00a0a toujours d\u00e9fendu les causes nationales de lib\u00e9ration en faisant de l&rsquo;Alg\u00e9rie une destination pour les r\u00e9volutionnaires et la Mecque des hommes libres\u00a0\u00bb.L&rsquo;Alg\u00e9rie qui comm\u00e9more sa disparition \u00ab\u00a0est totalement convaincue et d\u00e9termin\u00e9e \u00e0 aller de l&rsquo;avant vers l&rsquo;\u00e9dification d&rsquo;un Etat fort de ses institutions conform\u00e9ment aux valeurs de la r\u00e9volution du 1er novembre et de ses symboles\u00a0\u00bb, a-t-il soutenu. Il a \u00e9galement assur\u00e9 que l&rsquo;Alg\u00e9rie poursuivait, aujourd\u2019hui, le renforcement de ses institutions, la pr\u00e9servation de ses acquis et l&rsquo;exercice de sa souverainet\u00e9, \u00e0 m\u00eame de pr\u00e9server sa s\u00e9curit\u00e9 et la dignit\u00e9 de son peuple.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et d&rsquo;ajouter que \u00ab\u00a0l&rsquo;Alg\u00e9rie a plac\u00e9 tr\u00e8s haut, la barre de ses ambitions, consciente en cela des enjeux et pr\u00eate \u00e0 relever les d\u00e9fis, parall\u00e8lement au soutien des causes de sa Nation\u00a0\u00bb.A l&rsquo;occasion de ce 44e anniversaire de la mort du d\u00e9funt pr\u00e9sident Houari Boumedi\u00e8ne, le ministre a ajout\u00e9 que \u00ab\u00a0le Pr\u00e9sident Tebboune r\u00e9affirme son plein engagement et son attachement \u00e0 pr\u00e9server la m\u00e9moire et \u00e0 atteindre l&rsquo;immunit\u00e9 soci\u00e9tale, en glorifiant la m\u00e9moire des grands hommes, leurs hauts faits et leurs grands sacrifices\u00a0\u00bb.\u00a0\u00bbL&rsquo;Alg\u00e9rie fait de ses journ\u00e9es m\u00e9morables des haltes pour montrer la bonne voie trac\u00e9e par les vaillants chouhadas et pr\u00e9server notre Histoire nationale et notre M\u00e9moire collective\u00a0\u00bb, conclut le ministre.Les travaux du colloque ont \u00e9t\u00e9 marqu\u00e9s par la pr\u00e9sence de membres du gouvernement, des cadres de l&rsquo;Etat, des parlementaires, des moudjahidine, des chercheurs et des historiens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hocine Fadheli<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La veuve du regrett\u00e9 pr\u00e9sident Houari Boumedi\u00e8ne, Anissa Boumedi\u00e8ne, a fait hier une intervention \u00e9mouvante et remarqu\u00e9e lors du colloque<\/p>\n","protected":false},"author":3,"featured_media":33373,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-33367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La veuve du regrett\u00e9 pr\u00e9sident Houari Boumedi\u00e8ne, Anissa Boumedi\u00e8ne, a fait hier une intervention \u00e9mouvante et remarqu\u00e9e lors du colloque\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-27T21:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-27_194606671.png\" \/>\n\t<meta property=\"og:image:width\" content=\"764\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb\",\"datePublished\":\"2022-12-27T21:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/\"},\"wordCount\":737,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/image_2022-12-27_194606671.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/\",\"name\":\"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/image_2022-12-27_194606671.png\",\"datePublished\":\"2022-12-27T21:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/image_2022-12-27_194606671.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/image_2022-12-27_194606671.png\",\"width\":764,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2022\\\/12\\\/27\\\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/","og_locale":"fr_FR","og_type":"article","og_title":"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb - La Sentinelle","og_description":"La veuve du regrett\u00e9 pr\u00e9sident Houari Boumedi\u00e8ne, Anissa Boumedi\u00e8ne, a fait hier une intervention \u00e9mouvante et remarqu\u00e9e lors du colloque","og_url":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2022-12-27T21:05:00+00:00","og_image":[{"width":764,"height":395,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-27_194606671.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb","datePublished":"2022-12-27T21:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/"},"wordCount":737,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-27_194606671.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/","url":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/","name":"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-27_194606671.png","datePublished":"2022-12-27T21:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-27_194606671.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/image_2022-12-27_194606671.png","width":764,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2022\/12\/27\/anissa-boumediene-au-colloque-national-sur-le-defunt-president-houari-boumediene-se-caracterisait-par-un-grand-humanisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Anissa Boum\u00e9di\u00e8ne au colloque national sur le d\u00e9funt Pr\u00e9sident\u00a0: \u00ab\u00a0Houari Boum\u00e9di\u00e8ne se caract\u00e9risait par un grand humanisme\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/33367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=33367"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/33367\/revisions"}],"predecessor-version":[{"id":33374,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/33367\/revisions\/33374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/33373"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=33367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=33367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=33367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}