{"id":35838,"date":"2023-02-08T22:15:00","date_gmt":"2023-02-08T21:15:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=35838"},"modified":"2023-02-08T20:05:15","modified_gmt":"2023-02-08T19:05:15","slug":"ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/","title":{"rendered":"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression"},"content":{"rendered":"\n<p>Une trentaine de syndicats autonomes, relevant de la fonction publique, dont ceux de la sant\u00e9 et de l&rsquo;\u00e9ducation, ont sign\u00e9 conjointement une d\u00e9claration dans laquelle est \u00e9voqu\u00e9 l&rsquo;\u00e9ventualit\u00e9 d&rsquo;un recours \u00e0 un mouvement de protestationet ce, au sujet des deux avant-projets de loi, qu&rsquo;ils contestent, relatifs pour le premier aux modalit\u00e9s d&rsquo;exercice du droit syndical et pour le deuxi\u00e8me \u00e0 la pr\u00e9vention et au r\u00e8glement des conflits collectifs de travail et \u00e0 l&rsquo;exercice du droit de gr\u00e8ve.<\/p>\n\n\n\n<p>La commission de la sant\u00e9 et du travail de l&rsquo;Assembl\u00e9e populaire nationale (APN) poursuit l&rsquo;examen des deux avant-projets de loi relatifs aux modalit\u00e9s d&rsquo;exercice du droit syndical et \u00e0 la pr\u00e9vention et au r\u00e8glement des conflits collectifs de travail et \u00e0 l&rsquo;exercice du droit de gr\u00e8ve. Sa derni\u00e8re r\u00e9union, qui a eu lieu avant-hier, mardi, s&rsquo;est tenue en pr\u00e9sence de repr\u00e9sentants du minist\u00e8re du travail, comme cela a \u00e9t\u00e9 indiqu\u00e9 dans un communiqu\u00e9. Deux textes que les organisations syndicales, y compris l&rsquo;Union g\u00e9n\u00e9rale des travailleurs alg\u00e9riens (UGTA), voudraient voir retir\u00e9s. Apr\u00e8s de premi\u00e8res d\u00e9clarations dans lesquelles les syndicats mettent l&rsquo;accent sur les articles pr\u00e9sents dans les deux avant-projets de loi qui posent probl\u00e8me, aujourd&rsquo;hui, c&rsquo;est la menace d\u2019un mouvement de protestation qui est brandie. Dans une d\u00e9claration commune, sign\u00e9e par trente syndicats autonomes relevant de la fonction publique, dont bien \u00e9videmment ceux de la sant\u00e9 et de l&rsquo;\u00e9ducation, il est \u00e9voqu\u00e9 l&rsquo;\u00e9ventualit\u00e9 de recourir \u00e0 un \u00ab\u00a0mouvement de protestation\u00a0\u00bb, dont, comme il est pr\u00e9cis\u00e9, \u00ab\u00a0la forme et la date seront d\u00e9finis ult\u00e9rieurement\u00a0\u00bb. Ainsi, en attente d&rsquo;une r\u00e9ponse positive de la part des autorit\u00e9s \u00e0 leurs dol\u00e9ances, exprim\u00e9s dans un pr\u00e9c\u00e9dant communiqu\u00e9 dans lequel il est demand\u00e9 le retrait des deux textes, ces syndicats, se sont entendus pour \u00ab\u00a0mobiliser leurs bases respectives\u00a0\u00bb, dans le but de sensibiliser le monde du travail \u00ab\u00a0sur la dangerosit\u00e9 de ces deux textes sur le sort des fonctionnaires et travailleurs et leur vie professionnelle et syndicale\u00a0\u00bb. Les syndicats r\u00e9clament, par la m\u00eame occasion, la lev\u00e9e du \u00ab\u00a0flou qui entoure le dossier relatif \u00e0 l&rsquo;amendement de l&rsquo;Ordonnance n\u00b0 06-03 du 15 juillet 2006 portant statut g\u00e9n\u00e9ral de la Fonction publique et des diff\u00e9rents statuts particuliers\u00a0\u00bb qui n\u00e9cessitent, selon ces organisations syndicales, \u00ab\u00a0l&rsquo;implication des concern\u00e9s\u00a0\u00bb. D&rsquo;ailleurs, plus d&rsquo;une fois, les syndicats ont tenu \u00e0 relever le fait que les deux avant-projets de loi actuellement en examen \u00e0 l&rsquo;APN ont \u00e9t\u00e9 pr\u00e9par\u00e9s sans consulter les syndicats. Dans une d\u00e9claration faite \u00e0 une cha\u00eene de t\u00e9l\u00e9vision priv\u00e9e, le Dr Lyes Merabet, pr\u00e9sident du Syndicat national des praticiens de la sant\u00e9 publique (SNPSP), a tenu \u00e0 rappeler que le ministre du Travail s&rsquo;\u00e9tait engag\u00e9 au mois de f\u00e9vrier 2022 \u00e0 associer les syndicats \u00e0 la pr\u00e9paration de ces deux textes. Il a ajout\u00e9 que le pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, avait donn\u00e9 des instructions lors d&rsquo;un Conseil des ministres qui s&rsquo;est tenu en juillet 2022 pour que les repr\u00e9sentants des travailleurs soient impliqu\u00e9s dans ce chantier. Il n\u2019en fut rien, d&rsquo;apr\u00e8s Merabet. Entre autres points contest\u00e9s dans ces deux avant-projets, celui-ci a \u00e9voqu\u00e9 \u00ab\u00a0la remise en cause indirecte du droit de gr\u00e8ve\u00a0\u00bb, le statut du d\u00e9l\u00e9gu\u00e9 syndical ou bien encore la question de la repr\u00e9sentativit\u00e9 des syndicats.<\/p>\n\n\n\n<p>Il faut rappeler que m\u00eame l&rsquo;UGTA avait, \u00e0 travers un communiqu\u00e9 rendu public le 22 janvier dernier, exprim\u00e9 beaucoup de r\u00e9serves par rapport aux deux textes. La Centrale syndicale, et tout en appelant ses structures, unions et f\u00e9d\u00e9rations, \u00e0 se mobiliser, en organisant des r\u00e9unions autour des deux avant-projets de loi, a mis l&rsquo;accent sur le fait que les partenaires sociaux n&rsquo;ont pas \u00e9t\u00e9 associ\u00e9s \u00e0 leurpr\u00e9paration. Plusieurs r\u00e9unions, qui se sont sold\u00e9es par des communiqu\u00e9s, ont \u00e9t\u00e9 tenues. A cet effet, le chef de l&rsquo;Etat est sollicit\u00e9 pour qu&rsquo;il proc\u00e8de au retrait des deux textes, qui sont consid\u00e9r\u00e9s, par ces m\u00eames structures affili\u00e9es \u00e0 l&rsquo;UGTA, en contradiction avec les conventions internationales paraph\u00e9es par l&rsquo;Alg\u00e9rie. La Conf\u00e9d\u00e9ration des syndicats alg\u00e9riens (CSA), regroupant quinze syndicats autonomes, avait \u00e9galement adress\u00e9 une lettre au pr\u00e9sident de la R\u00e9publique, dans laquelle elle exprime la m\u00eame demande relative au retrait des deux textes. Les deux avant-projets de loi dont donc consensus contre eux. Ils sont rejet\u00e9s, avec leurs moutures actuelles, aussi bien par les syndicats autonomes que l&rsquo;UGTA. Et les choses risquent de se compliquer d&rsquo;avantage, dans les jours \u00e0 venir, s&rsquo;ils sont maintenus, tels qu&rsquo;arriv\u00e9s \u00e0 l&rsquo;APN.&nbsp;<\/p>\n\n\n\n<p><strong>Elyas Nour<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une trentaine de syndicats autonomes, relevant de la fonction publique, dont ceux de la sant\u00e9 et de l&rsquo;\u00e9ducation, ont sign\u00e9<\/p>\n","protected":false},"author":3,"featured_media":35845,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-35838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Une trentaine de syndicats autonomes, relevant de la fonction publique, dont ceux de la sant\u00e9 et de l&rsquo;\u00e9ducation, ont sign\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-08T21:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/02\/apn.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1491\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression\",\"datePublished\":\"2023-02-08T21:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/\"},\"wordCount\":843,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/apn.png\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/\",\"name\":\"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/apn.png\",\"datePublished\":\"2023-02-08T21:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/apn.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/apn.png\",\"width\":1491,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/02\\\/08\\\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/","og_locale":"fr_FR","og_type":"article","og_title":"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression - La Sentinelle","og_description":"Une trentaine de syndicats autonomes, relevant de la fonction publique, dont ceux de la sant\u00e9 et de l&rsquo;\u00e9ducation, ont sign\u00e9","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-02-08T21:15:00+00:00","og_image":[{"width":1491,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/02\/apn.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression","datePublished":"2023-02-08T21:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/"},"wordCount":843,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/02\/apn.png","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/","name":"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/02\/apn.png","datePublished":"2023-02-08T21:15:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/02\/apn.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/02\/apn.png","width":1491,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/02\/08\/ils-menacent-de-recourir-a-des-actions-de-protestation-les-syndicats-de-la-fonction-publique-mettent-la-pression\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Ils menacent de recourir \u00e0 des actions de protestation\u00a0: Les syndicats de la Fonction publique mettent la pression"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/35838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=35838"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/35838\/revisions"}],"predecessor-version":[{"id":35848,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/35838\/revisions\/35848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/35845"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=35838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=35838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=35838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}