{"id":38096,"date":"2023-03-19T22:05:00","date_gmt":"2023-03-19T21:05:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=38096"},"modified":"2023-03-19T19:29:23","modified_gmt":"2023-03-19T18:29:23","slug":"collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/","title":{"rendered":"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le ministre de l&rsquo;Int\u00e9rieur, des collectivit\u00e9s locales et de l&rsquo;am\u00e9nagement du territoire, Brahim Merad, a affirm\u00e9 samedi lors d\u2019une rencontre avec les acteurs de la soci\u00e9t\u00e9 civile \u00e0 In Salah que l&rsquo;Etat tient \u00e0 accompagner les nouvelles wilayas du sud pour favoriser leur d\u00e9collage \u00e9conomique et de d\u00e9veloppement. Le ministre qui a effectu\u00e9 une &nbsp;visite dans la wilaya o\u00f9 il \u00e9tait accompagn\u00e9 de la ministre de la Solidarit\u00e9 nationale, de la famille et de la condition de la femme, Mme Kaoutar Krikou, soulign\u00e9 que \u00ab\u00a0les nouvelles wilayas du sud b\u00e9n\u00e9ficient d&rsquo;un accompagnement permanent de l&rsquo;Etat en vue de leur permettre de r\u00e9aliser le d\u00e9collage \u00e9conomique et de d\u00e9veloppement\u00a0\u00bb, ajoutant que \u00ab\u00a0l&rsquo;objectif de ces visites de terrain dans les nouvelles wilayas est de s&rsquo;assurer que ces derni\u00e8res, appel\u00e9es \u00e0 devenir un centre de d\u00e9cision dans le futur, s&rsquo;acquittent pleinement de leurs missions\u00a0\u00bb. Il a ajout\u00e9 qu&rsquo;un rapport exhaustif sera soumis au pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune sur les potentialit\u00e9s des nouvelles wilayas et les moyens de les d\u00e9velopper, citant \u00ab\u00a0le lancement de nouveaux projets en faveur de ces wilayas dans divers domaines\u00a0\u00bb. R\u00e9pondant aux pr\u00e9occupations concernant la cr\u00e9ation d&rsquo;un centre universitaire \u00e0 In Salah, l&rsquo;acc\u00e8s des investisseurs et des agriculteurs \u00e0 l&rsquo;expansion de leurs activit\u00e9s, et l&rsquo;augmentation des quotas du logement rural, M. Merad a estim\u00e9 que ces demandes \u00e9taient \u00ab\u00a0objectives et raisonnables\u00a0\u00bb, annon\u00e7ant la cons\u00e9cration de 129 Mds centimes pour promouvoir le d\u00e9veloppement local dans la wilaya d&rsquo;In Salah. Le ministre a appel\u00e9 \u00e0 appuyer l&rsquo;investissement dans cette wilaya qui dispose d&rsquo;\u00e9normes potentialit\u00e9s dans le domaine de l&rsquo;agriculture \u00e0 m\u00eame de contribuer aux efforts de l&rsquo;Etat pour la r\u00e9alisation de l&rsquo;autosuffisance\u00a0\u00bb, M. Merad a relev\u00e9 \u00ab\u00a0l&rsquo;int\u00e9r\u00eat croissant pour l&rsquo;\u00e9conomie du savoir et les startups, d&rsquo;o\u00f9 l&rsquo;imp\u00e9ratif pour les jeunes de s&rsquo;orienter vers ce domaine\u00a0\u00bb.&nbsp; S&rsquo;agissant du renforcement de l&rsquo;infrastructure, le ministre a fait \u00e9tat d&rsquo;un programme ambitieux pour le renforcement du r\u00e9seau des routes nationales et de wilaya et le d\u00e9senclavement de certaines r\u00e9gions du pays. Insistant sur l&rsquo;importance du nouveau d\u00e9coupage administratif, notamment dans le rapprochement de l&rsquo;administration du citoyen et la promotion du d\u00e9veloppement local, M. Merad a pr\u00e9cis\u00e9 que pr\u00e8s de 13.000 zones d&rsquo;ombre \u00e0 travers le pays ont \u00e9t\u00e9 prises en charge.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De son c\u00f4t\u00e9, Mme Krikou a soulign\u00e9 \u00ab\u00a0l&rsquo;importance de soutenir et d&rsquo;encourager la femme au foyer et la femme rurale pour en faire un partenaire cl\u00e9 dans diff\u00e9rents volets de d\u00e9veloppement\u00a0\u00bb. La ministre a fait savoir que son d\u00e9partement minist\u00e9riel est pr\u00eat \u00e0 r\u00e9pondre aux diff\u00e9rentes demandes formul\u00e9es, appelant \u00e0 l&rsquo;occasion \u00e0 sensibiliser et \u00e0 orienter la femme pour \u00eatre un \u00e9l\u00e9ment actif notamment la femme au foyer et la femme rurale qui b\u00e9n\u00e9ficient d&rsquo;un programme sp\u00e9cial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R.N.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l&rsquo;Int\u00e9rieur, des collectivit\u00e9s locales et de l&rsquo;am\u00e9nagement du territoire, Brahim Merad, a affirm\u00e9 samedi lors d\u2019une rencontre<\/p>\n","protected":false},"author":3,"featured_media":38105,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-38096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le ministre de l&rsquo;Int\u00e9rieur, des collectivit\u00e9s locales et de l&rsquo;am\u00e9nagement du territoire, Brahim Merad, a affirm\u00e9 samedi lors d\u2019une rencontre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-19T21:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/dc.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas\",\"datePublished\":\"2023-03-19T21:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/\"},\"wordCount\":533,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/dc.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/\",\"name\":\"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/dc.png\",\"datePublished\":\"2023-03-19T21:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/dc.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/dc.png\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/19\\\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/","og_locale":"fr_FR","og_type":"article","og_title":"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas - La Sentinelle","og_description":"Le ministre de l&rsquo;Int\u00e9rieur, des collectivit\u00e9s locales et de l&rsquo;am\u00e9nagement du territoire, Brahim Merad, a affirm\u00e9 samedi lors d\u2019une rencontre","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-03-19T21:05:00+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/dc.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas","datePublished":"2023-03-19T21:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/"},"wordCount":533,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/dc.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/","name":"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/dc.png","datePublished":"2023-03-19T21:05:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/dc.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/dc.png","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/19\/collectivites-locales-merad-insiste-sur-laccompagnement-des-nouvelles-wilayas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Collectivit\u00e9s locales\u00a0: Merad insiste sur l\u2019accompagnement des nouvelles wilayas"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/38096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=38096"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/38096\/revisions"}],"predecessor-version":[{"id":38106,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/38096\/revisions\/38106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/38105"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=38096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=38096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=38096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}