{"id":38197,"date":"2023-03-20T22:17:00","date_gmt":"2023-03-20T21:17:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=38197"},"modified":"2023-03-20T20:47:27","modified_gmt":"2023-03-20T19:47:27","slug":"tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/","title":{"rendered":"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb"},"content":{"rendered":"\n<p>Le pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, a r\u00e9uni hier les membres de son Ex\u00e9cutif remani\u00e9 lors de leur premier Conseil des ministres depuis leur nomination jeudi dernier. Et comme il fallait s\u2019y attendre, cette r\u00e9union a permis au Pr\u00e9sident de d\u00e9rouler ses orientations et sa vision pour cette nouvelle \u00e9tape au cours de laquelle l\u2019accent est mis sur la rectification de la trajectoire et de la correction de l\u2019action gouvernementale. Il s\u2019agit surtout de ne pas r\u00e9\u00e9diter certaines pratiques et d\u00e9rives qui ont abouti \u00e0 des r\u00e9sultats plus que mitig\u00e9s dans certains secteurs et d\u2019\u00eatre plus \u00e0 l\u2019\u00e9coute des attentes des citoyens.<\/p>\n\n\n\n<p>Le pr\u00e9sident de la R\u00e9publique a clairement affich\u00e9, il y a quelques semaines son m\u00e9contentement quant \u00e0 l\u2019action de son Ex\u00e9cutif. Un m\u00e9contentement qui s\u2019est traduit par un nouveau remaniement gouvernemental, lequel a touch\u00e9 11 d\u00e9partements minist\u00e9riels. Et pour recommencer sur de nouvelles bases avec l\u2019Ex\u00e9cutif remani\u00e9, le pr\u00e9sident Tebboune a clairement affich\u00e9 sa vision des choses&nbsp;: Pour obtenir des r\u00e9sultats et concr\u00e9tiser les objectifs assign\u00e9s, il exige du Gouvernement, moins de r\u00e9unions, moins de paroles, moins de textes r\u00e9glementaires et d\u2019\u00eatre \u00e0 l\u2019\u00e9coute des citoyens en allant \u00e0 leur rencontre sur le terrain. Bref, il veut moins de discours et plus d\u2019action. Ainsi, et selon le communiqu\u00e9 des services de la pr\u00e9sidence de la R\u00e9publique qui a sanctionn\u00e9 les travaux de la r\u00e9union, Abdelmadjid Tebboune \u00ab&nbsp;a ordonn\u00e9 au Premier ministre de tenir les r\u00e9unions du gouvernement, seulement si n\u00e9cessaire, et d&rsquo;orienter tous les efforts vers le travail sur le terrain, l&rsquo;Alg\u00e9rie n&rsquo;ayant pas besoin, aujourd&rsquo;hui, de promulguer des lois susceptibles de perturber la vie des citoyens, mais plut\u00f4t d&rsquo;en annuler certaines, devenues caduques&nbsp;\u00bb.<\/p>\n\n\n\n<p>Le Chef de l\u2019\u00c9tat pense que la priorit\u00e9 doit \u00eatre donn\u00e9e \u00e0 la concr\u00e9tisation des projets qui impactent le quotidien des Alg\u00e9riens&nbsp;\u00bb. Il a ainsi enjoint l\u2019Ex\u00e9cutif \u00e0 \u00ab&nbsp;se concentrer sur la mise en oeuvre de programmes et projets qui concernent des millions d&rsquo;Alg\u00e9riens, et faire preuve de clairvoyance pour ce qui est du bien-\u00eatre et du confort des citoyens, tel que pr\u00e9vu dans le programme pr\u00e9sidentiel, pl\u00e9biscit\u00e9 et vot\u00e9 par le peuple&nbsp;\u00bb. Et pour mieux souligner la n\u00e9cessit\u00e9 de mettre en \u0153uvre toutes les d\u00e9cisions prises au cours des derniers mois en Conseil des ministres, d\u2019ailleurs principal grief que le pr\u00e9sident de la R\u00e9publique a adress\u00e9 au Gouvernement pr\u00e9c\u00e9dent, le Chef de l\u2019\u00c9tat institue un m\u00e9canisme des suivi des actions entreprises. Il a ainsi ordonn\u00e9 de \u00ab&nbsp;renforcer la coordination entre le Directeur de Cabinet de la Pr\u00e9sidence de la R\u00e9publique et le Secr\u00e9taire g\u00e9n\u00e9ral du Gouvernement en vue d&rsquo;assurer un suivi rigoureux, et une ex\u00e9cution ferme des d\u00e9cisions du Conseil des ministres&nbsp;\u00bb. De m\u00eame qu\u2019il il a ordonn\u00e9 \u00ab&nbsp;au ministre de l&rsquo;Int\u00e9rieur, sous la supervision du Premier ministre, de mettre en place un calendrier de visites sur le terrain, \u00e0 effectuer par les membres du Gouvernement dans les wilayas, en fonction des priorit\u00e9s en mati\u00e8re de d\u00e9veloppement et de pr\u00e9occupations quotidiennes des citoyens&nbsp;\u00bb.<\/p>\n\n\n\n<p>Le pr\u00e9sident de la R\u00e9publique a \u00e9galement tenu \u00e0 clarifier certains points concernant des d\u00e9rives constat\u00e9es et la r\u00e9surgence de certaines pratiques politiques qui portent pr\u00e9judice au processus de changement escompt\u00e9. Il a ainsi enjoint les membres de l\u2019Ex\u00e9cutif \u00ab&nbsp;de s&rsquo;abstenir d\u00e9finitivement de toute utilisation exag\u00e9r\u00e9e d&rsquo;expressions politiques st\u00e9r\u00e9otyp\u00e9es glorifiant les personnalit\u00e9s, \u00e0 travers tous supports m\u00e9diatiques, et sous-entendant que toute activit\u00e9 du Gouvernement, quelle qu&rsquo;en soit la nature, est men\u00e9e sur instruction du pr\u00e9sident de la R\u00e9publique&nbsp;\u00bb, souligne-t-on. Il \u00e9galement a mis en garde les ministres contre toutes promesses infond\u00e9es faites aux citoyens dans des d\u00e9lais d\u00e9raisonnables et selon des m\u00e9canismes irr\u00e9fl\u00e9chis. &nbsp;Le pr\u00e9sident de la R\u00e9publique a \u00e9galement \u00ab&nbsp;insist\u00e9 sur le respect rigoureux des citoyens et du sentiment g\u00e9n\u00e9ral dans toute d\u00e9marche entreprise, en ce sens que la satisfaction du peuple est l&rsquo;unique crit\u00e8re t\u00e9moin de la bonne performance, en vue d&rsquo;\u00e9difier une Alg\u00e9rie respectable et forte&nbsp;\u00bb, note le communiqu\u00e9.<\/p>\n\n\n\n<p>Le pr\u00e9sident de la R\u00e9publique s\u2019attarde aussi sur ce qu\u2019il consid\u00e8re comme \u00e9tant le principal obstacle au processus de changement qu\u2019il a amorc\u00e9, \u00e0 savoir le retard pris dans la num\u00e9risation. Il a ainsi ordonn\u00e9 au Gouvernement d&rsquo;entamer, imm\u00e9diatement, l&rsquo;acc\u00e9l\u00e9ration du processus de num\u00e9risation et de statistiques pr\u00e9cises, en tant que syst\u00e8me de travail de base dans tous les secteurs, notamment pour les domaines, les imp\u00f4ts, les douanes et le budget. \u00ab&nbsp;De m\u00eame qu&rsquo;il a instruit de cr\u00e9er une plate-forme num\u00e9rique mise \u00e0 jour qui fournit des donn\u00e9es et des indicateurs pr\u00e9cis, propices \u00e0 la prise de d\u00e9cisions appropri\u00e9es et \u00e0 la lutte contre la bureaucratie&nbsp;\u00bb indique le communiqu\u00e9 de la Pr\u00e9sidence. Il a enfin clos son discours d\u2019orientation aux nouveaux membres du Gouvernement en soulignant la n\u00e9cessit\u00e9 de faciliter l&rsquo;acte d&rsquo;investissement et encourager les investisseurs notamment \u00e0 travers le guichet unique.<\/p>\n\n\n\n<p><strong>Hocine Fadheli<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, a r\u00e9uni hier les membres de son Ex\u00e9cutif remani\u00e9 lors de leur premier<\/p>\n","protected":false},"author":3,"featured_media":38198,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-38197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, a r\u00e9uni hier les membres de son Ex\u00e9cutif remani\u00e9 lors de leur premier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-20T21:17:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/tebboune-une.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1331\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb\",\"datePublished\":\"2023-03-20T21:17:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/\"},\"wordCount\":953,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/tebboune-une.png\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/\",\"name\":\"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/tebboune-une.png\",\"datePublished\":\"2023-03-20T21:17:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/tebboune-une.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/tebboune-une.png\",\"width\":1331,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/03\\\/20\\\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/","og_locale":"fr_FR","og_type":"article","og_title":"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb - La Sentinelle","og_description":"Le pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, a r\u00e9uni hier les membres de son Ex\u00e9cutif remani\u00e9 lors de leur premier","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-03-20T21:17:00+00:00","og_image":[{"width":1331,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/tebboune-une.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb","datePublished":"2023-03-20T21:17:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/"},"wordCount":953,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/tebboune-une.png","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/","name":"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/tebboune-une.png","datePublished":"2023-03-20T21:17:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/tebboune-une.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/03\/tebboune-une.png","width":1331,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/03\/20\/tebboune-exige-de-ses-ministres-des-actions-concretes-allez-sur-terrain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Tebboune exige de ses ministres des actions concr\u00e8tes\u00a0: \u00ab\u00a0Allez sur terrain\u00a0!\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/38197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=38197"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/38197\/revisions"}],"predecessor-version":[{"id":38199,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/38197\/revisions\/38199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/38198"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=38197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=38197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=38197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}