{"id":41284,"date":"2023-05-17T22:17:00","date_gmt":"2023-05-17T21:17:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=41284"},"modified":"2023-05-17T21:42:49","modified_gmt":"2023-05-17T20:42:49","slug":"le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/","title":{"rendered":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite du Sommet arabe d\u2019Alger tenu au mois de novembre dernier. Et l\u2019empreinte des d\u00e9cisions prises \u00e0 Alger et de l\u2019effet de la pr\u00e9sidence alg\u00e9rienne de la Ligue arabe au Sommet est visible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que ce soit en ce qui concerne l\u2019unification des rangs et les efforts entrepris pour mettre fin aux divisions, notamment avec le retour de la Syrie au sein de la Ligue arabe, la d\u00e9marche entreprise pour la r\u00e9conciliation palestinienne et de la r\u00e9habilitation de la cause palestinienne en tant que question centrale pour le Monde arabe, de l\u2019approche en ce qui concerne les traitement des conflit dans la r\u00e9gion, ou encore de&nbsp;la d\u00e9marche entreprise pour le renforcement de la coordination arabe pour faire face aux d\u00e9fis impos\u00e9s par la conjoncture internationale actuelle, les d\u00e9cisions prises \u00e0 Alger continueront \u00e0 guider l\u2019action arabe au moment o\u00f9 l\u2019Alg\u00e9rie remettra la pr\u00e9sidence de la Ligue lors du Sommet de Djeddah. D\u2019ailleurs, l\u2019influence de l\u2019action men\u00e9e par l\u2019Alg\u00e9rie lors de sa pr\u00e9sidence s\u2019est faite sentir lors de la r\u00e9union des ministres des Affaires \u00e9trang\u00e8res de la Ligue arabe ouverte hier et lors de laquelle, le chef de la diplomatie alg\u00e9rienne, Ahmed Attaf a remis la pr\u00e9sidence Conseil de la Ligue arabe au niveau des ministres des affaires \u00e9trang\u00e8res \u00e0 son homologue saoudien Faisal bin Farhane Al Saoud. Ainsi et lors de son intervention, le ministre des Affaires \u00e9trang\u00e8res et de la Communaut\u00e9 nationale \u00e0 l&rsquo;\u00e9tranger a r\u00e9affirm\u00e9l&rsquo;imp\u00e9ratif d&rsquo;intensifier les efforts de renforcement de l&rsquo;action arabe. Ahmed Attaf a soulign\u00e9 que le Sommet arabe qui s\u2019ouvre demain \u00ab&nbsp;se tient dans un contexte r\u00e9gional particulier marqu\u00e9 par des d\u00e9veloppements effr\u00e9n\u00e9s qui impliquent la poursuite de l&rsquo;action pour resserrer nos rangs et unifier notre parole \u00e0 l&rsquo;effet de surmonter les obstacles et les d\u00e9fis qui emp\u00eachent de garantir une place qui sied \u00e0 notre nation arabe, notamment \u00e0 la lumi\u00e8re des d\u00e9s\u00e9quilibres qui affectent le syst\u00e8me des relations internationales existantes&nbsp;\u00bb. Le ministre a mis l&rsquo;accent sur la n\u00e9cessit\u00e9 de poursuivre l&rsquo;action et d&rsquo;intensifier les efforts \u00ab\u00a0pour gagner les paris de l&rsquo;action arabe commune et explorer ses perspectives prometteuses \u00e0 travers la valorisation des constantes authentiques qui rassemblent les pays arabes, en mettant \u00e0 l&rsquo;\u00e9cart les tiraillements qui les divisent\u00a0\u00bb, a-t-il poursuivi. Le ministre a rappel\u00e9 que l&rsquo;Alg\u00e9rie, sous la conduite du pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, a plac\u00e9 ces objectifs au centre des priorit\u00e9s de sa pr\u00e9sidence tournante du Conseil de la Ligue arabe. Elle a choisi \u00ab\u00a0le rassemblement\u00a0\u00bb comme th\u00e8me principal et objectif noble au sommet arabe qu&rsquo;elle a abrit\u00e9 au mois de novembre dernier. L&rsquo;Alg\u00e9rie \u00ab\u00a0s&rsquo;att\u00e8le avec d\u00e9termination \u00e0 servir nos projets et nos causes \u00e0 travers la concr\u00e9tisation des d\u00e9cisions justes et clairvoyantes issues des rencontres de nos dirigeants dans l&rsquo;int\u00e9r\u00eat de tous les pays et peuples arabes\u00a0\u00bb, a-t-il poursuivi.&nbsp;&nbsp;&nbsp; Evoquant la souffrance des Palestiniens du fait des pratiques du colonisateur et ses agressions criminelles et syst\u00e9miques \u00e0 Al-Qods et en Cisjordanie occup\u00e9es et la bande de Ghaza assi\u00e9g\u00e9e, en plus du blocage des perspectives du processus de la paix au Moyen-Orient, M. Attaf a mis l&rsquo;accent sur l&rsquo;imp\u00e9ratif de redoubler d&rsquo;efforts en vue d&rsquo;imposer le respect des droits du peuple palestinien, notamment son droit d&rsquo;\u00e9tablir son Etat ind\u00e9pendant avec Al-Qods pour capitale. Dans le m\u00eame contexte, il a mis en exergue l&rsquo;attachement de l&rsquo;Alg\u00e9rie lors du dernier Sommet arabe \u00e0 placer la cause palestinienne en la t\u00eate des priorit\u00e9s de l&rsquo;action arabe commune. Il a \u00e9galement insist\u00e9 sur la poursuite des efforts, sous la supervision directe du Pr\u00e9sident Tebboune, visant \u00e0 r\u00e9aliser la r\u00e9conciliation palestinienne en accompagnant toutes les parties vers la concr\u00e9tisation des \u00e9ch\u00e9ances nationales inscrites dans la \u00ab\u00a0D\u00e9claration d&rsquo;Alger de rassemblement pour l&rsquo;unit\u00e9 nationale palestinienne\u00a0\u00bb, sign\u00e9e le 13 octobre dernier \u00e0 Alger par l&rsquo;ensemble des factions palestiniennes. Dans le cadre de l&rsquo;activation des d\u00e9cisions sanctionnant le Sommet d&rsquo;Alger, ajoute M. Attaf, l&rsquo;Alg\u00e9rie poursuit \u00ab\u00a0en coordination avec l&rsquo;ensemble des fr\u00e8res arabes, ses efforts qui ont pour but de permettre \u00e0 l&rsquo;Etat de Palestine d&rsquo;obtenir plus de reconnaissance internationale, ainsi que la qualit\u00e9 de membre \u00e0 part enti\u00e8re au sein de l\u2019ONU\u00a0\u00bb. Par ailleurs, il s&rsquo;est, \u00e0 nouveau, f\u00e9licit\u00e9 du retour de la Syrie au sein de la Ligue arabe, affichant le soutien de l&rsquo;Alg\u00e9rie. Un retour qui a couronn\u00e9 les efforts de l\u2019Alg\u00e9rie d\u00e9ploy\u00e9s dans cet objectif et son action pour mettre fin aux divisions arabes. Il est utile de noter \u00e0 ce propos que le SG-adjoint de la Ligue arabe Houssam Zaki a confirm\u00e9 hier la pr\u00e9sence du pr\u00e9sident syrien Bachar Al Assad demain au Sommet arabe. Attaf a \u00e9galement \u00e9voqu\u00e9 les conflits dans la r\u00e9gion. Il a soulign\u00e9 les indicateurs positifs pour parvenir \u00e0 une solution permanente \u00e0 la crise au Y\u00e9men. Concernant le Soudan, M. Attaf a indiqu\u00e9 que \u00ab\u00a0la d\u00e9t\u00e9rioration grave\u00a0\u00bb de la situation dans ce pays, avec ses r\u00e9percussions s\u00e9curitaires, politiques et humanitaires, constitue \u00ab\u00a0une source de pr\u00e9occupation majeure\u00a0\u00bb, mettant en exergue l&rsquo;initiative du pr\u00e9sident Tebboune, en qualit\u00e9 de pr\u00e9sident en exercice du Sommet arabe, aupr\u00e8s de l&rsquo;ONU, de l&rsquo;Union africaine (UA) et de l&rsquo;Autorit\u00e9 intergouvernementale pour le d\u00e9veloppement (IGAD), pour cristalliser une initiative commune garantissant la cessation des hostilit\u00e9s et de l&rsquo;effusion de sang et le lancement d&rsquo;un processus politique global pour r\u00e9soudre la crise. Pour ce qui est de la Libye, le ministre a r\u00e9affirm\u00e9 la conviction ferme de l&rsquo;Alg\u00e9rie selon laquelle le retour \u00e0 la stabilit\u00e9 \u00ab\u00a0ne saurait intervenir qu&rsquo;\u00e0 travers un processus inter-libyen encourageant le consensus entre les enfants de ce pays fr\u00e8re, en vue d&rsquo;aller de l&rsquo;avant vers l&rsquo;organisation d&rsquo;\u00e9lections parlementaires et pr\u00e9sidentielle afin de mettre fin d\u00e9finitivement \u00e0 cette crise et de r\u00e9aliser les aspirations du peuple libyen \u00e0 \u00e9difier un Etat d\u00e9mocratique moderne\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notons que le chef de la diplomatie alg\u00e9rienne a &nbsp;pr\u00e9sid\u00e9 la r\u00e9union du Comit\u00e9 minist\u00e9riel en charge de la mise en \u0153uvre des propositions formul\u00e9es par le pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, concernant la r\u00e9forme et le d\u00e9veloppement de la Ligue arabe, adopt\u00e9es lors du Sommet d&rsquo;Alger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces propositions concernent la consolidation du r\u00f4le de la Ligue arabe dans la pr\u00e9vention et la r\u00e9solution des conflits \u00e0 travers la cr\u00e9ation d&rsquo;un comit\u00e9 de sages arabes, le renforcement de la dimension populaire de l&rsquo;action arabe commune par l&rsquo;instauration d&rsquo;un forum de dialogue interg\u00e9n\u00e9rationnel pour soutenir l&rsquo;action arabe commune, et la promotion du statut des jeunes et de l&rsquo;innovation en mettant en place un fonds arabe pour l&rsquo;appui aux start-up et un r\u00e9seau arabe d&rsquo;incubateurs. Les d\u00e9lib\u00e9rations des ministres des AE des pays membres ont \u00e9t\u00e9 ax\u00e9es sur les proc\u00e9dures pratiques \u00e0 m\u00eame d&rsquo;acc\u00e9l\u00e9rer la mise en \u0153uvre des propositions du pr\u00e9sident de la R\u00e9publique \u00ab\u00a0dans les meilleurs d\u00e9lais possibles\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lyes Saidi<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite<\/p>\n","protected":false},"author":3,"featured_media":41296,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_bluesky_share_type":"","_mastodon_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-41284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite du Sommet arabe d\u2019Alger tenu au mois de novembre dernier. Et l\u2019empreinte des d\u00e9cisions prises \u00e0 Alger et de l\u2019effet de la pr\u00e9sidence alg\u00e9rienne de la Ligue arabe au Sommet est visible. Que ce soit\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"La Sentinelle\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Sentinelle - Quotidien national d&#039;information\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah : Alger a trac\u00e9 la voie - La Sentinelle\" \/>\n\t\t<meta property=\"og:description\" content=\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite du Sommet arabe d\u2019Alger tenu au mois de novembre dernier. Et l\u2019empreinte des d\u00e9cisions prises \u00e0 Alger et de l\u2019effet de la pr\u00e9sidence alg\u00e9rienne de la Ligue arabe au Sommet est visible. Que ce soit\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif\" \/>\n\t\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-17T21:17:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-17T20:42:49+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/azzedine.lasentinelle.1\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah : Alger a trac\u00e9 la voie - La Sentinelle\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite du Sommet arabe d\u2019Alger tenu au mois de novembre dernier. Et l\u2019empreinte des d\u00e9cisions prises \u00e0 Alger et de l\u2019effet de la pr\u00e9sidence alg\u00e9rienne de la Ligue arabe au Sommet est visible. Que ce soit\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#blogposting\",\"name\":\"Le Sommet de la Ligue arabe s\\u2019ouvrira demain \\u00e0 Djeddah : Alger a trac\\u00e9 la voie - La Sentinelle\",\"headline\":\"Le Sommet de la Ligue arabe s\\u2019ouvrira demain \\u00e0 Djeddah\\u00a0: Alger a trac\\u00e9 la voie\",\"author\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Sommet.png\",\"width\":1350,\"height\":900},\"datePublished\":\"2023-05-17T22:17:00+01:00\",\"dateModified\":\"2023-05-17T21:42:49+01:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#webpage\"},\"articleSection\":\"\\u00c0 la Une, Actualit\\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lasentinelle.dz\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/category\\\/actualite\\\/#listItem\",\"name\":\"Actualit\\u00e9\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/category\\\/actualite\\\/#listItem\",\"position\":2,\"name\":\"Actualit\\u00e9\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/category\\\/actualite\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#listItem\",\"name\":\"Le Sommet de la Ligue arabe s\\u2019ouvrira demain \\u00e0 Djeddah\\u00a0: Alger a trac\\u00e9 la voie\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#listItem\",\"position\":3,\"name\":\"Le Sommet de la Ligue arabe s\\u2019ouvrira demain \\u00e0 Djeddah\\u00a0: Alger a trac\\u00e9 la voie\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/category\\\/actualite\\\/#listItem\",\"name\":\"Actualit\\u00e9\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"La Sentinelle La Sentinelle\",\"description\":\"Quotidien national d'information\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cropped-la-sentinelle-earth-golden-anima-5.gif\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#organizationLogo\",\"width\":450,\"height\":213},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/azzedine.lasentinelle.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/#author\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"La Sentinelle\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#webpage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/\",\"name\":\"Le Sommet de la Ligue arabe s\\u2019ouvrira demain \\u00e0 Djeddah : Alger a trac\\u00e9 la voie - La Sentinelle\",\"description\":\"Le Sommet de la Ligue arabe s\\u2019ouvrira demain \\u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\\u2019inscrit dans la suite du Sommet arabe d\\u2019Alger tenu au mois de novembre dernier. Et l\\u2019empreinte des d\\u00e9cisions prises \\u00e0 Alger et de l\\u2019effet de la pr\\u00e9sidence alg\\u00e9rienne de la Ligue arabe au Sommet est visible. Que ce soit\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Sommet.png\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#mainImage\",\"width\":1350,\"height\":900},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#mainImage\"},\"datePublished\":\"2023-05-17T22:17:00+01:00\",\"dateModified\":\"2023-05-17T21:42:49+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d'information\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah : Alger a trac\u00e9 la voie - La Sentinelle","description":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite du Sommet arabe d\u2019Alger tenu au mois de novembre dernier. Et l\u2019empreinte des d\u00e9cisions prises \u00e0 Alger et de l\u2019effet de la pr\u00e9sidence alg\u00e9rienne de la Ligue arabe au Sommet est visible. Que ce soit","canonical_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#blogposting","name":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah : Alger a trac\u00e9 la voie - La Sentinelle","headline":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie","author":{"@id":"https:\/\/lasentinelle.dz\/author\/redaction\/#author"},"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Sommet.png","width":1350,"height":900},"datePublished":"2023-05-17T22:17:00+01:00","dateModified":"2023-05-17T21:42:49+01:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#webpage"},"isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#webpage"},"articleSection":"\u00c0 la Une, Actualit\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz#listItem","position":1,"name":"Home","item":"https:\/\/lasentinelle.dz","nextItem":{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/category\/actualite\/#listItem","name":"Actualit\u00e9"}},{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/category\/actualite\/#listItem","position":2,"name":"Actualit\u00e9","item":"https:\/\/lasentinelle.dz\/index.php\/category\/actualite\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#listItem","name":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#listItem","position":3,"name":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie","previousItem":{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/category\/actualite\/#listItem","name":"Actualit\u00e9"}}]},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"La Sentinelle La Sentinelle","description":"Quotidien national d'information","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#organizationLogo","width":450,"height":213},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/azzedine.lasentinelle.1"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/author\/redaction\/#author","url":"https:\/\/lasentinelle.dz\/author\/redaction\/","name":"La Sentinelle","image":{"@type":"ImageObject","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","width":96,"height":96,"caption":"La Sentinelle"}},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#webpage","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/","name":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah : Alger a trac\u00e9 la voie - La Sentinelle","description":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite du Sommet arabe d\u2019Alger tenu au mois de novembre dernier. Et l\u2019empreinte des d\u00e9cisions prises \u00e0 Alger et de l\u2019effet de la pr\u00e9sidence alg\u00e9rienne de la Ligue arabe au Sommet est visible. Que ce soit","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#breadcrumblist"},"author":{"@id":"https:\/\/lasentinelle.dz\/author\/redaction\/#author"},"creator":{"@id":"https:\/\/lasentinelle.dz\/author\/redaction\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Sommet.png","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#mainImage","width":1350,"height":900},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#mainImage"},"datePublished":"2023-05-17T22:17:00+01:00","dateModified":"2023-05-17T21:42:49+01:00"},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d'information","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"La Sentinelle - Quotidien national d'information","og:type":"article","og:title":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah : Alger a trac\u00e9 la voie - La Sentinelle","og:description":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite du Sommet arabe d\u2019Alger tenu au mois de novembre dernier. Et l\u2019empreinte des d\u00e9cisions prises \u00e0 Alger et de l\u2019effet de la pr\u00e9sidence alg\u00e9rienne de la Ligue arabe au Sommet est visible. Que ce soit","og:url":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/","og:image":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif","og:image:secure_url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif","og:image:width":450,"og:image:height":213,"article:published_time":"2023-05-17T21:17:00+00:00","article:modified_time":"2023-05-17T20:42:49+00:00","article:publisher":"https:\/\/www.facebook.com\/azzedine.lasentinelle.1","twitter:card":"summary_large_image","twitter:title":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah : Alger a trac\u00e9 la voie - La Sentinelle","twitter:description":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite du Sommet arabe d\u2019Alger tenu au mois de novembre dernier. Et l\u2019empreinte des d\u00e9cisions prises \u00e0 Alger et de l\u2019effet de la pr\u00e9sidence alg\u00e9rienne de la Ligue arabe au Sommet est visible. Que ce soit","twitter:image":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif"},"aioseo_meta_data":{"post_id":"41284","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-05-02 05:40:04","updated":"2026-05-02 05:40:04","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lasentinelle.dz\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lasentinelle.dz\/index.php\/category\/actualite\/\" title=\"Actualit\u00e9\">Actualit\u00e9<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLe Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah : Alger a trac\u00e9 la voie\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/lasentinelle.dz"},{"label":"Actualit\u00e9","link":"https:\/\/lasentinelle.dz\/index.php\/category\/actualite\/"},{"label":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-17T21:17:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Sommet.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie\",\"datePublished\":\"2023-05-17T21:17:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/\"},\"wordCount\":1309,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Sommet.png\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/\",\"name\":\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Sommet.png\",\"datePublished\":\"2023-05-17T21:17:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Sommet.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Sommet.png\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/17\\\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie - La Sentinelle","og_description":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah en Arabie saoudite. Un Sommet qui s\u2019inscrit dans la suite","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-05-17T21:17:00+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Sommet.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie","datePublished":"2023-05-17T21:17:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/"},"wordCount":1309,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Sommet.png","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/","name":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Sommet.png","datePublished":"2023-05-17T21:17:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Sommet.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Sommet.png","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/17\/le-sommet-de-la-ligue-arabe-souvrira-demain-a-djeddah-alger-a-trace-la-voie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Le Sommet de la Ligue arabe s\u2019ouvrira demain \u00e0 Djeddah\u00a0: Alger a trac\u00e9 la voie"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/41284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=41284"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/41284\/revisions"}],"predecessor-version":[{"id":41297,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/41284\/revisions\/41297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/41296"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=41284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=41284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=41284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}