{"id":41834,"date":"2023-05-28T22:15:00","date_gmt":"2023-05-28T21:15:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=41834"},"modified":"2023-05-28T21:19:31","modified_gmt":"2023-05-28T20:19:31","slug":"faux-et-usage-des-faux-vers-un-renforcement-des-peines","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/","title":{"rendered":"Faux et usage des faux\u00a0: Vers un renforcement des peines"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le pr\u00e9sident de la R\u00e9publique a soulign\u00e9 hier la n\u00e9cessit\u00e9 de combattre les d\u00e9lits li\u00e9s au faux et \u00e0 l\u2019usage de faux. Des d\u00e9lits qui se propagent et se muent en v\u00e9ritable ph\u00e9nom\u00e8ne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019avant-projet d\u2019amendement de Code p\u00e9nal a \u00e9t\u00e9 examin\u00e9 hier lors de la r\u00e9union p\u00e9riodique du Conseil des ministres. Le texte doit permettre de mieux prot\u00e9ger les enseignants et les cat\u00e9gories vuln\u00e9rables, prot\u00e9ger les investisseurs et les gestionnaires publics en plus de de criminaliser les entraves \u00e0 l\u2019acte d\u2019investir. Le texte doit aussi prendre en charge les instructions du pr\u00e9sident de la R\u00e9publique sur le durcissement des peines applicables en mati\u00e8re de fraude et de falsification sous toutes ses formes. D\u2019ailleurs, au cours du Conseil des ministres tenu hier sous sa pr\u00e9sidence, Abdelmadjid Tebboune a soulign\u00e9 la n\u00e9cessit\u00e9 de combattre le faut et l\u2019usage de faux. Il ainsi ordonn\u00e9 au Gouvernement de pr\u00e9parer et d\u2019\u00e9laborer dans un d\u00e9lai d\u2019un mois au maximum un projet de loi sur le faut et l&rsquo;usage de faux, \u00ab&nbsp;afin de traiter ce ph\u00e9nom\u00e8ne devenu un comportement social dangereux, qui porte pr\u00e9judice de la majorit\u00e9 des citoyens alg\u00e9riens int\u00e8gres&nbsp;\u00bb, souligne le communiqu\u00e9 des services de la pr\u00e9sidence de la R\u00e9publique qui a sanctionn\u00e9 les travaux de la r\u00e9union. Et de souligner que l\u2019objectif du projet de texte porte sur \u00ab le traitement en profondeur et dissuasif de toutes les perturbations sociales, dans le but de concr\u00e9tiser la transparence, d&rsquo;\u00e9tablir une concurrence r\u00e9elle et \u00e9quitable dans tous les domaines&nbsp;\u00bb. Ainsi, le texte devra pr\u00e9voir les peines les plus s\u00e9v\u00e8res contre tout auteur de faux et usage de faux, qu&rsquo;il soit impliqu\u00e9 dans des affaires majeures ou mineures touchant les aspects les plus simples de la vie, pr\u00e9cise-t-on.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le pr\u00e9sident de la R\u00e9publique a \u00e9galement soulign\u00e9 la n\u00e9cessit\u00e9 de traiter d\u2019autres ph\u00e9nom\u00e8nes sociaux \u00e9mergents, comme les agressions qui ciblent les agents publics. Le pr\u00e9sident Tebboune a ainsi soulign\u00e9 la n\u00e9cessit\u00e9 d&rsquo;infliger les peines maximales aux agresseurs des agents de toutes les forces de s\u00e9curit\u00e9. Aussi et en plus de la protection des m\u00e9decins et du personnel m\u00e9dical, il a ordonn\u00e9 un durcissement des sanctions \u00e0 l&rsquo;encontre des agresseurs des enseignants. L\u2019autre ph\u00e9nom\u00e8ne qui prend de l\u2019ampleur, celui li\u00e9 au vol des c\u00e2bles en cuivre et les actes de vandalisme contre les infrastructures pour voler des mat\u00e9riaux ferreux et non ferreux a \u00e9galement \u00e9t\u00e9 \u00e9voqu\u00e9 par le Chef de l\u2019\u00c9tat lequel a insist\u00e9 sur la n\u00e9cessit\u00e9 de le combattre. Il a ainsi exig\u00e9 le renforcement des sanctions contre toute personne ou groupe organis\u00e9 ciblant les infrastructures vitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notons que la r\u00e9union a \u00e9galement permis d\u2019examiner le Code de proc\u00e9dures p\u00e9nales. Dans le cadre de cet examen, le Pr\u00e9sident Tebboune a consid\u00e9r\u00e9 que le syst\u00e8me des p\u00f4les judiciaires nationaux sp\u00e9cialis\u00e9s dans la justice est un syst\u00e8me efficace qui apporte une valeur ajout\u00e9e \u00e0 la mani\u00e8re de traiter les diff\u00e9rentes affaires. Il a ainsi ordonn\u00e9 la mise en place P\u00f4les judiciaires nationaux sp\u00e9cialis\u00e9s \u00e0 Oran, Constantine et Annaba, chacun dans son domaine de comp\u00e9tence. Il a \u00e9galement instruit le gouvernement \u00e0 l\u2019effet d\u2019enrichir le texte&nbsp; \u00e0 la lumi\u00e8re d\u2019un examen approfondi sur la protection des responsables locaux int\u00e8gres. Le pr\u00e9sident de la R\u00e9publique a estim\u00e9 n\u00e9cessaire que le texte d\u00e9finisse et pr\u00e9cise les cat\u00e9gories des responsables locaux et des gestionnaires d&rsquo;institutions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lyes Saidi<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la R\u00e9publique a soulign\u00e9 hier la n\u00e9cessit\u00e9 de combattre les d\u00e9lits li\u00e9s au faux et \u00e0 l\u2019usage<\/p>\n","protected":false},"author":3,"featured_media":41837,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-41834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Faux et usage des faux\u00a0: Vers un renforcement des peines - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faux et usage des faux\u00a0: Vers un renforcement des peines - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le pr\u00e9sident de la R\u00e9publique a soulign\u00e9 hier la n\u00e9cessit\u00e9 de combattre les d\u00e9lits li\u00e9s au faux et \u00e0 l\u2019usage\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-28T21:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Justice.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1579\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Faux et usage des faux\u00a0: Vers un renforcement des peines\",\"datePublished\":\"2023-05-28T21:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/\"},\"wordCount\":651,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Justice.png\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/\",\"name\":\"Faux et usage des faux\u00a0: Vers un renforcement des peines - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Justice.png\",\"datePublished\":\"2023-05-28T21:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Justice.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Justice.png\",\"width\":1579,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/05\\\/28\\\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faux et usage des faux\u00a0: Vers un renforcement des peines\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faux et usage des faux\u00a0: Vers un renforcement des peines - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/","og_locale":"fr_FR","og_type":"article","og_title":"Faux et usage des faux\u00a0: Vers un renforcement des peines - La Sentinelle","og_description":"Le pr\u00e9sident de la R\u00e9publique a soulign\u00e9 hier la n\u00e9cessit\u00e9 de combattre les d\u00e9lits li\u00e9s au faux et \u00e0 l\u2019usage","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-05-28T21:15:00+00:00","og_image":[{"width":1579,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Justice.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Faux et usage des faux\u00a0: Vers un renforcement des peines","datePublished":"2023-05-28T21:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/"},"wordCount":651,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Justice.png","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/","name":"Faux et usage des faux\u00a0: Vers un renforcement des peines - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Justice.png","datePublished":"2023-05-28T21:15:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Justice.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/05\/Justice.png","width":1579,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/05\/28\/faux-et-usage-des-faux-vers-un-renforcement-des-peines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Faux et usage des faux\u00a0: Vers un renforcement des peines"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/41834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=41834"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/41834\/revisions"}],"predecessor-version":[{"id":41846,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/41834\/revisions\/41846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/41837"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=41834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=41834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=41834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}