{"id":43153,"date":"2023-07-01T20:28:09","date_gmt":"2023-07-01T19:28:09","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=43153"},"modified":"2023-07-01T20:28:12","modified_gmt":"2023-07-01T19:28:12","slug":"jeux-sportifs-arabes-2023-les-premiers-tournois-lances","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/","title":{"rendered":"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les Jeux sportifs arabes que l\u2019Alg\u00e9rie abritera jusqu\u2019au 17 juillet s\u2019ouvriront mercredi. Et avant le d\u00e9but officiel de la comp\u00e9tition plusieurs villes se mettent d\u00e9j\u00e0 dans l\u2019ambiance de la grand-messe du sport arabe, notamment avec le d\u00e9but aujourd\u2019hui des matchs pr\u00e9paratoires du tournoi de football.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En effet, Annaba et Constantine, o\u00f9 les d\u00e9l\u00e9gations de plusieurs d\u00e9l\u00e9gations qui prennent part \u00e0 ce tournoi, sont arriv\u00e9es. C\u2019est le cas de l\u2019\u00e9quipe saoudienne qui est arriv\u00e9e vendredi \u00e0 Constantine et qui doit affronter, cet apr\u00e8s-midi, au stade du Chahid Hamlaoui, la s\u00e9lection syrienne. Dans la soir\u00e9e ce sera au tour de l\u2019\u00e9quipe de Palestine de faire face \u00e0 la s\u00e9lection mauritanienne. Au Stade du 19 mai d\u2019Annaba, le bal sera ouvert avec le match Liban-Soudan. Les Verts entreront en sc\u00e8ne dans la soir\u00e9e face \u00e0 leurs homologues omanais. Notons que l\u2019\u00e9quipe nationale U23 est arriv\u00e9e \u00e0 Annaba. Le s\u00e9lectionneur national Rachid Ait Mohamed a d\u00e9voil\u00e9 vendredi la liste des 23 joueurs retenus pour ce tournoi. En pr\u00e9vision des Jeux sportifs arabes 2023, la s\u00e9lection alg\u00e9rienne avait boucl\u00e9 lundi dernier son stage de pr\u00e9-s\u00e9lection entam\u00e9 le vendredi 23 juin \u00e0 Rouiba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Oran qui abritera les tournois de six disciplines dont entre autres, le handball, la natation, la p\u00e9tanque, la gymnastique et l\u2019athl\u00e9tisme, la s\u00e9lection alg\u00e9rienne d&rsquo;athl\u00e9tisme est \u00e0 pied d\u2019\u0153uvre depuis hier. &nbsp;Dans ce sens, le Pr\u00e9sident de la Ligue oranaise d\u2019athl\u00e9tisme et membre du comit\u00e9 d\u2019organisation du p\u00f4le d\u2019Oran, Brahim Ammoura affich\u00e9 son optimisme quant aux capacit\u00e9s des sportifs alg\u00e9riens de s&rsquo;adjuger la part de lion en mati\u00e8re des m\u00e9dailles, \u00ab\u00a0au regard de la belle forme qu\u2019ils ont affich\u00e9e lors des derni\u00e8res comp\u00e9titions internationales\u00a0\u00bb, a-t-il dit, tablant notamment sur les sp\u00e9cialistes dans les courses de demi-fond. Par ailleurs, le m\u00eame responsable a assur\u00e9 que le stade Miloud Hadefi, th\u00e9\u00e2tre des \u00e9preuves d\u2019athl\u00e9tisme, est \u00ab\u00a0fin pr\u00eat\u00a0\u00bb pour accueillir la comp\u00e9tition, \u00ab\u00a0comme v\u00e9rifi\u00e9 lors du meeting national d\u2019athl\u00e9tisme organis\u00e9 au m\u00eame site, la semaine pass\u00e9e\u00a0\u00bb, a-t-il encore pr\u00e9cis\u00e9. M\u00eame cas de figure pour le stade annexe qui a \u00e9t\u00e9 retenu pour les entrainements des sportifs participants aux Jeux sportifs arabes, a inform\u00e9 Brahim Ammour.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au-del\u00e0 de ces trois villes, la Capitale Alger et Tipaza abriteront les tournois d\u2019autres disciplines. Il est utile de rappeler, le ministre de la Jeunesse et des Sports, Abderrahmane Hammad, a affirm\u00e9, lundi que l&rsquo;Alg\u00e9rie \u00e9tait \u00ab\u00a0pr\u00eate\u00a0\u00bb \u00e0 faire de cet important \u00e9v\u00e9nement sportif \u00ab\u00a0un succ\u00e8s. Concernant les c\u00e9r\u00e9monies d\u2019ouverture et de cl\u00f4ture pr\u00e9vues au stade olympique du 5 Juillet, le premier responsable du secteur n\u2019a donn\u00e9 aucune pr\u00e9cision sur ce sujet, se contentant d\u2019assurer que ces deux c\u00e9r\u00e9monies seront \u00ab\u00a0de haut niveau et constitueront une v\u00e9ritable surprise\u00a0\u00bb. La 15e \u00e9dition des Jeux sportifs arabes (Alg\u00e9rie-2023), pr\u00e9vus du 5 au 15 juillet prochain dans cinq (5) villes alg\u00e9riennes, verra la participation de 18 pays, repr\u00e9sent\u00e9s par plus de 3.800 athl\u00e8tes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Chokri Hafed<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Jeux sportifs arabes que l\u2019Alg\u00e9rie abritera jusqu\u2019au 17 juillet s\u2019ouvriront mercredi. Et avant le d\u00e9but officiel de la comp\u00e9tition<\/p>\n","protected":false},"author":3,"featured_media":43154,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,33],"tags":[],"class_list":["post-43153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-sports"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Les Jeux sportifs arabes que l\u2019Alg\u00e9rie abritera jusqu\u2019au 17 juillet s\u2019ouvriront mercredi. Et avant le d\u00e9but officiel de la comp\u00e9tition\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-01T19:28:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-01T19:28:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/stade.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s\",\"datePublished\":\"2023-07-01T19:28:09+00:00\",\"dateModified\":\"2023-07-01T19:28:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/\"},\"wordCount\":559,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/stade.jpeg\",\"articleSection\":[\"\u00c0 la Une\",\"Sports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/\",\"name\":\"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/stade.jpeg\",\"datePublished\":\"2023-07-01T19:28:09+00:00\",\"dateModified\":\"2023-07-01T19:28:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/stade.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/stade.jpeg\",\"width\":1920,\"height\":1278},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/","og_locale":"fr_FR","og_type":"article","og_title":"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s - La Sentinelle","og_description":"Les Jeux sportifs arabes que l\u2019Alg\u00e9rie abritera jusqu\u2019au 17 juillet s\u2019ouvriront mercredi. Et avant le d\u00e9but officiel de la comp\u00e9tition","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-07-01T19:28:09+00:00","article_modified_time":"2023-07-01T19:28:12+00:00","og_image":[{"width":1920,"height":1278,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/stade.jpeg","type":"image\/jpeg"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s","datePublished":"2023-07-01T19:28:09+00:00","dateModified":"2023-07-01T19:28:12+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/"},"wordCount":559,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/stade.jpeg","articleSection":["\u00c0 la Une","Sports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/","name":"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/stade.jpeg","datePublished":"2023-07-01T19:28:09+00:00","dateModified":"2023-07-01T19:28:12+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/stade.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/stade.jpeg","width":1920,"height":1278},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/jeux-sportifs-arabes-2023-les-premiers-tournois-lances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Jeux sportifs arabes 2023&nbsp;: Les premiers tournois lanc\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/43153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=43153"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/43153\/revisions"}],"predecessor-version":[{"id":43155,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/43153\/revisions\/43155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/43154"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=43153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=43153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=43153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}