{"id":43180,"date":"2023-07-01T21:39:03","date_gmt":"2023-07-01T20:39:03","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=43180"},"modified":"2023-07-01T21:39:04","modified_gmt":"2023-07-01T20:39:04","slug":"mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/","title":{"rendered":"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un nouveau t\u00e9moignage met en lumi\u00e8re ce qui s\u2019est pass\u00e9 mardi lorsqu\u2019un policier a tir\u00e9 sur bout portant sur un jeune franco-alg\u00e9rien de 17 ans, au volant d\u2019une Mercedes de location, lors d\u2019un contr\u00f4le routier. &nbsp;De nouveau \u00e9l\u00e9ments confortent le fait que le tir du policier, inculp\u00e9 depuis pour homicide volontaire, \u00e9tait totalement injustifi\u00e9. Si une vid\u00e9o qui a circul\u00e9 sur les r\u00e9seaux sociaux sur les faits avait provoqu\u00e9 l\u2019\u00e9moi, le t\u00e9moignage de l\u2019un des passagers de la voiture choque. Ce dernier raconte les derniers instants de vie de Nahel aupr\u00e8s du quotidien fran\u00e7ais \u00ab&nbsp;Le Parisien&nbsp;\u00bb. &nbsp;\u00ab&nbsp;Ils sont arriv\u00e9s en courant (les policiers, NdlR). Ils nous ont dit de baisser la fen\u00eatre. Nahel a baiss\u00e9 la fen\u00eatre\u2026 Le motard qui \u00e9tait pr\u00e8s de la fen\u00eatre a dit : &lsquo;\u00c9teins le moteur !&rsquo;&nbsp;\u00bb, raconte le jeune homme sous le nom d\u2019emprunt de Fouad. \u00ab Nahel \u00e9tait paniqu\u00e9 et qu\u2019il ne savait pas quoi faire&nbsp;\u00bb, ajoute-il. \u00ab&nbsp;Il avait la t\u00eate qui tournait, il ne pouvait rien faire, m\u00eame pas parler. Il \u00e9tait vraiment traumatis\u00e9&nbsp;\u00bb, explique-t-il. Selon le m\u00eame t\u00e9moignage, les policiers auraient demand\u00e9 \u00e0 l\u2019adolescent de couper le moteur en le mena\u00e7ant de le \u201cshooter\u201d s\u2019il ne le faisait pas. \u00ab&nbsp;Je vais te mettre une balle dans la t\u00eate !&nbsp;\u00bb, aurait alors assen\u00e9 l\u2019un des policiers. Ce qui explique propos entendus dans la vid\u00e9o qui a circul\u00e9 sur les r\u00e9seaux sociaux. \u00ab&nbsp;Comme il \u00e9tait un peu sonn\u00e9, son pied s\u2019est enlev\u00e9 de la p\u00e9dale de frein. Comme la voiture, c\u2019est une automatique, elle a avanc\u00e9 toute seule. Le policier situ\u00e9 pr\u00e8s de la fen\u00eatre a dit \u00e0 son coll\u00e8gue : &lsquo;Shoote-le !&rsquo;\u2026 C\u2019est l\u00e0 que le motard qui \u00e9tait \u00e0 l\u2019avant a tir\u00e9&nbsp;\u00bb, t\u00e9moigne le jeune homme. Il explique : \u201cLe pied de Nahel s\u2019est bloqu\u00e9 sur l\u2019acc\u00e9l\u00e9rateur. Il a r\u00e9ussi \u00e0 \u00eatre l\u00e0 encore pendant trois secondes. Et, d\u2019un coup, il s\u2019est mis \u00e0 trembler. Il ne me r\u00e9pondait pas\u201d. Pris par la peur, le passager prend la fuite en laissant derri\u00e8re lui son t\u00e9l\u00e9phone qui se trouvait dans la Mercedes jaune. Le jeune devait se rendre aux autorit\u00e9s apr\u00e8s l\u2019enterrement de Nahel qui a eu lieu hier apr\u00e8s-midi. Notons qu\u2019une foule de plusieurs centaines de personnes s&rsquo;est press\u00e9e au fun\u00e9rarium de Nanterre, dans une mosqu\u00e9e de la ville puis au cimeti\u00e8re du Mont-Val\u00e9rien pour l&rsquo;enterrement de Nahel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Chokri Hafed<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nouveau t\u00e9moignage met en lumi\u00e8re ce qui s\u2019est pass\u00e9 mardi lorsqu\u2019un policier a tir\u00e9 sur bout portant sur un<\/p>\n","protected":false},"author":3,"featured_media":43181,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-43180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Un nouveau t\u00e9moignage met en lumi\u00e8re ce qui s\u2019est pass\u00e9 mardi lorsqu\u2019un policier a tir\u00e9 sur bout portant sur un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-01T20:39:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-01T20:39:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/nahel-mercedes.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture\",\"datePublished\":\"2023-07-01T20:39:03+00:00\",\"dateModified\":\"2023-07-01T20:39:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/\"},\"wordCount\":472,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/nahel-mercedes.jpeg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/\",\"name\":\"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/nahel-mercedes.jpeg\",\"datePublished\":\"2023-07-01T20:39:03+00:00\",\"dateModified\":\"2023-07-01T20:39:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/nahel-mercedes.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/nahel-mercedes.jpeg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/07\\\/01\\\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/","og_locale":"fr_FR","og_type":"article","og_title":"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture - La Sentinelle","og_description":"Un nouveau t\u00e9moignage met en lumi\u00e8re ce qui s\u2019est pass\u00e9 mardi lorsqu\u2019un policier a tir\u00e9 sur bout portant sur un","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-07-01T20:39:03+00:00","article_modified_time":"2023-07-01T20:39:04+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/nahel-mercedes.jpeg","type":"image\/jpeg"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture","datePublished":"2023-07-01T20:39:03+00:00","dateModified":"2023-07-01T20:39:04+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/"},"wordCount":472,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/nahel-mercedes.jpeg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/","name":"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/nahel-mercedes.jpeg","datePublished":"2023-07-01T20:39:03+00:00","dateModified":"2023-07-01T20:39:04+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/nahel-mercedes.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/07\/nahel-mercedes.jpeg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/07\/01\/mort-du-petit-nahel-le-temoignage-choquant-de-lun-des-passagers-de-la-voiture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Mort du petit Nahel&nbsp;: Le t\u00e9moignage choquant de l\u2019un des passagers de la voiture"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/43180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=43180"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/43180\/revisions"}],"predecessor-version":[{"id":43182,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/43180\/revisions\/43182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/43181"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=43180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=43180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=43180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}