{"id":45557,"date":"2023-09-16T20:57:36","date_gmt":"2023-09-16T19:57:36","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=45557"},"modified":"2023-09-16T20:57:39","modified_gmt":"2023-09-16T19:57:39","slug":"letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/","title":{"rendered":"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb"},"content":{"rendered":"\n<p>Le pr\u00e9sident de l\u2019Etat de Palestine, Mahmoud Abbas, a d\u00e9clar\u00e9 que le peuple palestinien, avec le soutien du Groupe des 77 +Chine, \u00ab est d\u00e9termin\u00e9 \u00e0 surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement et entrave ses aspirations depuis un si\u00e8cle \u00bb, a rapport\u00e9 l\u2019agence de presse palestinienne, WAFA. Dans un discours prononc\u00e9 lors du sommet du Groupe des 77 + Chine, tenu dans la capitale cubaine, la Havane, le pr\u00e9sident Abbas a soulign\u00e9 que les politiques de l\u2019entit\u00e9 sioniste \u00ab visent \u00e0 consolider son occupation coloniale et \u00e0 imposer la r\u00e9alit\u00e9 de l\u2019apartheid, qui ne doit pas \u00eatre tol\u00e9r\u00e9e \u00bb. Il a, en outre, a affirm\u00e9 que \u00ab la situation de d\u00e9veloppement en Palestine diff\u00e8re de celle des autres pays du monde, car elle est soumise au syst\u00e8me d\u2019apartheid institutionnel, \u00e0 l\u2019occupation (sioniste) ill\u00e9gale et au projet colonial qui nie le droit du peuple palestinien au d\u00e9veloppement \u00bb Et de poursuivre : \u00ab La puissance occupante, adopte des politiques syst\u00e9matiques visant \u00e0 saper le d\u00e9veloppement de tout un peuple \u00bb. Le pr\u00e9sident Abbas a soulign\u00e9 que \u00ab les politiques ill\u00e9gales de colonisation de nos terres, de pillage de nos richesses et de nos ressources naturelles, les punitions collectives, la d\u00e9gradation de l\u2019environnement et les restrictions de mouvement impos\u00e9es par la puissance occupante, ont conduit \u00e0 la destruction de notre \u00e9conomie \u00bb. \u00ab Au cours de ces ann\u00e9es, nous avons \u00e9t\u00e9 confront\u00e9s \u00e0 une grave crise \u00e9conomique, due \u00e0 l\u2019intransigeance (de l\u2019occupant sioniste) sur la voie politique et aux pratiques ill\u00e9gales sur le terrain \u00bb, a-t-il d\u00e9clar\u00e9, ajoutant que cette crise \u00ab pose une question morale et politique importante \u00e0 la communaut\u00e9 internationale, qui a investi politiquement et \u00e9conomiquement dans la solution \u00e0 deux Etats \u00bb. Le pr\u00e9sident Abbas a soulign\u00e9 : \u00ab ce statu quo doit cesser et que nous devons agir maintenant pour mettre fin \u00e0 l\u2019occupation (sioniste) depuis 1967 de la terre de l\u2019Etat de Palestine, avec El-Qods pour capitale, et r\u00e9soudre toutes les questions relatives au statut permanent, y compris la question des r\u00e9fugi\u00e9s palestiniens \u00bb. \u00ab Nous assurons nos partenaires du Groupe des 77 et de la Chine, que le peuple palestinien pers\u00e9v\u00e9rera et poursuivra sa lutte l\u00e9gitime pour obtenir ses droits, qui croit au caract\u00e8re in\u00e9vitable de la libert\u00e9 et de la prosp\u00e9rit\u00e9 en raison de ses sacrifices et de son engagement en faveur de la paix, ainsi que le soutien ferme d\u2019amis comme vous \u00bb a d\u00e9clar\u00e9 le pr\u00e9sident palestinien. Il a renouvel\u00e9 ses sinc\u00e8res remerciements au pr\u00e9sident cubain Miguel D\u00edaz-Canel&nbsp;&nbsp; et au peuple cubain ami, pour leur soutien aux droits du peuple palestinien dans toutes les enceintes internationales, et aux dirigeants des pays et aux chefs de d\u00e9l\u00e9gations. Le pr\u00e9sident Abbas a conclu : \u00ab Nous souhaitons le succ\u00e8s de cette conf\u00e9rence, dans l\u2019attente de pouvoir la tenir dans l\u2019Etat de Palestine, en tant qu\u2019expression de votre soutien moral et \u00e9thique \u00e0 nos droits et aspirations \u00bb.<\/p>\n\n\n\n<p>Sur le terrain, l\u2019occupation multiplie les provocations et redouble d\u2019agressivit\u00e9 envers les Palestiniens. Les forces de l\u2019occupation sioniste ont &nbsp;ainsi ferm\u00e9 la Mosqu\u00e9e Al-Ibrahimi devant les fid\u00e8les sous pr\u00e9texte de f\u00eates juives, a rapport\u00e9 l\u2019agence de presse palestinienne, WAFA. \u00ab Cette fermeture fait partie des tentatives de division temporelle et spatiale de la mosqu\u00e9e sainte, par l\u2019occupation, qui a d\u00e9j\u00e0 vol\u00e9 36% de sa superficie \u00bb, selon WAFA qui cite le directeur de la mosqu\u00e9e, Ghassan Radjbi. L\u2019occupation sioniste ferme la mosqu\u00e9e Al-Ibrahimi, 10 jours chaque ann\u00e9e, sous pr\u00e9texte de f\u00eates juives et confisque le droit de culte des fid\u00e8les palestiniens, rappelle WAFA. La Mosqu\u00e9e Al-Ibrahimi, situ\u00e9e \u00e0 al-Khalil en Cisjordanie occup\u00e9e, sera ferm\u00e9e les 16, 20, 24 et 25 septembre courant, a pr\u00e9cis\u00e9 la m\u00eame source<\/p>\n\n\n\n<p>R.I. avec agences<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de l\u2019Etat de Palestine, Mahmoud Abbas, a d\u00e9clar\u00e9 que le peuple palestinien, avec le soutien du Groupe des<\/p>\n","protected":false},"author":3,"featured_media":30045,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[37],"tags":[],"class_list":["post-45557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le pr\u00e9sident de l\u2019Etat de Palestine, Mahmoud Abbas, a d\u00e9clar\u00e9 que le peuple palestinien, avec le soutien du Groupe des\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-16T19:57:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-16T19:57:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/abbas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb\",\"datePublished\":\"2023-09-16T19:57:36+00:00\",\"dateModified\":\"2023-09-16T19:57:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/\"},\"wordCount\":668,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/abbas.png\",\"articleSection\":[\"Monde\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/\",\"name\":\"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/abbas.png\",\"datePublished\":\"2023-09-16T19:57:36+00:00\",\"dateModified\":\"2023-09-16T19:57:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/abbas.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/abbas.png\",\"width\":1800,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/09\\\/16\\\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb - La Sentinelle","og_description":"Le pr\u00e9sident de l\u2019Etat de Palestine, Mahmoud Abbas, a d\u00e9clar\u00e9 que le peuple palestinien, avec le soutien du Groupe des","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-09-16T19:57:36+00:00","article_modified_time":"2023-09-16T19:57:39+00:00","og_image":[{"width":1800,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/abbas.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb","datePublished":"2023-09-16T19:57:36+00:00","dateModified":"2023-09-16T19:57:39+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/"},"wordCount":668,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/abbas.png","articleSection":["Monde"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/","name":"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/abbas.png","datePublished":"2023-09-16T19:57:36+00:00","dateModified":"2023-09-16T19:57:39+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/abbas.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/11\/abbas.png","width":1800,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/09\/16\/letat-de-palestine-determine-a-surmonter-linjustice-historique-qui-etouffe-son-developpement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"L\u2019Etat de Palestine d\u00e9termin\u00e9 \u00e0 \u00ab surmonter l\u2019injustice historique qui \u00e9touffe son d\u00e9veloppement \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/45557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=45557"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/45557\/revisions"}],"predecessor-version":[{"id":45558,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/45557\/revisions\/45558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/30045"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=45557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=45557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=45557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}