{"id":47070,"date":"2023-11-13T22:05:29","date_gmt":"2023-11-13T21:05:29","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=47070"},"modified":"2023-11-13T22:05:31","modified_gmt":"2023-11-13T21:05:31","slug":"les-huit-defis-du-gouvernement-de-nadir-larbaoui","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/","title":{"rendered":"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Par Abderrahmane Mebtoul<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Professeur des Universit\u00e9s et expert international<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout projet social implique d&rsquo;am\u00e9liorer la situation sociale des citoyens, de concilier efficacit\u00e9 \u00e9conomique avec une profonde justice sociale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Face \u00e0 une situation g\u00e9ostrat\u00e9gique, \u00e9conomique et sociale complexe \u00e0 l\u2019horizon 2030, le nouveau gouvernement devrait axer sa strat\u00e9gie autour de huit axes directeurs, pour le redressement \u00e9conomique national, lequel suppose de mettre en place une vision strat\u00e9gique et de d\u00e9finir avec pr\u00e9cision la mise en \u0153uvre des projets : d\u00e9lais, co\u00fbts, les moyens humains et les modes de financement en devises et en dinars en incluant la protection de l\u2019environnement. C&rsquo;est que tout projet social est port\u00e9 par des partis politiques, en fonction d&rsquo;affinit\u00e9s id\u00e9ologiques et \u00e9conomiques dont le but, loin des slogans populistes, est d&rsquo;am\u00e9liorer la situation sociale des citoyens, de concilier efficacit\u00e9 \u00e9conomique avec une profonde justice sociale impliquant une \u00e9conomie forte, toute nation ne partageant que ce qu&rsquo;elle a pr\u00e9alablement produit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le premier axe est de mettre en \u0153uvre une politique s\u2019orientant vers un v\u00e9ritable processus d\u00e9mocratique, se fondant sur une soci\u00e9t\u00e9 plurielle plus participative des partis politiques cr\u00e9dibles, permettant la responsabilisation pleine et enti\u00e8re de la soci\u00e9t\u00e9 civile, signe \u00e9vident de la vitalit\u00e9 de toute soci\u00e9t\u00e9, conciliant la modernit\u00e9 et la pr\u00e9servation de notre authenticit\u00e9. La l\u00e9thargie, l\u2019activisme et le populisme conduisant au statu quo, \u00e9tant le signe de l\u2019immobilisme suicidaire, sont intol\u00e9rables. En raison des crises internes qui les secouent p\u00e9riodiquement, du discr\u00e9dit qui frappe la majorit\u00e9, les formations politiques actuelles et la majorit\u00e9 des segments de la soci\u00e9t\u00e9 civile ont aujourd&rsquo;hui une faible capacit\u00e9 de faire un travail de mobilisation et d&rsquo;encadrement efficient, de contribuer \u00e0 la socialisation politique et donc d&rsquo;apporter une contribution efficace \u00e0 l&rsquo;\u0153uvre de redressement national.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le second axe repose sur une nouvelle approche des relations tant internes qu\u2019internationales. Les ambassades d\u00e9-bureaucratis\u00e9es doivent servir d\u2019appui aux actions internes tout en \u00e9coutant \u00e0 l&rsquo;\u00e9coute de la diaspora.qui rec\u00e8le d&rsquo;importantes potentialit\u00e9s surtout scientifiques pour accompagner le pays d&rsquo;accueil $. Les relations de responsables \u00e0 Etat \u00e9tant de moins en moins efficaces, des r\u00e9seaux externes souples devraient \u00eatre cr\u00e9\u00e9s loin de tout esprit bureaucratique afin de donner une meilleure image de l\u2019Alg\u00e9rie au niveau international. Au niveau interne , la mise en place d\u2019un minimum de Smig social o\u00f9 les diff\u00e9rentes sensibilit\u00e9s puissent dialoguer dans un cadre organis\u00e9 se fondant sur la tol\u00e9rance et le droit \u00e0 la diff\u00e9rence afin de soutenir le d\u00e9veloppement par une administration centrale et locale r\u00e9nov\u00e9e, par la mutation progressive des services collectifs qui deviennent de plus en plus cr\u00e9ateurs de valeur ajout\u00e9e (\u00e9ducation, sant\u00e9, t\u00e9l\u00e9communication, transports, infrastructures), en introduisant les param\u00e8tres marchands pour tester leur efficacit\u00e9, tout en encourageant la mixit\u00e9 pour am\u00e9liorer les prestations fournies aux consommateurs<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le troisi\u00e8me axe est la refonte des institutions centrales et locales li\u00e9e \u00e0 la bonne gouvernance, li\u00e9e \u00e0 une v\u00e9ritable d\u00e9centralisation autour de six \u00e0 sept grands p\u00f4les \u00e9conomiques r\u00e9gionaux dont le pilier devra reposer sur la lutte contre la bureaucratisation de la soci\u00e9t\u00e9. Le terrorisme bureaucratise local et central enfante la sph\u00e8re informelle repr\u00e9sentant plus de 50% de la superficie \u00e9conomique hors hydrocarbures et donc la corruption dont l\u2019\u00e9radication suppose des m\u00e9canismes de r\u00e9gulation transparents pour redonner confiance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le quatri\u00e8me axe est une nouvelle politique \u00e9conomique marqu\u00e9e par l\u2019adaptation \u00e0 l\u2019universalisation de l\u2019\u00e9conomie de march\u00e9, tenant compte des sp\u00e9cificit\u00e9s sociales, o\u00f9 la dominance est le consommateur et l\u2019arbitre, les march\u00e9s financiers. Le v\u00e9ritable nationalisme se mesurera par la capacit\u00e9 des Alg\u00e9riens d\u2019am\u00e9liorer leur niveau de vie gr\u00e2ce \u00e0 leur contribution \u00e0 la valeur ajout\u00e9e locale et mondiale. Il s\u2019agira d\u2019 am\u00e9liorer le fonctionnement des march\u00e9s et des initiatives par l\u2019am\u00e9lioration du climat des affaires., avec une politique incitative d\u2019encadrement macro-\u00e9conomique et macro social solidaires, avoir une nette volont\u00e9 politique d\u2019aller vers une \u00e9conomie de march\u00e9 \u00e0 finalit\u00e9 sociale et une coh\u00e9rence dans la cr\u00e9ation des minist\u00e8res \u00e9vitant les interf\u00e9rences.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le cinqui\u00e8me axe, est la r\u00e9forme de Sonatrach lieu de production de la rente procurant avec les d\u00e9riv\u00e9es des hydrocarbures 97\/98% des ressources en devises et encore pour longtemps, ainsi que la dynamisation de la bourse des valeurs et la r\u00e9forme du syst\u00e8me financier, lieu de distribution de la rente , enjeu \u00e9norme de pouvoir ( banques, douane, fiscalit\u00e9, domaine renvoyant \u00e0 l\u2019\u00e9pineux probl\u00e8me du foncier ) avec un tableau de la valeur reli\u00e9 aux r\u00e9seaux internationaux pour d\u00e9tecter les surfacturations, avec l\u2019acc\u00e9l\u00e9ration de sa num\u00e9risation afin qu\u2019il s\u2019oriente dans la dynamisation de projets cr\u00e9ateurs de valeur ajout\u00e9e et pas seulement comme par le pass\u00e9 en favorisant l\u2019importation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le sixi\u00e8me axe est la restructuration des capitaux marchands de l\u2019Etat, d\u00e9p\u00e9naliser l\u2019acte de gestion pour permettre aux managers de prendre des risques, \u00e0 ne pas confondre avec la corruption, favoriser le partenariat public priv\u00e9, la privatisation partielle et totale, l\u2019acc\u00e9l\u00e9ration de la transition num\u00e9rique et \u00e9nerg\u00e9tique (efficacit\u00e9 \u00e9nerg\u00e9tique et \u00e9nergies renouvelables). L\u2019on devra imaginer une nouvelle politique non de l\u2019industrie, mais de l\u2019entreprise, loin des anciennes organisations hi\u00e9rarchiques bureaucratiques d\u00e9pass\u00e9es mais sur la souplesse des organisations, bas\u00e9es sur les r\u00e9seaux, gr\u00e2ce aux nouvelles technologies par la d\u00e9centralisation des d\u00e9cisions \u00e9conomiques, \u00e0 travers la gestion pr\u00e9visionnelle des comp\u00e9tences et le travail en groupes. Cette politique devra s\u2019inscrire dans le cadre de la dynamisation des projets structurants , si ils sont mis en \u0153uvre fin 2023, d\u00e9but 2024, pour les PMI\/PME, la rentabilit\u00e9 ne se fera pas avant trois ann\u00e9es et pour les grands projets pas avant 7\/8 ans, le temps ne se rattrapant jamais en \u00e9conomie<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le septi\u00e8me axe est de garantir un minimum de s\u00e9curit\u00e9 alimentaire, une nouvelle politique agricole ax\u00e9e sur la mise en valeur des terres et des hauts plateaux du Sud, renvoyant au foncier agricole. L\u2019Alg\u00e9rie \u00e9tant un pays semi-aride, une nouvelle politique de l\u2019eau par une lutte contre les fuites dans les canalisations, le recyclage des eaux us\u00e9es , une nouvelle politique des prix, renvoyant aux subventions, d\u00e9velopper le goutte \u00e0 goutte dans l\u2019agriculture, le d\u00e9vasement des barrages par un entretien r\u00e9gulier et l\u2019acc\u00e9l\u00e9ration de la construction d\u2019unit\u00e9s de dessalement de l\u2019eau de mer, \u00e9tant pr\u00e9vu par l\u2019ONU ; une s\u00e9cheresse en Afrique du Nord entre 2025\/2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le huiti\u00e8me axe, qui est le fondement du synth\u00e8se du tout est de : favoriser le primat de la connaissance, une Nation sans son \u00e9lite \u00e9tant comme un corps sans \u00e2me et une nouvelle politique de l\u2019emploi renvoyant \u00e0 une nouvelle politique de formation adapt\u00e9e aux nouvelles technologies, r\u00e9duire les in\u00e9galit\u00e9s sociales et revoir le syst\u00e8me fiscal par la combinaison de l\u2019\u00e9quit\u00e9 verticale et horizontale. Il s\u2019agit de revoir la politique des subventions cibl\u00e9es inter socioprofessionnelle et inter r\u00e9gionale<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conclusion, il faut si l\u2019on veut mobiliser la population et redonner confiance , en \u00e9vitant la sinistrose gratuite, les d\u00e9fis pour l\u2019Alg\u00e9rie sont une v\u00e9ritable strat\u00e9gie d\u2019adaptation pour une rapide relance \u00e9conomique en ce monde turbulent et instable, supposant de profondes r\u00e9formes afin de favoriser le d\u00e9veloppement durable et faire de l\u2019Alg\u00e9rie un pays pivot, r\u00e9gional, elle en a les potentialit\u00e9s. Faute de quoi ,il y a risque de r\u00e9gression tant dans le domaine \u00e9conomique, social, avec de graves incidences internes s\u00e9curitaires et g\u00e9ostrat\u00e9giques au niveau de la r\u00e9gion africaine et m\u00e9diterran\u00e9enne, que nul patriote ne souhaite .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Abderrahmane Mebtoul Professeur des Universit\u00e9s et expert international Tout projet social implique d&rsquo;am\u00e9liorer la situation sociale des citoyens, de<\/p>\n","protected":false},"author":3,"featured_media":7876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[56,38],"tags":[],"class_list":["post-47070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contribution","category-debats"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les huit d\u00e9fis du gouvernement de Nadir Larbaoui - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Par Abderrahmane Mebtoul Professeur des Universit\u00e9s et expert international Tout projet social implique d&rsquo;am\u00e9liorer la situation sociale des citoyens, de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-13T21:05:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T21:05:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui\",\"datePublished\":\"2023-11-13T21:05:29+00:00\",\"dateModified\":\"2023-11-13T21:05:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/\"},\"wordCount\":1367,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"articleSection\":[\"Contribution\",\"D\u00e9bats\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/\",\"name\":\"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"datePublished\":\"2023-11-13T21:05:29+00:00\",\"dateModified\":\"2023-11-13T21:05:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/11\\\/13\\\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/","og_locale":"fr_FR","og_type":"article","og_title":"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui - La Sentinelle","og_description":"Par Abderrahmane Mebtoul Professeur des Universit\u00e9s et expert international Tout projet social implique d&rsquo;am\u00e9liorer la situation sociale des citoyens, de","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-11-13T21:05:29+00:00","article_modified_time":"2023-11-13T21:05:31+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui","datePublished":"2023-11-13T21:05:29+00:00","dateModified":"2023-11-13T21:05:31+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/"},"wordCount":1367,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","articleSection":["Contribution","D\u00e9bats"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/","name":"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","datePublished":"2023-11-13T21:05:29+00:00","dateModified":"2023-11-13T21:05:31+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/11\/13\/les-huit-defis-du-gouvernement-de-nadir-larbaoui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Les huit d\u00e9fis du gouvernement de Nadir Larbaoui"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/47070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=47070"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/47070\/revisions"}],"predecessor-version":[{"id":47071,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/47070\/revisions\/47071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/7876"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=47070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=47070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=47070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}