{"id":48174,"date":"2023-12-22T20:08:56","date_gmt":"2023-12-22T19:08:56","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=48174"},"modified":"2023-12-22T20:08:58","modified_gmt":"2023-12-22T19:08:58","slug":"60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/","title":{"rendered":"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Par Abderrahmane Mebtoul<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Professeur des universit\u00e9s<\/strong><strong>, expert international <\/strong><strong>et ancien directeur d<\/strong><strong>e \u00e9tudes <\/strong><strong>au minist\u00e8re<\/strong><strong> de l\u2019\u00c9nergie <\/strong><strong>et \u00e0 la Sonatrach<\/strong><strong>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9cente orientation du gouvernement alg\u00e9rien concernant l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique est une prise de conscience de la mise en place d\u2019un nouveau mod\u00e8le de consommation \u00e9nerg\u00e9tique et d\u2019un nouveau management strat\u00e9gique de Sonatrach . Car le monde conna\u00eetra \u00e0 l\u2019horizon 2024\/2030\/2035, un profond bouleversement de la carte \u00e9nerg\u00e9tique et du pouvoir \u00e0 l\u2019\u00e9chelle mondiale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019Alg\u00e9rie n\u2019\u00e9chappe pas \u00e0 ces nouvelles mutations, les changements \u00e9conomiques survenus depuis quelques ann\u00e9es dans le monde avec la r\u00e9volution du num\u00e9rique, ainsi que ceux qui sont appel\u00e9s \u00e0 se produire dans un proche avenir, doivent n\u00e9cessairement trouver leur traduction dans des changements d\u2019ordre syst\u00e9mique destin\u00e9s \u00e0 les prendre en charge et \u00e0 organiser leur insertion dans un ordre social qui est lui-m\u00eame en devenir. D\u2019o\u00f9 l\u2019urgence de revoir le mod\u00e8le de consommation \u00e9nerg\u00e9tique afin de s\u2019adapter aux nouvelles mutations et d\u2019asseoir dans les faits les \u00e9nergies renouvelables repr\u00e9sentant en 2023, moins de 2% de la consommation int\u00e9rieure. D\u2019o\u00f9 l\u2019importance de l\u2019acc\u00e9l\u00e9ration de la transition \u00e9nerg\u00e9tique devant nous orienter vers plus de sobri\u00e9t\u00e9 \u00e9nerg\u00e9tique ( efficacit\u00e9 \u00e9nerg\u00e9tique) vers un MIX \u00e9nerg\u00e9tique combinant hydrocarbures traditionnels et \u00e9nergies renouvelables dont le solaire et l\u2019hydrog\u00e8ne vert. Cependant, il ne faut pas \u00eatre utopique. Sonatrach repr\u00e9sentera encore pour longtemps, fonction de profondes r\u00e9formes structurelles, l\u2019essentiel des ressources en devises d\u2019o\u00f9 l\u2019importance d\u2019un nouveau management strat\u00e9gique de Sonatrach qui en cette fin du mois de d\u00e9cembre 2023 procure avec les d\u00e9riv\u00e9es inclus dans la rubrique hors hydrocarbures environ 98% des recettes de l\u2019Alg\u00e9rie avec les d\u00e9riv\u00e9es inclus pour 67% dans la rubrique hors hydrocarbures .Ainsi en cette fin de l\u2019ann\u00e9e 2023 l\u2019Alg\u00e9rie, c\u2019est Sonatrach et Sonatrach c\u2019est l\u2019Alg\u00e9rie, o\u00f9 sur le plan \u00e9conomique apr\u00e8s plusieurs d\u00e9cennies d\u2019ind\u00e9pendance politique, Sonatrach est l\u2019un des puissants leviers de la souverainet\u00e9 nationale d\u2019o\u00f9 l\u2019importance d\u2019am\u00e9liorer son management strat\u00e9gique, dans la mesure o\u00f9 dans plusieurs audits men\u00e9s sous ma direction durant ces quarante derni\u00e8res ann\u00e9es, assist\u00e9 des cadres dirigeants du minist\u00e8re de l\u2019\u00c9nergie, de Sonatrach et d\u2019experts ind\u00e9pendants, il nous a \u00e9t\u00e9 difficile de cerner avec exactitude les co\u00fbts de production de ses diff\u00e9rentes structures. D\u2019o\u00f9 l\u2019impossibilit\u00e9 pour cette soci\u00e9t\u00e9 qui irrigue indirectement \u00e0 travers la d\u00e9pense publique toute la soci\u00e9t\u00e9, de se porter en bourse \u00e0 l\u2019instar d\u2019une grande soci\u00e9t\u00e9 comme Gazprom ou d\u2019autres compagnies internationales. Sonatrach est soumise \u00e0 des contraintes majeures qu\u2019il s\u2019agit de lever. Je propose 12 actions interd\u00e9pendantes pour am\u00e9liorer la gestion de Sonatrach \u00e9tant une question de s\u00e9curit\u00e9 nationale (voir notre intervention au Forum mondial du d\u00e9veloppement durable, Paris 13 mars 2017, sur les axes de la transition \u00e9nerg\u00e9tique de l\u2019Alg\u00e9rie face aux nouvelles mutations mondiales).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1.-Diagnostiquer l\u2019impact de l\u2019environnement national et international sur Sonatrach et l\u2019appr\u00e9ciation des domaines o\u00f9 l\u2019interface Sonatrach\/ environnement peut \u00eatre am\u00e9lior\u00e9e afin de rendre plus performante l\u2019entreprise et la hisser au niveau de la concurrence mondiale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2-. Mettre en place un audit financier interne s\u00e9rieux avec des experts ind\u00e9pendants qui devrait permettre d\u2019identifier les gisements de productivit\u00e9 et les niches de gains de co\u00fbts (comparaison avec des compagnies tests)- volume, rentabilit\u00e9 et analyser la strat\u00e9gie des principales institutions similaires dans le monde sur les plans : technologie \u2013 standards et normes- sous-traitance afin de r\u00e9duire les co\u00fbts et d\u2019avoir une strat\u00e9gie agressive, afin de prendre des parts du march\u00e9. L\u2019objectif est d\u2019optimiser les conditions de mise en \u0153uvre des options strat\u00e9giques dans un environnement international de plus en plus concurrentiel. Je propose 19 actions interd\u00e9pendantes ( voir notre intervention au Forum mondial du d\u00e9veloppement durable Paris 13 mars 2017 sur les axes de la transition \u00e9nerg\u00e9tique de l\u2019Alg\u00e9rie et notre contribution \u00e0 HEC Montr\u00e9al 2012 pour un nouveau management strat\u00e9gique de Sonatrach).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3-. Analyser les circuits banques primaire- Banque centrale -Sonatrach pour les conditions de paiement, afin d\u2019acc\u00e9l\u00e9rer la rapidit\u00e9 des op\u00e9rations, o\u00f9 actuellement les proc\u00e9dures bureaucratiques nuisent \u00e0 la prise de d\u00e9cision qui doit se faire en temps r\u00e9el, ainsi que les structures d\u2019appui techniques et de formation, l\u2019identification de la strat\u00e9gie des entreprises concurrentes et des institutions internationales et leurs facteurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4-. Mettre en \u0153uvre un mod\u00e8le de simulation qui doit aboutir \u00e0 plusieurs variantes en fonction des param\u00e8tres et variables, fonction de contraintes qu\u2019il s\u2019agira d\u2019\u00e9liminer pour \u00e9viter des effets pervers. Ce mod\u00e8le doit prendre en compte le niveau des r\u00e9serves d\u2019hydrocarbures, fonction du vecteur prix international, du co\u00fbt d\u2019exploitation, de la dur\u00e9e de vie du gisement, des d\u00e9couvertes technologiques et des \u00e9nergies substituables. Cela permettra d\u2019identifier chaque action, de d\u00e9crire le contenu, d\u2019\u00e9valuer les moyens, les d\u00e9lais, les co\u00fbts associ\u00e9s \u00e0 l\u2019action, v\u00e9rifier le niveau de gain attendu \u00e9ventuel, r\u00e9diger une fiche descriptive de chaque action accompagn\u00e9e d\u2019un tableau r\u00e9capitulatif des moyens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5-. Au niveau de la gestion interne, fixer les objectifs d\u2019am\u00e9lioration des performances reli\u00e9s \u00e0 chaque fonction ou \u00e0 chaque syst\u00e8me de gestion, selon une d\u00e9marche descendante et en v\u00e9rifier le r\u00e9alisme (ratios, contexte), v\u00e9rifier qu\u2019\u00e0 chaque objectif fix\u00e9 peuvent \u00eatre associ\u00e9s des indicateurs de performance faciles \u00e0 mettre en \u0153uvre et \u00e9valuer l\u2019ordre de grandeur des impacts attendus (gains, qualit\u00e9, d\u00e9lais, co\u00fbt\u2026), selon une d\u00e9marche ascendante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6-. Pr\u00e9parer un audit op\u00e9rationnel du patrimoine existant, en le r\u00e9actualisant \u00e0 la valeur du march\u00e9 ce qui implique la mise en place d\u2019une comptabilit\u00e9 transparente li\u00e9e \u00e0 la nouvelle organisation de Sonatrach pour r\u00e9duire les co\u00fbts et, notamment un audit des immobilisations corporelles et incorporelles. Ces immobilisations sont souvent trait\u00e9es d\u2019une mani\u00e8re superficielle, alors qu\u2019elles sont d\u00e9terminantes pour une entreprise comparable \u00e0 Sonatrach, ce qui renvoie d\u2019ailleurs au n\u00e9cessaire renouveau du Plan comptable national.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7-. \u00c9valuer le degr\u00e9 de comp\u00e9titivit\u00e9 des outils, \u00e9quipements et immobilisations utilis\u00e9s dans le contexte d\u2019\u00e9volution technologique international. Cette op\u00e9ration d\u2019audit consistera \u00e0 rassembler l\u2019information sur les caract\u00e9ristiques techniques, et les conditions de fonctionnement des \u00e9quipements et de gestion des immobilisations, \u00e9valuer ses \u00e9quipements et immobilisations corporelles et incorporelles, le niveau des stocks dormants, (objectif stock z\u00e9ro) supposant de conna\u00eetre le niveau d\u2019automatisation, le niveau de performance, les besoins de maintenance non satisfaits et enfin la comp\u00e9tence du personnel utilisateur. Cela permettra d\u2019analyser les forces et les faiblesses technologiques des \u00e9quipements, les alternatives strat\u00e9giques sur les programmes d\u2019investissements, le besoin de formations techniques et d\u2019acquisitions de savoir-faire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8-. Concentrer le d\u00e9veloppement de Sonatrach en amont qu\u2019en aval \u2013 noyau dur de l\u2019entreprise, \u00e9vitant la dispersion, en se sp\u00e9cialisant dans ses m\u00e9tiers de base. Pour les autres activit\u00e9s existantes, comme le raffinage, le transport, la transformation et la distribution, seuls les audits pourront tracer les actions concr\u00e8tes \u00e0 mener en envisageant soit d\u2019internaliser l\u2019activit\u00e9, soit de l\u2019externaliser avec une priorit\u00e9 au profit des cadres et travailleurs du secteur de certaines activit\u00e9s ou le partenariat afin d\u2019\u00e9viter la dispersion source de gaspillage des ressources et d\u2019inefficience de l\u2019entreprise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9-. Sur le plan organisationnel, \u00e9valuer l\u2019efficacit\u00e9 de la structuration actuelle en fonction des axes strat\u00e9giques de Sonatrach, mettre en place des structures organisationnelles plus adapt\u00e9es \u00e0 ses missions et \u00e9valuer les syst\u00e8mes d\u2019information en temps r\u00e9el quant \u00e0 leur efficacit\u00e9 sur le plan d\u00e9lai, co\u00fbt et atteinte des objectifs. Et ce, afin de d\u00e9terminer le test d\u2019efficacit\u00e9 des structures et organigrammes existants, de leur compatibilit\u00e9 avec les contraintes existantes, l\u2019\u00e9valuation des circuits et analyser les supports d\u2019information de gestion, afin de raccourcir les d\u00e9lais source de surco\u00fbts et des propositions concr\u00e8tes pour am\u00e9liorer l\u2019organisation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10-. Revoir le syst\u00e8me comptable, pour plus de transparence. Sonatrach, bien qu\u2019il existe une direction de l\u2019audit au niveau de la direction g\u00e9n\u00e9rale, \u00e9tablit souvent un bilan consolid\u00e9 o\u00f9 l\u2019on ne cerne pas correctement les centres de co\u00fbts, du fait de ce que les \u00e9conomistes appellent les comptes de transfert, pouvant voiler la mauvaise gestion d\u2019une division. Aussi faute de comptes physico-financiers \u00e0 prix constants, les ratios de gestion sont d\u2019une signification limit\u00e9e pour appr\u00e9cier la performance. D\u2019o\u00f9 l\u2019urgence de mettre en place des comptabilit\u00e9s analytiques, afin de discerner les centres de co\u00fbts en temps r\u00e9el et de mieux adapter les structures organisationnelles \u00e0 la mission et aux contraintes de Sonatrach.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11-. Analyser l\u2019ensemble des r\u00e8gles juridiques influen\u00e7ant le secteur \u00e9nerg\u00e9tique (environnement l\u00e9gal et institutions publiques), afin de permettre une gestion transparente des co\u00fbts et des contrats. Cela suppose la mise en place d\u2019une formation pointue et d\u2019 instruments adapt\u00e9s aux normes internationales, ce qui devrait permettre des \u00e9conomies, de d\u00e9velopper le partenariat dans la transparence, de mieux d\u00e9finir les projections \u00e9conomiques et financi\u00e8res et permettre les pr\u00e9visions par la simulation \/ mod\u00e9lisation et donc aider \u00e0 la prise de d\u00e9cision en temps r\u00e9el, afin d\u2019\u00e9viter les nombreux litiges qui se chiffrent en dizaines de millions de dollars.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12-. Pilier de Sonatrach, un audit de la gestion des ressources humaines qui est le fondement de l\u2019efficacit\u00e9 de Sonatrach, reposant sur le dialogue permanent avec le collectif des cadres et travailleurs et le renforcement des liens- centre de recherche -universit\u00e9, Sonatrach (voir la d\u00e9cision 312\/DG du 31 juillet 2021, 89 articles 96 pages), concernant les nouvelles modalit\u00e9s de passation des contrats qui accorde la priorit\u00e9 aux secteurs nationaux \u00e0.. Car force est de reconna\u00eetre que seulement pour le poste de services au niveau de la balance des paiements, (appel aux comp\u00e9tences \u00e9trang\u00e8res, posant la probl\u00e9matique de l\u2019exode des cerveaux), a \u00e9t\u00e9 entre 2010\/2019 entre 10\/11 milliards de dollars de sorties de devises par an et entre 2021\/2022, selon la Banque Mondiale de 6 milliards de dollars, une grande fraction \u00e9tant largement accapar\u00e9e par Sonatrach. La performance des ressources humaines, repose sur une formation permanente, ce qui implique un audit mettant en relief nettement la typologie du personnel existant, l\u2019ad\u00e9quation de la formation aux besoins de Sonatrach, la disponibilit\u00e9 des comp\u00e9tences ad\u00e9quates, les politiques de recrutement, l\u2019\u00e9volution de la productivit\u00e9 du travail, les appr\u00e9ciations des mesures d\u2019incitation et enfin, l\u2019\u00e9valuation du climat et de la culture d\u2019entreprise de Sonatrach (audit social et audit de la culture), dont la prise en compte d\u2019une gestion plus rationnelle des importantes sommes des \u0153uvres sociales que consacre, annuellement, Sonatrach.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9sum\u00e9, la nouvelle strat\u00e9gie \u00e9nerg\u00e9tique est ins\u00e9parable d\u2019une vision strat\u00e9gique globale tenant compte des nouvelles mutations tant internes que mondiales. C\u2019est \u00e0 ce titre que la lutte contre la bureaucratie est une priorit\u00e9 du redressement national, la bureaucratie bloquant les \u00e9nergies cr\u00e9atrices donc le d\u00e9veloppement, favorisant les d\u00e9lits d\u2019initi\u00e9s, dont les surfacturations en devises et en dinars&nbsp;? Cela renvoie \u00e0 l\u2019imp\u00e9rative bonne gouvernance condition de la relance de l\u2019\u00e9conomie nationale et et de la garantie de la n\u00e9cessaire coh\u00e9sion sociale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A.M.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Abderrahmane Mebtoul Professeur des universit\u00e9s, expert international et ancien directeur de \u00e9tudes au minist\u00e8re de l\u2019\u00c9nergie et \u00e0 la<\/p>\n","protected":false},"author":3,"featured_media":33165,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[56,38],"tags":[],"class_list":["post-48174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contribution","category-debats"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Par Abderrahmane Mebtoul Professeur des universit\u00e9s, expert international et ancien directeur de \u00e9tudes au minist\u00e8re de l\u2019\u00c9nergie et \u00e0 la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-22T19:08:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-22T19:08:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1349\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique\",\"datePublished\":\"2023-12-22T19:08:56+00:00\",\"dateModified\":\"2023-12-22T19:08:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/\"},\"wordCount\":1993,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"articleSection\":[\"Contribution\",\"D\u00e9bats\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/\",\"name\":\"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"datePublished\":\"2023-12-22T19:08:56+00:00\",\"dateModified\":\"2023-12-22T19:08:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"width\":1349,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2023\\\/12\\\/22\\\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/","og_locale":"fr_FR","og_type":"article","og_title":"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique - La Sentinelle","og_description":"Par Abderrahmane Mebtoul Professeur des universit\u00e9s, expert international et ancien directeur de \u00e9tudes au minist\u00e8re de l\u2019\u00c9nergie et \u00e0 la","og_url":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2023-12-22T19:08:56+00:00","article_modified_time":"2023-12-22T19:08:58+00:00","og_image":[{"width":1349,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique","datePublished":"2023-12-22T19:08:56+00:00","dateModified":"2023-12-22T19:08:58+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/"},"wordCount":1993,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","articleSection":["Contribution","D\u00e9bats"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/","url":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/","name":"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","datePublished":"2023-12-22T19:08:56+00:00","dateModified":"2023-12-22T19:08:58+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","width":1349,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2023\/12\/22\/60e-anniversaire-de-sonatrach-pour-un-nouveau-management-strategique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"60e anniversaire de Sonatrach\u00a0: Pour un nouveau management strat\u00e9gique"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/48174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=48174"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/48174\/revisions"}],"predecessor-version":[{"id":48175,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/48174\/revisions\/48175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/33165"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=48174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=48174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=48174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}