{"id":48984,"date":"2024-01-25T11:59:00","date_gmt":"2024-01-25T10:59:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=48984"},"modified":"2024-01-27T12:03:44","modified_gmt":"2024-01-27T11:03:44","slug":"attaf-la-communaute-internationale-face-a-trois-defis-majeurs","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/","title":{"rendered":"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La situation en Palestine occup\u00e9e et en particulier dans le Bande de Ghaza qui subit une agression sans commune mesure par l\u2019occupant sioniste depuis le 7 octobre a \u00e9t\u00e9 mardi au c\u0153ur d\u2019une r\u00e9union du Conseil de s\u00e9curit\u00e9. A l\u2019occasion, l\u2019Alg\u00e9rie qui si\u00e8ge au Conseil de s\u00e9curit\u00e9, en tant que membre non-permanent a insist\u00e9 sur la n\u00e9cessit\u00e9 d\u2019un r\u00e8glement rapide, \u00e9quitable et inclusif du conflit en Palestine, de m\u00eame qu\u2019elle a soulign\u00e9 la n\u00e9cessit\u00e9 d\u2019imposer des garde-fous juridiques \u00e0 l\u2019occupation. Lors de cette r\u00e9union tenue au niveau des ministres des Affaires \u00e9trang\u00e8res, le chef de la diplomatie alg\u00e9rienne, Ahmed Attaf a r\u00e9affirm\u00e9 la revendication historique de l\u2019Alg\u00e9rie de tenir une Conf\u00e9rence internationale pour la paix, sous l&rsquo;\u00e9gide des Nations unies, o\u00f9 il sera convenu de mettre fin au conflit arabo-isra\u00e9lien de mani\u00e8re d\u00e9finitive, conform\u00e9ment aux r\u00e9solutions de la L\u00e9galit\u00e9 internationale, et de mettre en \u0153uvre de la solution \u00e0 deux Etat \u00ab\u00a0sous la surveillance rigoureuse, le suivi \u00e9troit et la garantie s\u00fbre\u00a0\u00bb de la Communaut\u00e9 internationale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Ce qui se passe, aujourd&rsquo;hui, \u00e0 Ghaza nous interpelle plus que jamais quant \u00e0 l&rsquo;imp\u00e9ratif d&rsquo;acc\u00e9l\u00e9rer le traitement de l&rsquo;essence de ce conflit, \u00e0 travers le renouvellement et l&rsquo;activation de notre engagement collectif en faveur de la solution \u00e0 deux Etats, appuy\u00e9e par la Communaut\u00e9 internationale comme r\u00e8glement juste, viable et d\u00e9finitif\u00a0\u00bb, a affirm\u00e9 M. Attaf. A ce propos, le ministre des Affaires \u00e9trang\u00e8res a appel\u00e9 l&rsquo;ONU et le Conseil de s\u00e9curit\u00e9 \u00e0 \u00ab\u00a0r\u00e9pondre avec fermet\u00e9 aux voix isra\u00e9liennes qui clament haut et fort leur rejet de cette solution et aux positions qui font fi du consensus international et d\u00e9n\u00e9grent la L\u00e9galit\u00e9 internationale\u00a0\u00bb . \u00ab\u00a0Nous sommes appel\u00e9s, en ces heures d\u00e9cisives, \u00e0 contrer les illusions dont se nourrit l&rsquo;occupant isra\u00e9lien colonialiste pour renforcer sa s\u00e9curit\u00e9 en an\u00e9antissant le projet national palestinien\u00a0\u00bb, a soutenu le ministre. \u00ab\u00a0Nous nous devons aussi de contrecarrer les campagnes de confiscation et d&rsquo;annexion des terres palestiniennes, et d&rsquo;implantation et d&rsquo;expansion de colonies isra\u00e9liennes, dans une tentative d&#8217;emp\u00eacher l&rsquo;\u00e9tablissement d&rsquo;un Etat de Palestine ind\u00e9pendant et souverain\u00a0\u00bb.M. Attaf a \u00e9galement soulign\u00e9 qu'\u00a0\u00bbil est tout aussi imp\u00e9ratif de r\u00e9primer l&rsquo;imp\u00e9tuosit\u00e9 de l&rsquo;occupant et ses illusions quant au ressuscitement du projet du +Grand Isra\u00ebl+ sur les cendres et les d\u00e9combres du projet national palestinien\u00a0\u00bb. &nbsp;Attaf a affirm\u00e9 que \u00ab\u00a0la priorit\u00e9 majeure est au cessez-le-feu dont les atermoiements pour sa mise en \u0153uvre sont fustig\u00e9s de jour en jour, tout comme sont critiqu\u00e9s les pr\u00e9textes r\u00e9futables avanc\u00e9s pour justifier ces lenteurs\u00a0\u00bb. \u00a0\u00bb Face \u00e0 la poursuite des agressions et au \u00ab\u00a0blocage\u00a0\u00bb des perspectives d&rsquo;amener l&rsquo;occupant ennemi \u00e0 y mettre un terme, le ministre a estim\u00e9 que \u00ab\u00a0la Communaut\u00e9 internationale est devant trois d\u00e9fis majeurs: le premier consiste \u00e0 imposer le respect des r\u00e9solutions et lois d\u00e9cid\u00e9es en son nom et faire preuve d&rsquo;intransigeance face aux&nbsp; violations flagrantes de ses d\u00e9cisions, en vue de garantir un vivre-ensemble pacifique, civilisationnel et civilis\u00e9 entre ses membres\u00a0\u00bb. Pour le second d\u00e9fi, il s&rsquo;agit de \u00ab\u00a0ne pas admettre qu&rsquo;un des membres &nbsp;s&rsquo;arroge le droit de se placer au-dessus de tous et b\u00e9n\u00e9ficie d&rsquo;un traitement sur mesure, riche de d\u00e9rogations, de s\u00e9lections, de privil\u00e8ges et d&rsquo;immunit\u00e9 indus et inadmissibles\u00a0\u00bb, a-t-il ajout\u00e9. &nbsp;Le troisi\u00e8me d\u00e9fi consiste, quant \u00e0 lui, \u00e0 \u00ab\u00a0soumettre l&rsquo;occupation isra\u00e9lienne colonialiste aux garde-fous juridiques internationaux et mettre fin, avec rigueur et fermet\u00e9, \u00e0 ce qui est commun\u00e9ment appel\u00e9 +impunit\u00e9 et non reddition de comptes+\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ce sens, l&rsquo;Alg\u00e9rie salue \u00ab\u00a0hautement\u00a0\u00bb les pr\u00e9mices des \u00e9carts vis-\u00e0-vis de ces traitements privil\u00e9gi\u00e9s, qu&rsquo;on entrevoit \u00e0 travers des initiatives \u00ab\u00a0nobles, courageuses et audacieuses\u00a0\u00bb visant \u00e0 amener l&rsquo;occupant \u00e0 assumer ses responsabilit\u00e9s, a affirm\u00e9 M. Attaf qui a rappel\u00e9 l&rsquo;initiative du Pr\u00e9sident Tebboune portant mobilisation des experts juridiques et organisations juridiques internationales en vue de poursuivre l&rsquo;entit\u00e9 sioniste en justice devant les instances internationales, pour mettre un terme \u00e0 des d\u00e9cennies d&rsquo;impunit\u00e9 et de non reddition de comptes dont jouit cette entit\u00e9, ainsi que l&rsquo;initiative de l&rsquo;Afrique du Sud d&rsquo;intenter une action en justice contre l&rsquo;occupant devant la Cour internationale de justice (CIJ) pour g\u00e9nocide contre Ghaza. &nbsp;Le ministre a, en outre, rappel\u00e9 l&rsquo;initiative du Chili et du Mexique de saisir la Cour p\u00e9nale internationale (CPI) pour des crimes multiformes auxquels s&rsquo;est livr\u00e9e et se livre l&rsquo;agresseur sioniste contre la bande de Ghaza, soulignant que \u00ab\u00a0ces initiatives sont dignes de soutien et d&rsquo;encouragement, car constituant des d\u00e9marches judicieuses sur la voie de la raison\u00a0\u00bb. &nbsp;\u00ab\u00a0L&rsquo;Alg\u00e9rie qui exhorte ces instances judiciaires internationales \u00e0 s&rsquo;acquitter pleinement de leurs responsabilit\u00e9s et obligations juridiques, souligne l&rsquo;imp\u00e9ratif de s&rsquo;acquitter des responsabilit\u00e9s politiques et s\u00e9curitaires qui incombent au Conseil de s\u00e9curit\u00e9, en sa qualit\u00e9 de premi\u00e8re instance garante et gardienne de la paix et de la s\u00e9curit\u00e9 internationales\u00a0\u00bb, a-t-il poursuivi, r\u00e9it\u00e9rant l&rsquo;appel de l&rsquo;Alg\u00e9rie \u00e0 l&rsquo;octroi \u00e0 l&rsquo;Etat de Palestine la qualit\u00e9 de membre \u00e0 part enti\u00e8re \u00e0 l&rsquo;Organisation des Nations unies, \u00ab\u00a0une demande appuy\u00e9e par le Mouvement des Non-align\u00e9s \u00e0 l&rsquo;occasion de leur dernier Sommet, en tant que mesure urgente \u00e0 m\u00eame de consacrer les fondements essentiels de la solution \u00e0 deux Etats et en tant que pas incontournable de pr\u00e9servation des fondements juridiques de l&rsquo;\u00e9dification de l&rsquo;Etat de Palestine ind\u00e9pendant et souverain sur les fronti\u00e8res de 1967, avec Al-Qods pour capitale. \u00ab\u00a0A l&rsquo;heure qu&rsquo;il est, on ne peut plus faire marche arri\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hocine Fadheli<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La situation en Palestine occup\u00e9e et en particulier dans le Bande de Ghaza qui subit une agression sans commune mesure<\/p>\n","protected":false},"author":3,"featured_media":48985,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-48984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La situation en Palestine occup\u00e9e et en particulier dans le Bande de Ghaza qui subit une agression sans commune mesure\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-25T10:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-27T11:03:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/attaf.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1446\" \/>\n\t<meta property=\"og:image:height\" content=\"872\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb\",\"datePublished\":\"2024-01-25T10:59:00+00:00\",\"dateModified\":\"2024-01-27T11:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/\"},\"wordCount\":1016,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/attaf.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/\",\"name\":\"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/attaf.png\",\"datePublished\":\"2024-01-25T10:59:00+00:00\",\"dateModified\":\"2024-01-27T11:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/attaf.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/attaf.png\",\"width\":1446,\"height\":872},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/25\\\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/","og_locale":"fr_FR","og_type":"article","og_title":"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb - La Sentinelle","og_description":"La situation en Palestine occup\u00e9e et en particulier dans le Bande de Ghaza qui subit une agression sans commune mesure","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-01-25T10:59:00+00:00","article_modified_time":"2024-01-27T11:03:44+00:00","og_image":[{"width":1446,"height":872,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/attaf.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb","datePublished":"2024-01-25T10:59:00+00:00","dateModified":"2024-01-27T11:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/"},"wordCount":1016,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/attaf.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/","name":"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/attaf.png","datePublished":"2024-01-25T10:59:00+00:00","dateModified":"2024-01-27T11:03:44+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/attaf.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/attaf.png","width":1446,"height":872},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/25\/attaf-la-communaute-internationale-face-a-trois-defis-majeurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Attaf\u00a0: \u00ab La communaut\u00e9 internationale face \u00e0 trois d\u00e9fis majeurs\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/48984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=48984"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/48984\/revisions"}],"predecessor-version":[{"id":48986,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/48984\/revisions\/48986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/48985"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=48984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=48984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=48984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}