{"id":49045,"date":"2024-01-29T15:01:30","date_gmt":"2024-01-29T14:01:30","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=49045"},"modified":"2024-01-29T15:01:33","modified_gmt":"2024-01-29T14:01:33","slug":"sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/","title":{"rendered":"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie"},"content":{"rendered":"\n<p><strong>Par Abderrahmane Mebtoul<\/strong><\/p>\n\n\n\n<p><strong>Professeur des universit\u00e9s<\/strong><strong> et expert international<\/strong><strong>.<\/strong><\/p>\n\n\n\n<p>Nous nous orientons vers un monde multipolaire sur fond de tensions g\u00e9ostrat\u00e9giques et de nouvelles mutations mondiales qui annoncent un profond bouleversement.<\/p>\n\n\n\n<p>L\u2019Afrique est, en ce XXI\u00e8me si\u00e8cle, le continent de tous enjeux et des rivalit\u00e9s des grandes puissances et des nations \u00e9mergentes. Apr\u00e8s les sommets USA\/Afrique, Chine \/Afrique, Europe\/Afrique, Russie\/ Afrique , Turquie \/Afrique, Japon\/ Afrique et bien d\u2019autres rencontres internationales similaires, se tiendra le Sommet Italie-Afrique, l\u2019Italie \u00e9tantun des pays les plus touch\u00e9 par les flux migratoires, les 28 et 29 janvier \u00e0 Rome, afin d\u2019intensifier la de coop\u00e9ration autour d\u2019un ambitieux programme d\u2019investissements ax\u00e9 sur les \u00e9changes \u00e9conomiques avec le continent africain, appel\u00e9 \u00abplan Mattei pour l\u2019Afrique\u00bb, en pr\u00e9sence de la pr\u00e9sidente de la commission europ\u00e9enne, du pr\u00e9sident du Conseil europ\u00e9en, de la cheffe du FMI, du directeur g\u00e9n\u00e9ral de la FAO, de responsables des principales agences des Nations unies et chefs d\u2019Etat africains, de chefs de gouvernement et des ministres des affaires \u00e9trang\u00e8res. L\u2019Alg\u00e9rie y sera repr\u00e9sent\u00e9e par le ministre des Affaires \u00e9trang\u00e8res. Dans ce contexte , il me para\u00eet utile d\u2019analyser la situation de l\u2019\u00e9conomie italienne pour r\u00e9pondre aux attentes africaines et les perspectives de la coop\u00e9ration entre Alger et Rome en esp\u00e9rant des r\u00e9sultats concrets pour une prosp\u00e9rit\u00e9 partag\u00e9e<\/p>\n\n\n\n<p>Situation de l\u2019\u00e9conomie italienne<\/p>\n\n\n\n<p>Depuis 2014, l&rsquo;Italie a enclench\u00e9 une p\u00e9riode de d\u00e9clin de sa population, passant de plus de 60,3 millions d&rsquo;habitants \u00e0 moins de 59 millions en 2023. Le produit int\u00e9rieur brut (PIB) de l\u2019Italie a \u00e9t\u00e9 de 2108 milliards de dollars en 2021, de 2272 milliards de dollars en 2022 et pour , dans le top 10, l&rsquo;Italie \u00e9tant \u00e0 la 10e place, contre le 8e en 2022, avec un PIB de 2 010,43 milliards de dollars. Selon les derni\u00e8res pr\u00e9visions de la Commission europ\u00e9enne, la croissance \u00e9conomique italienne devrait atteindre 0,9 % en 2023 et 0,8 % en 2024. L\u2019\u00e9conomie italienne en 2023 a \u00e9chapp\u00e9 \u00e0 la r\u00e9cession que beaucoup lui pr\u00e9disaient \u00e0 l\u2019\u00e9t\u00e9 2022 \u00e0 la suite de la crise du gouvernement, marqu\u00e9e par la d\u00e9mission de Mario Draghi et l\u2019arriv\u00e9e de Giorgia Meloni \u00e0 la fonction de Pr\u00e9sidente du Conseil, port\u00e9 par le dynamisme des PMI\/PME innovantes , l\u2019industrie ayant un poids important o\u00f9 la part de l\u2019industrie dans la valeur ajout\u00e9e totale y atteint, en effet, 21,1 %, contre une moyenne de la zone euro de 20,2% , la France 14 %, le Portugal (17,1 %), l\u2019Espagne (17,4 %) ou encore la Belgique 17,7 %.<\/p>\n\n\n\n<p>Les importations de biens en 2020 ont \u00e9t\u00e9 de 422 milliards de dollars et de services 92 milliards de dollars, pour 2021, 409 milliards de dollars de biens et 101 milliards de dollars de services et pour 2023 les importations ont augment\u00e9 plus fortement (+35%) pour atteindre 783 Md\u20ac, soit 41% du PIB, la part des biens dans les \u00e9changes commerciaux \u00e9tant largement majoritaire (84%) et en augmentation depuis 2019 (+4pp), les \u00e9changes de services \u00e9tant plus marginaux s&rsquo;\u00e9levant \u00e0 245 Md\u20ac (en hausse de 32% sur l&rsquo;ann\u00e9e). Les exportations de biens ont \u00e9t\u00e9 en 2021 de 409 milliards de dollars de biens et 99 milliards de dollars de services, en 2022, de 496,12 milliards de dollars et des services 86,53 milliards de dollars soit au total : 582,65 milliards de dollars et pour 2023 , les exportations ont atteint 742 Md\u20ac, soit 38% du PIB, en hausse de 22% sur l&rsquo;ann\u00e9e. . Une reprise a \u00e9t\u00e9 constat\u00e9e en 2021 o\u00f9 l\u2019exc\u00e9dent commercial de l\u2019Italie a atteint 50,4 milliards d\u2019euros bien qu\u2019en baisse par rapport aux 63,17 milliards enregistr\u00e9s en 2020, selon l\u2019Institut national des statistiques (Istat). Pour 2022 le d\u00e9ficit commercial avait atteint -41 Md\u20ac en 2022, apr\u00e8s un exc\u00e9dent de 29 Md\u20ac en 2021 et 55 Md\u20ac en 2020. Ainsi, le d\u00e9ficit commercial de biens \u00e9tait de -31 Md\u20ac en 2022 (contre un exc\u00e9dent de +40,3 Md\u20ac en 2021), le d\u00e9ficit commercial de services ayant atteint -9,5 Md\u20ac (-18% par rapport \u00e0 2021). Mais la rapide r\u00e9sorption du d\u00e9ficit \u00e9nerg\u00e9tique (-19 Md\u20ac au T1 2023 contre -36 Md\u20ac au T3 2022) a permis \u00e0 l&rsquo;Italie de d\u00e9gager un exc\u00e9dent commercial d\u00e8s le T4 2022 (+0,7 Md\u20ac) qui s&rsquo;est accru d\u00e9but 2023 (5,4 Md\u20ac au T1). Quant aux autres indicateurs macro financiers et macro- sociaux, les r\u00e9serves de change d\u00e9passent en 2021 les 230 milliards de dollars, dont 2451,8 tonnes d\u2019or d\u2019une valeur d\u00e9passant les 80 milliards de dollars et fin 2023 atteignaient . 224 milliards de dollars. La dette publique de l\u2019Italie s\u2019est \u00e9lev\u00e9e \u00e0 153,5% du PIB en 2021, en l\u00e9g\u00e8re baisse par rapport \u00e0 2020 (155,6%), mais nettement au-dessus de la limite de 60% pr\u00e9vue par les r\u00e8gles de Maastricht et fin 2022, elle repr\u00e9sentait pr\u00e8s de 145 % de son PIB ayant certes diminu\u00e9 au cours des deux derni\u00e8res ann\u00e9es, mais demeure \u00e0 un niveau particuli\u00e8rement \u00e9lev\u00e9 plus de 140% du PIB fin 2023 soit la deuxi\u00e8me plus importante de la zone euro , apr\u00e8s la Gr\u00e8ce et en comparaison, celle de la France s&rsquo;\u00e9l\u00e8ve \u00e0 un peu plus de 109% du PIB. Ce poids qu&rsquo;elle porte depuis plus de 30 ans apporte une vuln\u00e9rabilit\u00e9 budg\u00e9taire au pays \u00bb, selon l&rsquo;institut Jacques Delors bien que l&rsquo;Italie, depuis les ann\u00e9es 2000, \u00ab a r\u00e9ussi \u00e0 retrouver un \u00e9quilibre budg\u00e9taire, et m\u00eame \u00e0 d\u00e9gager du surplus \u00bb, c&rsquo;est-\u00e0-dire \u00e0 obtenir des recettes sup\u00e9rieures \u00e0 ses d\u00e9penses qui selon cet institut serait davantage une bonne \u00e9l\u00e8ve sans ce fardeau. D\u2019une mani\u00e8re g\u00e9n\u00e9rale, la crise Covid-19 et la crise ukrainienne ont affect\u00e9 l\u2019\u00e9conomie italienne, comme toute l\u2019\u00e9conomie mondiale. Dans la phase de reprise , la croissance devrait s\u2019appuyer sur la mise en \u0153uvre du plan national de relance et de r\u00e9silience, adoss\u00e9 \u00e0 des r\u00e9formes structurelles, l\u2019Italie ayant b\u00e9n\u00e9fici\u00e9 de l\u2019impact positif du plan de relance europ\u00e9en (209 Md \u20ac). Mais la reprise des exportations sera d\u00e9pendante du rythme de celle du commerce mondial et du march\u00e9 int\u00e9rieur. Malgr\u00e9 les incertitudes, l\u2019Italie dispose d\u2019une solide industrie manufacturi\u00e8re sp\u00e9cialis\u00e9e dans des niches \u00e0 haute valeur ajout\u00e9e et int\u00e9gr\u00e9e aux cha\u00eenes de valeurs mondiales, la deuxi\u00e8me europ\u00e9enne apr\u00e8s l\u2019Allemagne. Structur\u00e9e autour de PME dynamiques, elle est la source de l\u2019exc\u00e9dent commercial. Mais comme impact de cette situation mondiale incertaine, les cons\u00e9quences sociales sont le taux d\u2019emploi faible et le taux ch\u00f4mage relativement \u00e9lev\u00e9, o\u00f9 selon les donn\u00e9es d\u2019Eurostat, le il atteint 7,6 % en 2023 alors qu\u2019il est de 5,9 % et 6,4 % en moyenne respectivement dans l\u2019Union europ\u00e9enne et en zone euro avec le ch\u00f4mage des jeunes parmi les plus \u00e9lev\u00e9s du continent europ\u00e9en, plus d\u2019un cinqui\u00e8me des jeunes actifs \u00e2g\u00e9s de moins de 25 ans \u00e9tant consid\u00e9r\u00e9 comme ch\u00f4meur et creusant les \u00e9carts entre les r\u00e9gions riches et celles pauvres, entre le Nord et le Sud (17,6%)Quant \u00e0 l\u2019inflation, les prix \u00e0 la consommation en Italie ont augment\u00e9 en moyenne de 5,7% sur l&rsquo;ann\u00e9e 2023, contre 8,1% en 2022, gr\u00e2ce \u00e0 l&rsquo;accalmie sur les tarifs de l&rsquo;\u00e9nergie, selon des donn\u00e9es d\u00e9finitives publi\u00e9es mardi par l&rsquo;Institut national de la statistique (Istat).<\/p>\n\n\n\n<p><strong>Coop\u00e9ration Alg\u00e9rie-Italie<\/strong><\/p>\n\n\n\n<p>Pour les relations commerciales, en 2022, la France \u00e9tait le 3\u00e8me client de l&rsquo;Alg\u00e9rie (10,5 % du total), derri\u00e8re l&rsquo;Italie (32,3 %) et l&rsquo;Espagne (12 %), \u2019Italie restant le premier client de l\u2019Alg\u00e9rie, achetant annuellement plus du tiers du gaz alg\u00e9rien export\u00e9, tandis qu\u2019elle occupe la deuxi\u00e8me place parmi les pays de l\u2019Union europ\u00e9enne (UE) fournisseurs de l\u2019Alg\u00e9rie. En 2020, le volume global des \u00e9changes commerciaux entre l\u2019Alg\u00e9rie et l\u2019Italie a atteint pr\u00e8s de 6 milliards de dollars (USD), dont 3,5 milliards USD d\u2019exportations alg\u00e9riennes vers l\u2019Italie (notamment des hydrocarbures) et 2,42 milliards USD d\u2019importations de ce pays (des \u00e9quipements surtout). Pour 2021, elles ont connu un accroissement s\u2019\u00e9tablissant \u00e0 8,5 milliards de dollars, dont 6,6 milliards de dollars d\u2019exportation de l\u2019Alg\u00e9rie et pour 2022 , l\u2019&rsquo;ambassadeur d&rsquo;Italie en Alg\u00e9rie, a r\u00e9v\u00e9l\u00e9 que les \u00e9changes entre l\u2019Alg\u00e9rie et l\u2019Italie atteint un niveau record de 20 milliards d&rsquo;euros en 2022. L\u2019Agence italienne Nova concernant la p\u00e9riode de 2022, indique que la balance commerciale reste en faveur de l&rsquo;Alg\u00e9rie qui a export\u00e9 pour plus de 18 milliards d&rsquo;euros sur le march\u00e9 italien contre 2,3 milliards d&rsquo;euros pour l&rsquo; Italie. Mais c\u2019est le secteur des hydrocarbures qui occupe une place importante dans la relation \u00e9conomique alg\u00e9ro-italienne gr\u00e2ce notamment au partenariat entre le Groupe Sonatrach et le groupe \u00e9nerg\u00e9tique italien Eni, pr\u00e9sent depuis 1981 en Alg\u00e9rie. Les deux Groupes g\u00e8rent le Gazoduc TransMed, aussi appel\u00e9 Enrico Mattei, reliant l\u2019Alg\u00e9rie \u00e0 l\u2019Italie via la Tunisie, d\u2019une capacit\u00e9 d\u2019un volume allant jusqu\u2019\u00e0 32 milliards de m\u00e8tres cubes de gaz alg\u00e9rien vers l\u2019Italie, ayant export\u00e9 en 2021 environ 21 milliards de m\u00e8tres cubes gazeux \u00e0 travers cette canalisation. Selon les donn\u00e9es de l&rsquo;Institut italien des statistiques (Istat), Pugliese 40% de la consommation italienne de gaz provient de l&rsquo;Alg\u00e9rie, Les volumes de gaz export\u00e9s selon les accords d\u2019entente Italie\/Alg\u00e9rie augmenter de 9 milliards m3\/an dans les ann\u00e9es \u00e0 venir, sous r\u00e9serve d\u2019investissements additionnels, \u00e0 la faveur de l&rsquo;accord sign\u00e9, le 11 avril 2022 \u00e0 Alger par les Pdg des groupes Sonatrach et le groupe Eni, \u00e9tant devenu en l\u2019espace d\u2019une ann\u00e9e et demie le plus important investisseur \u00e9tranger dans le domaine gazier en Alg\u00e9rie et selon le directeur des op\u00e9rations des ressources naturelles du groupe italien Eni il y a eu une augmentation des exp\u00e9ditions du gaz depuis l\u2019Alg\u00e9rie durant l\u2019ann\u00e9e 2023 15 milliards de m3 soit une augmentation de 3 milliards de m3 par rapport \u00e0 l\u2019ann\u00e9e 2022. Esp\u00e9rons l\u2019activation du projet Galsi gel\u00e9 depuis 2012, qui devait approvisionner la Sardaigne et la Corse d\u2019une capacit\u00e9 de 8 milliards de m\u00e8tres cubes gazeux et d\u2019un co\u00fbt estim\u00e9 en 2010 \u00e0 3 milliards de dollars (voir conf\u00e9rence du Pr Mebtoul en 2012- www.google.com sur ce sujet lors d\u2019une tourn\u00e9e en Sardaigne pour d\u00e9fendre ce projet). D\u2019une mani\u00e8re g\u00e9n\u00e9rale, l\u2019objectif strat\u00e9gique entre l\u2019Alg\u00e9rie et l\u2019Italie sera de diversifier la coop\u00e9ration \u00e9conomique et sur le plan politique de consolider davantage les r\u00e9alisations bilat\u00e9rales avec l\u2019objectif commun de promouvoir une plus grande stabilit\u00e9 et prosp\u00e9rit\u00e9 dans la r\u00e9gion m\u00e9diterran\u00e9enne. C\u2019est dans ce cadre que responsables alg\u00e9riens et italiens ont exprim\u00e9 r\u00e9cemment le souhait de voir la coop\u00e9ration bilat\u00e9rale entre Alger et Rome se diversifier. L\u2019Alg\u00e9rie est pr\u00eate \u00e0 accro\u00eetre ses exportations en direction de l\u2019Europe mais il appartient aux Europ\u00e9ens de venir investir en Alg\u00e9rie, dont l\u2019Italie tant dans les hydrocarbures traditionnels que dans les \u00e9nergies renouvelables et l\u2019hydrog\u00e8ne vert un des axes de la strat\u00e9gie \u00e9nerg\u00e9tique de l\u2019Alg\u00e9rie est le d\u00e9veloppement de l\u2019investissement dans les \u00e9nergies renouvelables et l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique ambitionnant de couvrir la consommation int\u00e9rieure de 40% \u00e0 partir des \u00e9nergies renouvelables horizon 2030\/2035, d\u2019exporter vers l\u2019Europe \u00e0 travers des interconnexions et exporter \u00e9galement l\u2019hydrog\u00e8ne vert pour couvrir les besoins de l\u2019Europe d\u2019environ 10\/15% horizon , \u00e9tant souhaitable que l\u2019annonce du c\u00e2ble \u00e9lectrique sous-marin reliant l\u2019Alg\u00e9rie \u00e0 la Sardaigne, un projet strat\u00e9gique, soit aliment\u00e9 par les \u00e9nergies renouvelables.<\/p>\n\n\n\n<p>Avec la pr\u00e9sence entrepreneuriale italienne en Alg\u00e9rie outre les hydrocarbures, un nombre d\u00e9passant les 200 entreprises italiennes en activit\u00e9 dans grands travaux publics, l&rsquo;industrie, les \u00e9quipements et le machinisme, l\u2019objectif sera de diversifier la coop\u00e9ration \u00e9conomique : pas seulement dans l\u2019\u00e9nergie, mais surtout d\u2019impulser les segments hors hydrocarbures, dont les infrastructures, les PME, l\u2019innovation technologique (donc le savoir pilier du XXI\u00e8me si\u00e8cle avec bonne gouvernance), l\u2019agro-industriel et les t\u00e9l\u00e9communications. Sur le plan politique, il s\u2019agira de consolider davantage les r\u00e9alisations bilat\u00e9rales avec l\u2019objectif commun de promouvoir une plus grande stabilit\u00e9 et prosp\u00e9rit\u00e9 dans la r\u00e9gion m\u00e9diterran\u00e9enne.<\/p>\n\n\n\n<p>En conclusion, la coop\u00e9ration entre l\u2019Alg\u00e9rie et l\u2019Italie ne concerne pas seulement le volet \u00e9conomique, mais les volets politiques, s\u00e9curitaires et culturels. Sur le plan \u00e9conomique, l\u2019Italie a une longue exp\u00e9rience d\u2019int\u00e9gration de la sph\u00e8re informelle, qui \u00e9tait dominante par le pass\u00e9, au sein de la sph\u00e8re r\u00e9elle et est \u00e9galement un vivier d\u2019exp\u00e9riences pour la dynamisation des PMI\/PME et peut \u00eatre b\u00e9n\u00e9fique pour l\u2019Alg\u00e9rie dans le cadre de ses r\u00e9formes structurelles, d\u00e9terminantes entre 2024\/2030. En bref, puisse la coop\u00e9ration Italie Afrique , contribuer \u00e0 faire des espaces euro-africains un lac de paix et une prosp\u00e9rit\u00e9 partag\u00e9e.<\/p>\n\n\n\n<p><strong>ademmebtoul@gmail.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Abderrahmane Mebtoul Professeur des universit\u00e9s et expert international. Nous nous orientons vers un monde multipolaire sur fond de tensions<\/p>\n","protected":false},"author":3,"featured_media":7876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[56,38],"tags":[],"class_list":["post-49045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contribution","category-debats"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Par Abderrahmane Mebtoul Professeur des universit\u00e9s et expert international. Nous nous orientons vers un monde multipolaire sur fond de tensions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-29T14:01:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-29T14:01:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie\",\"datePublished\":\"2024-01-29T14:01:30+00:00\",\"dateModified\":\"2024-01-29T14:01:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/\"},\"wordCount\":2197,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"articleSection\":[\"Contribution\",\"D\u00e9bats\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/\",\"name\":\"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"datePublished\":\"2024-01-29T14:01:30+00:00\",\"dateModified\":\"2024-01-29T14:01:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/01\\\/29\\\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/","og_locale":"fr_FR","og_type":"article","og_title":"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie - La Sentinelle","og_description":"Par Abderrahmane Mebtoul Professeur des universit\u00e9s et expert international. Nous nous orientons vers un monde multipolaire sur fond de tensions","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-01-29T14:01:30+00:00","article_modified_time":"2024-01-29T14:01:33+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie","datePublished":"2024-01-29T14:01:30+00:00","dateModified":"2024-01-29T14:01:33+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/"},"wordCount":2197,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","articleSection":["Contribution","D\u00e9bats"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/","name":"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","datePublished":"2024-01-29T14:01:30+00:00","dateModified":"2024-01-29T14:01:33+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/01\/29\/sommet-italie-afrique-les-perspectives-de-la-cooperation-en-lalgerie-et-litalie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Sommet Italie-Afrique\u00a0: Les perspectives de la coop\u00e9ration en l\u2019Alg\u00e9rie et l\u2019Italie"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/49045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=49045"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/49045\/revisions"}],"predecessor-version":[{"id":49046,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/49045\/revisions\/49046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/7876"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=49045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=49045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=49045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}