{"id":49496,"date":"2024-02-14T14:12:33","date_gmt":"2024-02-14T13:12:33","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=49496"},"modified":"2024-02-14T14:12:37","modified_gmt":"2024-02-14T13:12:37","slug":"opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/","title":{"rendered":"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb"},"content":{"rendered":"\n<p>Le Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;Organisation des pays arabes exportateurs de p\u00e9trole (OPAEP), Djamel Aissa El Loughani a soulign\u00e9 hier que l\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel. Un communique de l\u2019organisation a indiqu\u00e9 que lors de l\u2019audience qu&rsquo;il a accord\u00e9e \u00e0 l&rsquo;ambassadeur d&rsquo;Alg\u00e9rie au Kowe\u00eft, Noureddine Meriem, le SG de l&rsquo;OPAEP a rappel\u00e9 que \u00ab\u00a0l&rsquo;Alg\u00e9rie est l&rsquo;un des grands pays producteurs de gaz naturel \u00e0 l&rsquo;\u00e9chelle mondiale et l&rsquo;un des fournisseurs les plus fiables pour les pays europ\u00e9ens en termes de fourniture de gaz naturel, mais aussi un partenaire \u00e9nerg\u00e9tique important\u00a0\u00bb. &nbsp;Rappelons dans ce contexte qu\u2019un r\u00e9cent rapport de l\u2019organisation a soulign\u00e9 que l\u2019Alg\u00e9rie \u00ab fait partie des pays jouissant de relations strat\u00e9giques avec ses collaborateurs europ\u00e9ens, ainsi que d\u2019une grande cr\u00e9dibilit\u00e9 qui s\u2019\u00e9tend depuis des d\u00e9cennies en mati\u00e8re d\u2019approvisionnement en gaz naturel liqu\u00e9fi\u00e9 et de gaz par pipeline, gr\u00e2ce \u00e0 ce qu\u2019elle poss\u00e8de comme infrastructures d\u2019exportation, de stations de liqu\u00e9faction \u00e0 Skikda et Arzew (Oran), ou de pipelines la reliant au march\u00e9 europ\u00e9en comme l\u2019Italie et l\u2019Espagne \u00bb. Le m\u00eame rapport a indiqu\u00e9 que l\u2019Alg\u00e9rie s\u2019est hiss\u00e9e en 2023 au rang de premier exportateur de GNL en Afrique avec 13 millions de tonnes de GNL export\u00e9es, chiffre le plus \u00e9lev\u00e9 depuis 2010, contre 10,2 millions de tonnes export\u00e9es en 2022 soit \u00ab un taux de croissance annuel de 26,1%, le taux le plus \u00e9lev\u00e9 \u00e0 l\u2019\u00e9chelle arabe en 2023 \u00bb.<\/p>\n\n\n\n<p>Notons que lors de cette audience, le SG de l\u2019OPAEP a re\u00e7u des mains de l\u2019ambassadeur l&rsquo;invitation officielle adress\u00e9e par le ministre de l&rsquo;Energie et des Mines, Mohamed Arkab au Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;organisation pour assister 7e Sommet du Forum des pays exportateurs de gaz (GECF), pr\u00e9vu du 29 f\u00e9vrier au 2 mars \u00e0 Alger. Djamel Aissa El Loughani qui a confirm\u00e9 confirm\u00e9 sa participation \u00e0 la t\u00eate d&rsquo;une d\u00e9l\u00e9gation du Secr\u00e9tariat g\u00e9n\u00e9ral<\/p>\n\n\n\n<p>de l&rsquo;OPAEP a dans ce cadre salu\u00e9 les efforts consentis par l&rsquo;Alg\u00e9rie en pr\u00e9vision du Sommet, souhaitant plein succ\u00e8s aux travaux de cet \u00e9v\u00e8nement et la concr\u00e9tisation des objectifs escompt\u00e9s. Il a relev\u00e9, \u00e0 cette occasion, \u00ab\u00a0l&rsquo;importance capitale que rev\u00eat le Sommet compte tenu du contexte g\u00e9opolitique qui pr\u00e9vaut\u00a0\u00bb.<\/p>\n\n\n\n<p><strong>Sommet du GECF: un \u00e9v\u00e8nement d&rsquo;envergure<\/strong><\/p>\n\n\n\n<p>Il faut dire que le Sommet du GECF \u00e0 Alger rev\u00eat une importance particuli\u00e8re dans la mesure o\u00f9 il s\u2019agira de renforcer le r\u00f4le de l\u2019organisation sur le march\u00e9 gazier ainsi que sa coordination avec des organisations similaires \u00e0 l\u2019image de l\u2019Opep. Dans ce cadre un riche programme a \u00e9t\u00e9 concoct\u00e9.<\/p>\n\n\n\n<p>Abrit\u00e9 par le Centre international de conf\u00e9rences Abdelatif-Rahal (CIC, Alger), ce Sommet, qui se d\u00e9roulera avec la tenue de plusieurs \u00e9v\u00e8nements<\/p>\n\n\n\n<p>associ\u00e9s \u00e0 partir du 29 f\u00e9vrier. Il est pr\u00e9vu, au programme de la premi\u00e8re journ\u00e9e, une r\u00e9union des membres du groupe de travail ad hoc de haut niveau qui sera consacr\u00e9e \u00e0 la finalisation du projet de la D\u00e9claration d&rsquo;Alger et de l&rsquo;ordre du jour pour le soumettre \u00e0 l&rsquo;examen lors de la r\u00e9union minist\u00e9rielle extraordinaire qui pr\u00e9c\u00e8de la r\u00e9union au sommet des Chefs d&rsquo;Etat et de gouvernement du GECF. &nbsp;Durant la m\u00eame journ\u00e9e, il est attendu l&rsquo;organisation de la c\u00e9r\u00e9monie d&rsquo;inauguration officielle du si\u00e8ge de l&rsquo;Institut de recherche sur le gaz du GECF bas\u00e9 \u00e0 Alger et le lancement de la publication du GECF, le Global Gas Outlook, \u00e0 travers des pr\u00e9sentations faites aux d\u00e9l\u00e9gu\u00e9s et aux experts du pays h\u00f4te.<\/p>\n\n\n\n<p>La deuxi\u00e8me journ\u00e9e sera marqu\u00e9e, quant \u00e0 elle, par la tenue de la r\u00e9union minist\u00e9rielle extraordinaire du GECF devant pr\u00e9parer la documentation du Sommet, notamment le projet de la D\u00e9claration d&rsquo;Alger et l&rsquo;ordre du jour. Au menu de cette 2\u00e8me journ\u00e9e figurent l&rsquo;organisation de la 2e c\u00e9r\u00e9monie de remise des prix GECF pour honorer des personnalit\u00e9s et des institutions ayant apport\u00e9 des contributions exceptionnelles au secteur du gaz naturel et une c\u00e9r\u00e9monie de signature des protocoles d&rsquo;accords du GECF avec l&rsquo;Institut de recherche \u00e9conomique pour l&rsquo;ASEAN et l&rsquo;Asie de l&rsquo;Est et la Commission africaine de l&rsquo;\u00e9nergie relevant de l&rsquo;Union africaine (UA). La troisi\u00e8me et derni\u00e8re journ\u00e9e verra la r\u00e9union au Sommet des Chefs d&rsquo;Etat et de Gouvernement du Forum des pays exportateurs de gaz qui auront \u00e0 examiner et \u00e0 adopter la D\u00e9claration d&rsquo;Alger, laquelle sera suivie par la tenue d&rsquo;une conf\u00e9rence de presse. &nbsp;<\/p>\n\n\n\n<p>Sabrina Aziouez<\/p>\n\n\n\n<p><strong>Gaz&nbsp;: Les prix du gaz au plus bas depuis juillet<\/strong><\/p>\n\n\n\n<p>Une m\u00e9t\u00e9o particuli\u00e8rement cl\u00e9mente cette ann\u00e9e p\u00e8se la consommation de gaz en Europe et par cons\u00e9quent sur les prix sur les march\u00e9s libres. Le contrat \u00e0 terme du TTF n\u00e9erlandais, consid\u00e9r\u00e9 comme la r\u00e9f\u00e9rence europ\u00e9enne, grappillait 2,12% \u00e0 26,275 euros le m\u00e9gawattheure (MWh), se reprenant apr\u00e8s avoir touch\u00e9 la veille 25,625 euros, un plus bas depuis juillet 2023. Son homologue britannique a \u00e9galement atteint lundi un plus bas depuis juillet, \u00e0 62,35 pence par thermie, une unit\u00e9 de quantit\u00e9 de chaleur. \u00ab\u00a0Tant que l&rsquo;Europe reste bien approvisionn\u00e9e, avec des niveaux de stockage proches de 70% \u00e0 l&rsquo;approche de la fin de l&rsquo;hiver, l&rsquo;incertitude concernant les livraisons de gaz du Qatar ne suffit pas \u00e0 emp\u00eacher la chute du march\u00e9 du gaz\u00a0\u00bb, commentent les analystes d&rsquo;Energi Danmark. Les r\u00e9serves de gaz, pourtant tr\u00e8s sollicit\u00e9es pour le chauffage pendant l&rsquo;hiver, sont en effet encore remplies \u00e0 67% en moyenne dans les pays de l&rsquo;Union europ\u00e9enne, selon la plateforme europ\u00e9enne Agregated Gas Storage Inventory (AGSI). Les analystes notent \u00e9galement que \u00ab\u00a0les pr\u00e9visions (m\u00e9t\u00e9orologiques) indiquent un temps doux\u00a0\u00bb en Europe. Aux \u00c9tats-Unis, le gaz a quant \u00e0 lui atteint lundi un plus bas depuis juillet 2020, \u00e0 1,732 dollar par million de British thermal unit (BTU, une unit\u00e9 de mesure anglo-saxonne).<\/p>\n\n\n\n<p>R.E.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;Organisation des pays arabes exportateurs de p\u00e9trole (OPAEP), Djamel Aissa El Loughani a soulign\u00e9 hier que<\/p>\n","protected":false},"author":3,"featured_media":49302,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,29],"tags":[],"class_list":["post-49496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;Organisation des pays arabes exportateurs de p\u00e9trole (OPAEP), Djamel Aissa El Loughani a soulign\u00e9 hier que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-14T13:12:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T13:12:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/02\/gazoduc.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb\",\"datePublished\":\"2024-02-14T13:12:33+00:00\",\"dateModified\":\"2024-02-14T13:12:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/\"},\"wordCount\":1083,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/gazoduc.jpeg\",\"articleSection\":[\"\u00c0 la Une\",\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/\",\"name\":\"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/gazoduc.jpeg\",\"datePublished\":\"2024-02-14T13:12:33+00:00\",\"dateModified\":\"2024-02-14T13:12:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/gazoduc.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/gazoduc.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"Oil Or Gas Transportation With Blue Gas Or Pipe Line Valves On Soil And Sunrise Background\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/02\\\/14\\\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/","og_locale":"fr_FR","og_type":"article","og_title":"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb - La Sentinelle","og_description":"Le Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;Organisation des pays arabes exportateurs de p\u00e9trole (OPAEP), Djamel Aissa El Loughani a soulign\u00e9 hier que","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-02-14T13:12:33+00:00","article_modified_time":"2024-02-14T13:12:37+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/02\/gazoduc.jpeg","type":"image\/jpeg"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb","datePublished":"2024-02-14T13:12:33+00:00","dateModified":"2024-02-14T13:12:37+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/"},"wordCount":1083,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/02\/gazoduc.jpeg","articleSection":["\u00c0 la Une","\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/","name":"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/02\/gazoduc.jpeg","datePublished":"2024-02-14T13:12:33+00:00","dateModified":"2024-02-14T13:12:37+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/02\/gazoduc.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/02\/gazoduc.jpeg","width":1280,"height":720,"caption":"Oil Or Gas Transportation With Blue Gas Or Pipe Line Valves On Soil And Sunrise Background"},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/02\/14\/opaep-lalgerie-est-lun-des-fournisseurs-les-plus-fiables-de-gaz-naturel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"OPAEP\u00a0: \u00ab\u00a0L\u2019Alg\u00e9rie est l\u2019un des fournisseurs les plus fiables de gaz naturel\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/49496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=49496"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/49496\/revisions"}],"predecessor-version":[{"id":49497,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/49496\/revisions\/49497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/49302"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=49496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=49496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=49496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}