{"id":50447,"date":"2024-03-18T12:45:43","date_gmt":"2024-03-18T11:45:43","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=50447"},"modified":"2024-03-18T12:45:51","modified_gmt":"2024-03-18T11:45:51","slug":"transition-energetique-mondiale-quelle-strategie-pour-lalgerie","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/","title":{"rendered":"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0?"},"content":{"rendered":"\n<p>Par Abderrahmane Mebtoul<\/p>\n\n\n\n<p>Professeur des universit\u00e9s, expert international docteur, ancien directeur g\u00e9n\u00e9ral des \u00e9tudes \u00e9conomiques, haut magistrat premier conseiller \u00e0 la Cour des comptes, ancien directeur des \u00e9tudes au minist\u00e8re de l\u2019\u00c9nergie et \u00e0 la Sonatrach et Pr\u00e9sident de la commission transition \u00e9nerg\u00e9tique des 5+5+ Allemagne (2019-2020).<\/p>\n\n\n\n<p>Le d\u00e9veloppement des \u00e9nergies renouvelables contribue \u00e0 la transition \u00e9nerg\u00e9tique et l\u2019Alg\u00e9rie entend rattraper le retard en investissant, outre dans les \u00e9nergies traditionnelles, dans le solaire et l\u2019hydrog\u00e8ne , tout en n\u2019oubliant pas dan l\u2019un des plus grands r\u00e9servoir, soit l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique pour r\u00e9duire le gaspillage et la pollution.<\/p>\n\n\n\n<p>C\u2019est dans ce cadre que le 14 mars 2024, le groupe Sonelgaz a sign\u00e9, des contrats avec les soci\u00e9t\u00e9s nationales et \u00e9trang\u00e8res, 14 contrats avec huit soumissionnaires ayant remport\u00e9 l\u2019appel d\u2019offres, pour la production de 3.000 m\u00e9gawatts d\u2019\u00e9nergie solaire sur un programme horizon 2035 de 15.000 MW dont une partie est d\u00e9di\u00e9e \u00e0 l\u2019exportation et une autre destin\u00e9e \u00e0 couvrir la consommation int\u00e9rieure \u00e0 environ 40%. Le premier projet porte sur une capacit\u00e9 de 2.000 m\u00e9gawatts consistant en la r\u00e9alisation de 15 centrales solaires photovolta\u00efques, d\u2019une capacit\u00e9 de production de 80 \u00e0 220 MW chacune, r\u00e9parties sur 12 wilayas. Quant au projet Solar 1000, il comprend la construction de 5 centrales photovolta\u00efques, d\u2019une capacit\u00e9 allant de 50 \u00e0 300 m\u00e9gawatts. Les deux projets constituent la premi\u00e8re phase du programme EnR 15\u2009000 MW\u2009, qui consiste \u00e0 produire 15\u2009000 MW d\u2019\u00e9nergie solaire photovolta\u00efque \u00e0 l\u2019horizon 2035 \u00e0 travers plus de 40 wilayas. Selon le minist\u00e8re de l\u2019Energie et des Mines, ce projet permettra de concr\u00e9tiser des partenariats entre des entreprises nationales et \u00e9trang\u00e8res, qui contribueront au renforcement de l\u2019int\u00e9gration nationale et au transfert de technologie et par l\u00e0, \u00e0 l&rsquo;Alg\u00e9rie d&rsquo;honorer ses engagements internationaux, notamment au titre de l&rsquo;accord de Paris, avec la perspective de r\u00e9duire les gaz \u00e0 effet de serre \u00e0 l&rsquo;horizon 2030.<\/p>\n\n\n\n<p>D&rsquo;ici 2030\/2035, les investissements pr\u00e9vus dans le cadre de la transition \u00e9nerg\u00e9tique USA\/Europe\/Chine, Inde devraient d\u00e9passer les 4000 milliards de dollars\/an o\u00f9 les grosses compagnies devraient r\u00e9orienter leurs investissements pour le d\u00e9veloppement des \u00e9nergies renouvelables, les industries \u00e9cologiques et l&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique. Plus globalement, le plan climat des grandes puissances pr\u00e9voit d&rsquo;investir dans les segments intelligents au niveau des b\u00e2timents( nouveaux logements plus durables et \u00e9co-\u00e9nerg\u00e9tiques,) des infrastructures d&rsquo;eau, de transport \u00e0 travers une r\u00e9organisation de l&rsquo;industrie automobile, les voitures hybrides et \u00e9lectriques, supposant l&rsquo;installation de de dizaines de millions au niveau mondial de bornes de recharge publiques sur le territoire, durant une p\u00e9riode transitoire certains pays instaurant une prime \u00e0 la conversion. Pour l\u2019Europe par exemple, la Commission europ\u00e9enne a fix\u00e9, avec le r\u00e8glement d&rsquo;ex\u00e9cution 2020\/1294 du 15 septembre 2020, les r\u00e8gles du nouveau m\u00e9canisme de financement des \u00e9nergies renouvelables. Chaque \u00c9tat membre doit contribuer \u00e0 l&rsquo;objectif europ\u00e9en de 32% d&rsquo;\u00e9nergies renouvelables en 2030. Une trajectoire indicative a \u00e9t\u00e9 fix\u00e9e pour chacun d&rsquo;entre eux, pour la p\u00e9riode 2021-2030, avec des points de r\u00e9f\u00e9rence \u00e0 atteindre entre 2025 et 2027, devant mobiliser au moins 1000 milliards d&rsquo;euros d&rsquo;investissements durables dans les dix ann\u00e9es \u00e0 venir avec des incitations pour attirer les financements priv\u00e9s, gr\u00e2ce notamment au r\u00f4le essentiel que jouera la Banque europ\u00e9enne d&rsquo;investissement. La Chine et l&rsquo;Inde ont un fort engagement pour la transition \u00e9nerg\u00e9tique. Par exemple, selon le rapport de Global Wind Energy Council, la Chine et l&rsquo;Inde font partie des cinq pays regroupant 73% de l&rsquo;ensemble des capacit\u00e9s \u00e9oliennes mondiales install\u00e9es. En termes d&rsquo;\u00e9nergie solaire, le soutien des gouvernements indien et chinois stimule la comp\u00e9titivit\u00e9 de leurs fili\u00e8res solaires, faisant d&rsquo;eux les premiers acteurs au niveau mondial. La Chine pour tenter de r\u00e9duire la pollution atmosph\u00e9rique due \u00e0 cet usage incontr\u00f4l\u00e9 du charbon, investit massivement dans les \u00e9nergies renouvelables: elle pr\u00e9voit d&rsquo;investir d&rsquo;ici 2030, environ 375 \u00e0 400 milliards de dollars d\u2019investissements. Quant \u00e0 l&rsquo;Inde, elle s&rsquo;est engag\u00e9e \u00e0 fortement d\u00e9velopper les \u00e9nergies renouvelables, en disposant en particulier de 100 GW de capacit\u00e9s solaires et de 60 GW \u00e9oliens d&rsquo;ici \u00e0 fin 2022 contre 16,6 GW solaires et 32,7 GW \u00e9oliens \u00e0 fin novembre 2017), devant mobiliser pour cette p\u00e9riode pr\u00e8s de 190 milliards de dollars selon les estimations de la Climate Policy Initiative (CPI). Les USA\/Europe qui repr\u00e9sentent actuellement plus de 40% du PIB mondial pour une population inf\u00e9rieure \u00e0 un milliard d&rsquo;habitants poussent \u00e0 l&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique et \u00e0 la transition \u00e9nerg\u00e9tique afin de lutter contre le r\u00e9chauffement climatique. Car si les Chinois, les Indiens et les Africains avaient le m\u00eame mod\u00e8le de consommation \u00e9nerg\u00e9tique que les USA et l&rsquo;Europe, il faudrait cinq fois la plan\u00e8te actuelle pour satisfaire les besoins. Je rappelle que selon le rapport de l&rsquo;ONU une s\u00e9cheresse sans pr\u00e9c\u00e9dent frappera l&rsquo;Afrique du Nord et l&rsquo;Afrique subsaharienne entre horizon 2025\/2030 .En d\u00e9cidant un investissement massif dans le cadre de l&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique, les \u00e9nergies alternatives aux fossiles classiques dont les \u00e9nergies renouvelables, les USA, l&rsquo;Europe, la Chine et l\u2019Inde locomotives de l\u2019\u00e9conomie mondiale (70% du PIB mondial) ont les moyens de leurs politiques. Le monde devrait conna\u00eetre horizon 2030 un profond bouleversement de la carte \u00e9nerg\u00e9tique et donc du pouvoir \u00e9conomique mondial, l&rsquo;\u00e9nergie \u00e9tant au ceour de la s\u00e9curit\u00e9 des nations (interviews- Pr A. Mebtoul AfricaPresse Paris, American Herald Tribune et Financial Afrik 2018\/\/2023 &#8211; le professeur Abderrahmane Mebtoul a pr\u00e9sid\u00e9 avec les meilleurs experts des deux rives de la M\u00e9diterran\u00e9e praticiens, experts et op\u00e9rateurs, repr\u00e9sentant l&rsquo;Alg\u00e9rie, courant 2019\/2020, la commission de la transition \u00e9nerg\u00e9tique, des 5+5+ Allemagne o\u00f9 les axes de la transition \u00e9nerg\u00e9tique ont \u00e9t\u00e9 d\u00e9finis). Afin de rattraper son retard, l&rsquo;Alg\u00e9rie entend investir , en privil\u00e9giant un partenariat gagnant -gagnant, certes toujours dans les \u00e9nergies fossiles traditionnelles mais d\u00e9carbon\u00e9es dont le biogaz qui contribue \u00e0 la transition \u00e9nerg\u00e9tique, autour de trois axes directeurs. Le premier axe directeur pour l\u2019Alg\u00e9rie est l\u2019am\u00e9lioration de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique avec la r\u00e9vision des m\u00e9thodes de construction, car les anciennes normes induisent une forte consommation d\u2019\u00e9nergie, alors que les techniques modernes \u00e9conomisent de 40 \u00e0 50% de la consommation (\u00e9tude r\u00e9alis\u00e9e sous notre direction assist\u00e9 par le bureau d \u2018\u00e9tudes am\u00e9ricain Ernst &amp; Young 2008, une nouvelle politique de subventions des carburants Minist\u00e8re de \u2019l\u2019\u00e9nergie 2008, 7 volumes 680 pages) . Une nouvelle politique des prix s\u2019impose renvoyant \u00e0 une nouvelle politique des subventions cibl\u00e9es , les subventions g\u00e9n\u00e9ralis\u00e9es, injustes, occasionnant un gaspillage des ressources. Le deuxi\u00e8me axe est li\u00e9 au d\u00e9veloppement des \u00e9nergies renouvelables devant combiner le thermique et le photovolta\u00efque, le co\u00fbt de production mondiale ayant diminu\u00e9 de plus de 50% et il le sera plus \u00e0 l\u2019avenir. Avec plus de 3 000 heures d\u2019ensoleillement par an, l\u2019Alg\u00e9rie a tout ce qu\u2019il faut pour d\u00e9velopper l\u2019utilisation de l\u2019\u00e9nergie solaire. Mais le soleil tout seul ne suffit pas. Il faut la technologie et les \u00e9quipements pour transformer ce don du ciel en \u00e9nergie \u00e9lectrique .Le programme alg\u00e9rien consiste \u00e0 installer une puissance d\u2019origine renouvelable de pr\u00e8s de 22000 MW, dont 12 000 MW seront d\u00e9di\u00e9s \u00e0 couvrir la demande nationale de l\u2019\u00e9lectricit\u00e9 et 10 000 MW \u00e0 l\u2019exportation, d\u2019ici 2030, l\u2019objectif \u00e9tant de produire 40% des besoins internes en \u00e9lectricit\u00e9 \u00e0 partir des \u00e9nergies renouvelables alors qu\u2019en 2021, cela repr\u00e9sente seulement 1% donc cela n\u00e9cessite d\u2019importants financements et faire face \u00e0 la forte consommation int\u00e9rieure qui selon les donn\u00e9es du gouvernement repr\u00e9sente en 2023 45% de la production et pourrait aller vers 80% horizon 2030. Le troisi\u00e8me axe est le d\u00e9veloppement de l\u2019hydrog\u00e8ne vert , bleu et l\u2019hydrog\u00e8ne blanc souvent oubli\u00e9 le Minist\u00e8re de l\u2019Energie, pr\u00e9voyant d\u2019investir 20 \u00e0 25 milliards de dollars \u00e0 l\u2019horizon 2040 : ce programme serait divis\u00e9e en trois grands phases : le d\u00e9marrage via des projets pilotes (2023 \u00e0 2030), l\u2019expansion et la cr\u00e9ation de march\u00e9s (2030 \u00e0 2040) et l\u2019industrialisation et la comp\u00e9titivit\u00e9 du march\u00e9 (2040 \u00e0 2050). \u00c0 horizon 2040, l\u2019Alg\u00e9rie pr\u00e9voit de produire et d\u2019exporter 30 \u00e0 40 TWh d\u2019hydrog\u00e8ne gazeux et liquide, avec un mix \u00e0 la fois compos\u00e9 d\u2019hydrog\u00e8ne bleu, produit \u00e0 partir de gaz, et d\u2019hydrog\u00e8ne vert fabriqu\u00e9 par \u00e9lectrolyse gr\u00e2ce aux importantes ressources solaires du pays, avec pour objectif de fournir \u00e0 l\u2019Europe 10 % de ses besoins en hydrog\u00e8ne vert, d\u2019ici \u00e0 2040. Il ne faudrait pas oublier \u00e9galement le d\u00e9veloppement de l\u2019hydrog\u00e8ne blanc qui ne r\u00e9sulte pas d&rsquo;un proc\u00e9d\u00e9 \u00ab\u00a0humain\u00a0\u00bb comme l&rsquo;\u00e9lectrolyse o\u00f9 une transformation issue du gaz, sa formation est dite \u00ab\u00a0naturelle\u00a0\u00bb et peut r\u00e9sulter de diff\u00e9rents m\u00e9canismes : Une r\u00e9action d\u2019oxydor\u00e9duction qui alt\u00e8re des m\u00e9taux qui contiennent du fer au niveau hydrothermal et entraine la production d&rsquo;hydrog\u00e8ne ; une eau \u00e0 forte teneur en \u00e9l\u00e9ments tels que du plutonium ou de l\u2019uranium subit une radiolyse et un rayonnement ionisant peut alors causer la rupture des mol\u00e9cules d&rsquo;eau (H2O), scission qui peut provoquer \u00e0 son tour la lib\u00e9ration d&rsquo;hydrog\u00e8ne naturel. &lsquo;hydrog\u00e8ne blanc pr\u00e9sente deux avantages de taille par rapport aux autres types d&rsquo;hydrog\u00e8ne : contrairement \u00e0 certaines m\u00e9thodes de fabrication telles que le vaporeformage, sa production ne s&rsquo;accompagne d&rsquo;aucune \u00e9mission de dioxyde de carbone, car il est g\u00e9n\u00e9r\u00e9 naturellement par la Terre.<\/p>\n\n\n\n<p>En conclusion, la structuration du Mix \u00e9nerg\u00e9tique mondiale au 1<sup>er<\/sup> janvier 2023 est compos\u00e9e du p\u00e9trole 32% , du gaz naturel 24%, du charbon 27%, du nucl\u00e9aire 3% , du renouvelable y compris l\u2019\u00e9nergie hydraulique 14%.Cette structure est appel\u00e9e \u00e0 \u00e9voluer entre 2030\/2040\/2050 avec une croissance du gaz qui repr\u00e9senterait plus de 30%, le p\u00e9trole 25% , le nucl\u00e9aire 10% , l\u2019hydraulique et les \u00e9nergies renouvelables dans toute leur composante y compris l\u2019hydrog\u00e8ne vert et bleu 35% et entre 2035 et 2050 environ 60 \u00e0 65% de la consommation mondiale d\u2019\u00e9nergie sera constitu\u00e9e de la combinaison du gaz naturel, des \u00e9nergies renouvelables l\u2019\u00c9nergie hydraulique, l\u2019\u2019\u00c9nergie \u00e9olienne, l\u2019\u00c9nergie solaire, la Biomasse , la G\u00e9othermie, le d\u00e9veloppement de l\u2019hydrog\u00e8ne vert bleu et blanc. Aussi, les changements \u00e9conomiques survenus depuis quelques ann\u00e9es dans le monde ainsi que ceux qui sont appel\u00e9s \u00e0 se produire dans un proche avenir, doivent n\u00e9cessairement trouver leur traduction dans des changements d&rsquo;ordre syst\u00e9mique destin\u00e9s \u00e0 les prendre en charge et \u00e0 organiser leur insertion dans un ordre social qui est lui-m\u00eame en devenir, une strat\u00e9gie ax\u00e9e sur la bonne gouvernance, la valorisation du savoir avec l&rsquo;objectif horizon 2030\/2040, la transition num\u00e9rique et \u00e9nerg\u00e9tique.<\/p>\n\n\n\n<p>&nbsp;ademmebtoul@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Abderrahmane Mebtoul Professeur des universit\u00e9s, expert international docteur, ancien directeur g\u00e9n\u00e9ral des \u00e9tudes \u00e9conomiques, haut magistrat premier conseiller \u00e0<\/p>\n","protected":false},"author":3,"featured_media":7876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[56,38],"tags":[],"class_list":["post-50447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contribution","category-debats"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0? - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0? - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Par Abderrahmane Mebtoul Professeur des universit\u00e9s, expert international docteur, ancien directeur g\u00e9n\u00e9ral des \u00e9tudes \u00e9conomiques, haut magistrat premier conseiller \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-18T11:45:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-18T11:45:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0?\",\"datePublished\":\"2024-03-18T11:45:43+00:00\",\"dateModified\":\"2024-03-18T11:45:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/\"},\"wordCount\":1833,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"articleSection\":[\"Contribution\",\"D\u00e9bats\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/\",\"name\":\"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0? - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"datePublished\":\"2024-03-18T11:45:43+00:00\",\"dateModified\":\"2024-03-18T11:45:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/contribution.png\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/03\\\/18\\\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0? - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/","og_locale":"fr_FR","og_type":"article","og_title":"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0? - La Sentinelle","og_description":"Par Abderrahmane Mebtoul Professeur des universit\u00e9s, expert international docteur, ancien directeur g\u00e9n\u00e9ral des \u00e9tudes \u00e9conomiques, haut magistrat premier conseiller \u00e0","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-03-18T11:45:43+00:00","article_modified_time":"2024-03-18T11:45:51+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0?","datePublished":"2024-03-18T11:45:43+00:00","dateModified":"2024-03-18T11:45:51+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/"},"wordCount":1833,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","articleSection":["Contribution","D\u00e9bats"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/","name":"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0? - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","datePublished":"2024-03-18T11:45:43+00:00","dateModified":"2024-03-18T11:45:51+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/contribution.png","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/03\/18\/transition-energetique-mondiale-quelle-strategie-pour-lalgerie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Transition \u00e9nerg\u00e9tique mondiale\u00a0: Quelle strat\u00e9gie pour l&rsquo;Alg\u00e9rie\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/50447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=50447"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/50447\/revisions"}],"predecessor-version":[{"id":50449,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/50447\/revisions\/50449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/7876"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=50447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=50447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=50447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}