{"id":5154,"date":"2021-08-24T00:02:00","date_gmt":"2021-08-23T23:02:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=5154"},"modified":"2021-08-23T19:47:21","modified_gmt":"2021-08-23T18:47:21","slug":"assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/","title":{"rendered":"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste"},"content":{"rendered":"\n<p>Douze jours se sont \u00e9coul\u00e9s depuis le crime crapuleux commis contre le jeune artiste de Meliana, Djamel Bensmail. Un acte qui a endeuill\u00e9 toute une nation tant l\u2019acte en lui-m\u00eame rev\u00eat un caract\u00e8re d\u00e9passant l\u2019entendement et qu\u2019il n\u2019est plus utile de le d\u00e9crire encore une fois. Apr\u00e8s la vague d\u2019arrestation qui a vis\u00e9 quatre-vingt-douze personnes dont troisfemmes, toutes suspect\u00e9es d\u2019\u00eatre impliqu\u00e9es de pr\u00e8s ou de loin dans ce crime crapuleux, les mis en cause ont \u00e9t\u00e9 pr\u00e9sent\u00e9s, dans la matin\u00e9e d\u2019hier, devant le procureur de la R\u00e9publique pr\u00e8s le tribunal de Sidi M\u2019hamed \u00e0 Alger.Les chefs d\u2019accusations pour lesquels ces individus sont poursuivis sont d\u2019une extr\u00eame gravit\u00e9. Il s\u2019agit \u00ab d\u2019homicide volontaire, lynchage et immolation par le feu d\u2019un cadavre, violation d\u2019un poste de police, appartenance \u00e0 un groupe terroriste et actes de vandalismes portant atteinte \u00e0 la s\u00e9curit\u00e9 de l\u2019Etat \u00bb. Au regard de ces chefs d\u2019accusations face auxquels ces individus doivent s\u2019expliquer, l\u2019on retient celui relatif \u00e0 leur appartenance \u00e0 une entreprise terroriste. C\u2019est du moins l\u2019aveu fait par certains d\u2019entre eux affichant ouvertement leur appartenance au mouvement s\u00e9paratiste que dirige \u00e0 partir de son exil dor\u00e9, Ferhat M\u2019Henni. Ce qui a pouss\u00e9 certains analystes, comme Hassen Kacimi, expert des questions g\u00e9opolitiques, \u00e0 affirmer le caract\u00e8re pr\u00e9m\u00e9dit\u00e9 de ce crime commis symboliquement sur une place publique baptis\u00e9e du nom du chahid Abane Ramdane d\u2019abord et surtout \u00e0 une semaine de la c\u00e9l\u00e9bration du 65e anniversaire de la tenue du 1er congr\u00e8s du FLN r\u00e9volutionnaire dans la localit\u00e9 d\u2019Ifri Ouzellaguen, dans la vall\u00e9e de la Soummam. Une symbolique qui n\u2019a pas \u00e9chapp\u00e9 \u00e0 cet expert pour soutenir que le choix de cette place portant le nom de celui qui fut l\u2019architecte du 1er congr\u00e8s du FLN r\u00e9volutionnaire pour perp\u00e9trerune telle monstruosit\u00e9 vise \u00e0 enterrer l\u2019unit\u00e9 nationale. Partant de l\u00e0, l\u2019autorit\u00e9 judiciaire en charge de ce lourd dossier sera \u00e0 coup s\u00fbr appel\u00e9e \u00e0 recourir \u00e0 l\u2019application des textes de lois relatifs \u00e0 toute sorte d\u2019appartenance \u00e0 une quelconque organisation terroriste dont les membres, accus\u00e9s de sabotages, de crimes ou d\u2019un autre d\u00e9lit touchant aux int\u00e9r\u00eats et \u00e0 la s\u00e9curit\u00e9 de l\u2019Etat, seront jug\u00e9s en application des lois en vigueur.La comparution en audience publique de ces individus devant le magistrat charg\u00e9 de juger cette affaire que l\u2019on qualifie \u00e0 juste titre, d\u2019inhumaine, r\u00e9v\u00e8lera d\u2019autres graves d\u00e9lits. C\u2019est le message qui a \u00e9t\u00e9 donn\u00e9 par les \u00e9l\u00e9ments de la police charg\u00e9s de l\u2019enqu\u00eate en r\u00e9cup\u00e9rant l\u2019appareil photo appartenant \u00e0 la victime sur lequel figure des images \u00ab ahurissantes \u00bb. Cet indice avanc\u00e9 par la police \u00e0 la suite de la r\u00e9cup\u00e9ration de cet appareil photo suscite depuis lors moult interrogations quant \u00e0 son contenu. L\u2019artiste de Meliana, venu se solidariser avec la population de Larb\u00e2a Nait Irathen, partie en guerre contre les flammes avait-il pris en photo les pyromanes qui ont mis toute la Kabylie en feu pour un but trac\u00e9 \u00e0 partir du si\u00e8ge du MAK sis dans la capitale Fran\u00e7aise ? C\u2019est la th\u00e8se d\u00e9velopp\u00e9e par tous d\u00e8s les premiers aveux film\u00e9s par la t\u00e9l\u00e9vision Alg\u00e9rienne montrant ces individus d\u00e9voilant leur appartenance \u00e0 ce mouvement s\u00e9paratiste classifi\u00e9 par les autorit\u00e9 Alg\u00e9riennes comme organisation terroriste au m\u00eame titre que Rachad dont les dirigeants donnent des orientations \u00e0 partir de certaines capitales Europ\u00e9ennes, Gen\u00e8ve pour Mourad Dhina et Londres pour Larbi Zitout. Pour rappel, le jeuneDjamel Bensmail a \u00e9t\u00e9 sauvagement assassin\u00e9 le 11 ao\u00fbt dernier et dont les images de cette sc\u00e8ne ont \u00e9t\u00e9 largement diffus\u00e9es sur les r\u00e9seaux sociaux.Le p\u00e8re de la victime, faisant preuve d\u2019une grande sagesse, avait appel\u00e9 au calme tout en exigeant que les assassins de son fils doivent rendre compte de leur acte devant la justice Alg\u00e9rienne. C\u2019est ce qui est en train de se passer en attendant que cette horde sauvage, compos\u00e9e de 92 personnes, fassent d\u2019autres aveux face au juge. Ce qui \u00e9clairera un peu plus l\u2019opinion publique sur le but recherch\u00e9 \u00e0 travers ce mouvement s\u00e9paratiste qui n\u2019a pas r\u00e9ussi dans un pass\u00e9 r\u00e9cent \u00e0 entrainer la Kabylie dans la spirale de la violence en appelant les citoyens de cette r\u00e9gion du pays \u00e0 se constituer en milices arm\u00e9es.<\/p>\n\n\n\n<p>Idir Yaghmourassen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Douze jours se sont \u00e9coul\u00e9s depuis le crime crapuleux commis contre le jeune artiste de Meliana, Djamel Bensmail. Un acte<\/p>\n","protected":false},"author":3,"featured_media":5162,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-5154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Douze jours se sont \u00e9coul\u00e9s depuis le crime crapuleux commis contre le jeune artiste de Meliana, Djamel Bensmail. Un acte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-23T23:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/image_2021-08-23_194715.png\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste\",\"datePublished\":\"2021-08-23T23:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/\"},\"wordCount\":793,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_2021-08-23_194715.png\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/\",\"name\":\"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_2021-08-23_194715.png\",\"datePublished\":\"2021-08-23T23:02:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_2021-08-23_194715.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/image_2021-08-23_194715.png\",\"width\":580,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/08\\\/24\\\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/","og_locale":"fr_FR","og_type":"article","og_title":"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste - La Sentinelle","og_description":"Douze jours se sont \u00e9coul\u00e9s depuis le crime crapuleux commis contre le jeune artiste de Meliana, Djamel Bensmail. Un acte","og_url":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2021-08-23T23:02:00+00:00","og_image":[{"width":580,"height":350,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/image_2021-08-23_194715.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste","datePublished":"2021-08-23T23:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/"},"wordCount":793,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/image_2021-08-23_194715.png","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/","url":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/","name":"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/image_2021-08-23_194715.png","datePublished":"2021-08-23T23:02:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/image_2021-08-23_194715.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/image_2021-08-23_194715.png","width":580,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/08\/24\/assassinat-du-jeune-djamel-bensmail-92-personnes-poursuivies-pour-appartenance-a-un-groupe-terroriste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Assassinat du jeune Djamel Bensmail : 92 personnes poursuivies pour appartenance \u00e0 un groupe terroriste"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/5154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=5154"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/5154\/revisions"}],"predecessor-version":[{"id":5163,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/5154\/revisions\/5163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/5162"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=5154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=5154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=5154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}