{"id":51634,"date":"2024-04-26T13:58:17","date_gmt":"2024-04-26T12:58:17","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=51634"},"modified":"2024-04-26T13:58:20","modified_gmt":"2024-04-26T12:58:20","slug":"annaba-le-wali-sengage-pour-restaurer-limage-de-bone","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/","title":{"rendered":"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le chef de l\u2019ex\u00e9cutif de la wilaya a appel\u00e9 les responsables locaux \u00e0 apporter leur total soutien aux comit\u00e9s de la ville et associations de quartiers, afin de leur permettre de contribuer pleinement au d\u00e9veloppement de leur municipalit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le wali d\u2019Annaba, Abdelkader Djellaoui, a pr\u00e9sid\u00e9 cette semaine une r\u00e9union qui a regroup\u00e9 les comit\u00e9s de la ville du chef-lieu et associations de quartiers, au si\u00e8ge du palais des arts et de la culture \u00ab&nbsp;Mohamed Boudiaf \u00bb d\u2019Annaba. Qualifi\u00e9e de fructueuse, la r\u00e9union a trait\u00e9 outre l\u2019\u00e9tat de d\u00e9gradation pr\u00e9valant dans la ville, des moyens et des m\u00e9canismes pour y rem\u00e9dier. La rencontre a permis \u00e0 des centaines de repr\u00e9sentants des comit\u00e9s de la ville et des associations de quartiers d\u2019exposer les objectifs d\u00e9j\u00e0 atteints ou en cours de r\u00e9alisation. La rencontre \u00e9tait une opportunit\u00e9 pour les participants pour informer Abdelkader Djellaoui, sur les obstacles rencontr\u00e9s sur le terrain pour relancer des projets en rapport avec l\u2019am\u00e9lioration du cadre de vie. Des projets susceptibles d\u2019am\u00e9liorer le cadre de vie de la ville et donner une nouvelle image \u00e0 la wilaya d\u2019Annaba, a- t-on expliqu\u00e9. Lors de leurs interventions respectives, les intervenants repr\u00e9sentants divers comit\u00e9s de la ville et d\u2019associations de quartiers ont soulign\u00e9 de mani\u00e8re unanime l&rsquo;importance et la n\u00e9cessit\u00e9 de l\u2019am\u00e9lioration du cadre de vie, surtout que la saison estivale est \u00e0 quelques semaines et la wilaya s\u2019appr\u00eate \u00e0 accueillir les vacanciers et les touristes, a-t-on soulign\u00e9. C\u2019est dire que les habitants d\u2019Annaba tendent de redorer le blason de leur ville, ternie par une clochardisation, orchestr\u00e9e par l\u2019indiff\u00e9rence et le laxisme d\u2019ex-responsables, ont not\u00e9 les intervenants. Intervenant \u00e0 son tour, apr\u00e8s avoir pris connaissance des projets r\u00e9alis\u00e9s et ceux dont a encore besoin la ville, le wali a f\u00e9licit\u00e9 les repr\u00e9sentants des comit\u00e9s de la ville pour leur r\u00f4le dans l\u2019am\u00e9lioration du cadre de vie, en rappelant \u00e0 l\u2019assistance leurs principales missions. Il s\u2019agit ici de \u00ab d\u00e9finir le cadre d\u2019intervention et la d\u00e9marche \u00e0 entreprendre en mati\u00e8re d\u2019hygi\u00e8ne, de salubrit\u00e9 publique et de protection de l\u2019environnement \u00bb. Il a \u00e9galement soulign\u00e9 l\u2019importance de \u00ab surveiller la mise en \u0153uvre des op\u00e9rations d\u2019entretien des espaces publics, des diff\u00e9rents r\u00e9seaux, ainsi que la collecte des ordures m\u00e9nag\u00e8res et des d\u00e9chets solides \u00bb. Le chef de l\u2019ex\u00e9cutif de la wilaya a appel\u00e9 les responsables locaux \u00e0 apporter leur total soutien aux comit\u00e9s de la ville et associations de quartiers, afin de leur permettre de contribuer pleinement au d\u00e9veloppement de leur municipalit\u00e9. Il est \u00e0 noter que les comit\u00e9s de la ville (Coville) sont des structures charg\u00e9es de propositions et de concertation entre les \u00e9lus locaux et les administr\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sofia Chahine<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le chef de l\u2019ex\u00e9cutif de la wilaya a appel\u00e9 les responsables locaux \u00e0 apporter leur total soutien aux comit\u00e9s de<\/p>\n","protected":false},"author":3,"featured_media":31921,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[31],"tags":[],"class_list":["post-51634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le chef de l\u2019ex\u00e9cutif de la wilaya a appel\u00e9 les responsables locaux \u00e0 apporter leur total soutien aux comit\u00e9s de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T12:58:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T12:58:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Annaba.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne\",\"datePublished\":\"2024-04-26T12:58:17+00:00\",\"dateModified\":\"2024-04-26T12:58:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/\"},\"wordCount\":513,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Annaba.png\",\"articleSection\":[\"R\u00e9gions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/\",\"name\":\"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Annaba.png\",\"datePublished\":\"2024-04-26T12:58:17+00:00\",\"dateModified\":\"2024-04-26T12:58:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Annaba.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Annaba.png\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/04\\\/26\\\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/","og_locale":"fr_FR","og_type":"article","og_title":"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne - La Sentinelle","og_description":"Le chef de l\u2019ex\u00e9cutif de la wilaya a appel\u00e9 les responsables locaux \u00e0 apporter leur total soutien aux comit\u00e9s de","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-04-26T12:58:17+00:00","article_modified_time":"2024-04-26T12:58:20+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Annaba.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne","datePublished":"2024-04-26T12:58:17+00:00","dateModified":"2024-04-26T12:58:20+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/"},"wordCount":513,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Annaba.png","articleSection":["R\u00e9gions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/","name":"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Annaba.png","datePublished":"2024-04-26T12:58:17+00:00","dateModified":"2024-04-26T12:58:20+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Annaba.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Annaba.png","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/04\/26\/annaba-le-wali-sengage-pour-restaurer-limage-de-bone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Annaba\u00a0: Le wali s\u2019engage pour restaurer l\u2019image de B\u00f4ne"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/51634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=51634"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/51634\/revisions"}],"predecessor-version":[{"id":51635,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/51634\/revisions\/51635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/31921"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=51634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=51634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=51634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}