{"id":52312,"date":"2024-05-12T16:15:00","date_gmt":"2024-05-12T15:15:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=52312"},"modified":"2024-05-12T16:15:02","modified_gmt":"2024-05-12T15:15:02","slug":"charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/","title":{"rendered":"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates"},"content":{"rendered":"\n<p>Les d\u00e9couvertes de charniers se multiplient dans les h\u00f4pitaux de Ghaza, tandis que les attaques visant les \u00e9tablissements de sant\u00e9 et les camps de r\u00e9fugi\u00e9s en leur sein s\u2019amplifient en faisant de nouvelles victimes, des enfants, notamment. C\u2019est dans ce contexte que le Conseil de s\u00e9curit\u00e9 a appel\u00e9 \u00e0 des enqu\u00eates imm\u00e9diates, ind\u00e9pendantes, approfondies sur ces charniers<\/p>\n\n\n\n<p>Les d\u00e9bats au Conseil de s\u00e9curit\u00e9 sur les charniers d\u00e9couverts \u00e0 Ghaza, tenus \u00e0 la demande de l\u2019Alg\u00e9rie, ont abouti \u00e0 un consensus sur la n\u00e9cessit\u00e9 d\u2019ouvrir une enqu\u00eate sur ces charniers qui suscitent de r\u00e9elles inqui\u00e9tudes. Les membres du Conseil de s\u00e9curit\u00e9 ont ainsi adopt\u00e9 vendredi, \u00e0 l&rsquo;unanimit\u00e9, un communiqu\u00e9 de presse propos\u00e9 par l&rsquo;Alg\u00e9rie, appelant \u00e0 des enqu\u00eates imm\u00e9diates, ind\u00e9pendantes, approfondies, transparentes et impartiales, pour d\u00e9terminer les circonstances derri\u00e8re les charniers qui continuent d\u2019\u00eatre d\u00e9couverts dans la bande de Ghaza, montrant le tableau vrai et laid de la machine \u00e0 tuer de l&rsquo;entit\u00e9 sioniste. Rappelons dans ce contexte que l\u2019Alg\u00e9rie a convoqu\u00e9 mardi dernier, un d\u00e9bat \u00e0 huis clos du Conseil de s\u00e9curit\u00e9 sur les charniers \u00e0 Ghaza. Les membres du Conseil se sont d\u00e9clar\u00e9s profond\u00e9ment pr\u00e9occup\u00e9s par les informations faisant \u00e9tat de la d\u00e9couverte de charniers dans les h\u00f4pitaux Nasser et Chifa de Ghaza et ses alentours, o\u00f9 plusieurs centaines de corps, dont des femmes, des enfants et des personnes \u00e2g\u00e9es, \u00e9taient enterr\u00e9s. Les membres du Conseil ont \u00e9galement soulign\u00e9 l\u2019importance de permettre aux enqu\u00eateurs d&rsquo;acc\u00e9der sans entrave \u00e0 tous les sites de charniers \u00e0 Ghaza. Ce consensus met en \u00e9vidence l&rsquo;ampleur du ressentiment qui r\u00e8gne au sein de la communaut\u00e9 internationale face \u00e0 la persistance de l&rsquo;occupant dans ses crimes et le manque de confiance dans les enqu\u00eates men\u00e9es par les autorit\u00e9s d&rsquo;occupation. A cet \u00e9gard, les membres du Conseil ont soulign\u00e9 l\u2019importance que ceux qui violent le droit international r\u00e9pondent de leurs actes et ont demand\u00e9 \u00e0 toutes les parties de s&rsquo;acquitter strictement des obligations qui leur incombent en vertu du droit international, y compris le droit international humanitaire et le droit international des droits de l&rsquo;homme, en particulier en ce qui concerne la protection des civils. Face \u00e0 cette trag\u00e9die v\u00e9cue par les familles des victimes et des personnes disparues, les membres du Conseil ont not\u00e9, une fois de plus, qu&rsquo;il importait de permettre aux familles de savoir ce qu&rsquo;il \u00e9tait advenu de leurs proches disparus et o\u00f9 ils se trouvaient, conform\u00e9ment aux dispositions du droit international humanitaire. Les membres du Conseil ont \u00e9galement soulign\u00e9 que toutes les parties devaient appliquer imm\u00e9diatement et int\u00e9gralement les r\u00e9solutions 2728 (2024), 2720 (2023) et 2712 (2023) du Conseil de s\u00e9curit\u00e9 afin d&rsquo;all\u00e9ger les souffrances du peuple palestinien.<\/p>\n\n\n\n<p>Ainsi, l&rsquo;Alg\u00e9rie a r\u00e9ussi encore une fois, \u00e0 proposer un document du Conseil qui a pu b\u00e9n\u00e9ficier du consensus de tous ses membres sans exception, augmentant ainsi la pression internationale sur l&rsquo;occupant sioniste, qui ne peut plus se d\u00e9rober \u00e0 ses responsabilit\u00e9s. Il convient de noter que l&rsquo;adoption de cette d\u00e9claration est intervenue apr\u00e8s des efforts inlassables et des consultations et n\u00e9gociations intensives men\u00e9es par l&rsquo;Alg\u00e9rie \u00e0 New York avec les membres du Conseil de s\u00e9curit\u00e9 ainsi qu&rsquo;avec la partie palestinienne, au cours desquelles l&rsquo;Alg\u00e9rie a insist\u00e9 pour que les enqu\u00eates sur ces crimes odieux soient imm\u00e9diates, ind\u00e9pendantes, compl\u00e8tes, transparentes et impartiales. Malgr\u00e9 l&rsquo;objection de certains et les man\u0153uvres des repr\u00e9sentants de l&rsquo;occupant dans les couloirs de l&rsquo;ONU, craignant les appels \u00e0 la responsabilisation qui resserrent jour apr\u00e8s jour l&rsquo;\u00e9tau autour des responsables de l&rsquo;occupation, l&rsquo;Alg\u00e9rie a insist\u00e9 sur sa position amenant tous les membres \u00e0 acquiescer devant la force de l&rsquo;argument et la justice de la cause.<\/p>\n\n\n\n<p>Il serait utile de noter dans ce contexte que les autorit\u00e9s sanitaires palestiniennes ont annonc\u00e9, hier, la d\u00e9couverte de 80 corps de martyrs dans 3 fosses communes dans les cours du complexe m\u00e9dical d&rsquo;Al-Shifa, en plus de dizaines d&rsquo;autres \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;\u00e9tablissement. La m\u00eame source a d\u00e9clar\u00e9 que jusqu&rsquo;\u00e0 pr\u00e9sent, plus de 520 corps ont \u00e9t\u00e9 retrouv\u00e9s dans 7 fosses communes dans les h\u00f4pitaux de la bande de Ghaza, au cours des derniers mois apr\u00e8s le retrait des forces sionistes d&rsquo;Al-Shifa, du complexe m\u00e9dical Nasser et de l&rsquo;h\u00f4pital Kamal Adwan, et d&rsquo;autres. La m\u00eamesource a not\u00e9 qu'\u00a0\u00bbun examen des corps exhum\u00e9s des fosses communes a montr\u00e9 que la plupart appartenaient \u00e0 des patients priv\u00e9s de soins de sant\u00e9\u00a0\u00bb. \u00ab\u00a0Nous avons trouv\u00e9 des corps d\u00e9chiquet\u00e9s par les v\u00e9hicules de l&rsquo;arm\u00e9e (sioniste) et nous avons trouv\u00e9 des t\u00eates sans corps dans les fosses communes dans les cours du complexe d&rsquo;Al-Shifa\u00a0\u00bb, a-t-on ajout\u00e9. La m\u00eame source, a soulign\u00e9 qu'\u00a0\u00bbil existait des preuves que certaines des victimes avaient \u00e9t\u00e9 ex\u00e9cut\u00e9es, avec des blessures par balle \u00e0 la t\u00eate et \u00e0 la poitrine\u00a0\u00bb. &nbsp;\u00ab\u00a0310 membres du personnel m\u00e9dical sont d\u00e9tenus par l&rsquo;occupant\u00a0\u00bb, a indiqu\u00e9 la m\u00eame source, exigeant leur lib\u00e9ration imm\u00e9diate.<\/p>\n\n\n\n<p>Lyes Benisid<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les d\u00e9couvertes de charniers se multiplient dans les h\u00f4pitaux de Ghaza, tandis que les attaques visant les \u00e9tablissements de sant\u00e9<\/p>\n","protected":false},"author":3,"featured_media":52313,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-52312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Les d\u00e9couvertes de charniers se multiplient dans les h\u00f4pitaux de Ghaza, tandis que les attaques visant les \u00e9tablissements de sant\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-12T15:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-12T15:15:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/05\/charnier.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates\",\"datePublished\":\"2024-05-12T15:15:00+00:00\",\"dateModified\":\"2024-05-12T15:15:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/\"},\"wordCount\":920,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/charnier.jpeg\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/\",\"name\":\"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/charnier.jpeg\",\"datePublished\":\"2024-05-12T15:15:00+00:00\",\"dateModified\":\"2024-05-12T15:15:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/charnier.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/charnier.jpeg\",\"width\":864,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/05\\\/12\\\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/","og_locale":"fr_FR","og_type":"article","og_title":"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates - La Sentinelle","og_description":"Les d\u00e9couvertes de charniers se multiplient dans les h\u00f4pitaux de Ghaza, tandis que les attaques visant les \u00e9tablissements de sant\u00e9","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-05-12T15:15:00+00:00","article_modified_time":"2024-05-12T15:15:02+00:00","og_image":[{"width":864,"height":486,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/05\/charnier.jpeg","type":"image\/jpeg"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates","datePublished":"2024-05-12T15:15:00+00:00","dateModified":"2024-05-12T15:15:02+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/"},"wordCount":920,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/05\/charnier.jpeg","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/","name":"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/05\/charnier.jpeg","datePublished":"2024-05-12T15:15:00+00:00","dateModified":"2024-05-12T15:15:02+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/05\/charnier.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/05\/charnier.jpeg","width":864,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/05\/12\/charniers-a-ghaza-le-conseil-de-securite-demande-des-enquetes-immediates\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Charniers \u00e0 Ghaza\u00a0: Le Conseil de s\u00e9curit\u00e9 demande des enqu\u00eates imm\u00e9diates"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/52312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=52312"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/52312\/revisions"}],"predecessor-version":[{"id":52314,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/52312\/revisions\/52314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/52313"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=52312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=52312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=52312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}