{"id":54005,"date":"2024-07-02T20:31:12","date_gmt":"2024-07-02T19:31:12","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=54005"},"modified":"2024-07-02T20:31:13","modified_gmt":"2024-07-02T19:31:13","slug":"acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/","title":{"rendered":"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le repr\u00e9sentant permanent de l&rsquo;Alg\u00e9rie aupr\u00e8s des Nations Unies, l&rsquo;ambassadeur Amar Bendjama, a soulign\u00e9 hier, lors de la r\u00e9union du Conseil de s\u00e9curit\u00e9 sur la situation humanitaire \u00e0 Ghaza, la n\u00e9cessit\u00e9 de prendre des mesures urgentes pour acheminer l&rsquo;aide humanitaire vers la bande de Ghaza. Il a affirm\u00e9 que \u00ab\u00a0sans mesures urgentes et imm\u00e9diates, le monde sera t\u00e9moin d&rsquo;une catastrophe humanitaire qui restera grav\u00e9e dans les pages sombres de l&rsquo;histoire\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amar Bendjama a soulign\u00e9 au cours de son intervention que la faim et la malnutrition avaient caus\u00e9 une crise catastrophique dans la r\u00e9gion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour \u00e9viter une famine totale dans la bande de Gaza, le diplomate alg\u00e9rien a ajout\u00e9 : \u00ab\u00a0Nous avons besoin de rapidit\u00e9 pour assurer l&rsquo;acheminement de l&rsquo;aide vers le nord de la bande\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amar Bendjama a \u00e9galement rappel\u00e9 qu&rsquo; au mois de d\u00e9cembre dernier, &nbsp;\u00a0\u00bb le Conseil de s\u00e9curit\u00e9 a adopt\u00e9 une r\u00e9solution visant \u00e0 mettre en place un m\u00e9canisme pour faciliter l&rsquo;acc\u00e8s de l&rsquo;aide humanitaire \u00e0 la bande de Gaza, mais les \u00e9v\u00e9nements et les faits ont prouv\u00e9 l&rsquo;inefficacit\u00e9 de cette r\u00e9solution\u00a0\u00bb. \u00ab\u00a0Lorsque cette r\u00e9solution a \u00e9t\u00e9 adopt\u00e9e, environ 100 camions entraient quotidiennement dans la bande, alors qu&rsquo;avant le 7 octobre, 500 camions entraient quotidiennement\u00a0\u00bb. Il a soulign\u00e9 que les acteurs humanitaires rencontrent des difficult\u00e9s pour acc\u00e9der \u00e0 la bande de Ghaza. indiqu\u00e9 dans ce contexte que \u00ab\u00a0l&rsquo;utilisation de la famine comme outil de guerre par l&rsquo;occupation a emp\u00each\u00e9 l&rsquo;acheminement de l&rsquo;aide\u00a0\u00bb. Le diplomate alg\u00e9rien a \u00e9galement soulign\u00e9 le r\u00f4le central de l&rsquo;office des Nations unies de secours aux r\u00e9fugi\u00e9s palestiniens (UNRWA). La situation humanitaire est apocalyptique \u00e0 Ghaza. Elle est aggrav\u00e9e par la si\u00e8ge impos\u00e9 \u00e0 l&rsquo;enclave par l&rsquo;occupation sioniste, mais aussi les multiples d\u00e9placements forc\u00e9s de la population civile. Des travailleurs humanitaires de l&rsquo;Organisation des Nations unies ont d\u00e9crit lundi comme apocalyptique la situation dans la ville de Ghaza, au nord de l&rsquo;enclave, o\u00f9 plus de 84.000 personnes ont r\u00e9cemment quitt\u00e9 leurs foyers. La repr\u00e9sentante de l&rsquo;Agence des Nations unies pour les r\u00e9fugi\u00e9s palestiniens (UNRWA), Louise Wateridge, a d\u00e9clar\u00e9 que cet exode co\u00efncidait avec l&rsquo;augmentation des bombardements sionistes \u00e0 l&rsquo;est de la ville, alors que plusieurs chars y ont \u00e9galement \u00e9t\u00e9 identifi\u00e9s. \u00a0\u00bb L&rsquo;UNRWA s&rsquo;est d\u00e9clar\u00e9 pr\u00e9occup\u00e9e par le manque de carburant, d&rsquo;aide et de s\u00e9curit\u00e9 pour maintenir ses op\u00e9rations, consid\u00e9r\u00e9es comme les plus importantes pour les Palestiniens d\u00e9plac\u00e9s. L&rsquo;organisme a mis en garde contre la d\u00e9tresse de son personnel en g\u00e9n\u00e9ral, \u00ab\u00a0qui \u00e0 son tour lutte pour survivre pendant cette guerre\u00a0\u00bb. Selon l&rsquo;ONU, alors que le point de passage de Rafah est toujours ferm\u00e9, il est impossible d&rsquo;acheminer de l&rsquo;aide humanitaire pour la distribuer \u00e0 Ghaza en raison de l&rsquo;absence d&rsquo;ordre public et de s\u00e9curit\u00e9, ainsi que des hostilit\u00e9s en cours, des routes endommag\u00e9es, des p\u00e9nuries de carburant et de restrictions d&rsquo;acc\u00e8s. Pendant tout le mois de juin, les autorit\u00e9s de l&rsquo;occupant sioniste ont autoris\u00e9 moins de la moiti\u00e9 des 115 missions humanitaires pr\u00e9vues dans le nord de Ghaza. Plus d&rsquo;un tiers d&rsquo;entre elles ont \u00e9t\u00e9 bloqu\u00e9es, pr\u00e8s de 10 % se sont vu refuser l&rsquo;acc\u00e8s et environ 9 % ont \u00e9t\u00e9 annul\u00e9s pour des raisons logistiques, op\u00e9rationnelles ou de s\u00e9curit\u00e9, a confirm\u00e9 lundi St\u00e9phane Dujarric, porte-parole du secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;ONU, Antonio Guterres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1,9 million de Palestiniens d\u00e9plac\u00e9s<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il faut noter que la coordinatrice humanitaire de l&rsquo;ONU pour le territoire, Sigrid Kaag, a indiqu\u00e9 hier lors de la r\u00e9union du Conseil de s\u00e9curit\u00e9 qu&rsquo;il y a d\u00e9sormais 1,9 million de personnes d\u00e9plac\u00e9es dans la bande de Ghaza. \u00a0\u00bb Elle s&rsquo;est dit \u00ab\u00a0vivement pr\u00e9occup\u00e9e\u00a0\u00bb par les nouveaux ordres d&rsquo;\u00e9vacuation \u00e9mis \u00e0 Ghaza par les forces sionistes. De son cot\u00e9, l&rsquo;Office de secours et de travaux des Nations Unies pour les r\u00e9fugi\u00e9s de Palestine (UNRWA) a estim\u00e9 mardi que 250.000 Palestiniens seront contraints de quitter la ville de Khan Younes, au sud de la bande de Ghaza. L&rsquo;UNRWA) a estim\u00e9 hierque 250.000 Palestiniens seront contraints de quitter la ville de Khan Younes, au sud de la bande de Ghaza, soumise \u00e0 une agression g\u00e9nocidaire sioniste depuis 270 jours. \u00ab\u00a0Quelques semaines seulement apr\u00e8s que les gens ont \u00e9t\u00e9 forc\u00e9s de retourner dans Khan Younes d\u00e9vast\u00e9, (l&rsquo;occupant sioniste) a \u00e9mis de nouveaux ordres d&rsquo;\u00e9vacuation pour la r\u00e9gion\u00a0\u00bb, \u00e9crit l&rsquo;UNRWA dans un message publi\u00e9 sur la plateforme X. \u00ab\u00a0Une fois de plus, les familles sont confront\u00e9es \u00e0 un d\u00e9placement forc\u00e9. Nous estimons que 250.000 personnes devront quitter (la ville de Khan Younes), malgr\u00e9 l&rsquo;absence d&rsquo;endroits s\u00fbrs \u00e0 Ghaza\u00a0\u00bb, a d\u00e9plor\u00e9 l&rsquo;office onusien. De son c\u00f4t\u00e9, un responsable de l&rsquo;Organisation mondiale de la sant\u00e9 a averti que l&rsquo;h\u00f4pital europ\u00e9en de Khan Younes \u00e0 Ghaza est presque vide, le personnel et les patients ayant fui suite \u00e0 des ordres d&rsquo;\u00e9vacuation de la ville. S&rsquo;exprimant par vid\u00e9o-conf\u00e9rence depuis El Qods occup\u00e9e lors d&rsquo;une conf\u00e9rence de presse de l&rsquo;ONU, &nbsp;Rik Peeperkorn, repr\u00e9sentant de l&rsquo;OMS en Palestine a indiqu\u00e9 que seuls trois patients \u00e9taient encore sur place. \u00ab\u00a0Nous demandons que l&rsquo;h\u00f4pital europ\u00e9en de Ghaza soit \u00e9pargn\u00e9 et qu&rsquo;il ne soit pas endommag\u00e9\u00a0\u00bb, a-t-il d\u00e9clar\u00e9. Sur le terrain les massacres de l&rsquo;occupant se poursuivent. Ainsi, dix Palestiniens sont tomb\u00e9s en martyrs et d&rsquo;autres ont \u00e9t\u00e9 bless\u00e9s hierpar une frappe a\u00e9rienne des forces d&rsquo;occupation sioniste qui a vis\u00e9 un march\u00e9 au sud-est de la ville de Ghaza. L&rsquo;aviation des forces d&rsquo;occupation sioniste a bombard\u00e9 un march\u00e9 bond\u00e9 pr\u00e8s de la mosqu\u00e9e Shama&rsquo;a dans le quartier d&rsquo;Al-Zaytoun, faisant de nombreux martyrs et bless\u00e9s, ont rapport\u00e9 des m\u00e9dias. Notons que le bilan de l&rsquo;agression g\u00e9nocidaire sioniste contre la bande de Ghaza s&rsquo;est alourdi hier \u00e0 37.925 martyrs et 87.141 bless\u00e9s, depuis le 7 octobre dernier. Selon les autorit\u00e9s palestiniennes de la sant\u00e9, l&rsquo;arm\u00e9e d&rsquo;occupation sioniste a commis 3 massacres au cours des derni\u00e8res 24 heures dans la bande de Ghaza, faisant 25 martyrs et 81 bless\u00e9s. Les autorit\u00e9s palestiniennes de la sant\u00e9 ont indiqu\u00e9 qu&rsquo;un certain nombre de victimes palestiniennes se trouvaient encore sous les d\u00e9combres et sur les routes, et que les forces de l&rsquo;occupation emp\u00eachaient les ambulances et les \u00e9quipes de la Protection civile de leur porter secours.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lyes Sa\u00efdi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le repr\u00e9sentant permanent de l&rsquo;Alg\u00e9rie aupr\u00e8s des Nations Unies, l&rsquo;ambassadeur Amar Bendjama, a soulign\u00e9 hier, lors de la r\u00e9union du<\/p>\n","protected":false},"author":3,"featured_media":53765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-54005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le repr\u00e9sentant permanent de l&rsquo;Alg\u00e9rie aupr\u00e8s des Nations Unies, l&rsquo;ambassadeur Amar Bendjama, a soulign\u00e9 hier, lors de la r\u00e9union du\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T19:31:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T19:31:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/06\/amar_bendjama.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes\",\"datePublished\":\"2024-07-02T19:31:12+00:00\",\"dateModified\":\"2024-07-02T19:31:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/\"},\"wordCount\":1158,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/amar_bendjama.jpeg\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/\",\"name\":\"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/amar_bendjama.jpeg\",\"datePublished\":\"2024-07-02T19:31:12+00:00\",\"dateModified\":\"2024-07-02T19:31:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/amar_bendjama.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/amar_bendjama.jpeg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/02\\\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/","og_locale":"fr_FR","og_type":"article","og_title":"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes - La Sentinelle","og_description":"Le repr\u00e9sentant permanent de l&rsquo;Alg\u00e9rie aupr\u00e8s des Nations Unies, l&rsquo;ambassadeur Amar Bendjama, a soulign\u00e9 hier, lors de la r\u00e9union du","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-07-02T19:31:12+00:00","article_modified_time":"2024-07-02T19:31:13+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/06\/amar_bendjama.jpeg","type":"image\/jpeg"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes","datePublished":"2024-07-02T19:31:12+00:00","dateModified":"2024-07-02T19:31:13+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/"},"wordCount":1158,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/06\/amar_bendjama.jpeg","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/","name":"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/06\/amar_bendjama.jpeg","datePublished":"2024-07-02T19:31:12+00:00","dateModified":"2024-07-02T19:31:13+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/06\/amar_bendjama.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/06\/amar_bendjama.jpeg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/02\/acheminement-de-laide-humanitaire-a-ghaza-lalgerie-demande-des-mesures-urgentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Acheminement de l&rsquo;aide humanitaire \u00e0 Ghaza: L&rsquo;Alg\u00e9rie demande des mesures urgentes"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/54005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=54005"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/54005\/revisions"}],"predecessor-version":[{"id":54007,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/54005\/revisions\/54007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/53765"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=54005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=54005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=54005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}