{"id":54752,"date":"2024-07-22T20:45:33","date_gmt":"2024-07-22T19:45:33","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=54752"},"modified":"2024-07-22T20:45:35","modified_gmt":"2024-07-22T19:45:35","slug":"arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/","title":{"rendered":"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb"},"content":{"rendered":"\n<p>Le ministre de l&rsquo;\u00c9nergie et des Mines, Mohamed Arkab, a soulign\u00e9, hier \u00e0 Alger, les efforts du secteur de l&rsquo;\u00e9nergie pour s&rsquo;adapter aux exigences environnementales et att\u00e9nuer l&rsquo;impact du changement climatique tout en renfor\u00e7ant la position de l&rsquo;Alg\u00e9rie comme fournisseur d&rsquo;\u00e9nergie fiable sur la sc\u00e8ne internationale.<\/p>\n\n\n\n<p>S\u2019exprimant lors de la c\u00e9r\u00e9monie de signature de la nouvelle strat\u00e9gie climat du groupe Sonatrach, Mohamed Arkab a affirm\u00e9 qu&rsquo;il est d\u00e9sormais n\u00e9cessaire de renforcer la capacit\u00e9 d&rsquo;adaptation de notre secteur \u00e9nerg\u00e9tique et de trouver des moyens de d\u00e9veloppement plus durables, indiquant au passage&nbsp;&nbsp;que l&rsquo;Alg\u00e9rie avait \u00e9labor\u00e9, dans ce cadre, une strat\u00e9gie visant \u00e0 pr\u00e9server ses capacit\u00e9s et ses engagements \u00e0 long terme, tout en amor\u00e7ant un processus de transition graduel, responsable et pratique dans le secteur, en vue de r\u00e9pondre \u00e0 la demande croissante de mani\u00e8re durable, rentable et s\u00e9curis\u00e9e, tout en att\u00e9nuant l&rsquo;impact environnemental.&nbsp;&nbsp;Le premier responsable du secteur de l\u2019\u00e9nergie a affirm\u00e9 que le secteur du p\u00e9trole et du gaz traversait une \u00e9tape d\u00e9terminante r\u00e9gie par les exigences environnementales, l&rsquo;imp\u00e9rative r\u00e9duction des \u00e9missions de gaz \u00e0 effet de serre et la transition vers des sources d&rsquo;\u00e9nergie durables. Ce qui exige, selon le ministre, des solutions adapt\u00e9es et claires. Plus explicite, il a expliqu\u00e9 que le gaz naturel en tant qu&rsquo;\u00e9nergie cl\u00e9 pour la transition \u00e9nerg\u00e9tique mondiale et \u00e9l\u00e9ment fondamental de cette strat\u00e9gie, permettait \u00e0 l&rsquo;Alg\u00e9rie de garantir sa s\u00e9curit\u00e9 \u00e9nerg\u00e9tique tout en r\u00e9pondant \u00e0 la demande croissante de mani\u00e8re durable, renfor\u00e7ant ainsi son r\u00f4le de partenaire international fiable dans le domaine de l&rsquo;\u00e9nergie.&nbsp;&nbsp;Autrement dit, cette nouvelle strat\u00e9gie permettra, selon la m\u00eame source, \u00e0 l\u2019Alg\u00e9rie et au groupe Sonatrach de s\u2019arrimer aux normes et standards internationaux en termes de s\u00e9curit\u00e9 \u00e9nerg\u00e9tique et des r\u00e8gles r\u00e9gissant la protection de l\u2019environnement notamment la r\u00e9duction de l\u2019\u00e9mission des gaz \u00e0 effet de serre.&nbsp;<\/p>\n\n\n\n<p>En sus, l&rsquo;Alg\u00e9rie est pleinement engag\u00e9e dans le d\u00e9veloppement des \u00e9nergies renouvelables, avec pour objectif d&rsquo;atteindre une part importante de la production nationale d&rsquo;\u00e9lectricit\u00e9, pr\u00e9cise-t-il, soutenant que les initiatives visant \u00e0 atteindre 15 gigawatts d&rsquo;\u00e9nergie renouvelable d&rsquo;ici 2035 lui permettront dans une large mesure d&rsquo;atteindre ses objectifs climatiques internationaux.&nbsp;<\/p>\n\n\n\n<p>A cet effet, le ministre a cit\u00e9, dans ce sens, l&rsquo;approche alg\u00e9rienne, qualifi\u00e9e&nbsp;\u00ab&nbsp;d\u2019ambitieuse et responsable&nbsp;\u00bballiant production d&rsquo;\u00e9nergie conventionnelle et d\u00e9veloppement des \u00e9nergies renouvelables, qui place le pays, comme p\u00f4le actif et engag\u00e9 dans le processus de transition \u00e9nerg\u00e9tique dans la r\u00e9gion du Maghreb.<\/p>\n\n\n\n<p>Mohamed Arkab a rappel\u00e9, \u00e9galement, l&rsquo;engagement volontaire du groupe Sonatrach \u00e0 contribuer \u00e0 la lutte contre le changement climatique, \u00e0 travers une \u00e9valuation d\u00e9taill\u00e9e de ses \u00e9missions de gaz \u00e0 effet de serre, laquelle permet de fixer des objectifs ambitieux en termes de r\u00e9duction des \u00e9missions. Et d\u2019ajouter&nbsp;: le groupe Sonatrach s&rsquo;est engag\u00e9 \u00e0 investir un milliard de dollars sur dix ans dans un projet de grande envergure, en l\u2019occurrence le reboisement de 520.000 hectares, pr\u00e9cisant que ce projet environnemental et \u00e9conomique contribuera \u00e0 la s\u00e9questration du carbone, \u00e0 la cr\u00e9ation d&#8217;emplois et au d\u00e9veloppement socio\u00e9conomique en Alg\u00e9rie.<\/p>\n\n\n\n<p>Last but not least, le groupe Sonatrach participe activement \u00e0 des projets pilotes visant \u00e0 assurer une ma\u00eetrise totale de la cha\u00eene de valeur de l&rsquo;hydrog\u00e8ne, selon lui, annon\u00e7ant qu&rsquo;un projet d&rsquo;une capacit\u00e9 de 50 m\u00e9gawatts \u00e9tait \u00e0 l&rsquo;\u00e9tude pour la transformation de l&rsquo;hydrog\u00e8ne vert en ammoniac ou en produits secondaires.<\/p>\n\n\n\n<p>La nouvelle strat\u00e9gie climat du groupe Sonatrach, s\u2019inscrit dans le cadre des objectifs de d\u00e9veloppement durable et de la Convention-cadre des Nations Unies sur les changements climatiques sur lesquels l\u2019Alg\u00e9rie s\u2019est engag\u00e9e et s\u2019articule autour de plusieurs axes tels que, la r\u00e9duction des \u00e9missions des gaz \u00e0 effet de serre, l\u2019augmentation du niveau d\u2019int\u00e9gration des \u00e9nergies renouvelables, ainsi que le d\u00e9veloppement des solutions de s\u00e9questration naturelle et technologique du carbone, avec l\u2019ambition de parvenir \u00e0 un \u00e9quilibre entre nos \u00e9missions de GES et les absorptions par les puits de carbone au cours de la deuxi\u00e8me moiti\u00e9 du si\u00e8cle.<\/p>\n\n\n\n<p><strong>Hakim Aomar&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l&rsquo;\u00c9nergie et des Mines, Mohamed Arkab, a soulign\u00e9, hier \u00e0 Alger, les efforts du secteur de l&rsquo;\u00e9nergie<\/p>\n","protected":false},"author":3,"featured_media":32095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,29],"tags":[],"class_list":["post-54752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le ministre de l&rsquo;\u00c9nergie et des Mines, Mohamed Arkab, a soulign\u00e9, hier \u00e0 Alger, les efforts du secteur de l&rsquo;\u00e9nergie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-22T19:45:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T19:45:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/arkab.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb\",\"datePublished\":\"2024-07-22T19:45:33+00:00\",\"dateModified\":\"2024-07-22T19:45:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/\"},\"wordCount\":769,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/arkab.png\",\"articleSection\":[\"\u00c0 la Une\",\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/\",\"name\":\"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/arkab.png\",\"datePublished\":\"2024-07-22T19:45:33+00:00\",\"dateModified\":\"2024-07-22T19:45:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/arkab.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/arkab.png\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/","og_locale":"fr_FR","og_type":"article","og_title":"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb - La Sentinelle","og_description":"Le ministre de l&rsquo;\u00c9nergie et des Mines, Mohamed Arkab, a soulign\u00e9, hier \u00e0 Alger, les efforts du secteur de l&rsquo;\u00e9nergie","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-07-22T19:45:33+00:00","article_modified_time":"2024-07-22T19:45:35+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/arkab.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb","datePublished":"2024-07-22T19:45:33+00:00","dateModified":"2024-07-22T19:45:35+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/"},"wordCount":769,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/arkab.png","articleSection":["\u00c0 la Une","\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/","name":"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/arkab.png","datePublished":"2024-07-22T19:45:33+00:00","dateModified":"2024-07-22T19:45:35+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/arkab.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/arkab.png","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/arkab-le-gaz-naturel-est-la-cle-de-la-transition-energetique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Arkab: le gaz naturel est \u00ab\u00a0la cl\u00e9 de la transition \u00e9nerg\u00e9tique\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/54752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=54752"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/54752\/revisions"}],"predecessor-version":[{"id":54754,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/54752\/revisions\/54754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/32095"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=54752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=54752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=54752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}