{"id":54755,"date":"2024-07-22T20:47:38","date_gmt":"2024-07-22T19:47:38","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=54755"},"modified":"2024-07-22T20:47:39","modified_gmt":"2024-07-22T19:47:39","slug":"presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/","title":{"rendered":"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0"},"content":{"rendered":"\n<p>Le ministre de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et de l&rsquo;Am\u00e9nagement du territoire, M. Brahim Merad, a appel\u00e9, lundi \u00e0 Alger, les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se mobiliser pour assurer une couverture s\u00e9curitaire optimale de la Pr\u00e9sidentielle pr\u00e9vue le 7 septembre prochain et permettre ainsi aux citoyens d&rsquo;exercer leur droit constitutionnel dans un climat de qui\u00e9tude et de s\u00e9curit\u00e9.<\/p>\n\n\n\n<p>Pr\u00e9sidant la c\u00e9r\u00e9monie de c\u00e9l\u00e9bration du 62e anniversaire de la cr\u00e9ation de la Police alg\u00e9rienne au si\u00e8ge des Unit\u00e9s r\u00e9publicaines de s\u00e9curit\u00e9 (URS) \u00e0 El Hamiz, M. Merad a appel\u00e9, dans son allocution, les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 \u00ab\u00a0continuer \u00e0 garantir la s\u00e9curit\u00e9 du pays et des citoyens\u00a0\u00bb et \u00e0 se mobiliser, en pr\u00e9vision de la Pr\u00e9sidentielle du 7 septembre, pour \u00ab\u00a0assurer une couverture s\u00e9curitaire optimale de cette importante \u00e9ch\u00e9ance qui permettra aux citoyens d&rsquo;exercer leur droit constitutionnel dans un climat de qui\u00e9tude et de s\u00e9curit\u00e9\u00a0\u00bb.<\/p>\n\n\n\n<p>Cet anniversaire est \u00ab\u00a0l&rsquo;occasion d&rsquo;\u00e9valuer les progr\u00e8s notables r\u00e9alis\u00e9s par la S\u00fbret\u00e9 nationale en termes d&rsquo;effectifs, d&rsquo;\u00e9quipements et de m\u00e9thodes de travail reposant sur le professionnalisme, la modernisation et l&rsquo;efficacit\u00e9\u00a0\u00bb, a-t-il dit, estimant que \u00ab\u00a0ces progr\u00e8s ont \u00e9t\u00e9 atteints gr\u00e2ce \u00e0 l&rsquo;investissement dans la ressource humaine et \u00e0 la bonne pr\u00e9paration\u00a0\u00bb.<\/p>\n\n\n\n<p>M. Merad a, par l\u00e0 m\u00eame, rappel\u00e9 les r\u00e9alisations de la Police alg\u00e9rienne au cours des derni\u00e8res ann\u00e9es en termes d&rsquo;accompagnement de la dynamique de d\u00e9veloppement qu&rsquo;a connue notre pays sur tous les plans, conform\u00e9ment \u00e0 l&rsquo;int\u00e9r\u00eat que porte le pr\u00e9sident de la R\u00e9publique \u00e0 la s\u00e9curisation des citoyens.<\/p>\n\n\n\n<p>Entre 2020 et 2024, \u00ab\u00a0185 projets ont \u00e9t\u00e9 inscrits, dont 151 structures professionnelles et 34 structures socioprofessionnelles, pour une enveloppe financi\u00e8re de plus de 23 milliards de DA, tandis que le niveau national de couverture s\u00e9curitaire a atteint pr\u00e8s de 80%, avec un effectif total de plus de 223.000 \u00e9l\u00e9ments et la cr\u00e9ation de six (6) nouvelles sp\u00e9cialit\u00e9s de s\u00e9curit\u00e9\u00a0\u00bb, a-t-il d\u00e9taill\u00e9.<\/p>\n\n\n\n<p>Et d&rsquo;ajouter que les dix nouvelles wilayas cr\u00e9\u00e9es avaient b\u00e9n\u00e9fici\u00e9 de 45% du total des structures inscrites au cours des deux derni\u00e8res ann\u00e9es et d&rsquo;un effectif qualifi\u00e9 estim\u00e9 \u00e0 pr\u00e8s de 8.000 \u00e9l\u00e9ments.<\/p>\n\n\n\n<p>Il a aussi cit\u00e9 \u00ab\u00a0l&rsquo;\u00e9laboration d&rsquo;un plan dans le cadre du renforcement de la s\u00e9curit\u00e9 dans les nouvelles villes et les p\u00f4les urbains et de la lutte contre toutes les formes de criminalit\u00e9, \u00e0 travers la cr\u00e9ation \u00e0 leur niveau de 84 nouvelles structures\u00a0\u00bb.<\/p>\n\n\n\n<p>M. Merad a en outre affirm\u00e9 que la Police alg\u00e9rienne avait \u00ab\u00a0mis en \u0153uvre un programme ambitieux de modernisation et de num\u00e9risation de ses services \u00e0 travers la connexion de 1.000 services de Police \u00e0 la fibre optique, le lancement du projet de services intelligents au niveau de 1.268 structures de s\u00e9curit\u00e9, le d\u00e9veloppement de plusieurs syst\u00e8mes d&rsquo;information et applications et l&rsquo;intensification des activit\u00e9s de coop\u00e9ration et d&rsquo;\u00e9change d&rsquo;expertises aux niveaux r\u00e9gional, continental et international\u00a0\u00bb.<\/p>\n\n\n\n<p>De son c\u00f4t\u00e9, le Directeur g\u00e9n\u00e9ral de la S\u00fbret\u00e9 nationale, Ali Badaoui, a indiqu\u00e9 que la Police alg\u00e9rienne \u00ab\u00a0poursuit, \u00e0 la faveur du soutien des hautes autorit\u00e9s du pays, son processus de d\u00e9veloppement et de modernisation, en \u00e9tant d\u00e9termin\u00e9e \u00e0 franchir un cap qualitatif en mati\u00e8re de performance\u00a0\u00bb.<\/p>\n\n\n\n<p>Il a en outre affirm\u00e9 que la Direction g\u00e9n\u00e9rale de la S\u00fbret\u00e9 nationale \u00ab\u00a0s&rsquo;est attel\u00e9e \u00e0 moderniser et \u00e0 num\u00e9riser ce corps \u00e0 travers l&rsquo;am\u00e9lioration du service public et des m\u00e9thodes de travail, la mise en place de nouveaux m\u00e9canismes de gestion, le recours aux technologies de pointe pour maintenir l&rsquo;ordre et la s\u00e9curit\u00e9 publics et lutter contre la criminalit\u00e9, et la r\u00e9vision du syst\u00e8me de formation pour permettre aux \u00e9l\u00e9ments de la Police d&rsquo;accomplir leurs missions en toute efficacit\u00e9 dans le respect des lois de la R\u00e9publique\u00a0\u00bb.<\/p>\n\n\n\n<p>M. Badaoui a assur\u00e9 que la S\u00fbret\u00e9 nationale \u00e9tait \u00ab\u00a0pr\u00eate \u00e0 relever les nouveaux d\u00e9fis s\u00e9curitaires et \u00e0 coordonner avec l&rsquo;ensemble des partenaires s\u00e9curitaires et civils, notamment l&rsquo;Arm\u00e9e nationale populaire (ANP), pour garantir la s\u00e9curit\u00e9 du pays et l&rsquo;int\u00e9grit\u00e9 des citoyens et de leurs biens\u00a0\u00bb.<\/p>\n\n\n\n<p>A cette occasion, le si\u00e8ge de la direction des Unit\u00e9s r\u00e9publicaines de s\u00e9curit\u00e9 a \u00e9t\u00e9 baptis\u00e9 du nom du d\u00e9funt Moudjahid Mohamed Guenifed lors d&rsquo;une c\u00e9r\u00e9monie pr\u00e9sid\u00e9e par le ministre de l&rsquo;Int\u00e9rieur, qui a ensuite pass\u00e9 en revue les carr\u00e9s des \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale et proc\u00e9d\u00e9 \u00e0 la remise des grades aux \u00e9l\u00e9ments nouvellement promus et \u00e0 la distinction des meilleurs \u00e9l\u00e9ments \u00e0 qui il remit la m\u00e9daille de bravoure et de m\u00e9rite et l&rsquo;attestation minist\u00e9rielle.<\/p>\n\n\n\n<p>Les fonctionnaires partant \u00e0 la retraite ont \u00e9galement \u00e9t\u00e9 distingu\u00e9s \u00e0 cette occasion.<\/p>\n\n\n\n<p>Des d\u00e9monstrations d&rsquo;arts martiaux et de techniques de combat et de self-d\u00e9fense et des exercices de simulation d&rsquo;interventions polici\u00e8res ont \u00e9t\u00e9 ex\u00e9cut\u00e9s dans ce cadre.<\/p>\n\n\n\n<p>La c\u00e9r\u00e9monie a, par ailleurs, \u00e9t\u00e9 marqu\u00e9e par la projection de reportages mettant en avant l&rsquo;\u00e9volution de la Police et ses efforts dans la lutte contre la drogue.<\/p>\n\n\n\n<p>Pour rappel, la c\u00e9r\u00e9monie s&rsquo;est d\u00e9roul\u00e9e en pr\u00e9sence du directeur de Cabinet \u00e0 la Pr\u00e9sidence de la R\u00e9publique, M. Boualem Boualem, de membres du Gouvernement, de cadres sup\u00e9rieurs, de responsables d&rsquo;institutions et d&rsquo;instances officielles, et du Directeur g\u00e9n\u00e9ral de la police palestinienne, le G\u00e9n\u00e9ral-major Youssef Ali Youssef Al Helou, en tant qu&rsquo;invit\u00e9 d&rsquo;honneur.<\/p>\n\n\n\n<p>APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et de l&rsquo;Am\u00e9nagement du territoire, M. Brahim Merad, a appel\u00e9, lundi \u00e0 Alger,<\/p>\n","protected":false},"author":3,"featured_media":46584,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-54755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0 - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0 - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le ministre de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et de l&rsquo;Am\u00e9nagement du territoire, M. Brahim Merad, a appel\u00e9, lundi \u00e0 Alger,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-22T19:47:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T19:47:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/10\/Merad.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0\",\"datePublished\":\"2024-07-22T19:47:38+00:00\",\"dateModified\":\"2024-07-22T19:47:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/\"},\"wordCount\":999,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Merad.jpeg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/\",\"name\":\"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0 - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Merad.jpeg\",\"datePublished\":\"2024-07-22T19:47:38+00:00\",\"dateModified\":\"2024-07-22T19:47:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Merad.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Merad.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/07\\\/22\\\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0 - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/","og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0 - La Sentinelle","og_description":"Le ministre de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et de l&rsquo;Am\u00e9nagement du territoire, M. Brahim Merad, a appel\u00e9, lundi \u00e0 Alger,","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-07-22T19:47:38+00:00","article_modified_time":"2024-07-22T19:47:39+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/10\/Merad.jpeg","type":"image\/jpeg"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0","datePublished":"2024-07-22T19:47:38+00:00","dateModified":"2024-07-22T19:47:39+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/"},"wordCount":999,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/10\/Merad.jpeg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/","name":"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0 - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/10\/Merad.jpeg","datePublished":"2024-07-22T19:47:38+00:00","dateModified":"2024-07-22T19:47:39+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/10\/Merad.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/10\/Merad.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/07\/22\/presidentielle-du-7-septembre-merad-appelle-les-elements-de-la-surete-nationale-a-se\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9sidentielle du 7 septembre: Merad appelle les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale \u00e0 se\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/54755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=54755"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/54755\/revisions"}],"predecessor-version":[{"id":54756,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/54755\/revisions\/54756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/46584"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=54755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=54755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=54755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}