{"id":56230,"date":"2024-08-27T21:34:52","date_gmt":"2024-08-27T20:34:52","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=56230"},"modified":"2024-08-27T21:34:53","modified_gmt":"2024-08-27T20:34:53","slug":"blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/","title":{"rendered":"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers"},"content":{"rendered":"\n<p>L&rsquo;ONU et les Etats-Unis ont appel\u00e9 hier les acteurs politiques en Libye \u00e0 une r\u00e9union \u00ab\u00a0urgente\u00a0\u00bb pour d\u00e9samorcer la crise autour de la Banque centrale (BCL) et le blocus de la production et des exportations de p\u00e9trole.<\/p>\n\n\n\n<p>Exprimant sa \u00ab\u00a0profonde pr\u00e9occupation face \u00e0 la d\u00e9t\u00e9rioration de la situation\u00a0\u00bb, la Mission d&rsquo;appui de l&rsquo;ONU en Libye (Manul) a \u00ab\u00a0convoqu\u00e9 une r\u00e9union d&rsquo;urgence de toutes les parties impliqu\u00e9es dans la crise de la BCL pour atteindre un consensus fond\u00e9 sur des accords politiques, des lois et le principe de l&rsquo;ind\u00e9pendance de la BCL\u00a0\u00bb, selon un communiqu\u00e9. R\u00e9soudre la crise de la BCL \u00ab\u00a0est une n\u00e9cessit\u00e9 urgente\u00a0\u00bb, a soulign\u00e9 la Manul, mettant en garde contre un risque d'\u00a0\u00bbeffondrement financier et \u00e9conomique du pays\u00a0\u00bb.<\/p>\n\n\n\n<p>L&rsquo;ambassade des Etats-Unis en Libye a qualifi\u00e9 cette proposition de \u00ab\u00a0voie \u00e0 suivre pour r\u00e9soudre la crise entourant la Banque centrale\u00a0\u00bb.<\/p>\n\n\n\n<p>Cette nouvelle crise illustre la d\u00e9t\u00e9rioration de la situation en Libye qui vit une crise majeure depuis l&rsquo;assassinat de Mouammar Kadhafi en 2011 et perp\u00e9tuation des divisions dans le pays, malgr\u00e9 les efforts men\u00e9s sous l&rsquo;\u00e9gide de l&rsquo;ONU pour une r\u00e9solution de la crise. Le blocus p\u00e9trolier en Libye et la crise de la BCL sont le fruit des divisions en Libye dirig\u00e9e par deux gouvernements, l&rsquo;un bas\u00e9 \u00e0 Tripoli, dirig\u00e9 par Abdul Hamid Al-Dabaiba et reconnu par la communaut\u00e9 internationale et l&rsquo;ONU, et un gouvernement parall\u00e8le \u00e0 l&rsquo;est, dirig\u00e9 par Oussama Hammad, soutenu par le parlement de Tobrouk et les forces du seigneur de guerre Khalifa Haftar. Cette nouvelle crise a \u00e9t\u00e9 induite par la lutte pour le contr\u00f4le de la BCL. La Banque centrale libyenne, situ\u00e9e \u00e0 Tripoli, est charg\u00e9e de g\u00e9rer les revenus p\u00e9troliers et le budget de l&rsquo;\u00c9tat. Son gouverneur, Al-Siddiq al-Kabir, en poste depuis 2012, fait l&rsquo;objet de critiques croissantes concernant sa gestion des fonds publics. Derni\u00e8rement, ce gouverneur \u00e9tait critiqu\u00e9 pour sa gestion de la manne p\u00e9troli\u00e8re et du budget, consid\u00e9r\u00e9e comme trop favorable au clan Haftar.<\/p>\n\n\n\n<p>L&rsquo;escalade actuelle a \u00e9t\u00e9 d\u00e9clench\u00e9e par l&rsquo;entr\u00e9e d&rsquo;un \u00ab\u00a0Comit\u00e9 pour la passation et la r\u00e9ception des pouvoirs\u00a0\u00bb, nomm\u00e9 par le Conseil pr\u00e9sidentiel de Tripoli, dans les locaux de la Banque centrale. Le gouvernement parall\u00e8le a d\u00e9clar\u00e9, en riposte l&rsquo;\u00e9tat de \u00ab\u00a0force majeure\u00a0\u00bb sur tous les champs p\u00e9troliers et ports du pays. La fermeture des installations p\u00e9troli\u00e8res repr\u00e9sente un coup dur pour l&rsquo;\u00e9conomie libyenne. Le pays, qui poss\u00e8de les plus grandes r\u00e9serves p\u00e9troli\u00e8res d&rsquo;Afrique, avait r\u00e9cemment r\u00e9ussi \u00e0 augmenter sa production \u00e0 environ 1,2 million de barils par jour, se rapprochant des niveaux d&rsquo;avant 2011 (1,5 \u00e0 1,6 million de barils par jour). Cette interruption de la production risque non seulement d&rsquo;affecter les revenus de l&rsquo;\u00c9tat libyen, mais aussi d&rsquo;avoir des r\u00e9percussions sur le march\u00e9 p\u00e9trolier mondial, d\u00e9j\u00e0 tendu en raison des conflits g\u00e9opolitiques en cours. En effet, les deux principaux contrats sur l&rsquo;or noir, le&nbsp;<strong>Brent<\/strong>&nbsp;de mer du Nord et le&nbsp;<strong>WTI<\/strong>&nbsp;cot\u00e9 \u00e0 New York, ont pris tous les deux, lundi, plus de 2%, \u00e0 79,78 dollars le baril pour le premier et 76,53 dollars le baril pour le second.<\/p>\n\n\n\n<p>Lyes Sa\u00efdi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ONU et les Etats-Unis ont appel\u00e9 hier les acteurs politiques en Libye \u00e0 une r\u00e9union \u00ab\u00a0urgente\u00a0\u00bb pour d\u00e9samorcer la crise<\/p>\n","protected":false},"author":6,"featured_media":56231,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[37],"tags":[],"class_list":["post-56230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;ONU et les Etats-Unis ont appel\u00e9 hier les acteurs politiques en Libye \u00e0 une r\u00e9union \u00ab\u00a0urgente\u00a0\u00bb pour d\u00e9samorcer la crise\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-27T20:34:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-27T20:34:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/petrole-libye.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers\",\"datePublished\":\"2024-08-27T20:34:52+00:00\",\"dateModified\":\"2024-08-27T20:34:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/\"},\"wordCount\":583,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/petrole-libye.jpg\",\"articleSection\":[\"Monde\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/\",\"name\":\"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/petrole-libye.jpg\",\"datePublished\":\"2024-08-27T20:34:52+00:00\",\"dateModified\":\"2024-08-27T20:34:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/petrole-libye.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/petrole-libye.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Construction of the pipeline into the sea.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/08\\\/27\\\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/","og_locale":"fr_FR","og_type":"article","og_title":"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers - La Sentinelle","og_description":"L&rsquo;ONU et les Etats-Unis ont appel\u00e9 hier les acteurs politiques en Libye \u00e0 une r\u00e9union \u00ab\u00a0urgente\u00a0\u00bb pour d\u00e9samorcer la crise","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-08-27T20:34:52+00:00","article_modified_time":"2024-08-27T20:34:53+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/petrole-libye.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers","datePublished":"2024-08-27T20:34:52+00:00","dateModified":"2024-08-27T20:34:53+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/"},"wordCount":583,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/petrole-libye.jpg","articleSection":["Monde"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/","name":"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/petrole-libye.jpg","datePublished":"2024-08-27T20:34:52+00:00","dateModified":"2024-08-27T20:34:53+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/petrole-libye.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/petrole-libye.jpg","width":1280,"height":720,"caption":"Construction of the pipeline into the sea."},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/08\/27\/blocus-petrolier-en-libye-lonu-et-washington-appellent-a-des-pourparlers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Blocus p\u00e9trolier en Libye: L&rsquo;ONU et Washington appellent \u00e0 des pourparlers"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/56230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=56230"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/56230\/revisions"}],"predecessor-version":[{"id":56233,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/56230\/revisions\/56233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/56231"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=56230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=56230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=56230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}