{"id":60528,"date":"2024-12-15T12:53:05","date_gmt":"2024-12-15T11:53:05","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=60528"},"modified":"2024-12-15T12:53:06","modified_gmt":"2024-12-15T11:53:06","slug":"ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/","title":{"rendered":"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh"},"content":{"rendered":"\n<p>L&rsquo;ES S\u00e9tif a rat\u00e9 une excellente occasion de s&#8217;emparer seule du leadership de la Ligue 1 Mobilis de football, apr\u00e8s s&rsquo;\u00eatre content\u00e9e d&rsquo;un nul (2-2) \u00e0 domicile, dans le duel au sommet de la 13e journ\u00e9e, disput\u00e9 vendredi soir au stade du 8 mai 1945 contre la JS Kabylie, tandis que le MC Oran est tomb\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale face au MC El Bayadh (1-0), au moment o\u00f9 l&rsquo;ASO Chlef est revenue de tr\u00e8s loin \u00e0 B\u00e9char, pour arracher un pr\u00e9cieux nul (1-1) contre la JS Saoura.<\/p>\n\n\n\n<p>Apr\u00e8s une domination st\u00e9rile pendant pratiquement toute la premi\u00e8re mi-temps, l&rsquo;Aigle noir a r\u00e9ussi \u00e0 trouver le chemin des filets \u00e0 la 43e minute, par l&rsquo;interm\u00e9diaire de Diarra, avant de conc\u00e9der l&rsquo;\u00e9galisation devant Madani, ayant transform\u00e9 un p\u00e9nalty \u00e0 la (66e). Quoique, la joie des Canaris a \u00e9t\u00e9 de courte dur\u00e9e, puisque les S\u00e9tifiens ont r\u00e9ussi \u00e0 reprendre l&rsquo;avantage au score d\u00e8s la remise en jeu, par l&rsquo;interm\u00e9diaire de Cha\u00e2bi (68e). Seulement, au moment o\u00f9 tout le monde s&rsquo;attendait \u00e0 voir l&rsquo;Entente l&#8217;emporter (2-1), Sarr a surgi dans l&rsquo;ultime seconde du temps r\u00e9glementaire, pour offrir un pr\u00e9cieux nul \u00e0 son \u00e9quipe. Le point empoch\u00e9 ce vendredi suffit \u00e0 peine \u00e0 rejoindre les Sanafir \u00e0 cette fameuse premi\u00e8re place, avec 19 points pour chaque club, et idem pour les Canaris, qui rejoignent le MC Oran \u00e0 la troisi\u00e8me place, avec 18 unit\u00e9s. M\u00eame sc\u00e9nario \u00e0 B\u00e9char, o\u00f9 les choses avaient relativement bien commenc\u00e9 pour l&rsquo;\u00e9quipe locale, qui apr\u00e8s maintes tentatives a vu ses efforts r\u00e9compens\u00e9es \u00e0 la 35e, par une ouverture du score sign\u00e9e Ghorab. Une avance qu&rsquo;elle a jalousement d\u00e9fendue jusqu&rsquo;\u00e0 la 90e+6, avant de craquer devant l&rsquo;in\u00e9vitable Sadahine, le nouveau buteur-attitr\u00e9 de l&rsquo;ASO, ayant r\u00e9ussi \u00e0 arracher l&rsquo;\u00e9galisation et \u00e0 sauver son \u00e9quipe d&rsquo;une d\u00e9faite certaine. Le bal de cette 13e journ\u00e9e s&rsquo;\u00e9tait ouvert un peu plus t\u00f4t dans l&rsquo;apr\u00e8s-midi, avec le d\u00e9roulement des matchs MC El Bayadh &#8211; MC Oran (1-0) et NC Magra &#8211; Paradou AC (1-1). Le MCEB avait r\u00e9ussi \u00e0 trouver le chemin des filets d\u00e8s la 24e minute de jeu, gr\u00e2ce \u00e0 Toumi, soit pratiquement au m\u00eame moment qu&rsquo;avait choisi Marouani pour ouvrir le score en faveur du NCM dans l&rsquo;autre match (26e), mais \u00e0 la seule diff\u00e9rence que les gars d&rsquo;El Bayadh \u00e9taient parvenus \u00e0 conserver leur avance jusqu&rsquo;au coup de sifflet final, alors qu&rsquo;\u00e0 Magra, le NCM a fini par conc\u00e9der l&rsquo;\u00e9galisation en toute fin de match. C&rsquo;\u00e9tait devant l&rsquo;in\u00e9vitable Boulebina, qui avait surgi tel un diable \u00e0 la 84e minute de jeu pour offrir \u00e0 son \u00e9quipe un pr\u00e9cieux nul en d\u00e9placement, et face \u00e0 un concurrent direct pour le maintien. Malgr\u00e9 ce bon r\u00e9sultat, les Pacistes sont toujours derniers au classement g\u00e9n\u00e9ral de la Ligue 1 Mobilis, ex aequo avec l&rsquo;US Biskra, avec 10 points pour chaque club, mais ils comptent quatre matchs en retard, faisant que s&rsquo;ils arrivent \u00e0 bien les n\u00e9gocier, ils pourraient remonter sensiblement dans la hi\u00e9rarchie. En revanche, le MC Oran a r\u00e9alis\u00e9 une bien mauvaise op\u00e9ration lors de cette 13e journ\u00e9e, car ayant laiss\u00e9 filer une excellente occasion de s&#8217;emparer provisoirement de la premi\u00e8re place au classement g\u00e9n\u00e9ral, surtout que l&rsquo;actuel leader, le CS Constantine, ne jouera pas ce week-end. Finalement, et aussi courte fut-elle, sa d\u00e9faite \u00e0 El Bayadh a tout remis en cause. Pour rappel, cette 13e journ\u00e9e est amput\u00e9e de trois matchs, en raison de la participation de quatre clubs alg\u00e9riens aux diff\u00e9rentes comp\u00e9titions interclubs de la CAF, en l&rsquo;occurrence, le MC Alger et le CR Belouizdad en Ligue des champions, ainsi que l&rsquo;USM Alger et le CS Constantine en Coupe de la Conf\u00e9d\u00e9ration. Il s&rsquo;agit des matchs CR Belouizdad &#8211; CS Constantine, ES Mostaganem &#8211; MC Alger et USM Alger &#8211; USM Khenchela qui seront reprogramm\u00e9s ult\u00e9rieurement.<\/p>\n\n\n\n<p>APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ES S\u00e9tif a rat\u00e9 une excellente occasion de s&#8217;emparer seule du leadership de la Ligue 1 Mobilis de football, apr\u00e8s<\/p>\n","protected":false},"author":6,"featured_media":60529,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[33],"tags":[],"class_list":["post-60528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;ES S\u00e9tif a rat\u00e9 une excellente occasion de s&#8217;emparer seule du leadership de la Ligue 1 Mobilis de football, apr\u00e8s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-15T11:53:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-15T11:53:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/12\/JSK-ESS.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh\",\"datePublished\":\"2024-12-15T11:53:05+00:00\",\"dateModified\":\"2024-12-15T11:53:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/\"},\"wordCount\":716,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/JSK-ESS.jpeg\",\"articleSection\":[\"Sports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/\",\"name\":\"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/JSK-ESS.jpeg\",\"datePublished\":\"2024-12-15T11:53:05+00:00\",\"dateModified\":\"2024-12-15T11:53:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/JSK-ESS.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/JSK-ESS.jpeg\",\"width\":2048,\"height\":1366},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/15\\\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh - La Sentinelle","og_description":"L&rsquo;ES S\u00e9tif a rat\u00e9 une excellente occasion de s&#8217;emparer seule du leadership de la Ligue 1 Mobilis de football, apr\u00e8s","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-12-15T11:53:05+00:00","article_modified_time":"2024-12-15T11:53:06+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/12\/JSK-ESS.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh","datePublished":"2024-12-15T11:53:05+00:00","dateModified":"2024-12-15T11:53:06+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/"},"wordCount":716,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/12\/JSK-ESS.jpeg","articleSection":["Sports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/","name":"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/12\/JSK-ESS.jpeg","datePublished":"2024-12-15T11:53:05+00:00","dateModified":"2024-12-15T11:53:06+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/12\/JSK-ESS.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/12\/JSK-ESS.jpeg","width":2048,"height":1366},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/15\/ligue-1-mobilis-13e-journee-less-rate-le-coche-le-mco-tombe-a-el-bayadh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Ligue 1 Mobilis (13e journ\u00e9e) : L&rsquo;ESS rate le coche, le MCO tombe \u00e0 El Bayadh"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/60528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=60528"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/60528\/revisions"}],"predecessor-version":[{"id":60531,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/60528\/revisions\/60531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/60529"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=60528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=60528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=60528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}