{"id":60806,"date":"2024-12-23T12:29:51","date_gmt":"2024-12-23T11:29:51","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=60806"},"modified":"2024-12-23T12:29:52","modified_gmt":"2024-12-23T11:29:52","slug":"sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/","title":{"rendered":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d&rsquo;invention dont dispose Sonatrach avait augment\u00e9 \u00e0 30 brevets, faisant \u00e9tat du lancement de 40 projets de recherche et de d\u00e9veloppement. Cette annonce a \u00e9t\u00e9 faite lors de sa participation aux travaux d&rsquo;un s\u00e9minaire national intitul\u00e9 \u00ab\u00a0Strat\u00e9gie nationale de l&rsquo;innovation : Alg\u00e9rie horizon 2027\u00a0\u00bb, organis\u00e9 samedi \u00e0 Alger, par le Conseil national de la recherche scientifique et des technologies (CNRST), en pr\u00e9sence de son pr\u00e9sident, Mohamed Tahar Abadlia, et de PDG d&rsquo;entreprises nationales et priv\u00e9es membres de ce conseil, ainsi que de chercheurs et d&rsquo;experts relevant de divers secteurs. Selon M. Hachichi, les brevets d&rsquo;invention du Groupe a augment\u00e9 d&rsquo;un seul brevet en 2020 \u00e0 environ 30 brevets en 2024, souligne le communiqu\u00e9, faisant \u00e9tat du lancement de pr\u00e8s de 40 projets de recherche et de d\u00e9veloppement dont 70% sont r\u00e9alis\u00e9s dans le cadre de partenariats nationaux et internationaux. Le PDG du Groupe public a mis l&rsquo;accent dans son allocution sur l&rsquo;importance de la recherche, du d\u00e9veloppement et de l&rsquo;innovation, des \u00e9l\u00e9ments cl\u00e9s pour soutenir la transformation industrielle et r\u00e9aliser le d\u00e9veloppement durable dans le secteur de l&rsquo;\u00e9nergie, soulignant le r\u00f4le \u00ab\u00a0pionnier\u00a0\u00bb du Groupe dans l&rsquo;adoption de techniques modernes et le d\u00e9veloppement de solutions novatrices pour relever les d\u00e9fis environnementaux et \u00e9nerg\u00e9tiques actuels, selon la m\u00eame source. Le PDG de Sonatrach a soulign\u00e9 par ailleurs, \u00ab\u00a0l&rsquo;engagement de son Groupe \u00e0 renforcer la coop\u00e9ration avec les universit\u00e9s, les centres de recherche et les start-up afin d&rsquo;\u00e9tablir un syst\u00e8me global soutenant l&rsquo;innovation\u00a0\u00bb, ajoute le communiqu\u00e9. \u00ab\u00a0L&rsquo;investissement dans l&rsquo;innovation n&rsquo;est pas seulement un moyen de relever les d\u00e9fis actuels, mais il s&rsquo;agit, \u00e9galement, d&rsquo;une opportunit\u00e9 pour la refonte du secteur de l&rsquo;\u00e9nergie en vue de davantage de durabilit\u00e9 et de responsabilit\u00e9\u00a0\u00bb a soutenu M. Hachichi. Il a \u00e9galement mis l&rsquo;accent sur l&rsquo;importance du s\u00e9minaire national \u00ab\u00a0Strat\u00e9gie nationale de l&rsquo;innovation en Alg\u00e9rie\u00a0\u00bb, \u00e9tant \u00ab\u00a0une plateforme d&rsquo;\u00e9change d&rsquo;exp\u00e9riences et d&rsquo;encouragement d\u2019id\u00e9es, \u00e0 m\u00eame de cr\u00e9er un \u00e9cosyst\u00e8me favorable \u00e0 l&rsquo;innovation en Alg\u00e9rie\u00a0\u00bb. Dans le cadre de ce s\u00e9minaire, le PDG de Sonatrach a \u00e9t\u00e9 distingu\u00e9 par le pr\u00e9sident du CNRST, qui lui a remis un troph\u00e9e en reconnaissance des efforts d\u00e9ploy\u00e9s par Sonatrach pour soutenir la recherche scientifique et promouvoir l&rsquo;innovation dans le secteur de l&rsquo;\u00e9nergie, conclut la m\u00eame source.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d&rsquo;invention dont dispose<\/p>\n","protected":false},"author":6,"featured_media":33165,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_bluesky_share_type":"","_mastodon_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[29],"tags":[],"class_list":["post-60806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d&#039;invention dont dispose Sonatrach avait augment\u00e9 \u00e0 30 brevets, faisant \u00e9tat du lancement de 40 projets de recherche et de d\u00e9veloppement. Cette annonce a \u00e9t\u00e9 faite lors de sa participation aux travaux d&#039;un s\u00e9minaire national intitul\u00e9 &quot;Strat\u00e9gie nationale\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Sentinelle - Quotidien national d&#039;information\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sonatrach : 30 brevets d\u2019invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle\" \/>\n\t\t<meta property=\"og:description\" content=\"Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d&#039;invention dont dispose Sonatrach avait augment\u00e9 \u00e0 30 brevets, faisant \u00e9tat du lancement de 40 projets de recherche et de d\u00e9veloppement. Cette annonce a \u00e9t\u00e9 faite lors de sa participation aux travaux d&#039;un s\u00e9minaire national intitul\u00e9 &quot;Strat\u00e9gie nationale\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif\" \/>\n\t\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-12-23T11:29:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-12-23T11:29:52+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/azzedine.lasentinelle.1\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sonatrach : 30 brevets d\u2019invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d&#039;invention dont dispose Sonatrach avait augment\u00e9 \u00e0 30 brevets, faisant \u00e9tat du lancement de 40 projets de recherche et de d\u00e9veloppement. Cette annonce a \u00e9t\u00e9 faite lors de sa participation aux travaux d&#039;un s\u00e9minaire national intitul\u00e9 &quot;Strat\u00e9gie nationale\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#blogposting\",\"name\":\"Sonatrach : 30 brevets d\\u2019invention et 40 projets de recherche et de d\\u00e9veloppement enregistr\\u00e9s - La Sentinelle\",\"headline\":\"Sonatrach\\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\\u00e9veloppement enregistr\\u00e9s\",\"author\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"width\":1349,\"height\":900},\"datePublished\":\"2024-12-23T12:29:51+01:00\",\"dateModified\":\"2024-12-23T12:29:52+01:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#webpage\"},\"articleSection\":\"\\u00c9conomie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lasentinelle.dz\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/category\\\/economie\\\/#listItem\",\"name\":\"\\u00c9conomie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/category\\\/economie\\\/#listItem\",\"position\":2,\"name\":\"\\u00c9conomie\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/category\\\/economie\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#listItem\",\"name\":\"Sonatrach\\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\\u00e9veloppement enregistr\\u00e9s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#listItem\",\"position\":3,\"name\":\"Sonatrach\\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\\u00e9veloppement enregistr\\u00e9s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/category\\\/economie\\\/#listItem\",\"name\":\"\\u00c9conomie\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"La Sentinelle La Sentinelle\",\"description\":\"Quotidien national d'information\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/cropped-la-sentinelle-earth-golden-anima-5.gif\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#organizationLogo\",\"width\":450,\"height\":213},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/azzedine.lasentinelle.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#webpage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/\",\"name\":\"Sonatrach : 30 brevets d\\u2019invention et 40 projets de recherche et de d\\u00e9veloppement enregistr\\u00e9s - La Sentinelle\",\"description\":\"Le Pr\\u00e9sident directeur g\\u00e9n\\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\\u00e9 que le nombre de brevets d'invention dont dispose Sonatrach avait augment\\u00e9 \\u00e0 30 brevets, faisant \\u00e9tat du lancement de 40 projets de recherche et de d\\u00e9veloppement. Cette annonce a \\u00e9t\\u00e9 faite lors de sa participation aux travaux d'un s\\u00e9minaire national intitul\\u00e9 \\\"Strat\\u00e9gie nationale\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#mainImage\",\"width\":1349,\"height\":900},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#mainImage\"},\"datePublished\":\"2024-12-23T12:29:51+01:00\",\"dateModified\":\"2024-12-23T12:29:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d'information\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sonatrach : 30 brevets d\u2019invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle","description":"Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d'invention dont dispose Sonatrach avait augment\u00e9 \u00e0 30 brevets, faisant \u00e9tat du lancement de 40 projets de recherche et de d\u00e9veloppement. Cette annonce a \u00e9t\u00e9 faite lors de sa participation aux travaux d'un s\u00e9minaire national intitul\u00e9 \"Strat\u00e9gie nationale","canonical_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#blogposting","name":"Sonatrach : 30 brevets d\u2019invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle","headline":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s","author":{"@id":"https:\/\/lasentinelle.dz\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","width":1349,"height":900},"datePublished":"2024-12-23T12:29:51+01:00","dateModified":"2024-12-23T12:29:52+01:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#webpage"},"isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#webpage"},"articleSection":"\u00c9conomie"},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz#listItem","position":1,"name":"Home","item":"https:\/\/lasentinelle.dz","nextItem":{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/category\/economie\/#listItem","name":"\u00c9conomie"}},{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/category\/economie\/#listItem","position":2,"name":"\u00c9conomie","item":"https:\/\/lasentinelle.dz\/index.php\/category\/economie\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#listItem","name":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#listItem","position":3,"name":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s","previousItem":{"@type":"ListItem","@id":"https:\/\/lasentinelle.dz\/index.php\/category\/economie\/#listItem","name":"\u00c9conomie"}}]},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"La Sentinelle La Sentinelle","description":"Quotidien national d'information","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#organizationLogo","width":450,"height":213},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/azzedine.lasentinelle.1"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/author\/admin\/#author","url":"https:\/\/lasentinelle.dz\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#webpage","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/","name":"Sonatrach : 30 brevets d\u2019invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle","description":"Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d'invention dont dispose Sonatrach avait augment\u00e9 \u00e0 30 brevets, faisant \u00e9tat du lancement de 40 projets de recherche et de d\u00e9veloppement. Cette annonce a \u00e9t\u00e9 faite lors de sa participation aux travaux d'un s\u00e9minaire national intitul\u00e9 \"Strat\u00e9gie nationale","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#breadcrumblist"},"author":{"@id":"https:\/\/lasentinelle.dz\/author\/admin\/#author"},"creator":{"@id":"https:\/\/lasentinelle.dz\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#mainImage","width":1349,"height":900},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#mainImage"},"datePublished":"2024-12-23T12:29:51+01:00","dateModified":"2024-12-23T12:29:52+01:00"},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d'information","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"La Sentinelle - Quotidien national d'information","og:type":"article","og:title":"Sonatrach : 30 brevets d\u2019invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle","og:description":"Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d'invention dont dispose Sonatrach avait augment\u00e9 \u00e0 30 brevets, faisant \u00e9tat du lancement de 40 projets de recherche et de d\u00e9veloppement. Cette annonce a \u00e9t\u00e9 faite lors de sa participation aux travaux d'un s\u00e9minaire national intitul\u00e9 &quot;Strat\u00e9gie nationale","og:url":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/","og:image":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif","og:image:secure_url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif","og:image:width":450,"og:image:height":213,"article:published_time":"2024-12-23T11:29:51+00:00","article:modified_time":"2024-12-23T11:29:52+00:00","article:publisher":"https:\/\/www.facebook.com\/azzedine.lasentinelle.1","twitter:card":"summary_large_image","twitter:title":"Sonatrach : 30 brevets d\u2019invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle","twitter:description":"Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d'invention dont dispose Sonatrach avait augment\u00e9 \u00e0 30 brevets, faisant \u00e9tat du lancement de 40 projets de recherche et de d\u00e9veloppement. Cette annonce a \u00e9t\u00e9 faite lors de sa participation aux travaux d'un s\u00e9minaire national intitul\u00e9 &quot;Strat\u00e9gie nationale","twitter:image":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/cropped-la-sentinelle-earth-golden-anima-5.gif"},"aioseo_meta_data":{"post_id":"60806","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-05-10 17:34:22","updated":"2026-05-10 17:34:22","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lasentinelle.dz\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lasentinelle.dz\/index.php\/category\/economie\/\" title=\"\u00c9conomie\">\u00c9conomie<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSonatrach : 30 brevets d\u2019invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/lasentinelle.dz"},{"label":"\u00c9conomie","link":"https:\/\/lasentinelle.dz\/index.php\/category\/economie\/"},{"label":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d&rsquo;invention dont dispose\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-23T11:29:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-23T11:29:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1349\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s\",\"datePublished\":\"2024-12-23T11:29:51+00:00\",\"dateModified\":\"2024-12-23T11:29:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/\",\"name\":\"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"datePublished\":\"2024-12-23T11:29:51+00:00\",\"dateModified\":\"2024-12-23T11:29:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Sonatrach-1.png\",\"width\":1349,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/23\\\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/","og_locale":"fr_FR","og_type":"article","og_title":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle","og_description":"Le Pr\u00e9sident directeur g\u00e9n\u00e9ral (PDG) du groupe Sonatrach, Rachid Hachichi, a indiqu\u00e9 que le nombre de brevets d&rsquo;invention dont dispose","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-12-23T11:29:51+00:00","article_modified_time":"2024-12-23T11:29:52+00:00","og_image":[{"width":1349,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s","datePublished":"2024-12-23T11:29:51+00:00","dateModified":"2024-12-23T11:29:52+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/","name":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","datePublished":"2024-12-23T11:29:51+00:00","dateModified":"2024-12-23T11:29:52+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/12\/Sonatrach-1.png","width":1349,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/23\/sonatrach-30-brevets-dinvention-et-40-projets-de-recherche-et-de-developpement-enregistres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Sonatrach\u00a0: 30 brevets d&rsquo;invention et 40 projets de recherche et de d\u00e9veloppement enregistr\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/60806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=60806"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/60806\/revisions"}],"predecessor-version":[{"id":60808,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/60806\/revisions\/60808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/33165"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=60806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=60806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=60806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}