{"id":61027,"date":"2024-12-26T12:31:42","date_gmt":"2024-12-26T11:31:42","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=61027"},"modified":"2024-12-28T13:01:36","modified_gmt":"2024-12-28T12:01:36","slug":"la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/","title":{"rendered":"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le gouvernement, r\u00e9uni hier sous la pr\u00e9sidence du Premier ministre Nadir Larbaoui, a examin\u00e9 plusieurs dossiers majeurs, avec en t\u00eate de liste un avant-projet de loi portant sur la modification du r\u00e9gime des assurances sociales, particuli\u00e8rement en ce qui concerne le cong\u00e9 de maternit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette r\u00e9union gouvernementale s&rsquo;inscrit dans le cadre des engagements pris par le Pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, en faveur de l&rsquo;autonomisation et de la promotion des droits des femmes. L&rsquo;avant-projet de loi examin\u00e9 vise \u00e0 modifier et compl\u00e9ter la loi n\u00b083-11 du 2 juillet 1983 relative aux assurances sociales, avec pour objectif principal la prolongation de la dur\u00e9e du cong\u00e9 de maternit\u00e9, actuellement fix\u00e9e \u00e0 98 jours. Il est utile de rappeler dans ce sens que le Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;Union g\u00e9n\u00e9rale des travailleurs alg\u00e9riens (UGTA), Amar Takdjout, qui avait r\u00e9v\u00e9l\u00e9 au mois de mai dernier, avoir sollicit\u00e9 aupr\u00e8s du pr\u00e9sident de la R\u00e9publique une extension du cong\u00e9 de maternit\u00e9, particuli\u00e8rement pour les cas d&rsquo;accouchements avec malformations. L&rsquo;UGTA avait \u00e9galement propos\u00e9 l&rsquo;introduction d&rsquo;un r\u00e9gime de travail \u00e0 mi-temps pour ces situations particuli\u00e8res, une proposition qui avait re\u00e7u un accord de principe de la part du pr\u00e9sident Tebboune. La d\u00e9marche s&rsquo;aligne par ailleurs sur les recommandations de l&rsquo;Organisation mondiale de la Sant\u00e9 (OMS), qui pr\u00e9conise l&rsquo;allongement des cong\u00e9s de maternit\u00e9 et des heures d&rsquo;allaitement, soulignant leur importance cruciale dans le d\u00e9veloppement physique et mental des nouveau-n\u00e9s. Au-del\u00e0 de ce dossier prioritaire, le gouvernement s&rsquo;est \u00e9galement pench\u00e9 sur plusieurs autres questions strat\u00e9giques. Une attention particuli\u00e8re a \u00e9t\u00e9 port\u00e9e \u00e0 la modernisation du secteur de la justice, avec la pr\u00e9sentation d&rsquo;une communication d\u00e9taillant les mesures prises pour am\u00e9liorer les prestations des services publics judiciaires. Cette initiative s&rsquo;inscrit dans le cadre plus large de la transformation num\u00e9rique du secteur, conform\u00e9ment aux r\u00e9formes profondes initi\u00e9es par le Pr\u00e9sident de la R\u00e9publique pour moderniser l&rsquo;appareil judiciaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De nouvelles conditions pour les \u00e9tudiants \u00e9trangers<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le domaine de l&rsquo;enseignement sup\u00e9rieur, le gouvernement a finalis\u00e9 l&rsquo;examen d&rsquo;un projet de d\u00e9cret pr\u00e9sidentiel d\u00e9finissant les conditions et modalit\u00e9s d&rsquo;admission des \u00e9tudiants \u00e9trangers dans les \u00e9tablissements alg\u00e9riens d&rsquo;enseignement et de formation sup\u00e9rieurs. Cette mesure s&rsquo;inscrit dans une strat\u00e9gie plus vaste d&rsquo;ouverture de l&rsquo;universit\u00e9 alg\u00e9rienne et de renforcement de son attractivit\u00e9 internationale. Elle fait \u00e9cho aux engagements r\u00e9cents du pays, qui offre d\u00e9j\u00e0 2 000 bourses d&rsquo;\u00e9tudes dans l&rsquo;enseignement sup\u00e9rieur et 500 bourses dans la formation professionnelle aux \u00e9tudiants africains, des chiffres que le pr\u00e9sident Tebboune s&rsquo;est engag\u00e9 \u00e0 augmenter lors de la r\u00e9cente Conf\u00e9rence continentale sur l&rsquo;\u00e9ducation \u00e0 Nouakchott.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rappelons dans ce sens que Rachid Hamdi, directeur de la coop\u00e9ration au minist\u00e8re de l&rsquo;Enseignement sup\u00e9rieur et de la Recherche scientifique, a annonc\u00e9 il y a quelques jours la pr\u00e9paration d&rsquo;un texte r\u00e9glementaire qui permettrait \u00e0 tous les \u00e9tablissements universitaires alg\u00e9riens d&rsquo;accueillir des candidatures individuelles d&rsquo;\u00e9tudiants internationaux, toutes nationalit\u00e9s confondues. Enfin, le gouvernement a examin\u00e9 un projet de d\u00e9cret ex\u00e9cutif concernant les conditions et modalit\u00e9s de d\u00e9classement des terres relevant du domaine public forestier. Ce texte vise \u00e0 renforcer les mesures de protection des richesses foresti\u00e8res, en application des dispositions de la loi n\u00b023-21 du 23 d\u00e9cembre 2023 relative aux for\u00eats et aux richesses foresti\u00e8res.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lyna Larbi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gouvernement, r\u00e9uni hier sous la pr\u00e9sidence du Premier ministre Nadir Larbaoui, a examin\u00e9 plusieurs dossiers majeurs, avec en t\u00eate<\/p>\n","protected":false},"author":6,"featured_media":6126,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-61027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9 - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9 - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le gouvernement, r\u00e9uni hier sous la pr\u00e9sidence du Premier ministre Nadir Larbaoui, a examin\u00e9 plusieurs dossiers majeurs, avec en t\u00eate\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-26T11:31:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-28T12:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/CNAS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9\",\"datePublished\":\"2024-12-26T11:31:42+00:00\",\"dateModified\":\"2024-12-28T12:01:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/\"},\"wordCount\":630,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/CNAS.jpg\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/\",\"name\":\"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9 - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/CNAS.jpg\",\"datePublished\":\"2024-12-26T11:31:42+00:00\",\"dateModified\":\"2024-12-28T12:01:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/CNAS.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/CNAS.jpg\",\"width\":2000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2024\\\/12\\\/26\\\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9 - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/","og_locale":"fr_FR","og_type":"article","og_title":"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9 - La Sentinelle","og_description":"Le gouvernement, r\u00e9uni hier sous la pr\u00e9sidence du Premier ministre Nadir Larbaoui, a examin\u00e9 plusieurs dossiers majeurs, avec en t\u00eate","og_url":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2024-12-26T11:31:42+00:00","article_modified_time":"2024-12-28T12:01:36+00:00","og_image":[{"width":2000,"height":1000,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/CNAS.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9","datePublished":"2024-12-26T11:31:42+00:00","dateModified":"2024-12-28T12:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/"},"wordCount":630,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/CNAS.jpg","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/","url":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/","name":"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9 - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/CNAS.jpg","datePublished":"2024-12-26T11:31:42+00:00","dateModified":"2024-12-28T12:01:36+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/CNAS.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/08\/CNAS.jpg","width":2000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2024\/12\/26\/la-loi-sur-les-assurances-sociales-sur-la-table-du-gouvernement-le-conge-de-maternite-sera-prolonge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"La loi sur les assurances sociales sur la table du Gouvernement: Le cong\u00e9 de maternit\u00e9 sera prolong\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/61027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=61027"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/61027\/revisions"}],"predecessor-version":[{"id":61028,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/61027\/revisions\/61028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/6126"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=61027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=61027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=61027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}