{"id":61235,"date":"2025-01-02T11:31:49","date_gmt":"2025-01-02T10:31:49","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=61235"},"modified":"2025-01-04T11:32:32","modified_gmt":"2025-01-04T10:32:32","slug":"lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/","title":{"rendered":"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e"},"content":{"rendered":"\n<p><strong>La Palestine et l\u2019Afrique au c\u0153ur des priorit\u00e9s<\/strong><\/p>\n\n\n\n<p>L&rsquo;ann\u00e9e 2025 s&rsquo;ouvre sous le signe d&rsquo;une intense activit\u00e9 diplomatique pour l&rsquo;Alg\u00e9rie qui a pris hier la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 des Nations unies pour le mois de janvier. Cette pr\u00e9sidence intervient un an apr\u00e8s l&rsquo;\u00e9lection de l&rsquo;Alg\u00e9rie en tant que membre non permanent de cet organe onusien, et repr\u00e9sente une opportunit\u00e9 majeure pour le pays de renforcer son r\u00f4le sur la sc\u00e8ne internationale tout en d\u00e9fendant les causes qui lui sont ch\u00e8res.<\/p>\n\n\n\n<p>La situation au Moyen-Orient, particuli\u00e8rement la question palestinienne, figure au premier rang des priorit\u00e9s de la pr\u00e9sidence alg\u00e9rienne. Dans ce contexte, l&rsquo;Alg\u00e9rie pr\u00e9voit d&rsquo;organiser au niveau minist\u00e9riel le d\u00e9bat public trimestriel du Conseil sur \u00ab\u00a0La situation au Moyen-Orient, y compris la question palestinienne\u00a0\u00bb, un \u00e9v\u00e9nement qui devrait voir la participation du Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;ONU, Antonio Guterres. Cette initiative s&rsquo;inscrit dans la continuit\u00e9 des efforts diplomatiques d\u00e9ploy\u00e9s par l&rsquo;Alg\u00e9rie, qui ont notamment abouti en mars 2024 \u00e0 l&rsquo;adoption d&rsquo;une r\u00e9solution exigeant un cessez-le-feu \u00ab\u00a0imm\u00e9diat\u00a0\u00bb et \u00ab\u00a0permanent\u00a0\u00bb \u00e0 Ghaza, apr\u00e8s plusieurs tentatives infructueuses bloqu\u00e9es par le v\u00e9to am\u00e9ricain. L&rsquo;engagement de l&rsquo;Alg\u00e9rie sur la question palestinienne s&rsquo;est \u00e9galement manifest\u00e9 \u00e0 travers ses efforts pour relancer la question de l&rsquo;adh\u00e9sion pleine et enti\u00e8re de l&rsquo;\u00c9tat de Palestine \u00e0 l&rsquo;ONU, dans l&rsquo;optique de concr\u00e9tiser la solution \u00e0 deux \u00c9tats, conform\u00e9ment \u00e0 la l\u00e9galit\u00e9 internationale. Cette d\u00e9marche s&rsquo;inscrit dans une vision plus large visant \u00e0 \u00e9tablir une paix juste et durable au Moyen-Orient. La pr\u00e9sidence alg\u00e9rienne ne se limitera pas \u00e0 la question palestinienne. Le programme pr\u00e9voit \u00e9galement des r\u00e9unions cruciales sur le processus politique et la situation humanitaire en Syrie, ainsi que sur le Y\u00e9men, avec la participation attendue de Hans Grundberg, l&rsquo;envoy\u00e9 sp\u00e9cial des Nations unies pour le Y\u00e9men, et d&rsquo;un repr\u00e9sentant du Bureau de la coordination des affaires humanitaires (OCHA).<\/p>\n\n\n\n<p>Un autre axe majeur de la pr\u00e9sidence alg\u00e9rienne concerne la lutte contre le terrorisme en Afrique. Une r\u00e9union de haut niveau sera organis\u00e9e sur ce th\u00e8me, comme l&rsquo;a soulign\u00e9 le ministre d&rsquo;\u00c9tat, ministre des Affaires \u00e9trang\u00e8res, Ahmed Attaf, lors d\u2019une conf\u00e9rence de presse tenue lundi \u00e0 Alger. Cette r\u00e9union vise \u00e0 examiner l&rsquo;expansion pr\u00e9occupante des activit\u00e9s terroristes sur le continent africain et leurs implications pour la s\u00e9curit\u00e9 et la stabilit\u00e9 des pays concern\u00e9s. Cette pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 repr\u00e9sente pour l&rsquo;Alg\u00e9rie une plateforme id\u00e9ale pour porter la voix des pays arabes et africains et d\u00e9fendre leurs int\u00e9r\u00eats au plus haut niveau de la diplomatie internationale. Elle t\u00e9moigne \u00e9galement de la volont\u00e9 de l&rsquo;Alg\u00e9rie, sous la direction du pr\u00e9sident Abdelmadjid Tebboune, de jouer un r\u00f4le actif dans la r\u00e9solution des crises r\u00e9gionales et internationales, tout en promouvant le dialogue et la recherche de solutions pacifiques aux conflits.<\/p>\n\n\n\n<p>Salim Amokrane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Palestine et l\u2019Afrique au c\u0153ur des priorit\u00e9s L&rsquo;ann\u00e9e 2025 s&rsquo;ouvre sous le signe d&rsquo;une intense activit\u00e9 diplomatique pour l&rsquo;Alg\u00e9rie<\/p>\n","protected":false},"author":6,"featured_media":61236,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-61235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La Palestine et l\u2019Afrique au c\u0153ur des priorit\u00e9s L&rsquo;ann\u00e9e 2025 s&rsquo;ouvre sous le signe d&rsquo;une intense activit\u00e9 diplomatique pour l&rsquo;Alg\u00e9rie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-02T10:31:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-04T10:32:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/01\/algerie-CS.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e\",\"datePublished\":\"2025-01-02T10:31:49+00:00\",\"dateModified\":\"2025-01-04T10:32:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/\"},\"wordCount\":565,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/algerie-CS.jpeg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/\",\"name\":\"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/algerie-CS.jpeg\",\"datePublished\":\"2025-01-02T10:31:49+00:00\",\"dateModified\":\"2025-01-04T10:32:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/algerie-CS.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/algerie-CS.jpeg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/01\\\/02\\\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e - La Sentinelle","og_description":"La Palestine et l\u2019Afrique au c\u0153ur des priorit\u00e9s L&rsquo;ann\u00e9e 2025 s&rsquo;ouvre sous le signe d&rsquo;une intense activit\u00e9 diplomatique pour l&rsquo;Alg\u00e9rie","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-01-02T10:31:49+00:00","article_modified_time":"2025-01-04T10:32:32+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/01\/algerie-CS.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e","datePublished":"2025-01-02T10:31:49+00:00","dateModified":"2025-01-04T10:32:32+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/"},"wordCount":565,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/01\/algerie-CS.jpeg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/","name":"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/01\/algerie-CS.jpeg","datePublished":"2025-01-02T10:31:49+00:00","dateModified":"2025-01-04T10:32:32+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/01\/algerie-CS.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/01\/algerie-CS.jpeg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/01\/02\/lalgerie-prend-la-presidence-du-conseil-de-securite-de-lonu-en-ce-debut-dannee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"L\u2019Alg\u00e9rie prend la pr\u00e9sidence du Conseil de s\u00e9curit\u00e9 de l\u2019ONU en ce d\u00e9but d\u2019ann\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/61235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=61235"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/61235\/revisions"}],"predecessor-version":[{"id":61237,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/61235\/revisions\/61237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/61236"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=61235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=61235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=61235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}