{"id":62987,"date":"2025-02-16T13:10:03","date_gmt":"2025-02-16T12:10:03","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=62987"},"modified":"2025-02-16T13:10:04","modified_gmt":"2025-02-16T12:10:04","slug":"el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/","title":{"rendered":"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis"},"content":{"rendered":"\n<p>Les \u00e9l\u00e9ments de la brigade de lutte contre les d\u00e9lits \u00e9conomiques et financiers sont parvenus \u00e0 mettre fin \u00e0 l\u2019activit\u00e9 criminelle d\u2019un r\u00e9seau de trafic de m\u00e9taux pr\u00e9cieux et de devises. Selon les informations confi\u00e9es par une source s\u00e9curitaire, cette op\u00e9ration de qualit\u00e9 fait suite \u00e0 l\u2019exploitation d\u2019informations, faisant \u00e9tat d\u2019une tentative de faire passer de l\u2019autre c\u00f4t\u00e9 de la fronti\u00e8re terrestre Est du pays, une quantit\u00e9 d\u2019or et une importante somme en devise. Un v\u00e9hicule touristique signal\u00e9 a \u00e9t\u00e9 intercept\u00e9 sur l&rsquo;autoroute Est-Ouest. Il devait se rendre en Tunisie via le poste frontalier d&rsquo;Oum E\u2019Tboul commune d\u2019El Kala, dans l\u2019extr\u00eame Est de la wilaya d\u2019El Tarf, a-t-on pr\u00e9cis\u00e9. Les deux individus, dont une femme ont fait l\u2019objet d\u2019une v\u00e9rification identitaire, et la fouille du v\u00e9hicule a donn\u00e9e lieu \u00e0 la d\u00e9couverte d\u2019une importante quantit\u00e9 d&rsquo;or, estim\u00e9e \u00e0 3.543 grammes et 50.430 euros en plus un ch\u00e8que du tr\u00e9sor d&rsquo;une valeur de 7.500 euros, a d\u00e9taill\u00e9 notre source. Les deux pr\u00e9venus originaires respectivement d\u2019Alger et de Sidi Bel Abb\u00e8s, ont \u00e9t\u00e9 arr\u00eat\u00e9s et ont fait l\u2019objet d\u2019une enqu\u00eate, puis soumis aux mesures judiciaires et juridiques d\u2019usages. Ils ont \u00e9t\u00e9 d\u00e9f\u00e9r\u00e9s par devant le tribunal de Dr\u00e9an, relevant de la cour de justice de la wilaya d\u2019El Tarf, pour constitution d&rsquo;une bande de malfaiteurs, l\u2019atteinte \u00e0 l&rsquo;\u00e9conomie nationale et le trafic de devises, ont conclu nos sources.<\/p>\n\n\n\n<p><strong>S<\/strong><strong>. Chahine<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9l\u00e9ments de la brigade de lutte contre les d\u00e9lits \u00e9conomiques et financiers sont parvenus \u00e0 mettre fin \u00e0 l\u2019activit\u00e9<\/p>\n","protected":false},"author":6,"featured_media":55259,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[31],"tags":[],"class_list":["post-62987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Les \u00e9l\u00e9ments de la brigade de lutte contre les d\u00e9lits \u00e9conomiques et financiers sont parvenus \u00e0 mettre fin \u00e0 l\u2019activit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-16T12:10:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-16T12:10:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/devises.png\" \/>\n\t<meta property=\"og:image:width\" content=\"764\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis\",\"datePublished\":\"2025-02-16T12:10:03+00:00\",\"dateModified\":\"2025-02-16T12:10:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/\"},\"wordCount\":287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/devises.png\",\"articleSection\":[\"R\u00e9gions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/\",\"name\":\"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/devises.png\",\"datePublished\":\"2025-02-16T12:10:03+00:00\",\"dateModified\":\"2025-02-16T12:10:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/devises.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/devises.png\",\"width\":764,\"height\":513},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/02\\\/16\\\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/","og_locale":"fr_FR","og_type":"article","og_title":"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis - La Sentinelle","og_description":"Les \u00e9l\u00e9ments de la brigade de lutte contre les d\u00e9lits \u00e9conomiques et financiers sont parvenus \u00e0 mettre fin \u00e0 l\u2019activit\u00e9","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-02-16T12:10:03+00:00","article_modified_time":"2025-02-16T12:10:04+00:00","og_image":[{"width":764,"height":513,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/devises.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis","datePublished":"2025-02-16T12:10:03+00:00","dateModified":"2025-02-16T12:10:04+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/"},"wordCount":287,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/devises.png","articleSection":["R\u00e9gions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/","name":"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/devises.png","datePublished":"2025-02-16T12:10:03+00:00","dateModified":"2025-02-16T12:10:04+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/devises.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/08\/devises.png","width":764,"height":513},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/02\/16\/el-tarf-plus-de-35-kilos-dor-et-de-50-430-euros-saisis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"El Tarf : Plus de 3,5 kilos d&rsquo;or et de 50.430 euros saisis"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/62987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=62987"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/62987\/revisions"}],"predecessor-version":[{"id":62989,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/62987\/revisions\/62989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/55259"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=62987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=62987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=62987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}