{"id":65926,"date":"2025-04-19T13:48:00","date_gmt":"2025-04-19T12:48:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=65926"},"modified":"2025-04-19T14:09:53","modified_gmt":"2025-04-19T13:09:53","slug":"investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/","title":{"rendered":"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&nbsp;Le Groupe Sonatrach a sign\u00e9 durant le mois d&rsquo;avril en cours, plusieurs conventions de financement et de parrainage au niveau de plusieurs wilayas, dans le cadre de son programme d&rsquo;investissement social, indique, jeudi, un communiqu\u00e9 du groupe. A Tamanrasset, une convention a \u00e9t\u00e9 sign\u00e9e le 16 avril en cours, portant financement d&rsquo;\u00e9quipements et de mat\u00e9riels m\u00e9dicaux au profit des structures sanitaires locales. La c\u00e9r\u00e9monie de signature s&rsquo;est d\u00e9roul\u00e9e en pr\u00e9sence du wali de Tamanrasset, Boudraa Mohamed, de cadres relevant du d\u00e9partement parrainage et investissement social et des autorit\u00e9s locales. En date du 14 avril, le groupe p\u00e9tro-gazier a conclu, au si\u00e8ge de la wilaya d&rsquo;Illizi, un accord dans le domaine de l&rsquo;investissement social, pr\u00e9voyant le financement de l&rsquo;acquisition d&rsquo;\u00e9quipements et de mat\u00e9riels m\u00e9dicaux au profit du secteur m\u00e9dical, et ce en pr\u00e9sence du repr\u00e9sentant du groupe, Ahc\u00e8ne Khaldi, et des autorit\u00e9s locales. A Timimoune, le Groupe a sign\u00e9, le 10 avril en cours, une convention de parrainage avec les autorit\u00e9s locales, en vertu de laquelle un financement sera allou\u00e9 pour la dotation d&rsquo;une \u00e9cole mod\u00e8le en mat\u00e9riel informatique ainsi que pour l&rsquo;acquisition de livres au profit de la biblioth\u00e8que de l&rsquo;\u00e9cole. Cette convention qui s&rsquo;inscrit dans le cadre du soutien au secteur de l&rsquo;\u00e9ducation et du renforcement des moyens p\u00e9dagogiques au profit des \u00e9l\u00e8ves, s&rsquo;est d\u00e9roul\u00e9e sous la supervision du wali de Timimoune, et en pr\u00e9sence des repr\u00e9sentants de sonatrach, et des autorit\u00e9s locales. Aussi, des aides financi\u00e8res ont \u00e9t\u00e9 octroy\u00e9es par le groupe Sonatrach et ses diff\u00e9rentes filiales, au profit des wilayas de Timimoune, Illizi, Djanet, et Tamanrasset, \u00e0 travers des conventions de sponsoring destin\u00e9es au soutien des clubs sportifs locaux. En tout, plus de 64 conventions ont \u00e9t\u00e9 sign\u00e9es dans le cadre de ces initiatives, ce qui refl\u00e8te l&rsquo;engagement du groupe \u00e0 encourager le sport local, et son attachement \u00e0 \u00e9riger l&rsquo;activit\u00e9 sportive en un levier essentiel du d\u00e9veloppement soci\u00e9tal. Ces conventions refl\u00e8tent \u00e9galement \u00ab\u00a0l&rsquo;attachement constant du groupe \u00e0 s&rsquo;acquitter de son r\u00f4le en tant que partenaire essentiel dans le soutien du processus de d\u00e9veloppement durable, \u00e0 travers des initiatives responsables visant \u00e0 contribuer \u00e0 l&rsquo;am\u00e9lioration du cadre de vie des citoyens\u00a0\u00bb, ajoute le communiqu\u00e9. \u00ab\u00a0Ces projets traduisent \u00e9galement l&rsquo;engagement du Groupe \u00e0 renforcer sa pr\u00e9sence avec son environnement social, et \u00e0 ancrer les valeurs de citoyennet\u00e9 et d&rsquo;entraide, \u00e0 travers des projets concrets au service de la soci\u00e9t\u00e9 et r\u00e9pondant \u00e0 ses aspirations dans divers domaines\u00a0\u00bb, conclut le communiqu\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Le Groupe Sonatrach a sign\u00e9 durant le mois d&rsquo;avril en cours, plusieurs conventions de financement et de parrainage au niveau<\/p>\n","protected":false},"author":6,"featured_media":65927,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[29],"tags":[],"class_list":["post-65926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"&nbsp;Le Groupe Sonatrach a sign\u00e9 durant le mois d&rsquo;avril en cours, plusieurs conventions de financement et de parrainage au niveau\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-19T12:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-19T13:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/04\/491360910_992535159733721_5371679458108690629_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1365\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage\",\"datePublished\":\"2025-04-19T12:48:00+00:00\",\"dateModified\":\"2025-04-19T13:09:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/491360910_992535159733721_5371679458108690629_n.jpg\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/\",\"name\":\"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/491360910_992535159733721_5371679458108690629_n.jpg\",\"datePublished\":\"2025-04-19T12:48:00+00:00\",\"dateModified\":\"2025-04-19T13:09:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/491360910_992535159733721_5371679458108690629_n.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/491360910_992535159733721_5371679458108690629_n.jpg\",\"width\":1365,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/04\\\/19\\\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/","og_locale":"fr_FR","og_type":"article","og_title":"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage - La Sentinelle","og_description":"&nbsp;Le Groupe Sonatrach a sign\u00e9 durant le mois d&rsquo;avril en cours, plusieurs conventions de financement et de parrainage au niveau","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-04-19T12:48:00+00:00","article_modified_time":"2025-04-19T13:09:53+00:00","og_image":[{"width":1365,"height":1365,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/04\/491360910_992535159733721_5371679458108690629_n.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage","datePublished":"2025-04-19T12:48:00+00:00","dateModified":"2025-04-19T13:09:53+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/04\/491360910_992535159733721_5371679458108690629_n.jpg","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/","name":"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/04\/491360910_992535159733721_5371679458108690629_n.jpg","datePublished":"2025-04-19T12:48:00+00:00","dateModified":"2025-04-19T13:09:53+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/04\/491360910_992535159733721_5371679458108690629_n.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/04\/491360910_992535159733721_5371679458108690629_n.jpg","width":1365,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/04\/19\/investissement-social-sonatrach-signe-plusieurs-conventions-de-financement-et-de-parrainage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Investissement social: Sonatrach signe plusieurs conventions de financement et de parrainage"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/65926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=65926"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/65926\/revisions"}],"predecessor-version":[{"id":65928,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/65926\/revisions\/65928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/65927"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=65926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=65926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=65926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}