{"id":67430,"date":"2025-05-15T11:01:25","date_gmt":"2025-05-15T10:01:25","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=67430"},"modified":"2025-05-17T11:02:00","modified_gmt":"2025-05-17T10:02:00","slug":"lalgerie-mene-une-guerre-implacable-contre-la-drogue","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/","title":{"rendered":"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&rsquo;Alg\u00e9rie intensifie sa lutte contre le trafic de stup\u00e9fiants sur fond d&rsquo;augmentation alarmante des saisies et d&rsquo;un durcissement l\u00e9gislatif sans pr\u00e9c\u00e9dent. Face \u00e0 ce fl\u00e9au consid\u00e9r\u00e9 d\u00e9sormais comme une menace pour la s\u00e9curit\u00e9 nationale, le ministre de la Justice, Lotfi Boudjemaa, a r\u00e9affirm\u00e9 la d\u00e9termination de l&rsquo;\u00c9tat \u00e0 mener \u00ab\u00a0une guerre implacable contre les bandes de trafiquants de drogue\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors d&rsquo;une s\u00e9ance \u00e0 l&rsquo;Assembl\u00e9e populaire nationale (APN) consacr\u00e9e au projet de loi relatif \u00e0 la pr\u00e9vention contre la drogue, le ministre a soulign\u00e9 la gravit\u00e9 de la situation actuelle, d\u00e9clarant qu&rsquo;il s&rsquo;agissait d&rsquo;une v\u00e9ritable \u00ab\u00a0guerre contre l&rsquo;Alg\u00e9rie\u00a0\u00bb. Dans ce contexte, le pays est r\u00e9solu, \u00ab\u00a0gr\u00e2ce \u00e0 ses hommes loyaux des corps de s\u00e9curit\u00e9 et de l&rsquo;Arm\u00e9e nationale populaire (ANP)\u00a0\u00bb, \u00e0 neutraliser les r\u00e9seaux de narcotrafiquants, avec l&rsquo;assurance que \u00ab\u00a0la justice sera intransigeante et les \u00e9radiquera\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La modification de la l\u00e9gislation en vigueur s&rsquo;explique, selon le garde des Sceaux, par la \u00ab\u00a0prolif\u00e9ration alarmante\u00a0\u00bb du ph\u00e9nom\u00e8ne, n\u00e9cessitant une r\u00e9vision urgente \u00ab\u00a0pour mettre un terme \u00e0 ce crime par des moyens coercitifs\u00a0\u00bb. Le ministre a rappel\u00e9 \u00e0 cet \u00e9gard les importantes quantit\u00e9s de substances psychotropes saisies ces derniers mois dans diff\u00e9rentes r\u00e9gions du pays. Le projet de loi pr\u00e9voit plusieurs dispositions novatrices, notamment des incitations financi\u00e8res pour les lanceurs d&rsquo;alerte. M. Boudjemaa a pr\u00e9cis\u00e9 que \u00ab\u00a0l&rsquo;Alg\u00e9rie est le seul pays arabe \u00e0 adopter une telle mesure\u00a0\u00bb, tout en soulignant qu&rsquo;il s&rsquo;agit d&rsquo;une \u00ab\u00a0r\u00e9compense p\u00e9cuniaire accord\u00e9e uniquement \u00e0 toute personne ayant fourni des informations ayant conduit \u00e0 des r\u00e9sultats positifs\u00a0\u00bb, tandis que \u00ab\u00a0toute information visant \u00e0 impliquer injustement une personne engage l&rsquo;enti\u00e8re responsabilit\u00e9 de son auteur\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le texte aborde \u00e9galement la possibilit\u00e9 de fermeture d&rsquo;\u00e9tablissements h\u00f4teliers impliqu\u00e9s dans le trafic. Le ministre a tenu \u00e0 clarifier que cette disposition \u00ab\u00a0s&rsquo;adresse au propri\u00e9taire ou au responsable de l&rsquo;h\u00f4tel ayant transform\u00e9 l&rsquo;\u00e9tablissement en lieu de trafic de drogues\u00a0\u00bb. Concernant la pr\u00e9vention, le projet de loi pr\u00e9voit l&rsquo;obligation pour les candidats aux concours de recrutement de pr\u00e9senter des tests m\u00e9dicaux n\u00e9gatifs au d\u00e9pistage de substances psychotropes. M. Boudjemaa a expliqu\u00e9 que l&rsquo;objectif de cette mesure est de \u00ab\u00a0prendre en charge les concern\u00e9s en cas de r\u00e9sultats positifs\u00a0\u00bb, pr\u00e9cisant que toutes les wilayas disposent d\u00e9j\u00e0 de centres de d\u00e9sintoxication et que, \u00ab\u00a0en application des instructions du pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, il sera proc\u00e9d\u00e9 \u00e0 la construction de quatre autres centres modernes de prise en charge des victimes de drogues\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L&rsquo;\u00c9tat pour l&rsquo;ex\u00e9cution de la peine capitale<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;une des dispositions les plus importantes du projet de loi concerne l&rsquo;introduction de la peine capitale pour certains crimes li\u00e9s au trafic de stup\u00e9fiants. Interrog\u00e9 sur ce point, le ministre de la Justice a d\u00e9fendu avec fermet\u00e9 cette orientation, affirmant que l&rsquo;Alg\u00e9rie \u00ab\u00a0en tant qu&rsquo;\u00c9tat souverain est libre de prendre n&rsquo;importe quelle d\u00e9cision pour lutter contre le crime selon la mani\u00e8re qu&rsquo;elle juge la plus appropri\u00e9e\u00a0\u00bb. Il a ajout\u00e9 que face \u00e0 la gravit\u00e9 de la situation actuelle, l&rsquo;\u00c9tat alg\u00e9rien a estim\u00e9 que cela \u00ab\u00a0exige l&rsquo;activation de la peine capitale\u00a0\u00bb. Cette position marque un tournant dans la politique p\u00e9nale du pays, qui observe un moratoire de fait sur les ex\u00e9cutions depuis pr\u00e8s de trois d\u00e9cennies, bien que la peine de mort figure toujours dans l&rsquo;arsenal juridique alg\u00e9rien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le garde des Sceaux a \u00e9galement abord\u00e9 la question de l&rsquo;incitation \u00e0 la consommation de drogues, quel qu&rsquo;en soit le moyen, y compris par le chant, r\u00e9it\u00e9rant que toute forme d&rsquo;encouragement \u00e0 un acte criminel est punissable par la loi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un ph\u00e9nom\u00e8ne d&rsquo;une ampleur alarmante<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les statistiques r\u00e9centes t\u00e9moignent de l&rsquo;ampleur pr\u00e9occupante qu&rsquo;a prise le trafic de drogue en Alg\u00e9rie. &nbsp;Le bilan annuel 2024 de la Gendarmerie nationale confirme cette tendance avec une augmentation de 152% des saisies de drogues dures par rapport \u00e0 2023. Les services comp\u00e9tents ont d\u00e9mantel\u00e9 82 r\u00e9seaux de trafic de drogue et 110 r\u00e9seaux sp\u00e9cialis\u00e9s dans les comprim\u00e9s psychotropes, saisissant plus de 26 tonnes de kif trait\u00e9, 9,9 millions de comprim\u00e9s psychotropes et plus de 147 kilogrammes de coca\u00efne. Le nombre de narcotrafiquants arr\u00eat\u00e9s a augment\u00e9 de 18%, atteignant plus de 24 000 individus, parmi lesquels des barons de la drogue et des trafiquants marocains. L&rsquo;ANP pr\u00e9sente un bilan tout aussi \u00e9loquent pour 2024 avec l&rsquo;arrestation de 2 621 narcotrafiquants et la mise en \u00e9chec de l&rsquo;introduction de 36,8 tonnes de kif trait\u00e9 provenant des fronti\u00e8res avec le Maroc, sans compter 631 kilogrammes de coca\u00efne et 25 millions de comprim\u00e9s psychotropes saisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Monstre d&rsquo;Oran, la mise au point<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le ministre de la Justice, Lotfi Boudjemaa, a tenu \u00e0 apporter des clarifications concernant des informations r\u00e9cemment relay\u00e9es sur les r\u00e9seaux sociaux, relatives au viol de \u00ab\u00a040 enfants dans la wilaya d&rsquo;Oran\u00a0\u00bb par un individu, ainsi qu&rsquo;\u00e0 l&rsquo;arrestation d&rsquo;un fonctionnaire du minist\u00e8re en possession de stup\u00e9fiants. Il a pr\u00e9cis\u00e9 que la premi\u00e8re affaire concerne un individu actuellement \u00ab\u00a0sous enqu\u00eate judiciaire\u00a0\u00bb, et que l&rsquo;affaire \u00ab\u00a0concerne, pr\u00e9sentement, un seul cas de viol\u00a0\u00bb. Quant \u00e0 la seconde affaire, le ministre a indiqu\u00e9 que le fonctionnaire en question, qui est un chauffeur, \u00e9tait en possession de \u00ab\u00a079 grammes\u00a0\u00bb de stup\u00e9fiants et de deux t\u00e9l\u00e9phones portables, et qu&rsquo;il se trouvait dans son v\u00e9hicule personnel, contrairement \u00e0 ce qui avait \u00e9t\u00e9 rapport\u00e9 dans certains m\u00e9dias. Il a par ailleurs appel\u00e9 \u00e0 la prudence face aux informations non v\u00e9rifi\u00e9es circulant notamment sur les r\u00e9seaux sociaux, rappelant que, lorsqu&rsquo;une affaire n\u00e9cessite d&rsquo;\u00eatre port\u00e9e \u00e0 la connaissance de l&rsquo;opinion publique, \u00ab\u00a0les parquets de la R\u00e9publique communiquent l&rsquo;information via des communiqu\u00e9s\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chokri Hafed<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Alg\u00e9rie intensifie sa lutte contre le trafic de stup\u00e9fiants sur fond d&rsquo;augmentation alarmante des saisies et d&rsquo;un durcissement l\u00e9gislatif sans<\/p>\n","protected":false},"author":6,"featured_media":42978,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,27],"tags":[],"class_list":["post-67430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;Alg\u00e9rie intensifie sa lutte contre le trafic de stup\u00e9fiants sur fond d&rsquo;augmentation alarmante des saisies et d&rsquo;un durcissement l\u00e9gislatif sans\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T10:01:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-17T10:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1210\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue\",\"datePublished\":\"2025-05-15T10:01:25+00:00\",\"dateModified\":\"2025-05-17T10:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/\"},\"wordCount\":1037,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/kif.jpg\",\"articleSection\":[\"\u00c0 la Une\",\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/\",\"name\":\"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/kif.jpg\",\"datePublished\":\"2025-05-15T10:01:25+00:00\",\"dateModified\":\"2025-05-17T10:02:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/kif.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/kif.jpg\",\"width\":1210,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/15\\\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/","og_locale":"fr_FR","og_type":"article","og_title":"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue - La Sentinelle","og_description":"L&rsquo;Alg\u00e9rie intensifie sa lutte contre le trafic de stup\u00e9fiants sur fond d&rsquo;augmentation alarmante des saisies et d&rsquo;un durcissement l\u00e9gislatif sans","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-05-15T10:01:25+00:00","article_modified_time":"2025-05-17T10:02:00+00:00","og_image":[{"width":1210,"height":682,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue","datePublished":"2025-05-15T10:01:25+00:00","dateModified":"2025-05-17T10:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/"},"wordCount":1037,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","articleSection":["\u00c0 la Une","Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/","name":"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","datePublished":"2025-05-15T10:01:25+00:00","dateModified":"2025-05-17T10:02:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","width":1210,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/15\/lalgerie-mene-une-guerre-implacable-contre-la-drogue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Alg\u00e9rie m\u00e8ne \u00ab\u00a0une guerre implacable\u00a0\u00bb contre \u00a0la drogue"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/67430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=67430"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/67430\/revisions"}],"predecessor-version":[{"id":67432,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/67430\/revisions\/67432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/42978"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=67430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=67430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=67430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}